{"id":70981,"date":"2009-08-12T10:04:58","date_gmt":"2009-08-12T10:04:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/12\/les-etats-de-lunion-contre-la-militarisation-corporatiste\/"},"modified":"2009-08-12T10:04:58","modified_gmt":"2009-08-12T10:04:58","slug":"les-etats-de-lunion-contre-la-militarisation-corporatiste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/12\/les-etats-de-lunion-contre-la-militarisation-corporatiste\/","title":{"rendered":"Les Etats de l&rsquo;Union contre la \u201cmilitarisation corporatiste\u201d"},"content":{"rendered":"<p><h2 class=\"common-article\">Les Etats de l&rsquo;Union contre la militarisation corporatiste<\/h2>\n<\/p>\n<p><p>\t12 ao\u00fbt 2009  Nous revenons sur l&rsquo;information que nous avons d\u00e9velopp\u00e9e dans notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-les_etats_de_l_union_contre_le_pentagone_11_08_2009.html\" class=\"gen\">11 ao\u00fbt 2009<\/a>, concernant l&rsquo;opposition des Etats de l&rsquo;Union \u00e0 certains projets du Pentagone, essentiellement celui de prendre sous contr\u00f4le, en cas de situation d&rsquo;urgence, le commandement des unit\u00e9s militaires (Garde Nationale) dont l&rsquo;autorit\u00e9 rel\u00e8ve des gouverneurs. <\/p>\n<\/p>\n<p><p>\tCette p\u00e9rip\u00e9tie doit \u00eatre consid\u00e9r\u00e9e \u00e0 la lumi\u00e8re de l&rsquo;affrontement entre le pouvoir central (f\u00e9d\u00e9ral) et les pouvoirs des Etats, qui est au cur de la fragilit\u00e9 structurelle des USA. Cette fragilit\u00e9 est aujourd&rsquo;hui mise en \u00e9vidence par la tension n\u00e9e de la crise, qui conduit \u00e0 charger les Etats de l&rsquo;Union d&rsquo;obligations budg\u00e9taires consid\u00e9rables constantes alors que leurs ressources ne cessent de se r\u00e9duire. Cela conduit \u00e0 des situations de quasi-faillite qui sont aujourd&rsquo;hui largement connues, qui exacerbent effectivement les rapports avec le centre f\u00e9d\u00e9ral que les Etats continuent \u00e0 subventionner par les imp\u00f4ts de ses citoyens sans que ce pouvoir f\u00e9d\u00e9ral ne les aide \u00e0 mesure, en retour.<\/p>\n<\/p>\n<p><p>\tLa question des projets du Pentagone est d&rsquo;une autre cat\u00e9gorie, mais elle entre effectivement dans la m\u00eame structure crisique des rapports entre les Etats et le centre. (Cette structure crisique a bien entendu touch\u00e9 le centre en priorit\u00e9, qui s&rsquo;est \u00e0 la fois bureaucratis\u00e9 et privatis\u00e9 avec les rapports structurels massifs \u00e9tablis entre les bureaucraties et les diverses puissances priv\u00e9es dans diff\u00e9rents domaines.) Ces projets du Pentagone sont de pur type bureaucratique, avec la tendance de la bureaucratie \u00e0 toujours \u00e9tendre ses investissements, ses pouvoirs de contr\u00f4le, etc. Ses projets de contr\u00f4le de la Garde Nationale sont \u00e0 placer sur le m\u00eame plan que son expansion continuelle dans un r\u00e9seau de bases ext\u00e9rieurs (plus de 700), le r\u00e9sultat \u00e9tant d&rsquo;ailleurs, comme toujours dans le mouvement bureaucratique, un accroissement constant des charges sans avantages politiques et militaires d\u00e9cisifs, et m\u00eame, en temps de crise, pour un r\u00e9sultat contraire. Le but recherch\u00e9 n&rsquo;est d&rsquo;ailleurs pas politique et militaire mais un simple mouvement automatique de renforcement de soi-m\u00eame (de la bureaucratie).<\/p>\n<\/p>\n<p><p>\tMais le projet interne aux USA de militarisation a un aspect particulier int\u00e9ressant, c&rsquo;est qu&rsquo;il soul\u00e8ve de v\u00e9ritables et fortes  r\u00e9sistances au cur m\u00eame de l&rsquo;institution militaire. Il faut signaler pour cela un article tr\u00e8s int\u00e9ressant publi\u00e9 dans la revue de l&rsquo;USAF et de la National Air University, <em>Air &#038; Space Power Journal<\/em> (ASPJ). Une premi\u00e8re version en langue originale (l&rsquo;article date du 1er mars 2008) a \u00e9t\u00e9 publi\u00e9 dans ASPJ, num\u00e9ro du <a href=\"http:\/\/www.airpower.maxwell.af.mil\/airchronicles\/apj\/apj08\/spr08\/watson.html\" class=\"gen\">printemps 2008<\/a>. Il semble avoir \u00e9t\u00e9 jug\u00e9 assez significatif et int\u00e9ressant pour \u00eatre publi\u00e9 \u00e0 nouveau, en traduction fran\u00e7aise, dans le num\u00e9ro de l&rsquo;\u00e9t\u00e9 2009 de ASPJ en version fran\u00e7aise (nous avons d\u00e9j\u00e0 parl\u00e9 de cette <a href=\"http:\/\/www.dedefensa.org\/article-une_initiative_revelatrice_10_02_2006.html?admin=1\" class=\"gen\">version fran\u00e7aise<\/a>), sous le titre: \u00ab<em>La descente sur la pente glissante : les op\u00e9rations sur le territoire national, l&rsquo;externalisation et l&rsquo;\u00e9rosion de la culture militaire.<\/em>\u00bb (Actuellement, le contenu du num\u00e9ro \u00e9t\u00e9 2009 de ASPJ <a href=\"http:\/\/www.airpower.au.af.mil\/apjinternational\/aspjfrench.html\" class=\"gen\">en fran\u00e7ais<\/a> n&rsquo;est pas encore mis en ligne ; dans ce titre, le mot &lsquo;externalisation, qui d\u00e9finit les t\u00e2ches militaires, correspond \u00e0 notre id\u00e9e de privatisation, c&rsquo;est-\u00e0-dire des accords contractuels avec des entreprises priv\u00e9es pour des missions militaires.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;article est du major Bryan D. Watson, de l&rsquo;USAF, qui est un juge militaire install\u00e9 \u00e0 la base de l&rsquo;USAF de Randolph, au Texas, o\u00f9 il pr\u00e9side des cours martiales, des tribunaux militaires et des commissions administratives. Cet article est int\u00e9ressant dans la mesure o\u00f9 il relie d&rsquo;une mani\u00e8re intime, presque avec un rapport r\u00e9ciproque de cause \u00e0 effet, l&rsquo;extension des t\u00e2ches de l&rsquo;arm\u00e9e US sur le territoire nationale et la privatisation de l&rsquo;arm\u00e9e. Watson juge tr\u00e8s s\u00e9v\u00e8rement ces deux \u00e9volutions, comme constituant une trahison de l&rsquo;esprit militaire et de la culture militaire, nullement au profit d&rsquo;un pouvoir de l&rsquo;arm\u00e9e mais aux d\u00e9pens de la sp\u00e9cificit\u00e9 des forces arm\u00e9es.<\/p>\n<\/p>\n<p><p>\tNotamment, l&rsquo;article rassemble un nombre de pr\u00e9cisions impressionnantes sur la privatisation de l&rsquo;arm\u00e9e, sur le fait que les contractants priv\u00e9s sont aujourd&rsquo;hui instruits pour intervenir dans des cas de contr\u00f4le des actions les plus avanc\u00e9es (comme celui du contr\u00f4le de v\u00e9hicules a\u00e9riens sans pilotes qui interviennent dans des conflits). Certains syst\u00e8mes militaires, notamment certains v\u00e9hicules, sont quasiment r\u00e9serv\u00e9s aux contractants civils puisqu&rsquo;aucun entra\u00eenement ni instruction de base pour leur usage n&rsquo;est pr\u00e9vu pour des militaires.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>True, the American military historically has relied upon contractors&rsquo; services, but in Iraq and Afghanistan, the reliance became unprecedented. In Iraq we employed contractors after we fielded systems so new that the services could not develop training courses for uniformed personnel. For example, during the first combat deployment of the RQ-4A Global Hawk unmanned aerial vehicle in support of Operation Enduring Freedom, 56 contractors deployed as part of an 82-member military, civil service, and contractor team. Subsequently, the use of contractors in this type of role grew further, to the point that contractors began conducting combat-type operations that included operat[ing] the [Global Hawk] and even serv[ing] as Global Hawk pilots.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous citons la conclusion de son article (en anglais). La forme du texte est distrayante parce que d\u00e9velopp\u00e9e selon la forme de la politique-fiction; Watson se place comme s&rsquo;il \u00e9crivait en 2017, constatant combien les choses ont chang\u00e9, non seulement pour l&rsquo;omnipr\u00e9sence des forces arm\u00e9es aux USA m\u00eame, mais <strong>d&rsquo;abord<\/strong> pour la compl\u00e8te dissolution de la culture militaire au profit (?) d&rsquo;un amalgame incontr\u00f4lable, o\u00f9 l&rsquo;on ne reconna\u00eet plus un v\u00e9ritable soldat d&rsquo;un contractant de Blackwater ou d&rsquo;une autre soci\u00e9t\u00e9 priv\u00e9e, o\u00f9 l&rsquo;on ne sait plus qui commande quoi, qui donne des ordres \u00e0 qui, etc.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>As I close, I ask you to consider the fact that our government has long recognized that the military is, by necessity, a specialized society separate from civilian society. (Parker v. Levy, in Supreme Court Reporter, vol. 94 (1974), 2547.) Consequently, other governmental officials historically have had a willingness to defer to the judgments of military decision makers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Well, according to some folks in our government, a specialized society separate from civilian society simply no longer exists. They argue that the blending of contractors and interagency workers into our domestic military structure has ended a separate culture. After all, why should military members fall into some different category when they do the same job as contractors? Today, does anything really set the military apart?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>To cite a quick example, currently in 2017 you should know about the push to expand the MEJA as a comprehensive replacement for the UCMJ. As you might recall from my earlier comments, the MEJA served as a mechanism for addressing criminal activity among civilians in support of combat operations overseas. Now, however, some people argue that civilian laws should remain the sole means of addressing criminal activity by all members of the defense teamthat we should treat contractors, military, National Guard, and other employees equally under the law. To the uninitiated, this argument might seem compelling. However, if this effort succeeds, commanders will no longer be involved in even the most serious disciplinary issues affecting their troops. Interestingly, some analysts say that these efforts arise from the fact that few lawmakers nowadays have any military experience.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I ask you to consider carefully a couple of final thoughts. First, think about George Washington&rsquo;s famous admonition that discipline is the soul of an army. If that&rsquo;s trueand I think it is where does that leave us today, when we rely so heavily on contractors? Second, as you think about the proper role of a military in a democracy, I want you to consider Chief Justice Earl Warren&rsquo;s observation that the military establishment is, of course, a necessary organ of government; but the reach of its power must be carefully limited lest the delicate balance between freedom and order be upset. Has our society somehow lost the ability to limit the military establishment&rsquo;s reach? Does it matter that the definition of our military establishment has radically changed?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In terms of the bottom line, we face some tough times, but I&rsquo;m confident that we&rsquo;ll work through them. This afternoon, I&rsquo;m headed back to Washington to continue reconstituting our force, but before I go, I really want to know what you think.<\/em>\u00bb<\/p>\n<h3>La d\u00e9volution structurante<\/h3>\n<\/p>\n<p><p>\tNous sommes habitu\u00e9s \u00e0 penser et \u00e0 parler en termes europ\u00e9ens (fran\u00e7ais) et en termes politiques, d\u00e9finissant le plus souvent des situations d\u00e9pass\u00e9es, relevant d&rsquo;\u00e9v\u00e9nements souvent int\u00e9rieurs du XX\u00e8me si\u00e8cle (et m\u00eame en-de\u00e7a), avec les frustrations sans nombre qui vont avec puisque l&rsquo;histoire politique n&rsquo;est qu&rsquo;une suite d&rsquo;\u00e9checs par rapport aux utopies qui servirent de r\u00e9f\u00e9rences. Ainsi, lorsque nous envisageons un tel cas de volont\u00e9 d&rsquo;expansion du contr\u00f4le du Pentagone sur le territoire US, nous songeons aussit\u00f4t au pouvoir militaire, au pouvoir dictatorial,  et, bien entendu, pour certains, comme un bon vieux r\u00e9flexe conditionn\u00e9 du bon vieux temps,  au fascisme.<\/p>\n<\/p>\n<p><p>\tLa situation actuelle n&rsquo;a strictement aucun rapport avec ces termes d\u00e9crivant des situations compl\u00e8tement d\u00e9pass\u00e9es. Le centre f\u00e9d\u00e9ral, comme tous les pouvoirs politiques occidentalistes en g\u00e9n\u00e9ral, n&rsquo;a cess\u00e9 de perdre sa puissance,  pour ne pas parler de la puissance r\u00e9galienne inconnue aux USA (mais \u00e9videmment connue en Europe, surtout en France). Cela s&rsquo;est fait au profit d&rsquo;une \u00e9volution absolument d\u00e9structurante, qui est le m\u00e9lange d\u00e9crit plus haut pour l&rsquo;arm\u00e9e,  bureaucratie plus privatisation. L&rsquo;incursion de la privatisation (voir l&rsquo;historique du <a href=\"http:\/\/www.dedefensa.org\/article-l_histoire_du_manifeste_powell_ou_la_mise_a_nu_de_l_histoire_de_l_amerique_plongee_dans_sa_bataille_interne_sans_pitie_23_08_2002.html\" class=\"gen\">Manifeste Powell<\/a>), \u00e9manant de ce que Naomi Klein nomme le <em>corporate power<\/em>, sugg\u00e8re, \u00e0 cause m\u00eame de cette expression, une image trompeuse. Les entit\u00e9s \u00e9conomiques ne forment pas, dans leur rassemblement, un pouvoir coh\u00e9rent. Elles r\u00e9pondent \u00e0 des int\u00e9r\u00eats qui leur sont propres, qui sont naturellement divergents. Elles n&rsquo;ont qu&rsquo;une chose en commun, qui est la lutte contre le pouvoir politique par simple dynamique antagoniste; parce qu&rsquo;elles sont naturellement d\u00e9structurantes, tandis que le pouvoir politique est \u00e0 l&rsquo;origine une proposition fondamentalement structurante (encore plus, bien s\u00fbr, s&rsquo;il est r\u00e9galien). Un pouvoir \u00e0 vocation d\u00e9structurante est une contradiction en soi; il est tout sauf un pouvoir.<\/p>\n<\/p>\n<p><p>\tLe Pentagone est une entit\u00e9 extr\u00eamement bureaucratis\u00e9e et d\u00e9sormais fortement corporatis\u00e9e (employons ce n\u00e9ologisme plut\u00f4t que privatis\u00e9e, mais l&rsquo;id\u00e9e est la m\u00eame), o\u00f9 le pouvoir politique est de plus en plus impuissant (c&rsquo;est l&rsquo;image du secr\u00e9taire \u00e0 la d\u00e9fense Cohen en 1998: le secr\u00e9taire \u00e0 la d\u00e9fense comme un Achab impuissant sur un <em>Moby Dick<\/em> d\u00e9cha\u00een\u00e9). Son mouvement vers le contr\u00f4le de l&rsquo;int\u00e9rieur du pays est donc un mouvement bureaucratis\u00e9 et corporatis\u00e9, selon la philosophie que d\u00e9nonce le major-juge Watson de l&rsquo;USAF. (Watson lui oppose la culture militaire,  quel que soit son contenu, qui n&rsquo;est pas ici le sujet,  parce qu&rsquo;il s&rsquo;agit bien d&rsquo;une expression d\u00e9signant, pour un militaire, une situation structur\u00e9e avec des valeurs p\u00e9rennes propres \u00e0 la fonction militaire et qui sont en train de dispara\u00eetre: discipline, honneur, etc.) Le but du Pentagone n&rsquo;est pas le pouvoir politique sur le territoire (dictature, fascisme et ainsi de suite) mais la destruction du pouvoir politique. C&rsquo;est pourquoi il s&rsquo;attaque aux pouvoirs des Etats de l&rsquo;Union, qu&rsquo;il per\u00e7oit comme des pouvoirs politiques \u00e9chappant au grand mouvement d\u00e9structurant qui est en cours, et tr\u00e8s efficacement, \u00e0 Washington, dans le cur du centre.<\/p>\n<\/p>\n<p><p>\tCette situation est int\u00e9ressante parce qu&rsquo;elle permet de mieux d\u00e9finir les enjeux en cours aux USA. L&rsquo;attaque du Pentagone pourrait, \u00e0 premi\u00e8re vue, para\u00eetre structurante, quoique de mauvaise r\u00e9putation, en luttant contre la tendance \u00e0 la d\u00e9volution (ou \u00e0 la s\u00e9cession),  th\u00e8se type-pouvoir militaire\/fasciste. En fait, c&rsquo;est compl\u00e8tement le contraire. Cette attaque est d\u00e9structurante par sa nature m\u00eame, en r\u00e9pandant le poison d\u00e9structurant qui d\u00e9truit tout pouvoir politique puisqu&rsquo;il est lui-m\u00eame l&rsquo;antith\u00e8se du pouvoir politique. On arrive ainsi au paradoxe de constater qu&rsquo;aux USA, le mouvement en apparence d\u00e9structurant de la d\u00e9volution (de la s\u00e9cession) serait en r\u00e9alit\u00e9 un mouvement qui aurait pour effet de prot\u00e9ger, voire de renforcer les structures politiques existantes (dans les Etats de l&rsquo;Union), c&rsquo;est-\u00e0-dire qu&rsquo;il s&rsquo;agirait d&rsquo;un mouvement absolument structurant. Mais nous nous y retrouvons \u00e9videmment: un mouvement de d\u00e9structuration (la d\u00e9volution) d&rsquo;un ensemble dont la dynamique est devenue d\u00e9structurante, est structurant par cons\u00e9quence contradictoire.<\/p>\n<\/p>\n<p><p>\tEn fait, plus les USA resteront unis comme ils sont, avec un centre cherchant \u00e0 se renforcer, plus le d\u00e9sordre s&rsquo;y accentuera; et plus, bien entendu, ils seront un centre de diffusion du d\u00e9sordre r\u00e9pandu \u00e0 travers le monde, comme le sont aujourd&rsquo;hui toutes leurs entreprises militaires. C&rsquo;est le contraire de l&rsquo;h\u00e9g\u00e9monie imp\u00e9riale triomphante et  sa stabilit\u00e9,  ce qui effectivement rejoint le sch\u00e9ma d&rsquo;une phase destructrice (ouverte \u00e0 la fin des ann\u00e9es 1970, apr\u00e8s le <a href=\"http:\/\/www.dedefensa.org\/article-l_histoire_du_manifeste_powell_ou_la_mise_a_nu_de_l_histoire_de_l_amerique_plongee_dans_sa_bataille_interne_sans_pitie_23_08_2002.html\" class=\"gen\">Manifeste Powell<\/a>) de l&rsquo;h\u00e9g\u00e9monie par influence des USA, triomphante entre 1945 et 1975. Si la chose avait lieu un jour prochain, l&rsquo;\u00e9clatement des USA, au profit des pouvoirs politiques des Etats de l&rsquo;Union, sans doute regroup\u00e9s en zones, serait  un \u00e9v\u00e9nement majeur de tentative de remise en ordre de la situation g\u00e9n\u00e9rale, une pouss\u00e9e structurante importante. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Etats de l&rsquo;Union contre la militarisation corporatiste 12 ao\u00fbt 2009 Nous revenons sur l&rsquo;information que nous avons d\u00e9velopp\u00e9e dans notre Bloc-Notes du 11 ao\u00fbt 2009, concernant l&rsquo;opposition des Etats de l&rsquo;Union \u00e0 certains projets du Pentagone, essentiellement celui de prendre sous contr\u00f4le, en cas de situation d&rsquo;urgence, le commandement des unit\u00e9s militaires (Garde Nationale)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[5078,3568,6579,6398,4889,3194,6326,2949,7845,4935,41,8559],"class_list":["post-70981","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-aspj","tag-corporate","tag-destructurant","tag-devolution","tag-etats","tag-pentagone","tag-privatisation","tag-secession","tag-structurant","tag-union","tag-usaf","tag-watson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70981"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70981\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}