{"id":70984,"date":"2009-08-13T13:46:42","date_gmt":"2009-08-13T13:46:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/13\/le-rapport-csba-la-danse-du-scalp-autour-du-jsf-continue\/"},"modified":"2009-08-13T13:46:42","modified_gmt":"2009-08-13T13:46:42","slug":"le-rapport-csba-la-danse-du-scalp-autour-du-jsf-continue","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/08\/13\/le-rapport-csba-la-danse-du-scalp-autour-du-jsf-continue\/","title":{"rendered":"Le rapport CSBA: la danse du scalp autour du JSF continue"},"content":{"rendered":"<p><p>C&rsquo;est bien un signe de l&rsquo;urgence de la situation lorsqu&rsquo;une agence de presse g\u00e9n\u00e9rale comme Reuters, pr\u00e9sentant un rapport du Center for Strategic and Budgetary Assessments (CSBA) sur la r\u00e9forme n\u00e9cessaire du Pentagone en g\u00e9n\u00e9ral, avec les ajustements budg\u00e9taires qui vont avec, pour accompagner la revue strat\u00e9gique dite QDR (Quadrennial Defense Review) FY2010 en cours de d\u00e9veloppement au sein de ce m\u00eame Pentagone, choisit de centrer son analyse sur le programme F-35\/JSF; nous voulons dire, un signe de l&rsquo;urgence de la situation pour le JSF, certes.<\/p>\n<\/p>\n<p><p>\tLe rapport du CSBA disponible le <a href=\"http:\/\/www.csbaonline.org\/4Publications\/PubLibrary\/R.20090812.Analysis_of_the_FY\/R.20090812.Analysis_of_the_FY.pdf\" class=\"gen\">12 ao\u00fbt 2009<\/a> sur le site de ce <em>think tank<\/em>, analyse en effet la situation du Pentagone en g\u00e9n\u00e9ral. Il la juge tr\u00e8s difficile, de plus en plus difficile dans le cadre g\u00e9n\u00e9ral de la crise financi\u00e8re et \u00e9conomique.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Options for dealing with the tightening budget situation are limited. In the coming years, pressure will likely continue to grow for DoD to scale back its plans, including both major modernization efforts and force structure plans. This <\/em>[FY2010] <em>budget begins the process of cutting some modernization efforts that have been deemed unnecessary or unaffordable. Further cuts may prove challenging as the need to recapitalize equipment continues to grow. It will likely be difficult or impossible to make reductions in some programs and activitiesespecially in the Army and Marine Corps force structureso long as a large US military presence is required in Iraq and Afghanistan or it is deemed necessary to maintain the capability to conduct such large-scale stability operations in the future. The ongoing Quadrennial Defense Review (QDR) will attempt to address many of these strategic questions. Whatever path is selected, effectively addressing the growing cost of DoD&rsquo;s plans and the growing size of the federal deficit will require making some hard decisions. And the sooner those decisions are made the less painful they will be to carry out.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;analyse de Reuters, publi\u00e9e le <a href=\"http:\/\/www.reuters.com\/article\/rbssIndustryMaterialsUtilitiesNews\/idUSN1211640520090812?pageNumber=1\" class=\"gen\">12 ao\u00fbt 2009<\/a> \u00e9galement, d\u00e9veloppe le th\u00e8me, mais en prenant le F-35 comme exemple de la situation au Pentagone<\/p>\n<\/p>\n<p><p>\t\u00ab<em> The Pentagon may want to consider scaling back Lockheed Martin Corp&rsquo;s multinational F-35 fighter program, the costliest-ever U.S. arms-purchase plan, as part of stepped-up budget belt-tightening, an analysis by an influential research group said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The private Center for Strategic and Budgetary Assessments, several of whose one-time experts are now serving in senior Obama administration jobs, cited the F-35 as just one example of programs ripe for review by the Department of Defense during its once-every-four-year, top-to-bottom re-assessment now under way.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Rather than buying both new long-range bombers and thousands of short-range F-35 fighters, DoD might consider whether the new bombers &#8230; could represent a cost-effective substitute for some number of these new fighters, said the CSBA analysis, of President Barack Obama&rsquo;s fiscal 2010 budget request.<\/em> [] <em>Moreover, the use of unmanned systems \u00ab\u00a0could enable a radically different force structure that achieves the same level of effectiveness at a much lower cost,\u00a0\u00bb added the report by the center&rsquo;s Todd Harrison.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn autre aspect important, d&rsquo;ailleurs effleur\u00e9 dans la citation ci-dessus, se trouve dans les pr\u00e9cisions apport\u00e9es sur les liens entre le CSBA et l&rsquo;administration Obama. Reuters consacre un passage, qui n&rsquo;est pas innocent dans ce contexte, \u00e0 cet aspect de la chose.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The private Center for Strategic and Budgetary Assessments, several of whose one-time experts are now serving in senior Obama administration jobs<\/em> [] [<em>The report&rsquo;s author Todd Harrison<\/em>] <em>was tapped this year to replace the CSBA&rsquo;s long-time defense budget analyst, Steven Kosiak, who now oversees defense spending at the White House Office of Management and Budget. Kosiak, along with the center&rsquo;s Barry Watts, voiced similar concerns in a 2007 CSBA report, concluding a decision on the F-35&rsquo;s future should be reached sooner rather than later.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe site hollandais <em>JSF Nieuws<\/em> (ici en traduction anglaise) insiste \u00e9galement beaucoup, ce <a href=\"http:\/\/translate.google.com\/translate?u=http%3A%2F%2Fwww.jsfnieuws.nl&#038;hl=en&#038;ie=UTF-8&#038;sl=nl&#038;tl=en\" class=\"gen\">13 ao\u00fbt 2009<\/a>, sur les liens de l&rsquo;administration Obama, via Kosiak, avec le CSBA. Il se r\u00e9f\u00e8re \u00e9galement \u00e0 cette \u00e9tude de 2007, du m\u00eame Kosiak, qui recommandait de r\u00e9duire la commande USAF de JSF d&rsquo;au moins 50%, et de combler ces vides par un achat de F-16 derni\u00e8re version (F-16C Block 60)<\/p>\n<\/p>\n<p><p>\tA cette lumi\u00e8re, la parution du rapport du CSBA n&rsquo;est pas fortuite. Elle appara\u00eet comme un accompagnement, une mise en condition du monde politique, industriel et m\u00e9diatique, dans une orientation g\u00e9n\u00e9rale qui semble bien \u00eatre celle d&rsquo;une remise en cause des situations g\u00e9n\u00e9rales r\u00e9gnant au Pentagone. Aujourd&rsquo;hui, la crise du Pentagone est une r\u00e9alit\u00e9 accept\u00e9e, act\u00e9e par l&rsquo;administration Obama et par le Congr\u00e8s, et, dans cette crise, la crise du JSF est \u00e0 la fois l&rsquo;arch\u00e9type et, dans le domaine de l&rsquo;acquisition, la partie la plus pressante et la plus lourde. Le climat est en train d&rsquo;\u00e9voluer, \u00e9ventuellement avec une possibilit\u00e9 de basculement, entre l&rsquo;attitude maximaliste tenue ces derniers mois (faire le JSF \u00e0 tout prix et le plus vite possible) et le constat de la crise (impossible de poursuivre comme cela, il faut restructurer le programme JSF). Si, effectivement, l&rsquo;analyse entre dans la r\u00e9solution de la restructuration du programme, des bouleversements sont possibles, sinon probables, selon la philosophie, interpr\u00e9t\u00e9e dans le bon sens, de la bo\u00eete de Pandorre; une fois ce programme expos\u00e9 \u00e0 une \u00e9valuation serr\u00e9e, avec la r\u00e9elle mesure de sa situation, la restructuration qui s&rsquo;annoncerait aurait toutes les chances de d\u00e9clencher un encha\u00eenement de cons\u00e9quences r\u00e9visionnistes. (On notera \u00e9galement pour confirmer cette fragilit\u00e9 crucial du JSF, la nouvelle, avec l&rsquo;interpr\u00e9tation du site <em>ELP Defens(c)e<\/em>, ce <a href=\"http:\/\/ericpalmer.wordpress.com\/2009\/08\/12\/the-warning-signs-are-there-to-see\/\" class=\"gen\">13 ao\u00fbt 2009<\/a>, de nouveaux signes de diffciult\u00e9s internes du programme; il s&rsquo;agit de l&rsquo;annonce du <em>upgrading<\/em> d&rsquo;un certain nombre d&rsquo;avions de production-prototypes, eux-m\u00eames en cours de d\u00e9monstration en vol du programme.) <\/p>\n<\/p>\n<p><p>\tIl semble qu&rsquo;on puisse de plus en plus consid\u00e9rer l&rsquo;hypoth\u00e8se que l&rsquo;intervention du JET, avec le <a href=\"http:\/\/www.dedefensa.org\/article-bho_jet_et_jsf_a_la_recherche_de_la_realite_29_07_2009.html\" class=\"gen\">soutien officiel<\/a> pour en faire une sorte de juge de paix du programme JSF, est un tournant politique important. Cela marque peut-\u00eatre la marche vers la reconqu\u00eate du pouvoir d&rsquo;un programme compl\u00e8tement annex\u00e9 par l&rsquo;\u00e9quipe JPO-LM (JSF Program Office du Pentagone, avec Lockheed Martin) ces derni\u00e8res ann\u00e9es.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 ao\u00fbt 2009 \u00e0 13H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est bien un signe de l&rsquo;urgence de la situation lorsqu&rsquo;une agence de presse g\u00e9n\u00e9rale comme Reuters, pr\u00e9sentant un rapport du Center for Strategic and Budgetary Assessments (CSBA) sur la r\u00e9forme n\u00e9cessaire du Pentagone en g\u00e9n\u00e9ral, avec les ajustements budg\u00e9taires qui vont avec, pour accompagner la revue strat\u00e9gique dite QDR (Quadrennial Defense Review) FY2010 en cours&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6856,2969,4399,8500,7474,250,6855,3501,3502,4482,4105],"class_list":["post-70984","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-csba","tag-f-35","tag-harrison","tag-jet","tag-jp","tag-jsf","tag-kosiak","tag-lockheed","tag-martin","tag-qdr","tag-reuters"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=70984"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/70984\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=70984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=70984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=70984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}