{"id":71072,"date":"2009-09-15T06:33:12","date_gmt":"2009-09-15T06:33:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/15\/le-vieux-couple-et-lenfant-terrible\/"},"modified":"2009-09-15T06:33:12","modified_gmt":"2009-09-15T06:33:12","slug":"le-vieux-couple-et-lenfant-terrible","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/15\/le-vieux-couple-et-lenfant-terrible\/","title":{"rendered":"Le \u201cvieux couple\u201d et l&rsquo;enfant terrible"},"content":{"rendered":"<p><p>Les \u00e9lections allemandes devaient se pr\u00e9parer sur un rythme tranquille, dans une campagne \u00e9lectorale que les strat\u00e8ges \u00e9lectoraux avaient pr\u00e9par\u00e9e avec attention. Le d\u00e9bat t\u00e9l\u00e9vis\u00e9 du 13 septembre 2009 entre la chanceli\u00e8re Merkel, chr\u00e9tienne-d\u00e9mocrate, et son ministre des affaires \u00e9trang\u00e8res Frank-Walter Steinmeier, social-d\u00e9mocrate, a marqu\u00e9 combien ces plans de campagne \u00e9taient fragiles. Non seulement Merkel a \u00e9t\u00e9 domin\u00e9e alors que son parti m\u00e8ne largement dans les sondages, mais surtout ont \u00e9t\u00e9 mis en \u00e9vidence deux points qui peuvent \u00eatre contradictoires et dont la confrontation pourrait \u00eatre explosive:<\/p>\n<\/p>\n<p><p>\t Le caract\u00e8re extr\u00eame d&rsquo;une part du comportement conformiste des candidas, attentifs \u00e0 suivre une ligne extr\u00eamement contr\u00f4l\u00e9e pour \u00e9viter tout contact un peu trop rude avec la r\u00e9alit\u00e9. Un intervenant dans les questions accompagnant le d\u00e9bat t\u00e9l\u00e9vis\u00e9 a fait la remarque ironique que les deux adversaires politiques, par ailleurs partenaires dans le gouvernement, semblaient comme un vieux couple mari\u00e9 tr\u00e8s harmonieux.<\/p>\n<\/p>\n<p><p>\t L&rsquo;irruption officielle dans la campagne de l&rsquo;engagement allemand en Afghanistan, extr\u00eamement impopulaire en Allemagne (il est rejet\u00e9 par plus de 60% des Allemands, selon la ligne g\u00e9n\u00e9rale des sondages). Alors que Merkel s&rsquo;en tient \u00e0 la ligne officielle, qui passe aujourd&rsquo;hui par la conf\u00e9rence sous l&rsquo;\u00e9gide de l&rsquo;ONU sur la situation afghane propos\u00e9e par l&rsquo;Allemagne, l&rsquo;Angleterre et la France, Steinmeier a \u00e9voqu\u00e9 la possibilit\u00e9 d&rsquo;un calendrier de retrait des forces allemandes, \u00e9ventuellement pour 2013, \u00e9ventuellement plus t\u00f4t<\/p>\n<\/p>\n<p><p>\tSelon <em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/europe\/merkel-loses-first-tv-debate-with-rival-1786970.html\" class=\"gen\">14 septembre 2009<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Viewer polls conducted by Germany&rsquo;s ZDF television channel showed that Mr Steinmeier, the Foreign Minister who is running against Ms Merkel in the election on 27 September, was more than 10 per cent ahead of his rival after the 90-minute debate.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Steinmeier, who has been lagging well over 20 points behind Ms Merkel in the opinion polls, seized the initiative in the debate by calling for German troops to be withdrawn from Afghanistan by 2013.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We went to Afghanistan to prevent terrorist attacks, including those against ourselves, Mr Steinmeier said. But we don&rsquo;t want to stay forever. The aim over the course of the next parliamentary period is to lay the foundations for withdrawal, he said. Although Mr Steinmeier named the date of 2013 for the withdrawal of more than 4,000 German troops deployed in northern Afghanistan, he suggested during the TV debate that the date would be the earliest point at which a decision about a pullout could be made.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMalgr\u00e9 l&rsquo;apparence de d\u00e9saccord, il n&rsquo;y a gu\u00e8re eu de manifestation de d\u00e9saccord entre Merkel et son ministre, adversaire pour le temps d&rsquo;une campagne. Tous s&rsquo;entendent d&rsquo;abord pour \u00e9carter les r\u00e9alit\u00e9s trop contraignantes des \u00e9v\u00e9nements du monde, qui mettent en \u00e9vidence la paralysie des directions politiques. Mais il faut tout de m\u00eame tenter de remporter les \u00e9lections, et le SPD sait bien que Merkel a des plans pour abandonner la grande coalition et faire alliance avec le parti lib\u00e9ral. Il faut donc aller chercher un peu d&rsquo;aide dans la r\u00e9alit\u00e9, pour tenter de modifier ces perspectives \u00e9lectorales qui semblent trac\u00e9es d&rsquo;avance si l&rsquo;on s&rsquo;en tient \u00e0 la popularit\u00e9 de Merkel  cette id\u00e9e-l\u00e0, essentiellement pour les sociaux-d\u00e9mocrates. D&rsquo;o\u00f9 l&rsquo;irruption explosive, quoique contr\u00f4l\u00e9, de l&rsquo;argument afghan dans la campagne avec Steinmeier proposant une date de retrait.<\/p>\n<\/p>\n<p><p>\tOn dit irruption contr\u00f4l\u00e9e parce que Steinmeier a \u00e9voqu\u00e9 la chose \u00e0 pas de loup et avec prudence. Le SPD, comme les autres, est comptable de la situation virtualiste de la direction politique allemande, qui conduit un engagement en Afghanistan dont elle ignore la signification et le but, sinon celui de se conformer aux consignes g\u00e9n\u00e9rales du syst\u00e8me, mais dont elle n&rsquo;ignore certainement l&rsquo;extr\u00eame popularit\u00e9 dans le public allemand. On dit irruption explosive parce que cette sorte d&rsquo;argument, m\u00eame mani\u00e9 avec la plus grande pr\u00e9caution, peut \u00e9chapper \u00e0 ceux qui le pr\u00e9sentent, \u00e0 cause de l&rsquo;impopularit\u00e9 tr\u00e8s grande de la guerre qu&rsquo;il rencontre et des pr\u00e9cautions qu&rsquo;on a pris jusqu&rsquo;ici pour n&rsquo;en pas parler, qui exacerbent cette impopularit\u00e9. Effectivement, si le SPD sent qu&rsquo;il tient l\u00e0 une bonne ouverture pour modifier les perspectives de sa fortune (de son infortune) \u00e9lectorale, il peut \u00eatre tent\u00e9 d&rsquo;insister de plus en plus sur l&rsquo;argument afghan, et c&rsquo;est alors que la chose contr\u00f4l\u00e9e pourrait rencontrer sa v\u00e9ritable nature explosive. Ici, comme ailleurs dans tant de situations politiques, on retrouve cette tension permanente entre le virtualisme du discours politique et la puissance consid\u00e9rable des pressions de la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 septembre 2009 \u00e0 06H38<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9lections allemandes devaient se pr\u00e9parer sur un rythme tranquille, dans une campagne \u00e9lectorale que les strat\u00e8ges \u00e9lectoraux avaient pr\u00e9par\u00e9e avec attention. Le d\u00e9bat t\u00e9l\u00e9vis\u00e9 du 13 septembre 2009 entre la chanceli\u00e8re Merkel, chr\u00e9tienne-d\u00e9mocrate, et son ministre des affaires \u00e9trang\u00e8res Frank-Walter Steinmeier, social-d\u00e9mocrate, a marqu\u00e9 combien ces plans de campagne \u00e9taient fragiles. Non seulement Merkel&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,3878,4141,4633,8667,610],"class_list":["post-71072","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-conformisme","tag-elections","tag-merkel","tag-steinmeir","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71072"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71072\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}