{"id":71088,"date":"2009-09-19T06:06:03","date_gmt":"2009-09-19T06:06:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/19\/lotan-rasmussen-rogozine-et-les-chemins-de-la-liberte\/"},"modified":"2009-09-19T06:06:03","modified_gmt":"2009-09-19T06:06:03","slug":"lotan-rasmussen-rogozine-et-les-chemins-de-la-liberte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/19\/lotan-rasmussen-rogozine-et-les-chemins-de-la-liberte\/","title":{"rendered":"L&rsquo;OTAN, Rasmussen, Rogozine et les chemins de la libert\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;OTAN, Rasmussen, Rogozine et les chemins de la libert\u00e9<\/h2>\n<\/p>\n<p><p>Pour faire croire que nous \u00e9tions bien \u00e0 la conf\u00e9rence d&rsquo;hier midi \u00e0 Bruxelles, \u00e0 la Carnegie, du nouveau secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN Rasmussen, nous pouvons rapporter avec une certaine s&ucirc;ret\u00e9 que le repr\u00e9sentant de la Russie aupr\u00e8s de l&rsquo;OTAN, le p\u00e9tulant Dimitri Rogozine, \u00e9tait au premier rang, \u00e0 la premi\u00e8re chaise face au secr\u00e9taire g\u00e9n\u00e9ral. Quand celui-ci s&rsquo;est rassis pour la s\u00e9ance des questions-r\u00e9ponses, on aurait dit, nous glissa opportun\u00e9ment un de nos amis sinon un de nos voisins (si nous avions \u00e9t\u00e9 pr\u00e9sents comme cela est possible), \u00ab\u00a0que Rasmussen [parlait] directement \u00e0 Rogozine\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on, c&rsquo;\u00e9tait le cas. Dans son discours qui \u00e9tait \u00e0 la gloire de l&rsquo;amiti\u00e9 entre l&rsquo;OTAN et la Russie, Rasmussen glissa une proposition remarquable de coop\u00e9ration avec la Russie. Pour bien faire sentir que la chose est publique, nous citons le <em>Guardian<\/em> du <a class=\"gen\" href=\"http:\/\/www.guardian.co.uk\/world\/2009\/sep\/18\/nato-russia-defence-planning\">18 septembre 2009<\/a>, o&ugrave; l&rsquo;intervention de Rasmussen est rapport\u00e9e, avec certaines remarques sur les \u00e0-c\u00f4t\u00e9s &ndash; remarques sur lesquelles nous reviendrons plus loin.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>In echoing the White House rhetoric about \u00ab\u00a0pressing the reset button\u00a0\u00bb on relations with Russia, Rasmussen went further than the US by calling for Nato and Russia to conduct a joint threat assessment of the big global security challenges.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0I propose that we undertake a joint review of Nato&rsquo;s and Russia&rsquo;s common threats and challenges,\u00a0\u00bb he said. \u00ab\u00a0We need an agreed analytical basis which we can then use to further enhance our practical cooperation.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>This offer is believed to have the backing of the US and the Germans, but the British and Canadians have reservations and central Europeans could also object. Diplomats said British officials asked Rasmussen to drop this part of his speech earlier this week, but the Dane refused.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Quoi qu&rsquo;il en soit, il est possible qu&rsquo;on ait vu, \u00e0 cet instant, Rogozine branler du chef d&rsquo;une mani\u00e8re approbatrice, comme Rasmussen lui-m\u00eame aurait fait, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-rasmussen_a-t-il_branle_du_chef_dans_le_bon_sens_04_09_2009.html\">aux dires<\/a> de Rogozine, qui le visitait le 11 ao&ucirc;t dernier. Apr\u00e8s tout, Rogozine lui proposait une chose assez semblable, certainement dans l&rsquo;esprit, et cela avait \u00e9t\u00e9 pr\u00e9sent\u00e9e de la sorte, par <em>Bloomberg.News<\/em>:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>\u00ab\u00a0It is in the interests of NATO to make Russia a permanent participant in all the discussions, professional discussions, closed discussions that are being held on Afghanistan in Brussels and Mons,\u00a0\u00bb Rogozin said.<\/em> [&hellip;] <em>Rogozin said he broached Russia&rsquo;s proposals to Anders Fogh Rasmussen, a former Danish prime minister who became NATO secretary general on Aug. 11. Rasmussen responded with an \u00ab\u00a0approving nod,\u00a0\u00bb he said.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Rasmussen gave his account of that Aug. 11 encounter at a briefing today in Brussels, calling it a \u00ab\u00a0a very successful, very fruitful and very useful meeting.\u00a0\u00bb NATO is \u00ab\u00a0reflecting on which further steps could be taken,\u00a0\u00bb Rasmussen said.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;atmosph\u00e8re qui r\u00e9gnait lors de cette r\u00e9union d&rsquo;hier midi b\u00e9n\u00e9ficiait de l&rsquo;euphorie de l&rsquo;annonce, la veille, de la fin du BMDE qui a l&rsquo;air de lib\u00e9rer tout le monde d&rsquo;un grand poids; tous se r\u00e9p\u00e9taient le bon mot de Rogozine au m\u00eame <em>Guardian<\/em>, qui lui avait demand\u00e9 ce qu&rsquo;il pensait de la d\u00e9cision sur la fin du BMDE, et qui avait r\u00e9pondu: \u00ab\u00a0C&rsquo;est comme si vous aviez un cadavre en d\u00e9composition dans votre bureau, que vous vous en d\u00e9barrassez parce qu&rsquo;il commence \u00e0 sentir, pour pouvoir enfin vous mettre s\u00e9rieusement au travail.\u00a0\u00bb On peut noter, pour le climat, une question de la salle au secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, qui pourrait se formuler d&rsquo;une fa\u00e7on lapidaire, de la sorte: \u00ab\u00a0Pourquoi pas la Russie dans l&rsquo;OTAN?\u00a0\u00bb (sous-entendu: \u00ab\u00a0puisque vous vous entendez si bien\u00a0\u00bb). R\u00e9ponse un peu impr\u00e9cise du secr\u00e9taire g\u00e9n\u00e9ral, reconnaissant que la chose est tout \u00e0 fait possible, et qui sait, etc. L\u00e0, on reconna&icirc;t un terrain min\u00e9, sur lequel il est encore d\u00e9licat d&rsquo;avancer un pied devant l&rsquo;autre.<\/p>\n<\/p>\n<p><p>(Pour m\u00e9moire et parce que c&rsquo;est dr\u00f4le, et parce que c&rsquo;est instructif, les Russes, alors connus sous le nom de Sovi\u00e9tiques, firent une premi\u00e8re demande d&rsquo;adh\u00e9sion \u00e0 l&rsquo;OTAN le 31 mars 1954. Lord Ismay, premier secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, \u00e9crivit dans son livre de m\u00e9moire <em>L&rsquo;OTAN, les 5 premi\u00e8res ann\u00e9es<\/em>: &laquo;<em>De m\u00eame, tous les membres du Conseil se sont entretenus de la note adress\u00e9e le 31 mars 1954 par le gouvernement sovi\u00e9tique aux trois puissances occupantes et dans laquelle &mdash; proposition assez singuli\u00e8re &mdash; ce gouvernement se d\u00e9clarait \u00ab\u00a0pr\u00eat \u00e0 examiner conjointement avec les gouvernements int\u00e9ress\u00e9s la question de la participation de l&rsquo;URSS au Trait\u00e9 de l&rsquo;Atlantique Nord\u00a0\u00bb. Les gouvernements des Etats-Unis, de la France et du Royaume-Uni tinrent pleinement compte des points de vue des autres gouvernements membres de l&rsquo;OTAN en pr\u00e9parant leur r\u00e9ponse \u00e0 cette note.<\/em>&raquo; L&rsquo;on refusa cette occasion en or, et l&rsquo;on exprima ce refus, le 23 avril 1954, dans des termes d&rsquo;une platitude qui valait bien celle de ceux d&rsquo;en face, qui auraient pu devenir pour cette occasion historique, l&rsquo;URSS d\u00e9barrass\u00e9e de Staline et engag\u00e9e dans un d\u00e9gel radical, \u00ab\u00a0quelques-uns des n\u00f4tres\u00a0\u00bb: &laquo;<em>Le Conseil, apr\u00e8s avoir examin\u00e9 l&rsquo;\u00e9volution de la situation internationale depuis sa derni\u00e8re r\u00e9union, a estim\u00e9 que rien ne semblait indiquer un changement dans les objectifs ultimes de l&rsquo;Union Sovi\u00e9tique et a constat\u00e9 que la puissance militaire de l&rsquo;URSS et des ses satellites n&rsquo;a cess\u00e9 de cro&icirc;tre. En cons\u00e9quence, le Conseil a affirm\u00e9 \u00e0 nouveau la n\u00e9cessit\u00e9 pour les peuples libres de rester vigilants, unis et pers\u00e9v\u00e9rants dans l&rsquo;effort.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Cette conf\u00e9rence du nouveau secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN et cette proximit\u00e9 plus ou moins accidentelle avec Rogozine constituent un point anecdotique assez int\u00e9ressant dans la situation d\u00e9sormais en pleine fusion, et par cons\u00e9quent un peu en pleine confusion, de la s\u00e9curit\u00e9 europ\u00e9enne. La proximit\u00e9 entre le discours de Rasmussen et la d\u00e9cision d&rsquo;Obama sur le BMDE, qui nous est pr\u00e9sent\u00e9e comme \u00ab\u00a0purement accidentelle\u00a0\u00bb (le discours \u00e9tait de toutes les fa\u00e7ons pr\u00e9vu depuis un certain temps, le soir m\u00eame du 17 septembre o&ugrave; fut annonc\u00e9e la d\u00e9cision, et remis finalement au lendemain midi), a \u00e9galement la vertu d&rsquo;une illustration symbolique de la situation. Il y a des appr\u00e9ciations diff\u00e9rentes des modalit\u00e9s du discours de Rasmussen, et il n&rsquo;est pas s&ucirc;r que la version du <em>Guardian<\/em>, qui devrait s&rsquo;\u00eatre aliment\u00e9 aux sources diplomatiques UK habituelles, qui ont int\u00e9r\u00eat \u00e0 faire penser certaines choses, soit absolument v\u00e9ridique. Au reste, cette version du <em>Guardian<\/em> est \u00e9crite dans des termes ambig\u00fces, sans que l&rsquo;on sache si c&rsquo;est l&rsquo;id\u00e9e \u00e9mise peut-\u00eatre auparavant par Rasmussen, ou la proposition \u00e9crite elle-m\u00eame, dans le discours, qui a suscit\u00e9 ces r\u00e9actions. D&rsquo;autres sources indiquent que le discours \u00e9tait en cours de r\u00e9daction ces derniers jours et qu&rsquo;il n&rsquo;est nullement assur\u00e9, bien au contraire, que les diff\u00e9rentes d\u00e9l\u00e9gations des pays-membres en aient eu communication avant la r\u00e9union publique; que ce discours repr\u00e9senterait donc une d\u00e9marche de ce nouveau secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN pour pr\u00e9tendre affirmer une certaine attitude d&rsquo;autonomie, qui serait une nouveaut\u00e9 par rapport \u00e0 la tradition de la chose. Dans ce cas, Rasmussen pourrait trouver en Rogozine un partenaire int\u00e9ress\u00e9. L&rsquo;homme, le repr\u00e9sentant russe aupr\u00e8s de l&rsquo;OTAN, a assez de faconde et d&rsquo;autonomie de mouvement pour envisager d&rsquo;\u00e9ventuels \u00ab\u00a0coups\u00a0\u00bb comme on peut parfois envisager au niveau diplomatique interm\u00e9diaire, dans cette sorte de p\u00e9riode.<\/p>\n<\/p>\n<p><p>&hellip;Car il est manifeste, le climat \u00e0 Bruxelles le dit, que la d\u00e9cision US a agi comme un choc \u00ab\u00a0lib\u00e9rateur\u00a0\u00bb des attitudes et des pens\u00e9es. On d\u00e9couvre combien \u00ab\u00a0le cadavre en d\u00e9composition\u00a0\u00bb de Rogozine, le BMDE, qui constituait une initiative de fortune et de rapine bien dans la mani\u00e8re de l&rsquo;administration Bush, \u00e9tait par cons\u00e9quent soutenue par un discours virtualiste qui paralysait compl\u00e8tement la pens\u00e9e. Dans ces circonstances nouvelles, l&rsquo;OTAN pourrait trouver int\u00e9ressant d&rsquo;affirmer une certaine politique autonome, qui correspond&icirc;t \u00e0 ses int\u00e9r\u00eats propres, \u00e0 une vision sp\u00e9cifique que Rasmussen se chargerait d&rsquo;impulser. Entre l&rsquo;extraordinaire impopularit\u00e9, la charge \u00e9pouvantable qu&rsquo;est la guerre en Afghanistan d&rsquo;une part, l&rsquo;ouverture nouvelle vers la Russie qui est le nouveau le mot d&rsquo;ordre g\u00e9n\u00e9ral, qui s&rsquo;appuie d\u00e9sormais sur le socle puissant de l&rsquo;abandon du BMDE, une \u00ab\u00a0politique de l&rsquo;OTAN\u00a0\u00bb qui se voudrait responsable et ambitieuse semble avoir une voie toute trac\u00e9e qui est de rechercher par tous les moyens une am\u00e9lioration spectaculaire des relations avec les Russes. Cela demande beaucoup de diplomatie, car la chose (une \u00ab\u00a0certaine politique autonome\u00a0\u00bb) n&rsquo;est nullement dans les habitudes de la maison, o&ugrave; les Etats-membres ont toujours veill\u00e9 jalousement \u00e0 leur contr\u00f4le de l&rsquo;institution. Mais les circonstances sont propices. Il y a pour l&rsquo;instant un flottement \u00e9vident, tenant bien s&ucirc;r \u00e0 la d\u00e9cision US qui bouleverse la situation et n\u00e9cessite pour chacun de retrouver des r\u00e9f\u00e9rences stables; une sorte de \u00ab\u00a0d\u00e9sordre\u00a0\u00bb de l&rsquo;orientation \u00e0 suivre, mais plut\u00f4t \u00ab\u00a0d\u00e9sordre cr\u00e9ateur\u00a0\u00bb puisqu&rsquo;on se d\u00e9barrasse d&rsquo;une chape de plomb qui contraignait la pens\u00e9e et les possibles initiatives. Dans ce cadre flottant, la direction de l&rsquo;OTAN sait, ou va r\u00e9aliser bient\u00f4t qu&rsquo;elle a une carte \u00e0 jouer, comme d&rsquo;autres organisations, et les Etats-membres eux-m\u00eames ont une carte \u00e0 jouer &ndash; et celui qui la jouera le mieux orientera effectivement la situation &ndash; et cette carte \u00e0 jouer, bien entendu, avec la Russie. Le tout est couronn\u00e9 par une relative position en retrait des USA, compl\u00e8tement concentr\u00e9s sur la catastrophe afghane et sur leurs tensions et crises int\u00e9rieures. C&rsquo;est une \u00e9poque extr\u00eamement ouverte qui s&rsquo;ouvre en Europe, au niveau de la s\u00e9curit\u00e9 et des relations avec la Russie.<\/p>\n<\/p>\n<p><p>Mis en ligne le 18 septembre 2009 \u00e0 06H07<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;OTAN, Rasmussen, Rogozine et les chemins de la libert\u00e9 Pour faire croire que nous \u00e9tions bien \u00e0 la conf\u00e9rence d&rsquo;hier midi \u00e0 Bruxelles, \u00e0 la Carnegie, du nouveau secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN Rasmussen, nous pouvons rapporter avec une certaine s&ucirc;ret\u00e9 que le repr\u00e9sentant de la Russie aupr\u00e8s de l&rsquo;OTAN, le p\u00e9tulant Dimitri Rogozine, \u00e9tait au&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8679,6318,4314,3631,8681,2604,4220,8680,3287,5084,584,3607,7650,2614,2730,963],"class_list":["post-71088","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-8679","tag-autonomie","tag-bmde","tag-bruxelles","tag-commune","tag-des","tag-evaluation","tag-ismay","tag-liberte","tag-menaces","tag-otan","tag-planification","tag-rasmussen","tag-rogozine","tag-russie","tag-urss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71088"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71088\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}