{"id":71099,"date":"2009-09-23T09:32:37","date_gmt":"2009-09-23T09:32:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/23\/les-forces-armees-us-la-route-vers-la-banqueroute\/"},"modified":"2009-09-23T09:32:37","modified_gmt":"2009-09-23T09:32:37","slug":"les-forces-armees-us-la-route-vers-la-banqueroute","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/23\/les-forces-armees-us-la-route-vers-la-banqueroute\/","title":{"rendered":"Les forces arm\u00e9es US: la route vers la banqueroute"},"content":{"rendered":"<p><p>L&rsquo;analyste Loren B. Thompson, lorsqu&rsquo;il n&rsquo;est pas trop sollicit\u00e9 par ses liens encombrants avec ses divers commanditaires du complexe militaro-industriel, peut nous donner d&rsquo;int\u00e9ressantes pr\u00e9cisions et r\u00e9flexions sur ces pr\u00e9cisions. Il le fait, ce <a href=\"http:\/\/www.lexingtoninstitute.org\/the-all-volunteer-force-is-becoming-unaffordable?a=1&#038;c=1129\" class=\"gen\">22 septembre 2009<\/a>, sur le site de l&rsquo;institut qu&rsquo;il co-dirige, le Lexington Institute, \u00e0 propos de la situation des forces arm\u00e9es des USA, dans leur statut d&rsquo;arm\u00e9e de m\u00e9tier (<em>All-Volunteer Force<\/em>).<\/p>\n<\/p>\n<p><p>\tCe que Thompson met en \u00e9vidence, c&rsquo;est le co\u00fbt extraordinaire de cette arm\u00e9e au niveau du personnel. Un soldat de l&rsquo;U.S. Army co\u00fbte au minimum un peu plus de $100.000 par an au d\u00e9partement de la d\u00e9fense, encore avec certaines autres d\u00e9penses dissimul\u00e9es, et cela \u00e9tant indicatif d&rsquo;une tendance puisqu&rsquo;il y a eu une augmentation de ces co\u00fbts de 55% dans les douze derni\u00e8res ann\u00e9es . Cette situation tendancielle repr\u00e9sente d&rsquo;ailleurs l&rsquo;inflation des \u00e9quipements de protection et des rotations acc\u00e9l\u00e9r\u00e9es, l&rsquo;alourdissement des charges institutionnelles des soldats, des arrangements sociaux n\u00e9cessit\u00e9s par les pressions ext\u00e9rieures, etc., tout cela conform\u00e9ment \u00e0 la d\u00e9cadence bureaucratique du syst\u00e8me. (Encore existent-ils de nombreux trous noirs dans cette situation, ce qui t\u00e9moigne de l&rsquo;incurie et du gaspillage des d\u00e9penses. Le syst\u00e8me hospitalier et le traitement des d\u00e9sordres psychologiques dus au combat sont dans un \u00e9tat d\u00e9plorable, comme plussieurs scandales l&rsquo;ont montr\u00e9.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>I have written an essay about this subject in the current issue of Armed Forces Journal.  It draws upon the work of Congressional Research Service analyst Stephen Daggett, former Pentagon comptroller Dov Zakheim, and others to paint an alarming picture of defense personnel trends.  In constant 2009 dollars, the average cost of each warfighter has increased 45% over the past dozen years  from $55,000 to $80,000.  When growing military healthcare costs (up 150% in this decade) are added to this baseline figure, the current cost of each warfighter rises above $100,000 annually.  And that&rsquo;s before the cost of training and equipping the fighters to do their jobs is factored in!  When the totality of all necessary outlays to field a typical soldier or airman is calculated, it becomes apparent that the All-Volunteer Force is astronomically, absurdly expensive.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>One of the reasons policymakers have failed to grasp this impending crisis is that the defense budget is not organized to reflect the full burden of people costs.  For example, the baseline budget for fiscal 2010 (not counting supplemental war expenditures) contains $136 billion for Military Personnel  considerably more than the $107 billion allocated to Procurement, but considerably less than the $186 billion set aside for Operations and Maintenance (O&#038;M).  What many people don&rsquo;t realize, though, is that over half of the O&#038;M budget is also people-related outlays, such as military healthcare expenditures and pay for civil servants.  The real driver of increasing O&#038;M costs in the regular defense budget isn&rsquo;t rising optempo as frequently alleged, but rising personnel costs.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tThompson juge que cette situatin est intenable sur le terme pour les USA, notamment en imposant un budget de la d\u00e9fense qui n&rsquo;est plus acceptable par rapport aux moyens budg\u00e9taires des USA en temps de crise: \u00ab[S]<em>ince the current decade began, America&rsquo;s economy has fallen from roughly a third to a quarter of global output.  In other words, 5% of the world&rsquo;s population is generating 25% of global output while trying to sustain 50% of military spending.  These numbers do not add up: defense spending will have to be brought into closer alignment with budgetary resources in the years ahead, as will entitlements, otherwise we will bankrupt the Treasury and forfeit our future.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuelle solution pr\u00e9conise Thompson? On retrouve la quadrature du cercle habituelle au syst\u00e8me US. Il n&rsquo;est pas question d&rsquo;un retour \u00e0 la conscription, parce que  Thompson ne le dit pas, alors nous le disons pour lui  cela est beaucoup trop <a href=\"http:\/\/www.dedefensa.org\/article-gulliver_et_sa_tasse_de_the_22_09_2009.html\" class=\"gen\">dangereux<\/a> pour la politique de s\u00e9curit\u00e9 nationale d&rsquo;un syst\u00e8me qui encha\u00eene guerre impopulaire sur guerre impopulaire et ne veut pas en subir le contrecoup au niveau int\u00e9rieur US, comme lors de la catastrophe vietnamienne. Alors, que faire? R\u00e9duire les d\u00e9penses de personnel (\u00ab<em>The answer isn&rsquo;t a return to conscription, but to halt the increase in active-duty headcount and stop dreaming up new military benefits like they are campaign ribbons.<\/em>\u00bb). C&rsquo;est-\u00e0-dire, demander au Pentagone de r\u00e9duire ses d\u00e9penses et de d\u00e9penser mieux&#8230; Bonne chance, Loren B.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 septembre 2009 \u00e0 09H36<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;analyste Loren B. Thompson, lorsqu&rsquo;il n&rsquo;est pas trop sollicit\u00e9 par ses liens encombrants avec ses divers commanditaires du complexe militaro-industriel, peut nous donner d&rsquo;int\u00e9ressantes pr\u00e9cisions et r\u00e9flexions sur ces pr\u00e9cisions. Il le fait, ce 22 septembre 2009, sur le site de l&rsquo;institut qu&rsquo;il co-dirige, le Lexington Institute, \u00e0 propos de la situation des forces arm\u00e9es&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3109,8695,3767,3228,3473,3194,8696,3474],"class_list":["post-71099","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-b","tag-budgetaire","tag-cout","tag-crise","tag-loren","tag-pentagone","tag-personnel","tag-thompson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71099"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71099\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}