{"id":71101,"date":"2009-09-24T07:32:02","date_gmt":"2009-09-24T07:32:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/24\/notes-sur-limpossible-revolution\/"},"modified":"2009-09-24T07:32:02","modified_gmt":"2009-09-24T07:32:02","slug":"notes-sur-limpossible-revolution","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/24\/notes-sur-limpossible-revolution\/","title":{"rendered":"Notes sur l&rsquo;impossible \u201cr\u00e9volution\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur l&rsquo;impossible \u00ab\u00a0r\u00e9volution\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Nous notons r\u00e9guli\u00e8rement la situation o&ugrave; nous nous nous trouvons, dans les pays d\u00e9velopp\u00e9s qui conduisent le syst\u00e8me, de voir l&rsquo;impossibilit\u00e9 que certains sentiments publics de r\u00e9volte s&rsquo;expriment par des actes collectifs classiques violents (\u00e9meutes, r\u00e9volution, prise de pouvoir). Nous notons \u00e9galement que cette impossibilit\u00e9 d&rsquo;une expression directe du m\u00e9contentement public n&rsquo;en interdit pas l&rsquo;expression par des voies indirectes &ndash; sans avoir encore d\u00e9termin\u00e9 les effets d&rsquo;une telle situation.<\/p>\n<\/p>\n<p><p>Nous voudrions d\u00e9velopper ce point d&rsquo;une fa\u00e7on analytique pour mieux faire comprendre notre pens\u00e9e \u00e0 nos lecteurs. Il s&rsquo;agit sans aucun doute d&rsquo;une situation extr\u00eamement originale, qui m\u00e9rite toute notre attention par rapport au jugement commun de l&rsquo;effacement complet du sentiment politique. Nous ne donnons pas seulement une appr\u00e9ciation th\u00e9orique, car nous pensons qu&rsquo;il existe d&rsquo;ores et d\u00e9j\u00e0 des \u00e9v\u00e9nements qui peuvent \u00eatre inscrits dans le sch\u00e9ma que nous nous proposons de pr\u00e9senter: dans un pass\u00e9 proche, le r\u00e9f\u00e9rendum fran\u00e7ais de mai 2005; aujourd&rsquo;hui, aux USA, peut-\u00eatre, et peut-\u00eatre d&rsquo;une fa\u00e7on plus \u00ab\u00a0r\u00e9volutionnaire\u00a0\u00bb selon cette conception postmoderniste, le mouvement du <em>Tea Party<\/em>. On y viendra plus loin.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0R\u00e9volution\u00a0\u00bb et communication<\/h3>\n<\/p>\n<p><p>Donnons d&rsquo;abord une r\u00e9f\u00e9rence pr\u00e9cise. Il s&rsquo;agit d&rsquo;une situation cr\u00e9\u00e9e par le ph\u00e9nom\u00e8ne de la communication, qui est \u00e0 notre sens la caract\u00e9ristique sp\u00e9cifique essentielle de l&rsquo;activit\u00e9 de notre civilisation postmoderniste, et g\u00e9n\u00e9ratrice de la plus grande puissance. Nous avons not\u00e9 quelques caract\u00e8res qui nous semblent essentiels de cette situation, par exemple dans un r\u00e9cent <em>F&#038;C<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_etrange_bataille__17_08_2009.html\">17 ao&ucirc;t 2009<\/a> sur les \u00e9v\u00e9nements, aux USA, sur la position d&rsquo;Obama, dans la crise des \u00ab\u00a0soins de sant\u00e9\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Voici la citation du passage concern\u00e9:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>Ici notre \u00ab\u00a0fascination\u00a0\u00bb (bien dans le sens de \u00ab\u00a0profonde impression \u00e9prouv\u00e9e par quelqu&rsquo;un\u00a0\u00bb), car nous en \u00e9prouvons aujourd&rsquo;hui, effectivement, et plus int\u00e9ressante que celle, anecdotique, que nous avions pour Bush. Elle va \u00e0 une \u00e9poque, \u00e0 un temps \u00ab\u00a0maistrien\u00a0\u00bb, \u00e0 une situation o&ugrave; un homme doit suivre son destin ou bien \u00ab\u00a0tomber ignoblement\u00a0\u00bb. A nouveau cette citation de Maistre: \u00ab\u00a0On a remarqu\u00e9, avec grande raison, que la r\u00e9volution fran\u00e7aise m\u00e8ne les hommes plus que les hommes la m\u00e8nent. Cette observation est de la plus grande justesse&#8230; [&#8230;] Les sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement.\u00a0\u00bb Nous aurions tendance \u00e0 juger que le mot de \u00ab\u00a0sc\u00e9l\u00e9rat\u00a0\u00bb est un peu s\u00e9v\u00e8re pour BHO, et d&rsquo;autres doivent penser le contraire. Ce n&rsquo;est pas ce qui importe; ce qui importe, c&rsquo;est la situation, c&rsquo;est elle qui nous fascine; et, pour l&rsquo;instant, BHO en est l&rsquo;acteur central: ou bien il se soumet \u00e0 son destin, qui est \u00ab\u00a0de conduire la r\u00e9volution\u00a0\u00bb anti-syst\u00e8me d&rsquo;une fa\u00e7on ou l&rsquo;autre, ou bien il \u00ab\u00a0tombera ignoblement\u00a0\u00bb &ndash; et la r\u00e9volution se fera sans lui. Ce qui est fascinant, c&rsquo;est que l&rsquo;Histoire fait de BHO, qu&rsquo;il le veuille ou non, un homme qui pose des mines destin\u00e9es \u00e0 exploser, qu&rsquo;il veuille ou non leur explosion.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>La question est de savoir comment (comment la \u00ab\u00a0r\u00e9volution\u00a0\u00bb se fera avec ou sans lui). Dans notre \u00e9poque de communication, nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit, les circonstances extraordinaires de mouvement de l&rsquo;information par la communication interdisent les actes r\u00e9volutionnaires parce que \u00ab\u00a0spontan\u00e9s\u00a0\u00bb dans leur caract\u00e8re soudain d\u00e9cisif et alors incontr\u00f4lables dans leur d\u00e9roulement, puisqu&rsquo;au contraire la communication interdit cette spontan\u00e9it\u00e9-l\u00e0 des \u00e9v\u00e9nements. Par contre, la communication, qui brouille tout, rend aussi les \u00e9v\u00e9nements incompr\u00e9hensibles, et les attitudes psychologiques vis-\u00e0-vis d&rsquo;eux idem. Ce que la psychologie ne peut exprimer directement par une \u00ab\u00a0r\u00e9volution\u00a0\u00bb, elle l&rsquo;exprime, d&rsquo;une fa\u00e7on chaotique, \u00e0 d&rsquo;autres occasions, d&rsquo;une fa\u00e7on compl\u00e8tement fortuite. La soudaine agitation US, sid\u00e9rante, incompr\u00e9hensible, autour de la question des \u00ab\u00a0soins de sant\u00e9\u00a0\u00bb, est-elle une de ces circonstances? Suivons-l\u00e0 comme si c&rsquo;\u00e9tait une possibilit\u00e9. Jusqu&rsquo;ici, il faut observer que certains de ses prolongements, y compris la dramatisation de la position de BHO, ne d\u00e9mentent pas cette interpr\u00e9tation. Pour la suite, on verra.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\"><em>Tea Party<\/em> et r\u00e9volution<\/h3>\n<\/p>\n<p><p>Ces remarques ont pris, \u00e0 notre sens, une actualit\u00e9 nouvelle avec le d\u00e9veloppement (ou la r\u00e9alisation du d\u00e9veloppement) du mouvement du <em>Tea Party<\/em>, tel que nous l&rsquo;avons observ\u00e9 dans notre <em>F&#038;C<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-anatomie_de_la_tasse_de_the_23_09_2009.html\">23 septembre 2009<\/a>. C&rsquo;est \u00e0 partir de ce constat plus r\u00e9cent, et en revenant \u00e0 lui dans la conclusion de la r\u00e9flexion, que nous d\u00e9veloppons cette r\u00e9flexion.<\/p>\n<\/p>\n<p><p>C&rsquo;est dire l&rsquo;importance potentielle que nous accordons \u00e0 ce mouvement. C&rsquo;est dire \u00e9galement combien nous estimons qu&rsquo;il poss\u00e8de des particularit\u00e9s qui peuvent aider \u00e0 r\u00e9pondre \u00e0 la question implicite &ndash; plut\u00f4t aux deux questions implicites: peut-on encore faire une r\u00e9volution aujourd&rsquo;hui? Qu&rsquo;est-ce que c&rsquo;est qu&rsquo;une r\u00e9volution aujourd&rsquo;hui?<\/p>\n<\/p>\n<p><p>[Bien entendu, nous prenons le terme \u00ab\u00a0r\u00e9volution\u00a0\u00bb dans un sens d\u00e9barrass\u00e9 de tous ses oripeaux id\u00e9ologiques, de toutes les orientations politiques dont le terme est marqu\u00e9e depuis deux si\u00e8cles. Nous demandons \u00e0 nos lecteurs de faire cet effort d&rsquo;abstraction. Le contexte o&ugrave; nous \u00e9voquons cette situation implique une \u00ab\u00a0r\u00e9volution\u00a0\u00bb contre ce que nous nommons \u00ab\u00a0le syst\u00e8me\u00a0\u00bb, qui est la puissance m\u00e9canique et bureaucratique dominante du monde, d&rsquo;o&ugrave; sont issues les puissances financi\u00e8res, militaires, etc. Pour nous, ce \u00ab\u00a0syst\u00e8me\u00a0\u00bb est issu des deux derniers si\u00e8cles d&rsquo;Histoire, depuis la fin du XVIII\u00e8me si\u00e8cle, donc issu notamment des \u00e9v\u00e9nements r\u00e9volutionnaires de ces deux si\u00e8cles; par exemple, le capitalisme int\u00e9gral, qui pr\u00f4ne la \u00ab\u00a0destruction cr\u00e9atrice\u00a0\u00bb, r\u00e9pond, dans sa d\u00e9finition fondamentalement d\u00e9structurante, aux dynamiques r\u00e9volutionnaires des deux derniers si\u00e8cles. C&rsquo;est dire si le terme \u00ab\u00a0r\u00e9volution\u00a0\u00bb que nous utilisons, selon notre logique du contre feu, est objectivement adversaire d&rsquo;un syst\u00e8me issu d&rsquo;un processus r\u00e9volutionnaire; s&rsquo;il lui fallait \u00e0 tout prix une \u00e9tiquette politique &ndash; ce que nous jugeons inutile sinon pour expliciter le propos, justement \u00e0 cause de la charge id\u00e9ologique de cette identification &ndash; ce serait plut\u00f4t \u00ab\u00a0contre-r\u00e9volutionnaire\u00a0\u00bb.]<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;\u00e9v\u00e9nement cr\u00e9ateur: Mai 68<\/h3>\n<\/p>\n<p><p>Le probl\u00e8me que nous posons est bien celui de la communication, nullement de l&rsquo;information. Il s&rsquo;agit de l&rsquo;ensemble de moyens, de r\u00e9seaux, de m\u00e9dias, qui v\u00e9hiculent l&rsquo;information, d&rsquo;une fa\u00e7on universelle, \u00e0 une tr\u00e8s grande vitesse, vers un acc\u00e8s de plus en plus g\u00e9n\u00e9ralis\u00e9. Pour mieux exprimer notre sentiment, nous allons revenir sur le pr\u00e9c\u00e9dent fameux des \u00e9v\u00e9nements \u00e9meutiers de mai 1968, \u00e0 Paris.<\/p>\n<\/p>\n<p><p>Un aspect important de ces \u00e9v\u00e9nements fut l&rsquo;omnipr\u00e9sence des radios (RTL, Europe n&deg;1, etc.) durant les \u00e9v\u00e9nements, sur place, au c&oelig;ur des \u00e9meutes, c&rsquo;est-\u00e0-dire l&rsquo;omnipr\u00e9sence du ph\u00e9nom\u00e8ne de la communication de l&rsquo;information. Certains mirent gravement en cause ce ph\u00e9nom\u00e8ne, comme un moyen de propagation de l&rsquo;\u00e9meute. On estima qu&rsquo;il avait permis la localisation et l&rsquo;identification des divers groupes, la connaissance de l&rsquo;\u00e9volution de la situation, etc. Les radios servirent de porte-voix aux leaders \u00e9meutiers, en les interviewant, ce qui facilita la mobilisation, l'\u00a0\u00bbappel aux armes\u00a0\u00bb, les regroupements, etc. Il s&rsquo;agirait ici du ph\u00e9nom\u00e8ne <strong>tactique<\/strong> du r\u00f4le de l&rsquo;information, par ailleurs bien connu dans toutes les situations de guerre et d&rsquo;affrontement.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;\u00e9meute contrainte par la communication<\/h3>\n<\/p>\n<p><p>Notre propos serait alors pr\u00e9cis\u00e9ment contraire au jugement selon lequel cette pr\u00e9sence des radios a facilit\u00e9 les \u00e9v\u00e9nements \u00ab\u00a0r\u00e9volutionnaires\u00a0\u00bb. Nous pr\u00e9tendons que, de ce point de vue des \u00e9v\u00e9nements de rue, mai 1968 fut caract\u00e9ristique du surgissement du ph\u00e9nom\u00e8ne de la communication qui, au lieu de permettre la diffusion et l&rsquo;extension de l&rsquo;\u00e9meute, et surtout l&rsquo;aggravation de l&rsquo;\u00e9meute jusqu&rsquo;au coup de force et \u00e0 la r\u00e9volution, la contint au contraire dans les bornes d&rsquo;une restriction fondamentale, interdisant l&rsquo;\u00e9v\u00e9nement lui-m\u00eame fondamental de la \u00ab\u00a0r\u00e9volution\u00a0\u00bb. Il s&rsquo;agirait ici du premier ph\u00e9nom\u00e8ne <strong>psychologique<\/strong> de la communication.<\/p>\n<\/p>\n<p><p>Pour qu&rsquo;une \u00e9meute devienne une r\u00e9volution, il faut une rupture qui est de l&rsquo;ordre du psychologique et non du tactique. A partir d&rsquo;un certain moment, la dynamique de l&rsquo;\u00e9v\u00e9nement conduit ceux qui le font \u00e0 \u00eatre conduit par elle, et cette dynamique les emporte alors dans un monde nouveau (qui est en m\u00eame temps cr\u00e9\u00e9 par elle). (On retrouve l\u00e0 l&rsquo;observation de Joseph de Maistre, mais nous l&rsquo;utilisons pour un autre propos.) Il y a alors rupture avec le monde dont l&rsquo;on faisait partie et dont on ne fait plus partie, qui devient \u00ab\u00a0ancien monde\u00a0\u00bb &ndash; et la rupture c&rsquo;est la r\u00e9volution. Il s&rsquo;agit d&rsquo;abord d&rsquo;un processus psychologique. Pour <strong>\u00eatre<\/strong>, la r\u00e9volution doit \u00eatre per\u00e7ue comme telle par ceux qui la font puis sont emport\u00e9s par elle.<\/p>\n<\/p>\n<p><p>Puisqu&rsquo;elle est psychologique, la rupture doit exister \u00e9galement au niveau de l&rsquo;information. On ne parle plus le m\u00eame langage que celui de l'\u00a0\u00bbancien monde\u00a0\u00bb, on ne vit plus les m\u00eames \u00e9v\u00e9nements. Le processus de mai 1968 emp\u00eacha cette rupture r\u00e9volutionnaire. Si tactiquement, la diffusion d&rsquo;information servit les \u00e9meutiers, en revanche elle emp\u00eacha toute rupture psychologique. Les \u00e9meutiers, et leurs chefs, rest\u00e8rent dans l'\u00a0\u00bbancien monde\u00a0\u00bb (RTL, Europe n&deg;1, Geismar ou Cohn Bendit cherchant \u00e0 \u00eatre interview\u00e9 \u00e0 20H00 parce que c&rsquo;est l&rsquo;heure de grande \u00e9coute, tout \u00e7a c&rsquo;est de l'\u00a0\u00bbancien monde\u00a0\u00bb). L'\u00a0\u00bbancien monde\u00a0\u00bb resta le monde commun \u00e0 tous et il n&rsquo;y eut pas de rupture r\u00e9volutionnaire. Si la communication facilite la diffusion de l&rsquo;information, elle interdit la rupture tragique qui introduit l&rsquo;id\u00e9e r\u00e9volutionnaire dans la psychologie.<\/p>\n<\/p>\n<p><p>Finalement, ces \u00e9v\u00e9nements qui eurent un \u00e9cho extraordinaire, n&rsquo;eurent, comme l&rsquo;on sait, que tr\u00e8s peu d&rsquo;effets politiques. Marcel Jouhandeau avait raison, qui disait des \u00ab\u00a0enrag\u00e9s\u00a0\u00bb, en mai 1968: &laquo;<em>Ils finiront tous notaires&hellip;<\/em>&raquo; (ou d\u00e9put\u00e9s europ\u00e9ens, ce qui revient au m\u00eame). Par contre, il est indiscutable que ces \u00e9v\u00e9nements suscit\u00e8rent des cons\u00e9quences sociales et psychologiques consid\u00e9rables sur le terme, par les changements qu&rsquo;ils suscit\u00e8rent dans l'\u00a0\u00bbancien monde\u00a0\u00bb lui-m\u00eame, rest\u00e9 notre monde \u00e0 tous.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La r\u00e9volution interdite par la communication<\/h3>\n<\/p>\n<p><p>Il va de soi que nous n&rsquo;avons pas pris mai 1968 comme \u00ab\u00a0mod\u00e8le\u00a0\u00bb politique digne d&rsquo;\u00eatre suivi &ndash; c&rsquo;est un autre d\u00e9bat, et nous aurions alors une position bien tranch\u00e9e, mettant bien s&ucirc;r mai 1968 comme \u00e9v\u00e9nement d\u00e9structurant et moderniste; nous l&rsquo;avons pris comme mod\u00e8le du moment fondamental o&ugrave;, dans le ph\u00e9nom\u00e8ne communication-information (la communication charriant l&rsquo;information), la communication prit le dessus sur l&rsquo;information.<\/p>\n<\/p>\n<p><p>Depuis, cette tendance s&rsquo;est prodigieusement acc\u00e9l\u00e9r\u00e9e avec la prodigieuse acc\u00e9l\u00e9ration des moyens de communication, tandis que l&rsquo;information reste \u00e9gale \u00e0 elle-m\u00eame, compl\u00e8tement d\u00e9pendante de la communication, et donc perdant de plus en plus d&rsquo;importance dans le rapport communication-information quant \u00e0 l&rsquo;effet sur la forme des \u00e9v\u00e9nements. Aujourd&rsquo;hui, une r\u00e9volution avec rupture psychologique comme nous la d\u00e9crivons plus haut, dans les conditions de hautes technologies de nos soci\u00e9t\u00e9s, est compl\u00e8tement impossible. La rapidit\u00e9 et l&rsquo;universalit\u00e9 de la diffusion des informations par la communication interdisent d\u00e9cisivement toute situation de spontan\u00e9it\u00e9, d&rsquo;isolement \u00e9v\u00e9nementiel qui, seule, permet la possibilit\u00e9 d&rsquo;une rupture r\u00e9volutionnaire de la forme que nous avons signal\u00e9e plus haut.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Acc\u00e9l\u00e9ration des effets psychologiques<\/h3>\n<\/p>\n<p><p>Dans cette nouvelle situation d&rsquo;omnipr\u00e9sence et de pression tyrannique de la communication, par contre, l&rsquo;effet cach\u00e9 sur la psychologie et sur les arrangements sociaux que nous d\u00e9crivions dans le cas de mai 1968 comme une cons\u00e9quence du moyen et du long terme est devenu incomparablement plus rapide. Il se r\u00e9alise presque dans le m\u00eame temps que se produit l&rsquo;\u00e9v\u00e9nement de la communication, alors qu&rsquo;il fallut plusieurs ann\u00e9es, sinon une ou deux d\u00e9cennies, pour int\u00e9grer les effets de mai 1968.<\/p>\n<\/p>\n<p><p>Les \u00e9v\u00e9nements, aujourd&rsquo;hui, sont contenus brutalement dans un sch\u00e9ma contraint, avec impossibilit\u00e9, r\u00e9alis\u00e9e par les \u00ab\u00a0r\u00e9volt\u00e9s\u00a0\u00bb eux-m\u00eames, de s&rsquo;\u00e9vader de l'\u00a0\u00bbancien monde\u00a0\u00bb sous une forme de rupture r\u00e9volutionnaire. De ce point de vue, la psychologie est directement contrainte par l&rsquo;absence de radicalit\u00e9 tragique de l&rsquo;\u00e9v\u00e9nement. Par contre, l&rsquo;\u00e9volution psychologique souterraine, concernant les appr\u00e9ciations de cette situation bloqu\u00e9e, la frustration, en m\u00eame temps que l&rsquo;\u00e9volution qui permet aux relations et aux jugements sociaux et politiques de se radicaliser, est extr\u00eamement rapide, voire instantan\u00e9e.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9v\u00e9nement du r\u00e9f\u00e9rendum de mai 2005 en France est le type m\u00eame d&rsquo;\u00e9v\u00e9nement r\u00e9volutionnaire sans \u00ab\u00a0r\u00e9volution\u00a0\u00bb (sans rupture). L&rsquo;\u00e9v\u00e9nement politique lui-m\u00eame n&rsquo;a d\u00e9bouch\u00e9 sur aucune insurrection, sur aucun bouleversement, mais l&rsquo;\u00e9volution psychologique radicale a \u00e9t\u00e9 remarquable de puissance pendant la campagne, par les moyens de communication non traditionnels qu&rsquo;on sait, et a eu des effets psychologiques ind\u00e9niables sur les directions politiques, effets qu&rsquo;on mesurera historiquement. Nous pr\u00e9tendons que, depuis ce r\u00e9f\u00e9rendum qui n&rsquo;eut rien de d\u00e9cisif dans les \u00e9v\u00e9nements eux-m\u00eames, l&rsquo;Europe institutionnelle, contre laquelle a eu lieu la r\u00e9volte (et non \u00ab\u00a0l&rsquo;Europe\u00a0\u00bb en soi, certes, contre laquelle les \u00ab\u00a0non\u00a0\u00bb du r\u00e9f\u00e9rendum n&rsquo;avaient aucune animosit\u00e9), cette Europe est bloqu\u00e9e comme elle ne le fut jamais.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;\u00e9v\u00e9nement conduit les hommes<\/h3>\n<\/p>\n<p><p>Cette situation s&rsquo;est g\u00e9n\u00e9ralis\u00e9e \u00e0 mesure de l&rsquo;affirmation de la communication qu&rsquo;on a dite, et elle a accru encore certains caract\u00e8res remarquables. On constate la multiplication d&rsquo;\u00e9v\u00e9nements sans aucun doute de protestation, qui semblent n&rsquo;avoir que bien peu de sens et de direction, parce que d\u00e9pourvus d&rsquo;objectifs \u00ab\u00a0r\u00e9volutionnaires\u00a0\u00bb identifiables (prise du pouvoir, notamment). Ils sont \u00e9galement d\u00e9pourvus de dirigeants notables, parce que l&rsquo;\u00e9volution ne d\u00e9pend pas de ces facteurs ext\u00e9rieurs. Ce qui compte, c&rsquo;est l&rsquo;\u00e9volution psychologique que marquent ces \u00e9v\u00e9nements, et l&rsquo;effet psychologique qu&rsquo;ils ont <strong>imm\u00e9diatement<\/strong> sur les dirigeants &ndash; paralysie, d\u00e9sordre \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me, incompr\u00e9hension des mouvements de protestation et donc m\u00e9sentente \u00e0 l&rsquo;int\u00e9rieur des directions pour r\u00e9agir, etc.<\/p>\n<\/p>\n<p><p>On pense bien entendu, et principalement, au mouvement US de protestation dit <em>Tea Party<\/em>, puisqu&rsquo;on en parle ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-anatomie_de_la_tasse_de_the_23_09_2009.html\">23 septembre 2009<\/a>, mais \u00e9galement de mouvements pr\u00e9tendument (qui peut le dire, et quelle importance de le dire?) d&rsquo;un autre sens id\u00e9ologique, comme le mouvements anti-globalisation sous toutes ces formes et certains aspects de ce qu&rsquo;on nomme la guerre de quatri\u00e8me g\u00e9n\u00e9ration (G4G) dans le sens le plus large, comme nous avons souvent tent\u00e9 de la d\u00e9finir. Tous ces mouvements semblent n&rsquo;aller nulle part ou m\u00e9langer des revendications anarchiques et sans coh\u00e9sion. L&rsquo;important est au niveau de la communication, avec l&rsquo;\u00e9volution psychologique qu&rsquo;ils font subir tant aux participants qu&rsquo;aux dirigeants divers qui les observent et sont d&rsquo;autant plus effray\u00e9s qu&rsquo;ils n&rsquo;y comprennent rien &ndash; parce qu&rsquo;en premi\u00e8re analyse et analyse de surface, il n&rsquo;y a rien \u00e0 comprendre, sinon le rejet g\u00e9n\u00e9ral d&rsquo;un syst\u00e8me qui ne peut \u00eatre pris en compte par ces m\u00eames dirigeants.<\/p>\n<\/p>\n<p><p>Dans ce sens, nous sommes exactement dans la logique et la dynamique du mouvement maistrien. L&rsquo;\u00e9v\u00e9nement prend une telle puissance qu&rsquo;il se cr\u00e9e lui-m\u00eame, qu&rsquo;il se nourrit lui-m\u00eame de sa puissance. Il conduit les hommes bien plus qu&rsquo;il n&rsquo;est conduit par eux, et il leur impose sa logique. Simplement, les moyens ont chang\u00e9: c&rsquo;est la communication, avec ses divers effets indirects sur la psychologie, qui se charge de transmettre l&rsquo;impulsion dynamique de l&rsquo;\u00e9v\u00e9nement.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La communication contre le syst\u00e8me<\/h3>\n<\/p>\n<p><p>Maintenant, et pour aller au bout de cette rapide analyse, il faut aller jusqu&rsquo;au bout de la question en parlant du sens cach\u00e9 de l&rsquo;\u00e9v\u00e9nement qui semble n&rsquo;avoir pas de sens. M\u00eame si la forme de l&rsquo;\u00e9v\u00e9nement telle qu&rsquo;on a tent\u00e9 de la d\u00e9crire a notamment comme mod\u00e8le mai 68, le sens politique doit \u00eatre compris comme tr\u00e8s diff\u00e9rent, si pas oppos\u00e9. Mai 68 s&rsquo;attaquait express\u00e9ment \u00e0 des forces structur\u00e9es, dans un but de d\u00e9structuration. Dans ce sens, le fondement du mouvement a triomph\u00e9, avec l&rsquo;extension du mod\u00e8le am\u00e9ricaniste dans la globalisation.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est certainement pas un hasard si l&rsquo;\u00e9crasante majorit\u00e9 des <em>leaders<\/em> soi-disant r\u00e9volutionnaires de mai 68 se retrouvent aujourd&rsquo;hui, soigneusement rang\u00e9s dans le camp de la globalisation et de l&rsquo;hyper-lib\u00e9ralisme. (Cette remarque, nuanc\u00e9e de ceci: c&rsquo;\u00e9tait le cas, au moins jusqu&rsquo;\u00e0 la crise du 15 septembre 2008, un peu comme tous les hagiographes de la globalisation et de la lib\u00e9ralisation, chacun ayant mis depuis, \u00e0 doses changeantes, un petit peu de vin ros\u00e9e d&rsquo;un soup\u00e7on de contestation dans son eau globalis\u00e9e.) Cohn-Bendit est un bon mod\u00e8le du genre, un exemple sans un pli d&rsquo;un reclassement qui n&rsquo;en est pas vraiment un: ce qu&rsquo;il est devenu, non pas notaire mais d\u00e9put\u00e9 europ\u00e9en partisan de la globalisation hyper-lib\u00e9rale, il l&rsquo;est devenu dans un monde qu&rsquo;il a fortement contribu\u00e9 \u00e0 pr\u00e9parer et \u00e0 dessiner d\u00e8s mai 68.<\/p>\n<\/p>\n<p><p>Au contraire, les mouvements actuels, s&rsquo;ils sont d\u00e9structurants, le sont d&rsquo;une puissance, le syst\u00e8me, qui est elle-m\u00eame d\u00e9structurante, agissant ainsi selon le principe du contre-feu qu&rsquo;on cite souvent et qu&rsquo;on a cit\u00e9 plus haut. Ils constituent objectivement, par induction alg\u00e9brique, une force structurante. On comprend alors l&rsquo;inutilit\u00e9 de leur chercher un sens id\u00e9ologique, comme certains font aujourd&rsquo;hui pour le mouvement du <em>Tea Party<\/em>. A cet \u00e9gard, la communication a tu\u00e9 impitoyablement l&rsquo;id\u00e9ologie. Il s&rsquo;agit d&rsquo;une ironie profonde, puisque la communication a \u00e9t\u00e9 cr\u00e9\u00e9e par le syst\u00e8me pour nourrir sa puissance et l&rsquo;id\u00e9ologie unique qui manifeste cette puissance. La communication fournit aujourd&rsquo;hui le processus qui rend caduques les id\u00e9ologies, et qui semble ainsi avoir la capacit\u00e9 potentielle d&rsquo;avoir raison, dans un avenir peut-\u00eatre proche, de l'\u00a0\u00bbid\u00e9ologie unique\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur l&rsquo;impossible \u00ab\u00a0r\u00e9volution\u00a0\u00bb Nous notons r\u00e9guli\u00e8rement la situation o&ugrave; nous nous nous trouvons, dans les pays d\u00e9velopp\u00e9s qui conduisent le syst\u00e8me, de voir l&rsquo;impossibilit\u00e9 que certains sentiments publics de r\u00e9volte s&rsquo;expriment par des actes collectifs classiques violents (\u00e9meutes, r\u00e9volution, prise de pouvoir). Nous notons \u00e9galement que cette impossibilit\u00e9 d&rsquo;une expression directe du m\u00e9contentement public&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4520,8697,4579,3015,6744,398,4734,3100,8698,3096,7069,1225,2879,8256],"class_list":["post-71101","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-4520","tag-8697","tag-cohn-bendit","tag-communication","tag-emeutes","tag-europe","tag-impossible","tag-information","tag-insurrection","tag-mai","tag-party","tag-referendum","tag-revolution","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71101"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71101\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}