{"id":71112,"date":"2009-09-28T06:18:19","date_gmt":"2009-09-28T06:18:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/28\/un-g20-au-gout-depasse\/"},"modified":"2009-09-28T06:18:19","modified_gmt":"2009-09-28T06:18:19","slug":"un-g20-au-gout-depasse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/28\/un-g20-au-gout-depasse\/","title":{"rendered":"Un G20 au go\u00fbt d\u00e9pass\u00e9"},"content":{"rendered":"<p><p>Le G20 a eu lieu \u00e0 Pittsburgh, o\u00f9 la vedette lui a \u00e9t\u00e9 vol\u00e9e par les nouvelles <a href=\"http:\/\/www.dedefensa.org\/article-l_ouest_face_a_l_iran_et_bho_en_forme_28_09_2009.html?admin=1\" class=\"gen\">iraniennes<\/a>. Cette interf\u00e9rence correspondait assez bien au climat de la r\u00e9union, qui n&rsquo;a fait qu&rsquo;esquisser des mesures sans grandes port\u00e9es et ent\u00e9riner les diff\u00e9rences de visions, de conceptions, etc. De ce point de vue, et en \u00e9cartant les r\u00e9f\u00e9rences martiales au vocabulaire trotskiste, nous serions assez tent\u00e9s de suivre l&rsquo;analyse de <em>WSWS.org<\/em>, du <a href=\"http:\/\/www.wsws.org\/articles\/2009\/sep2009\/summ-s26.shtml\" class=\"gen\">26 septembre 2009<\/a>, qui note \u00e9galement que le sommet a d\u00e9finitivement ent\u00e9rin\u00e9 cette enceinte et ce format, de pr\u00e9f\u00e9rence au G8 destin\u00e9 d\u00e9sormais \u00e0 p\u00e9ricliter, comme enceinte pour d\u00e9battre, ou ne pas d\u00e9battre des probl\u00e8mes \u00e9conomico-strat\u00e9giques.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Pittsburgh summit of the Group of 20 leading economies concluded Friday with the issuing of a joint communiqu\u00e9 contrived to mask sharpening conflicts between the major powers over policies to revive the world economy and stave off another financial meltdown.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The major points of contentionbetween the US and Europe, the US and China, the so-called emerging economies of Asia and Latin America and the most powerful Western economieswere evaded in the summit declaration, ensuring that national and regional tensions will continue to fester in the coming weeks and months.<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The main substantive decisions taken by the summit were to continue economic stimulus measures and subsidies to the banks until the purported recovery is firmly in placesomething that had been agreed by all parties in advance of the meetingand to make the G20 group the central forum for international economic discussion, rather than the old G8 group of established industrialized countries.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The latter decision represented an acknowledgment of the increasing weight of countries such as China, India and Brazil in world economic affairs and the relative decline of both the US and Europe. But it also, like most of the initiatives advanced by the US, was designed to strengthen the position of Washington in relation to its major European competitors, especially Germany. It is the European powers that will see the most significant dilution of their influence as a result of the replacement of the G8 by the G20.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout de m\u00eame, il existe quelques \u00e0-c\u00f4t\u00e9s qui m\u00e9ritent d&rsquo;\u00eatre mentionn\u00e9s, pour situer le climat, l&rsquo;enjeu, les perspectives, etc. Egalement, pour parler de la r\u00e9alit\u00e9<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.reuters.com\/article\/topNews\/idUSTRE58G34Z20090925\" class=\"gen\">25 septembre 2009<\/a>, Reuters pr\u00e9sentait la sommet G20, sur sa fin, comme un succ\u00e8s, conform\u00e9ment \u00e0 la doctrine officielle. Comme dans les guerres dont on ne parvient pas \u00e0 se d\u00e9barrasser, la victoire sur la crise fut donc proclam\u00e9e puisqu&rsquo;il semble qu&rsquo;elle ne s&rsquo;imposait pas d&rsquo;elle-m\u00eame. \u00ab<em>The Group of 20 rich and developing nations declared their crisis-fighting efforts a success on Friday and promised to give rising powers such as China more say in rebuilding and guiding the global economy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t La m\u00eame agence Reuters, le m\u00eame <a href=\"http:\/\/www.reuters.com\/article\/businessNews\/idUSTRE5881Q720090925\" class=\"gen\">25 septembre 2009<\/a>, nous annon\u00e7ait que Wall Street avait encore chut\u00e9 \u00e0 l&rsquo;annonce des mauvaises nouvelles de l&rsquo;\u00e9conomie, faisant na\u00eetre des questions \u00e0 propos de la solidit\u00e9 de la reprise. \u00ab<em>U.S. stocks fell for a third straight day on Friday on disappointing housing and durable goods data, while Research In Motion&rsquo;s lackluster results dented optimism about technology spending. Economic reports showed that new orders for long-lasting U.S. manufactured goods fell by their biggest margin in seven months, while August sales of new home fell short of Wall Street&rsquo;s expectations, raising questions about the strength of the recovery.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Toujours ce <a href=\"http:\/\/www.huffingtonpost.com\/2009\/09\/25\/neil-barofsky-tarp-inspec_n_300178.html\" class=\"gen\">25 septembre 2009<\/a>, <em>Huffington.Post<\/em> pr\u00e9sentait une vid\u00e9o d&rsquo;une interview de Neil Barkovsky, l&rsquo;Inspecteur G\u00e9n\u00e9ral charg\u00e9 du contr\u00f4le de l&rsquo;utilisation des fonds publics dispens\u00e9s (TARP) aux banques par le plan Paulson et tous les plans qui ont suivi  pour une somme autour de $3.000 milliards. Sa conclusion: le syst\u00e8me financier est aujourd&rsquo;hui beaucoup plus dangereux&rsquo; qu&rsquo;il ne l&rsquo;\u00e9tait avant la crise Barkovsky se pr\u00e9pare \u00e0 un nouvel audit des banques en octobre, le pr\u00e9c\u00e9dent datant de juillet. \u00ab<em>During an interview with the Huffington Post Investigative Fund, Barofsky made some striking observations. Among them were:  He found hundreds of banks capable of tracking their use of the TARP money  despite claims by the U.S. Treasury that the task was impossible.  If the purpose of the TARP rescue was to increase lending, it has failed.  The U.S. financial system, now dependent on bigger and fewer banks, is shakier than ever.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Pourquoi avons-nous employ\u00e9 le terme des probl\u00e8mes \u00e9conomico-strat\u00e9giques pour caract\u00e9riser le G20? Parce que, effectivement, les probl\u00e8mes \u00e9conomiques colossaux et totalement irr\u00e9solus, sinon <strong>insolubles<\/strong> (le soulign\u00e9 gras montre notre pr\u00e9f\u00e9rence, dont on trouve des signes dans les nouvelles donn\u00e9es en annexe ci-dessus, avec ce qui concerne le G20), ces probl\u00e8mes qui ont \u00e9t\u00e9 \u00e9voqu\u00e9s au G20 de Pittsburgh quittent de plus en plus cette sorte d&rsquo;enceinte et le domaine de la concertation, pour s&rsquo;ordonner selon les r\u00e8gles strat\u00e9giques, parce qu&rsquo;ils r\u00e9v\u00e8lent de plus en plus leur dimension strat\u00e9gique. Ils ne changent pas de substance mais la m\u00e9thode de les traiter change, avec le facteur strat\u00e9gique s&rsquo;imposant et rendant plus politique la substance des probl\u00e8mes qui constituent la crise. L&rsquo;illusoire solidarit\u00e9 et la fausse coop\u00e9ration de la premi\u00e8re ann\u00e9e de la crise laissent place \u00e0 la r\u00e9alit\u00e9 des situations r\u00e9elles d&rsquo;affrontement, tandis que le domaine s&rsquo;\u00e9largit hors de l&rsquo;\u00e9conomie. L&rsquo;intrusion de l&rsquo;affaire iranienne dans le G20 \u00e9tait un signe puissant \u00e0 cet \u00e9gard. La solidarit\u00e9 des trois pays, montr\u00e9e \u00e0 cette occasion comme on monte un spectacle, est \u00e9galement illusoire, surtout faite pour masquer l&rsquo;absence de solidarit\u00e9 du G20.<\/p>\n<\/p>\n<p><p>\tLe G20 perd toute possibilit\u00e9 d&rsquo;exprimer une force en soi, au moment o\u00f9 il remplace le G8. Si ce n&rsquo;avait \u00e9t\u00e9 le cas (le G8 remplac\u00e9 par le G20), la situation aurait \u00e9t\u00e9 similaire, et le G8 aurait perdu directement toute possibilit\u00e9 d&rsquo;exercer une force en soi. D\u00e9sormais, le G20 va devenir le lieu o\u00f9 viendront \u00eatre confront\u00e9es les visions et les conceptions diff\u00e9rentes, non pour les r\u00e9soudre en des compromis multilat\u00e9ralistes, mais pour que les uns et les autres en soient parfaitement inform\u00e9s et se situent plus pr\u00e9cis\u00e9ment. Cela n&#8217;emp\u00eache pas des alliances ou des proximit\u00e9s temporaires, selon les int\u00e9r\u00eats, voire les humeurs des uns et des autres, mais c&rsquo;est l&rsquo;aspect temporaire qui domine. Le d\u00e9litement des capacit\u00e9s, de l&rsquo;autorit\u00e9 et de la pseudo-l\u00e9gitimit\u00e9 du tissu institutionnel qui a pr\u00e9c\u00e9d\u00e9 dans son installation et son fonctionnement pendant des d\u00e9cennies la globalisation pour l&rsquo;accompagner (toutes les organisations internationales, y compris l&rsquo;ONU et l&rsquo;OTAN, les rassemblements semi-informels comme le G20), commence \u00e0 se marquer, toutes ces institutions perdant de leur substance \u00e0 la suite du d\u00e9litement de la globalisation. Cela ne signifie pas que ce tissu institutionnel va dispara\u00eetre ou va \u00eatre compl\u00e8tement inutile, mais essentiellement qu&rsquo;il perd tr\u00e8s vite l&rsquo;importance essentielle qu&rsquo;on lui accordair. Ce cas inclut \u00e9videmment, pour un un sort similaire dans les ann\u00e9es qui viennent, les organisations financi\u00e8res qui ont eu un r\u00f4le pr\u00e9pond\u00e9rant (le FMI), et le dollar lui-m\u00eame. Tout cela suit une logique de dissolution de l&rsquo;ordre du monde mis en place en 1945 et apr\u00e8s.<\/p>\n<\/p>\n<p><p>\tLa question politique primordiale, aujourd&rsquo;hui, notamment sous la pression des conditions de la crise \u00e9conomique, va concerner les coh\u00e9sions internes de certains pays, au premier rang duquel les USA. Les inqui\u00e9tudes pour des violences internes aux USA ne cessent de grandir (nous reviendrons tr\u00e8s vite sur cette question), avec <a href=\"http:\/\/www.dedefensa.org\/article-anatomie_de_la_tasse_de_the_23_09_2009.html\" class=\"gen\">le ph\u00e9nom\u00e8ne<\/a> <em>Tea Party<\/em> comme signe annonciateur. Le G20 a paradoxalement montr\u00e9 des dirigeants plus pr\u00e9occup\u00e9s par cet ensemble de probl\u00e8mes que les questions qu&rsquo;ils \u00e9taient cens\u00e9s discuter. De toutes les fa\u00e7ons, quelle mesure peut-on donner d&rsquo;une r\u00e9union qui se termine en affirmant que la victoire sur la crise  a \u00e9t\u00e9 remport\u00e9e, que la chose est implicite dans le communiqu\u00e9, que ce communiqu\u00e9 est notamment sign\u00e9 par un Sarkozy qui disait, <a href=\"http:\/\/www.dedefensa.org\/article-la_france_parle_sarko_s_execute_25_09_2009.html\" class=\"gen\">deux jours<\/a> auparavant, \u00e0 la tribune de l&rsquo;ONU, que nous nous trouvons dans et devant une crise sans exemple dans l&rsquo;Histoire et de dimensions et de forme eschatologiques?<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 septembre 2009 \u00e0 06H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le G20 a eu lieu \u00e0 Pittsburgh, o\u00f9 la vedette lui a \u00e9t\u00e9 vol\u00e9e par les nouvelles iraniennes. Cette interf\u00e9rence correspondait assez bien au climat de la r\u00e9union, qui n&rsquo;a fait qu&rsquo;esquisser des mesures sans grandes port\u00e9es et ent\u00e9riner les diff\u00e9rences de visions, de conceptions, etc. De ce point de vue, et en \u00e9cartant les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3228,8710,7932,2632,6208,8623,4590],"class_list":["post-71112","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-crise","tag-depasse","tag-g20","tag-globalisation","tag-obama","tag-pittsburgh","tag-sarkozy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71112"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71112\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}