{"id":71120,"date":"2009-09-30T06:00:01","date_gmt":"2009-09-30T06:00:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/30\/le-jsf-une-merveille-a-10\/"},"modified":"2009-09-30T06:00:01","modified_gmt":"2009-09-30T06:00:01","slug":"le-jsf-une-merveille-a-10","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/09\/30\/le-jsf-une-merveille-a-10\/","title":{"rendered":"Le JSF, une merveille \u00e0 10%"},"content":{"rendered":"<p><p>Ce soir \u00e0 minuit se termine, pour le Pentagone, l&rsquo;ann\u00e9e fiscale 2009 (FY2009). Nous nous int\u00e9ressons \u00e0 l&#8217;emploi de ce temps annuel par le tr\u00e8s populaire et m\u00e9diatique Joint Strike Fighter, <em>alias<\/em> JSF, <em>alias<\/em> F-35. C&rsquo;est-\u00e0-dire, pour \u00eatre juste, qu&rsquo;il s&rsquo;agit de Bill Sweetman qui s&rsquo;est mis au travail. On conna\u00eet bien l&rsquo;ami  <LIEN=http:\/\/www.dedefensa.org\/article-jsf_versus_sweetman_sous_le_regard_de_row__14_01_2009.html>Sweetman, journaliste rigoureux et d&rsquo;esprit ind\u00e9pendant, que le parti du JSF (Lockheed Martin [LM] et JSF Program Office [JPO]) n&rsquo;aime gu\u00e8re, qu&rsquo;il tente r\u00e9guli\u00e8rement de clouer au pilori. <\/p>\n<\/p>\n<p><p>\tSweetman a entrepris de calculer pr\u00e9cis\u00e9ment le programme d&rsquo;essai en vol du JSF pour l&rsquo;ann\u00e9e FY2009, parce que la question du programme d&rsquo;essai est un point essentiel du programme, un point de pol\u00e9mique fondamental. (Le JSF pourra-t-il r\u00e9aliser son programme d&rsquo;essais en vol selon la planification pr\u00e9vue pour tenir le calendrier actuel, d\u00e9j\u00e0 fortement retard\u00e9 par rapport aux pr\u00e9visions g\u00e9n\u00e9rales? Rencontrera-t-il des probl\u00e8mes qui interf\u00e9reront plus ou moins gravement sur la production qui est parall\u00e8lement lanc\u00e9e?  ce qui n&rsquo;est pas la moindre originalit\u00e9 du programme, ce parall\u00e9lise entre les essais encore \u00e0 r\u00e9aliser et la production d\u00e9j\u00e0 lanc\u00e9e) <\/p>\n<\/p>\n<p><p>\tSweetman nous expose les r\u00e9sultats de son enqu\u00eate sur son <em>blog<\/em>, sur <em>AviationWeek.com<\/em>, le <a href=\"http:\/\/www.aviationweek.com\/aw\/blogs\/defense\/index.jsp?plckController=Blog&#038;plckBlogPage=BlogViewPost&#038;newspaperUserId=27ec4a53-dcc8-42d0-bd3a-01329aef79a7&#038;plckPostId=Blog%3a27ec4a53-dcc8-42d0-bd3a-01329aef79a7Post%3a4c1c0ed5-5e49-4349-8516-694ffe03ff18&#038;plckScript=blogScript&#038;plckElementId=blogDest\" class=\"gen\">29 septembre2009<\/a>. <\/p>\n<\/p>\n<p><p>\t Sweetman s&rsquo;appuie sur des documents officiels, un organigramme de d\u00e9veloppement de janvier 2009 et un rapport du Governement Accounting Office (GAO) de mars 2009, r\u00e9alis\u00e9 d&rsquo;apr\u00e8s les documents \u00e9videmment officiels recueillis par le GAO. Lorsque le rapport du GAO fut publi\u00e9 en mars 2009, il annon\u00e7ait toujours le but officiel de 317 vols d&rsquo;essai pour le JSF pour la FY2009. Cette campagne d&rsquo;essais \u00e9tait d\u00e9crite avec pr\u00e9cision dans les documents de janvier 2009. Sweetman constatait d\u00e8s cette \u00e9poque (mars 2009) que ce programme d&rsquo;essais aurait fort peu de chance de s&rsquo;accomplir puisque, au moment de la parution du rapport du GAO, au milieu de la FY2009 (en mars 2009), il y avait eu seulement 17 vols d&rsquo;essai r\u00e9alis\u00e9s. S&rsquo;appuyant avec confiance sur l&rsquo;annonce officielle que six nouveaux F-35 allaient alors entrer dans le programme d&rsquo;essais en vol, Sweetman estimait que l&rsquo;on pourrait atteindre 80 vols d&rsquo;essai au lieu des 317 pr\u00e9vus \u00e0 la fin de FY2009.<\/p>\n<\/p>\n<p><p>\t Le r\u00e9sultat, selon le d\u00e9compte qu&rsquo;en fait Sweetman, est stup\u00e9fiant. Au final, ce soir \u00e0 minuit, il y aura eu 33 vols d&rsquo;essai dans l&rsquo;ann\u00e9e FY2009 (au lieu des 317 pr\u00e9vus) et un seul des six avions suppl\u00e9mentaires a effectivement vol\u00e9 \u00ab<em>As it was, the program managed about 15 flights in the latter half of the 2009 fiscal year, ending it with 33 flights (by my count)  or about one-tenth of what was planned. Only one of the six jets that were supposed to fly before the end of FY09 has done so. (If you include CATBird test-bed flights the number for FY2009 may be higher &#8211; but not by much.)<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuelles sont les explications donn\u00e9es pour ces extraordinaires \u00e9carts entre les pr\u00e9cisions prospectives et la r\u00e9alit\u00e9? LM explique que les avions sortis de la cha\u00eene de production, dont on attendait qu&rsquo;ils volassent aussit\u00f4t, ne sont pas encore termin\u00e9s (\u00ab<em>with a lot of work to do before they were ready to fly, and <\/em>[] <em>being held until a much higher state of compl\u00e9tion rather than being reworked after roll-out<\/em>\u00bb). Cet \u00e9tat d&rsquo;impr\u00e9paration au vol d&rsquo;exemplaires sortant de production vient, semble-t-il de consignes de production prises en amont, qui ne paraissent pas avoir atteint le niveau des pr\u00e9visionnistes annon\u00e7ant le programme d&rsquo;essais, puisque celui-ci s&rsquo;est av\u00e9r\u00e9 compl\u00e8tement faux. On promet que les choses vont changer et que les prochains mois vont voir une acc\u00e9l\u00e9ration significative du rythme des vols d&rsquo;essai.<\/p>\n<\/p>\n<p><p>\tApr\u00e8s les explications, Sweetman cherche la cause fondamentale de cette situation. Il \u00e9met des hypoth\u00e8ses.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>However, you still have to wonder about the milestones chart published in January<\/em> [2009]<em>. I can think of two explanations  other than outright deception, which I&rsquo;ll rule out for the time being   for the fact that its predictions were so wrong. <\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>First, it could be that nobody in the program was fully aware that the aircraft being rolled off the assembly line were so far from ready to fly  which doesn&rsquo;t speak well for the overall management and control of this fast-paced and complex effort. Second, there may be a problem with the upflow of bad news in the program  an issue which many believe also affects the Boeing 787.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 qui m\u00e9rite quelques r\u00e9flexions Le plus remarquable dans cet expos\u00e9 que nous fait Bill Sweetman est sans aucun doute le parall\u00e9lisme entre les affirmations officielles du rythme des essais et le d\u00e9menti que les faits apportent presque simultan\u00e9ment, sans r\u00e9el espoir ni possibilit\u00e9 que la confrontation entre les deux soit \u00e9vit\u00e9e. Cette remarque est in\u00e9vitable quand la disparit\u00e9 est si consid\u00e9rable, de un (33 vols d&rsquo;essais effectu\u00e9s) \u00e0 dix (317 vols d&rsquo;essai pr\u00e9vus). On est conduit, devant une telle \u00e9vidence du fonctionnement vici\u00e9 du programme \u00e0 rejeter l&rsquo;option de la d\u00e9sinformation consciente (propagande), comme semble le faire Sweetman (\u00ab<em> other than outright deception, which I&rsquo;ll rule out for the time being<\/em>\u00bb). Il est absurde, selon le simple bon sens d&rsquo;un propagandiste, de continuer \u00e0 proclamer, selon une d\u00e9marche <strong>consciemment<\/strong> trompeuse, de tels objectifs (317 vols pour FY2009) en janvier 2009, puis repris en mars 2009, alors que l&rsquo;ann\u00e9e FY2009 est en cours depuis octobre 2008 et que le rythme \u00e9vident et public des vols montre qu&rsquo;il n&rsquo;y a aucune possibilit\u00e9 qu&rsquo;on puisse seulement approcher cette pr\u00e9vision.<\/p>\n<\/p>\n<p><p>\tOn tire de ces constats l&rsquo;observation que la cause centrale est bien l&rsquo;absence compl\u00e8te de contr\u00f4le du programme, bien plus par organisation fautive r\u00e9pondant \u00e0 une d\u00e9marche intellectuelle syst\u00e9mique de type virtualiste (au sens d&rsquo;une d\u00e9marche intellectuelle allant dans le sens de l&rsquo;int\u00e9r\u00eat du syst\u00e8me tel qu&rsquo;il est pr\u00e9sent\u00e9 par les services de relations publiques) que par d\u00e9sordre, et cela \u00e0 l&rsquo;int\u00e9rieur m\u00eame de Lockheed Martin, au cur m\u00eame du d\u00e9veloppement et de la production de l&rsquo;avion. Les deux explications de la cause centrale du vice de l&rsquo;entreprise qu&rsquo;expose Sweetman se confondraient: personne ne serait au courant de ce qui se passe vraiment (\u00ab<em>it could be that nobody in the program was fully aware<\/em>\u00bb), notamment de l&rsquo;\u00e9tat de capacit\u00e9 de voler des avions sortant de la ligne de production, parce que l&rsquo;organisation fondamentale fait que la circulation des informations \u00e0 l&rsquo;int\u00e9rieur du programme \u00e9carte les mauvaises nouvelles (\u00ab<em>there may be a problem with the upflow of bad news in the program<\/em>\u00bb). Dans ce cas, il s&rsquo;agit d&rsquo;une organisation syst\u00e9mique qui a \u00e9t\u00e9 install\u00e9e, notamment et principalement \u00e0 l&rsquo;occasion du syst\u00e8me JSF, qui implique une priorit\u00e9 faite \u00e0 l&rsquo;orientation des nouvelles du programme selon le but poursuivi et d\u00e9crit par la pr\u00e9sentation virtualiste du programme, qui est sa r\u00e9ussite selon des crit\u00e8res absolument imp\u00e9ratifs fix\u00e9s selon cette pr\u00e9sentation virtualiste. Cela signifierait que ce nous avons d\u00e9sign\u00e9 comme un programme virtualiste, le JSF, l&rsquo;est au-del\u00e0 de ce qu&rsquo;on envisageait dans les hypoth\u00e8ses les plus audacieuses, il l&rsquo;est au sein m\u00eame du constructeur, au cur m\u00eame de la production. Il n&rsquo;y a aucune intention sp\u00e9cifique, consciente, dans le d\u00e9tail de la d\u00e9marche, de tromper; tout le syst\u00e8me lui-m\u00eame est trompeur pour lui-m\u00eame, avec l&rsquo;installation d&rsquo;une philosophie de l&rsquo;information qui tend \u00e0 brider les mauvaises nouvelles dans le flot de l&rsquo;information, au profit des bonnes nouvelles, pour accorder l&rsquo;\u00e9tat g\u00e9n\u00e9ral du syst\u00e8me \u00e0 la pr\u00e9sentation virtualiste qui en est faite. La correction des faiblesses constat\u00e9e avec le constat des faits est elle-m\u00eame virtualiste. Elle ne se fait pas dans la modification des proc\u00e9dures (instruction de donner toutes les nouvelles, m\u00eame lorsqu&rsquo;elles sont mauvaises), mais dans l&rsquo;annonce, apr\u00e8s chaque constat catastrophique, que, cette fois, \u00e0 cause de telle ou telle mesure concernant le programme, les choses vont changer pour l&rsquo;avenir.<\/p>\n<\/p>\n<p><p>\tDans un tel cadre g\u00e9n\u00e9ral d&rsquo;activit\u00e9, les erreurs, les faiblesses, etc., ne sont pas corrig\u00e9es parce qu&rsquo;elles ne sont pas identifi\u00e9es comme erreurs, faiblesses, etc. Il n&rsquo;y a pas de rem\u00e8de puisqu&rsquo;il n&rsquo;y a pas de mal. Dans ce cas, ce n&rsquo;est pas le JSF qui est fautif, puisqu&rsquo;il ne peut \u00eatre fautif selon la perception qu&rsquo;impose l&rsquo;organisation syst\u00e9mique. La chose devient une fascinante aventure car, selon cette logique du refus du r\u00e9el  le JSF serait un n\u00e9gationniste de la r\u00e9alit\u00e9   il est vraiment tr\u00e8s difficile d&rsquo;imaginer une issue o\u00f9 le JSF serait <strong>autoris\u00e9<\/strong> \u00e0 se r\u00e9concilier avec la r\u00e9alit\u00e9 \u00e0 quelque moment que ce soit; voire m\u00eame, il est tr\u00e8s difficile d&rsquo;imaginer une situation o\u00f9 l&rsquo;on puisse conclure qu&rsquo;il y a une r\u00e9alit\u00e9 avec laquelle il serait n\u00e9cessaire de r\u00e9concilier le JSF. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 septembre 2009 \u00e0 06H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce soir \u00e0 minuit se termine, pour le Pentagone, l&rsquo;ann\u00e9e fiscale 2009 (FY2009). Nous nous int\u00e9ressons \u00e0 l&#8217;emploi de ce temps annuel par le tr\u00e8s populaire et m\u00e9diatique Joint Strike Fighter, alias JSF, alias F-35. C&rsquo;est-\u00e0-dire, pour \u00eatre juste, qu&rsquo;il s&rsquo;agit de Bill Sweetman qui s&rsquo;est mis au travail. On conna\u00eet bien l&rsquo;ami Sweetman, journaliste&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3662,8721,250,3501,3502,8722,8703,8033,3534,3747,5713,5899,2766,6769,3087],"class_list":["post-71120","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-desinformation","tag-essais","tag-jsf","tag-lockheed","tag-martin","tag-mauvaises","tag-negationniste","tag-nouvelles","tag-production","tag-propagande","tag-publiques","tag-realite","tag-relations","tag-sweetman","tag-virtualiste"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71120"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71120\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}