{"id":71155,"date":"2009-10-10T07:30:46","date_gmt":"2009-10-10T07:30:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/10\/dedefensaorg-trente-jours-apres\/"},"modified":"2009-10-10T07:30:46","modified_gmt":"2009-10-10T07:30:46","slug":"dedefensaorg-trente-jours-apres","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/10\/dedefensaorg-trente-jours-apres\/","title":{"rendered":"<em>dedefensa.org<\/em>, trente jours apr\u00e8s"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>dedefensa.org<\/em>, trente jours apr\u00e8s<\/h2>\n<\/p>\n<p><p>\t10 octobre 2009  Effectivement, cela fait trente jours, ou un mois, qu&rsquo;a commenc\u00e9 notre phase du domaine payant \u00e0 c\u00f4t\u00e9 de l&rsquo;acc\u00e8s libre classique du site depuis son origine. C&rsquo;est une date importante, ces trente jours, parce que commence aujourd&rsquo;hui la question, centrale pour nous, du renouvellement des abonnements d&rsquo;un mois, qui sont l&rsquo;\u00e9crasante majorit\u00e9, et que nous percevons \u00e9videmment comme des abonnements d&rsquo;essai au nouveau service mis en place.<\/p>\n<\/p>\n<p><p>\tEn attendant, nous allons donner de la chair \u00e0 ce qui serait en passe de devenir une rubrique (ce <em>F&#038;C<\/em> du samedi concernant <em>dedefensa.org<\/em>)  mais qui ne l&rsquo;est tout de m\u00eame pas, une rubrique, rassurons-nous et rassurez-vous  qui constitue simplement la marque de temps exceptionnels pour nous. Nous allons surtout nous appuyer, dans ce texte, sur deux lecteurs qui sont intervenus directement aupr\u00e8s de nous, et personnellement aupr\u00e8s de Philippe Grasset. C&rsquo;est pourquoi on retrouvera parfois dans le texte, essentiellement dans la r\u00e9ponse \u00e0 l&rsquo;intervention du premier lecteur, le je caract\u00e9ristique de la personne prenant le parole, ou parfois un PhG s&rsquo;y substituant<\/p>\n<h3>De la part de Ad Vitam Eternam<D><\/h3>\n<\/p>\n<p><p>\tNotre premier lecteur, lui-m\u00eame abonn\u00e9, se pr\u00e9sente sous le pseudonyme de <em>Ad Vitam Etenam<\/em>. Voici son message.<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Etant votre \u00e9ternel abonn\u00e9, et donc \u00e0 l&rsquo;abri d&rsquo;\u00e9ventuels changements, je pense pouvoir me permettre une remarque: plus \u00e7a va, moins je comprends le mod\u00e8le \u00e9conomique de dedefensa.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Vous n&rsquo;\u00eates \u00e9videmment pas contraint \u00e0 la transparence, mais l&rsquo;opacit\u00e9 limite \u00e0 mon avis les efforts consentis par vos lecteurs. Les donations ont \u00e9t\u00e9 un \u00e9chec, mais sans conna\u00eetre vos autres ressources on peine \u00e0 estimer l&rsquo;urgence de la situation. L&rsquo;offre de defensa (une lettre? une autre lettre? une revue?) a un aspect n\u00e9buleux, et chaque \u00e9claircissement rend les choses un peu plus floues.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Votre activit\u00e9 a un co\u00fbt, et m\u00e9rite r\u00e9mun\u00e9ration, c&rsquo;est entendu. Pourquoi ne pas expliquer, pourquoi ne pas d\u00e9crire de defensa? Est-ce vous seul, puisque vous signez tous les articles? Quelle part du total repr\u00e9sentait votre appel \u00e0 donations? Quelles autres charges faut-il couvrir? Des salari\u00e9s, des prestations externes, des frais g\u00e9n\u00e9raux? Des activit\u00e9s b\u00e9n\u00e9ficiaires, d&rsquo;autres d\u00e9ficitaires? Pourquoi ne pas dire simplement quelles sont vos charges, et demander \u00e0 vos lecteurs comment ils comptent les couvrir?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Vous n&rsquo;\u00eates sans doute pas dans la m\u00eame situation que lui, mais il y a maintenant un pr\u00e9c\u00e9dent Paul Jorion. La r\u00e8gle est simple: annoncer ses besoins, et compter sur les lecteurs pour les couvrir. L&rsquo;exercice n\u00e9cessite la transparence, il impose une grande confiance r\u00e9ciproque, mais il me semble moins risqu\u00e9 que vos derniers t\u00e2tonnements.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Bref, ne le prenez pas mal mais vous me semblez moins clairvoyant pour de defensa que pour la marche du monde. Je ne pr\u00e9tends pas voir la solution, mais je vous propose une piste. Vous avez peut-\u00eatre mille raisons de ne pas la suivre. Si c&rsquo;est le cas, disons que je n&rsquo;ai pas \u00e9crit ce mail; dans le cas contraire, je suis \u00e0 votre disposition pour en discuter.<\/em>\u00bb <\/p>\n<h3>La r\u00e9ponse de l&rsquo;int\u00e9ress\u00e9<\/h3>\n<\/p>\n<p><p>\tJe vous remercie de votre message et, naturellement, par respect pour votre statut d&rsquo;\u00e9ternit\u00e9, j&rsquo;y r\u00e9ponds pr\u00e9cis\u00e9ment.<\/p>\n<\/p>\n<p><p>\tJ&rsquo;ai accueilli avec int\u00e9r\u00eat vos remarques critiques, que j&rsquo;ai ressenties comme dites sur un ton tr\u00e8s chaleureux. Vous prendrez ma r\u00e9ponse sur le m\u00eame ton, j&rsquo;en suis s\u00fbr. Allons-y.<\/p>\n<\/p>\n<p><p>\tSi je comprends, vous me dites deux choses :<\/p>\n<\/p>\n<p><p>\t Que la situation de <em>dedefensa.org<\/em> est tr\u00e8s mal expos\u00e9e, tant dans son historique que dans son actualit\u00e9.<\/p>\n<\/p>\n<p><p>\t Qu&rsquo;il me faut, pour obtenir les soutiens auxquels nous pr\u00e9tendons, pr\u00e9senter les choses en exposant la r\u00e9alit\u00e9 de nos besoins d&rsquo;une fa\u00e7on pr\u00e9cise, presque comptable en un sens.<\/p>\n<\/p>\n<p><p>\tSur le premier point, je vous r\u00e9pondrai que j&rsquo;ai d\u00e9j\u00e0 dit beaucoup. Il me semble qu&rsquo;en consultant simplement deux textes (il y en a d&rsquo;autres), vous conna\u00eetrez  avec le premier, l&rsquo;historique du site <em>dedefensa.org<\/em>, y compris par rapport \u00e0 la Lettre d&rsquo;Analyse <em>dedefensa &#038; eurostrat\u00e9gie<\/em> (<em>dd&#038;e<\/em>): le <a href=\"http:\/\/www.dedefensa.org\/article-journal_de_bord_de_dedefensaorg_070824_reflexions_et_commentaires_pour_un_lecteur_l_autre_i_25_08_2007.html\" class=\"gen\">25 ao\u00fbt 2007<\/a>   avec le second, l&rsquo;historique rapproch\u00e9e de la fin de <em>dd&#038;e<\/em>, de sa transformation en <em>dde.crisis<\/em> et de son int\u00e9gration dans le site: le <a href=\"http:\/\/www.dedefensa.org\/article-journal_de_bord_de_dedefensaorg_090415_a_tout_lecteur_tout_honneur_15_04_2009.html\" class=\"gen\">15 avril 2009<\/a>.<\/p>\n<\/p>\n<p><p>\tEnfin, pour la facilit\u00e9, r\u00e9sumons le destin de la chose jusqu&rsquo;\u00e0 aujourd&rsquo;hui: la Lettre <em>dd&#038;e<\/em> existe depuis 1985, a bien march\u00e9, a nourri son homme. Chemin faisant, PhG s&rsquo;est convaincu d&rsquo;ouvrir un site (en 1999), parall\u00e8lement, sans rien toucher de la Lettre, sans aucune ambition pr\u00e9cise. Le site a grandi, a pris de plus en plus d&rsquo;importance, sans le moindre effort de promotion, jusqu&rsquo;\u00e0 la situation pr\u00e9sente. L&rsquo;aventure s&rsquo;exaltait d&rsquo;elle-m\u00eame, et l&rsquo;entretien et le d\u00e9veloppement du site co\u00fbtaient de l&rsquo;argent, de plus en plus, puis le temps pris pour son contenu, qui finit par devenir du temps vol\u00e9 \u00e0 la Lettre et de l&rsquo;activit\u00e9 prise \u00e0 la soci\u00e9t\u00e9 \u00e9ditrice. La danseuse (<em>dedefensa.org<\/em>) fut nourrie par la Lettre, jusqu&rsquo;\u00e0 ce que la Lettre commence \u00e0 p\u00e9ricliter et que la situation se tende. Il fallut envisager que le site se nourrisse de lui-m\u00eame, ce qui a son co\u00fbt si l&rsquo;on veut faire quelque chose de convenable. Ce fut la tentative (rat\u00e9e) des donations, lorsque j&rsquo;entretenais encore des illusions sur une philosophie purement de type-Internet. A cette occasion, \u00e0 la diff\u00e9rence de ce que vous observez, les besoins furent clairement chiffr\u00e9s: un minimum vital de 3 donations de 13.000, soit 39.000 par an. Echec.<\/p>\n<\/p>\n<p><p>\tLes conditions \u00e9conomiques (la crise) acc\u00e9l\u00e9r\u00e8rent le d\u00e9clin de la Lettre, jusqu&rsquo;\u00e0 l&rsquo;id\u00e9e d&rsquo;int\u00e9grer la Lettre dans le site (<em>dd&#038;e<\/em> devenant <em>dde.crisis<\/em>), qui est une id\u00e9e d&rsquo;abord \u00e9conomique de rentabilisation et de compression des frais. Il y avait des abonn\u00e9s \u00e0 cette Lettre, il fallait donc suivre la ligne des abonnements de la Lettre pour englober le tout, avec une formule moyenne acc\u00e8s libre\/domaine payant.<\/p>\n<\/p>\n<p><p>\tPour r\u00e9sumer, ce qui est tent\u00e9 se d\u00e9marque de l&rsquo;habitude. L&rsquo;habitude, c&rsquo;est:<\/p>\n<\/p>\n<p><p>\t Soit un site compl\u00e8tement Internet, qui s&rsquo;installe comme tel et adopte compl\u00e8tement la philosophie du r\u00e9seau, qui n&rsquo;est pas celle du m\u00e9tier de l&rsquo;information et de l&rsquo;analyse, mais qui a ses propres r\u00e8gles, o\u00f9 pr\u00e9dominent la libert\u00e9 le plus souvent indiff\u00e9rente \u00e0 la responsabilit\u00e9, et la pol\u00e9mique. Le caract\u00e8re essentiel de cette philosophie est l&rsquo;irresponsabilit\u00e9 professionnelle. Je ne la condamne en rien et en aucune fa\u00e7on, c&rsquo;est dit; mais ce n&rsquo;est pas mon choix, d&rsquo;une fa\u00e7on de plus en plus affirm\u00e9e.<\/p>\n<\/p>\n<p><p>\t Soit un site \u00e9manant d&rsquo;un support papier comme on en voit avec tant de journaux de la presse officielle, compl\u00e9mentaire de ce support. Ce site r\u00e9pond alors aux normes \u00e9conomiques du syst\u00e8me officiel. Inutile de faire un dessin ni de d\u00e9velopper un long discours puisque ce n&rsquo;est pas notre dessein. Passons outre.<\/p>\n<\/p>\n<p><p>\t Dans le cas de <em>dedefensa.org<\/em>, il s&rsquo;agit du mariage d&rsquo;un site qui se suffisait \u00e0 lui-m\u00eame et d&rsquo;une publication-papier qui se suffisait \u00e0 elle-m\u00eame. Les deux suffisances ont p\u00e9riclit\u00e9 et l&rsquo;on a d\u00e9cid\u00e9 de les marier pour r\u00e9duire leur co\u00fbt. Le but recherch\u00e9 n&rsquo;est pas la r\u00e9ussite d&rsquo;un mod\u00e8le \u00e9conomique mais la poursuite d&rsquo;une aventure intellectuelle en fonction de l&rsquo;\u00e9volution d\u00e9grad\u00e9e des conditions \u00e9conomiques qui affectent surtout la composante \u00e9dition papier \u00e0 cause des co\u00fbts techniques fixes. La r\u00e8gle, la philosophie, est totalement celle de la responsabilit\u00e9 professionnelle, au sens le plus large de l&rsquo;expression (\u00e9ventuellement, avec une dimension \u00e9thique).<\/p>\n<\/p>\n<p><p>\tLorsque nous parlons (dans des textes pr\u00e9c\u00e9dents) de la survie du site, c&rsquo;est de cela, du site seulement tel qu&rsquo;il appara\u00eet avec cette fusion dont nous parlons et rien d&rsquo;autre. En th\u00e9orie, demain, le vieux bonhomme (PhG) peut d\u00e9cider d&rsquo;arr\u00eater tout. Il a une retraite plus ou moins d\u00e9cente, une maison qu&rsquo;il a achev\u00e9 de payer, tr\u00e8s peu de besoin et horreur des vacances. Il passera donc une vieillesse malheureuse (s&rsquo;il n&rsquo;\u00e9crit plus, ce qui est difficilement concevable) ou heureuse (il \u00e9crira d&rsquo;une autre fa\u00e7on), en mangeant \u00e0 sa faim et en regardant le monde s&rsquo;\u00e9crouler.<\/p>\n<\/p>\n<p><p>\tMaintenant, la derni\u00e8re partie de vos remarques, cher <em>Ad Vitam Eternam<\/em>: pourquoi ne pas exposer en pleine transparence mes besoins? Parce que cela n&rsquo;a aucun sens pour ma conception de mon m\u00e9tier. Demandez-vous, en achetant <em>Le Monde Diplomatique<\/em>, si le mobilier de leur bureau est remis \u00e0 neuf? Demandez-vous, en achetant <em>Marianne<\/em>, combien de salari\u00e9s ils emploient? Tout cela, pour ajuster le prix que vous allez payer, ou la donation que vous allez d\u00e9terminer? Sur ce point, ma position est compl\u00e8tement intraitable. Il y a un aspect priv\u00e9, qui  ne regarde que moi, de mes activit\u00e9s. J&rsquo;\u00e9crivais dans un des textes cit\u00e9s, le 25 ao\u00fbt 2007:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A ces demandes d&rsquo;explication comme \u00e0 d&rsquo;autres, nous pourrions r\u00e9pondre par le simple bon sens : en quoi tout cela concerne-t-il nos lecteurs? Mais non, jouons le jeu. Nous le faisons, nous l&rsquo;avouons, selon un r\u00e9flexe professionnel,  pour vous informer de nos conceptions, de notre fa\u00e7on de voir, autant que de notre situation. Et puis aussi, disons ce mot que nous r\u00e9p\u00e9terons : par courtoisie.<\/em>\u00bb  Cela est plus vrai que jamais, plus absolu, plus incontestable, plus intraitable, pour le principe \u00e9voqu\u00e9 <em>in fine<\/em>; si j&rsquo;avais \u00e0 r\u00e9crire cette phrase, ce serait en des termes bien plus tranch\u00e9s. La courtoisie demeure \u00e9galement, si nous jugeons que nous pouvons faire telle ou telle remarque pour faire avancer les choses dans l&rsquo;esprit des lecteurs, mais le principe est totalement et absolument intangible. C&rsquo;est une question de dignit\u00e9 et d&rsquo;ind\u00e9pendance de l&rsquo;individu; et notez bien ceci qui est fondamental: si je sacrifiais cette dignit\u00e9 et cette ind\u00e9pendance, je sais parfaitement que le niveau des r\u00e9flexions et des chroniques en p\u00e2tiraient. Je ne veux pas avoir \u00e0 jouer une sorte de r\u00f4le d&rsquo;entretenu, venir tous les quinze jours en vous parlant du mobilier qu&rsquo;il faut remplacer ou d&rsquo;une fuite d&rsquo;eau, ou d&rsquo;un ordinateur qui vieillit; pourquoi ne pas vous parler aussi de mes humeurs d\u00e9pressives, de mes angoisses, qui sont nombreuses, et demander une contribution accentu\u00e9e \u00e0 cause d&rsquo;un traitement psychanalytique? Non, cela n&rsquo;a pas de sens pour moi.<\/p>\n<\/p>\n<p><p>\tIl y a un travail de journaliste, de chroniqueur, d&rsquo;historien, et c&rsquo;est la seule chose qui doit \u00eatre prise en compte. On appr\u00e9cie cela ou non, on suit le site ou on l&rsquo;abandonne. Puisque nous sommes dans le syst\u00e8me o\u00f9 nous sommes, cela se paye, comme vous-m\u00eames \u00eates pay\u00e9s et comme vous payez \u00e0 votre tour dans toutes les activit\u00e9s de la vie. Les prix fix\u00e9s sont ce qu&rsquo;ils sont, et si certains les trouvent scandaleusement \u00e9lev\u00e9s, d&rsquo;autres les trouvent compl\u00e8tement et absolument justifi\u00e9s. Si certains objectent que <em>Le Monde<\/em> co\u00fbte moins cher, qu&rsquo;ils aillent voir du c\u00f4t\u00e9 du <em>Monde<\/em> et ils verront que <em>dedefensa.org<\/em> ne s&rsquo;y trouve pas, dans l&rsquo;esprit et dans la forme, et <em>dedefensa.org<\/em> se passera d&rsquo;eux  et ainsi de suite. Voil\u00e0 pour les principes.<\/p>\n<\/p>\n<p><p>\tBien entendu, hors des principes, on peut, on doit \u00eatre souple, mais cette souplesse ne s&rsquo;exercera qu&rsquo;en faveur de la facilit\u00e9 donn\u00e9e \u00e0 la diffusion des \u00e9crits, en aidant les lecteurs \u00e0 y avoir acc\u00e8s. Je sens que l&rsquo;\u00e9volution \u00e0 venir pourrait donc conduire \u00e0 certains am\u00e9nagements. Il y aurait peut-\u00eatre la formule d&rsquo;un prix r\u00e9duit pour ceux qui, <strong>en conscience<\/strong>, ne peuvent pas payer 150 pour les articles (pour prendre la r\u00e9f\u00e9rence centrale)  et ce serait aux abonn\u00e9s eux-m\u00eames, <strong>en conscience<\/strong>, de d\u00e9cider qu&rsquo;ils choisiront cette formule de prix r\u00e9duit qui ne nous avantage pas. Mais le bar\u00e8me actuel des prix resterait absolument la r\u00e9f\u00e9rence. (Et les int\u00e9r\u00eats des abonn\u00e9s qui n&rsquo;auraient pas connu ce syst\u00e8me, si ce syst\u00e8me \u00e9tait install\u00e9, seraient absolument prot\u00e9g\u00e9s  j&rsquo;insiste fortement sur ce point.) Je ne parle ici que d&rsquo;une possibilit\u00e9, rien d&rsquo;autre.<\/p>\n<\/p>\n<p><p>\tUne autre \u00e9volution, <strong>in\u00e9luctable<\/strong> celle-l\u00e0, vue la difficult\u00e9 d&rsquo;avoir des abonnements pour nous, ce sera la r\u00e9duction grandissante du domaine d&rsquo;acc\u00e8s libre, parce qu&rsquo;en l&rsquo;occurrence ceux que nous voulons privil\u00e9gier sont ceux qui font l&rsquo;effort de payer. Ce n&rsquo;est pas \u00e0 un lecteur \u00e9ternel que je vais apprendre cela. Si cela ne r\u00e9ussit pas pour <em>dedefensa.org<\/em>, eh bien tant pis pour le site (et pour ses lecteurs?). La loi du nombre aura parl\u00e9 et cela ne me donnera pas une consid\u00e9ration tr\u00e8s positive de la d\u00e9mocratie directe type-Internet..<\/p>\n<\/p>\n<p><p>\tP.S. de PhG: entretemps, j&rsquo;ai re\u00e7u une appr\u00e9ciation de <em>Ad Vitam Eternam<\/em> sur ce texte qui \u00e9tait d&rsquo;abord ma r\u00e9ponse \u00e0 son intervention. Il m&rsquo;a affirm\u00e9 que nous n&rsquo;\u00e9tions nullement en d\u00e9saccord apr\u00e8s ce que j&rsquo;avais \u00e9crit, que j&rsquo;avais rappel\u00e9 quelques faits que les lecteurs oublient souvent. Je partage compl\u00e8tement cet avis et voil\u00e0 confirm\u00e9 l&rsquo;int\u00e9r\u00eat de publier cette rapide correspondance.<\/p>\n<h3>A propos du prix des abonnements<\/h3>\n<\/p>\n<p><p>\tUn autre lecteur, que nous remercions \u00e9galement avec chaleur de son int\u00e9r\u00eat et de ses encouragements, nous a envoy\u00e9 un court message \u00e9crit sous le feu d&rsquo;un juste sentiment d&rsquo;indignation devant certaines r\u00e9ticences exprim\u00e9es ici et l\u00e0 dans tel ou <em>Forum<\/em> du site. Il nous a autoris\u00e9 \u00e0 le publier, et nous le faisons d&rsquo;autant plus volontiers qu&rsquo;il r\u00e9sume grandement ce que nous pensons souvent \u00e0 propos des jugements n\u00e9gatifs concernant le montant des abonnements lorsque le choix et les moyens existent chez ceux qui font ces arguments  et mettant \u00e0 part ceux qui, naturellement, en sont emp\u00each\u00e9s par leur situation \u00e9conomique r\u00e9elle (pour lesquels il sera sans doute recherch\u00e9 une formule ad\u00e9quate).<\/p>\n<\/p>\n<p><p>\tAinsi, monsieur Philippe Bray nous \u00e9crit-il ceci:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>300 par an, c&rsquo;est moins que ce que la plupart de ceux qui trouvent l&rsquo;abonnement trop cher paient pour leur  pr\u00e9cieux GSM. Quant \u00e0 ceux \u00e0 qui il manque 120 pour faire les 150 d&rsquo;un demi-abonnement, c&rsquo;est juste ce qu&rsquo;ils paient, en France, pour le droit de poss\u00e9der chez eux un poste de TV &#8211; l\u00e0 encore, question de  choix.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le syst\u00e8me nous rackette et nous conditionne au point que l&rsquo;on trouve cela normal, et on r\u00e9tice \u00e0 contribuer au plus estimable, sinon au seul, site anti-syst\u00e8me francophone?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On est partag\u00e9 entre l&rsquo;indignation et la tristesse compatissante qu&rsquo;inspire un tel formatage des coeurs et des esprits, comme on disait du temps de l&rsquo;Empire.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Restez ferme sur les prix.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Lisant cela, pour un peu nous avons failli nous pr\u00e9cipiter pour prendre notre abonnement.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>dedefensa.org, trente jours apr\u00e8s 10 octobre 2009 Effectivement, cela fait trente jours, ou un mois, qu&rsquo;a commenc\u00e9 notre phase du domaine payant \u00e0 c\u00f4t\u00e9 de l&rsquo;acc\u00e8s libre classique du site depuis son origine. C&rsquo;est une date importante, ces trente jours, parce que commence aujourd&rsquo;hui la question, centrale pour nous, du renouvellement des abonnements d&rsquo;un mois,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[8639,8773,8772,2981,8775,3997,8774],"class_list":["post-71155","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-abonnements","tag-ad","tag-bray","tag-dedefensa-org","tag-eternam","tag-philippe","tag-vitam"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71155"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71155\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}