{"id":71165,"date":"2009-10-13T10:22:25","date_gmt":"2009-10-13T10:22:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/13\/wall-street-soutien-officiel-de-la-politique-de-lideologie-et-de-linstinct\/"},"modified":"2009-10-13T10:22:25","modified_gmt":"2009-10-13T10:22:25","slug":"wall-street-soutien-officiel-de-la-politique-de-lideologie-et-de-linstinct","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/13\/wall-street-soutien-officiel-de-la-politique-de-lideologie-et-de-linstinct\/","title":{"rendered":"Wall Street soutien officiel de \u201cla politique de l&rsquo;id\u00e9ologie et de l&rsquo;instinct\u201d"},"content":{"rendered":"<p><p>Il n&rsquo;est sans doute pas de plus convaincante indication de la d\u00e9cadence du syst\u00e8me de l&rsquo;am\u00e9ricanisme que cette <a href=\"http:\/\/treasury.gov\/press\/releases\/tg317.htm\" class=\"gen\">intervention<\/a> d&rsquo;un haut fonctionnaire du d\u00e9partement US du tr\u00e9sor devant l&rsquo;American Bankers Association, pr\u00e9sent\u00e9e par Jason Ditz le <a href=\"http:\/\/news.antiwar.com\/2009\/10\/12\/treasury-department-at-the-center-of-us-invention-abroad\/\" class=\"gen\">13 octobre 2009<\/a>, sur <em>Antiwar.com<\/em>. En un mot, il s&rsquo;agit de l&rsquo;observation que Wall Street soutient la politique interventionniste et belliciste des USA, la fameuse <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct ch\u00e8re \u00e0 nos curs, et, surtout, <strong>essentiellement<\/strong>, que Wall Street le dise publiquement (par l&rsquo;interm\u00e9diaire d&rsquo;un fonctionnaire du tr\u00e9sor, mais c&rsquo;est la m\u00eame chose).<\/p>\n<\/p>\n<p><p>\tCertes, vont s&rsquo;exclamer aussit\u00f4t les connaisseurs qui en connaissent un rayon, quelle na\u00efvet\u00e9 de croire que Wall Street serait neutre dans cette affaire! Le complot am\u00e9ricaniste \u00e9tant universel, multiple et tentaculaire, Wall Street en fait partie  quoi d&rsquo;\u00e9tonnant \u00e0 cela? Certes (<em>bis<\/em>), nous le savons bien, mais nous savons aussi qu&rsquo;il y a des normes et des conventions \u00e0 respecter dans ce syst\u00e8me de l&rsquo;am\u00e9ricanisme, et que l&rsquo;une d&rsquo;elles est que Wall Street s&rsquo;occupe <strong>officiellement<\/strong> du <em>racket<\/em> des USA et du <em>Rest Of the World<\/em>, et qu&rsquo;il doit s&rsquo;abstenir d&rsquo;afficher officiellement et <strong>publiquement<\/strong> son soutien actif et r\u00e9f\u00e9renc\u00e9 \u00e0 sa propre participation \u00e0 ce qui rel\u00e8ve du domaine de la s\u00e9curit\u00e9 nationale (DoD, CIA, forces arm\u00e9es, organisations subversives US diverses, etc.). Le proclamer est une grave faute formelle dans un syst\u00e8me qui est b\u00e2ti sur l&rsquo;apparence formelle du virtualisme pour permettre \u00e0 sa division communication de faire voter le bon peuple dans le sens qu&rsquo;il faut.<\/p>\n<\/p>\n<p><p>\tQuelques mots de Jason Ditz:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Speaking at a conference for the American Bankers Association, Assistant Secretary of the Treasury David S. Cohen went into excruciating detail about his department&rsquo;s role in ensuring that the American banking industry is on the front lines of fights the world over.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And it really is the world over. From propping up Mexico&rsquo;s government in what he called a courageous fight against the drug cartels to preventing Iran from developing nuclear weapons, there appears to be no overseas endeavor in which Secretary Cohen doesn&rsquo;t envision a massive role for the Treasury Department, and for the ostensibly private organizations that make up the banking industry.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Il faut bien avoir \u00e0 l&rsquo;esprit que le syst\u00e8me de l&rsquo;am\u00e9ricanisme repose sur un fondement communicationnel marqu\u00e9 par les formes, l&rsquo;apparence, le conformisme complet, et, depuis quelques ann\u00e9es, <em>at full speed<\/em> depuis 9\/11, par une construction virtualiste compl\u00e8te. Cette architecture compl\u00e8tement artifactuelle et faussaire devrait pr\u00e9senter une coh\u00e9rence, une coh\u00e9sion, une logique interne et le vernis de la morale am\u00e9ricaniste qui fait l&rsquo;argument essentiel de l&rsquo;influence US sur le monde. Lorsque ces r\u00e8gles d&rsquo;apparence ne sont plus respect\u00e9es, c&rsquo;est bien que le syst\u00e8me est compl\u00e8tement d\u00e9traqu\u00e9.<\/p>\n<\/p>\n<p><p>\tDe tous les temps, Wall Street (le d\u00e9partement du tr\u00e9sor) a \u00e9t\u00e9 int\u00e9ress\u00e9 \u00e0 la politique ext\u00e9rieure US, et le secr\u00e9taire au tr\u00e9sor fait partie des r\u00e9unions de s\u00e9curit\u00e9 nationale  autour du NSC et du pr\u00e9sident  qui conseillent le pr\u00e9sident; mais ces r\u00e9unions sont discr\u00e8tes par nature. De tous les temps, les banquiers, avocats d&rsquo;affaire et hommes de Wall Street ont jou\u00e9 un r\u00f4le essentiel dans la politique de s\u00e9curit\u00e9 nationale, devenue politique h\u00e9g\u00e9monique et belliciste de fa\u00e7on couverte dans ses intentions depuis 1945-48 (soi-disant d\u00e9fense du Monde Libre face au communisme) et de fa\u00e7on compl\u00e8tement ouverte depuis 1991-1996 (<a href=\"http:\/\/www.dedefensa.org\/article-d_atlanta-1996_a_new_orleans-2005_02_09_2005.html\" class=\"gen\">1996<\/a>, parce que fin de la p\u00e9riode d\u00e9pressionnaire des USA entre 1989 et 1996). Mais leur r\u00f4le ne devenait ouvert et affich\u00e9 que lorsqu&rsquo;ils entraient, comme ils firent en grand nombre, dans l&rsquo;administration \u00e0 des postes de responsabilit\u00e9 de la politique de s\u00e9curit\u00e9 nationale. (Les exemples abondent: James Forrestal, banquier de Wall Street, secr\u00e9taire \u00e0 la Navy durant la guerre puis premier secr\u00e9taire \u00e0 la d\u00e9fense des USA en 1947; les fr\u00e8res Dulles, tous deux avocats d&rsquo;affaires \u00e0 Wall Street, l&rsquo;un [Foster] devenu le secr\u00e9taire d&rsquo;Etat fameux d&rsquo;Eisenhower, l&rsquo;autre [Allen] prenant la CIA en mains durant la m\u00eame p\u00e9riode). Dans tout cela, Wall Street conservait sa vertu d&rsquo;apparence de ne pas s&rsquo;impliquer directement et <strong>publiquement<\/strong> dans le soutien de cette politique expansionniste et belliciste.<\/p>\n<\/p>\n<p><p>\tL&rsquo;intervention du haut fonctionnaire Cohen est effectivement le signe d&rsquo;une rupture de cette posture de communication dans l&rsquo;ensemble virtualiste du syst\u00e8me. Elle rompt l&rsquo;arrangement d&rsquo;apparence du syst\u00e8me. Elle marque donc la rupture d\u00e9cadente du syst\u00e8me, puisque tout syst\u00e8me faussaire de cette sorte doit tenir bon jusqu&rsquo;au bout sur l&rsquo;apparence des fonctions et des pr\u00e9rogatives sous peine de laisser d\u00e9couvrir d&rsquo;une fa\u00e7on insupportable sa vraie nature.<\/p>\n<\/p>\n<p><p>\tApr\u00e8s l&rsquo;\u00e9poustouflant \u00e9pisode de Wall Street s&rsquo;effondrant et manquant d&#8217;emmener le monde dans sa chute, puis remis \u00e0 flot par l&rsquo;intervention d\u00e9lirante d&rsquo;obsc\u00e9nit\u00e9 de l&rsquo;administration Obama, cette sorte de prise de position montre que les dirigeants financiers US ont compl\u00e8tement perdu le sens des priorit\u00e9s de leur propre syst\u00e8me, et donc le sens de leur propre r\u00e9alit\u00e9. Confits dans l&rsquo;arrogance et l&rsquo;aveuglement, ils ne comprennent m\u00eame plus comment fonctionne le syst\u00e8me qui les sauve r\u00e9guli\u00e8rement de la banqueroute pour leur permettre de poursuivre leurs activit\u00e9s de brigandage international. La stupidit\u00e9 profonde du personnel actuel du syst\u00e8me, par contraste avec l&rsquo;intelligence de ceux qui le servaient \u00e0 son \u00e2ge d&rsquo;or et qui savaient se tenir, lorsqu&rsquo;il existait une aristocratie de l&rsquo;am\u00e9ricanisme (ce qui ne r\u00e9duit pas la responsabilit\u00e9 du syst\u00e8me mais indiquait qu&rsquo;il marchait bien), cette stupidit\u00e9 arrogante est une bonne mesure de la d\u00e9cadence psychologique qui accompagne l&rsquo;effondrement de la chose. Les hommes du syst\u00e8me sont pass\u00e9s du stade d&rsquo;un personnel de haute valeur conscient de ses responsabilit\u00e9s vis-\u00e0-vis du syst\u00e8me en une bande d&rsquo;arsouilles nouveaux riches, sans la moindre conscience de ce que c&rsquo;est que la responsabilit\u00e9. Il n&rsquo;y a rien, absolument rien \u00e0 sortir de ce fatras chaotique que constitue aujourd&rsquo;hui le syst\u00e8me de l&rsquo;am\u00e9ricanisme, o\u00f9 plus personne ne respecte aucune r\u00e8gle, aucune forme, o\u00f9 l&rsquo;arrogance stupide se d\u00e9cha\u00eene. La d\u00e9cadence poursuit ferme sa chute en m\u00eame temps que Wall Street suscitera, avec cette sorte d&rsquo;intervention, une haine encore plus grande dans le bon peuple \u00e0 qui il arrive de se mettre en col\u00e8re (<a href=\"http:\/\/www.dedefensa.org\/article-la_guerre_d_independance_de_tea_party_a_commence_13_10_2009.html\" class=\"gen\">voir<\/a> <em>Tea Party<\/em>).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 ctobre 2009 \u00e0 10H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il n&rsquo;est sans doute pas de plus convaincante indication de la d\u00e9cadence du syst\u00e8me de l&rsquo;am\u00e9ricanisme que cette intervention d&rsquo;un haut fonctionnaire du d\u00e9partement US du tr\u00e9sor devant l&rsquo;American Bankers Association, pr\u00e9sent\u00e9e par Jason Ditz le 13 octobre 2009, sur Antiwar.com. En un mot, il s&rsquo;agit de l&rsquo;observation que Wall Street soutient la politique interventionniste&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8528,3089,4204,2631,5185,3888,2651,4390,8360,8361,2937,4607,4205,3372,7054,610,3132],"class_list":["post-71165","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-banquiers","tag-cohen","tag-david","tag-de","tag-decadence","tag-departement","tag-du","tag-et","tag-lideologie","tag-linstinct","tag-nationale","tag-politique","tag-securite","tag-street","tag-tresor","tag-virtualisme","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71165"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71165\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}