{"id":71175,"date":"2009-10-16T12:08:09","date_gmt":"2009-10-16T12:08:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/16\/anti-missiles-et-folies-ukrainiennes\/"},"modified":"2009-10-16T12:08:09","modified_gmt":"2009-10-16T12:08:09","slug":"anti-missiles-et-folies-ukrainiennes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/16\/anti-missiles-et-folies-ukrainiennes\/","title":{"rendered":"Anti-missiles et folies ukrainiennes"},"content":{"rendered":"<p><p>La revue  comme l&rsquo;on parle d&rsquo;une revue de <em>music-hall<\/em> ou de la revue des Folies-Berg\u00e8res  continue dans l&rsquo;affaire des anti-missiles et de l&rsquo;Ukraine, avec la question d&rsquo;un radar qui pourrait servir au futur r\u00e9seau anti-missiles rempla\u00e7ant le d\u00e9funt BMDE. Il y a eu les  <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_revenez-y_du_vrai-faux_bmde_12_10_2009.html\" class=\"gen\">d\u00e9clarations<\/a> d&rsquo;Alexander Vershbow, du Pentagone, suivies de <a href=\"http:\/\/www.dedefensa.org\/article-euphorie_russie-usa_a_moscou_et_vershbow_bmde_en_ukraine_aux_oubliettes_14_10_2009.html\" class=\"gen\">la visite euphorique<\/a> d&rsquo;Hillary Clinton \u00e0 Moscou, avec des d\u00e9clarations allant dans le sens contraire, ou bien diff\u00e9rent, de celles de Vershbow. Maintenant, il y a de nouvelles d\u00e9clarations qui pourraient sembler contredire en partie (ou bien aller dans un sens diff\u00e9rent) celles de la visite de Clinton, qui semblaient contredire celles de Vershbow. Donc, suivez-nous si vous le pouvez: on affirme, puis on para\u00eet d\u00e9mentir sans le dire express\u00e9ment, puis on para\u00eet r\u00e9affirmer sans le dire express\u00e9ment.<\/p>\n<\/p>\n<p><p>\tTout cela se passe autour de Washington, de la Maison-Blanche, du d\u00e9partement d&rsquo;Etat et du Pentagone; accessoirement avec l&rsquo;Ukraine en vedette am\u00e9ricaine, puisque le ministre ukrainien des affaires \u00e9trang\u00e8res affirmait le 9 octobre : \u00ab<em>Le d\u00e9ploiement de l&rsquo;ABM sur le territoire ukrainien serait \u00e0 mon avis ill\u00e9gitime, voire anticonstitutionnel<\/em>\u00bb, et que son ambassadeur \u00e0 Washington affirmait ce qui suit, hier, qui est repris par Novosti le <a href=\"http:\/\/fr.rian.ru\/world\/20091015\/123515391.html\" class=\"gen\">15 octobre 2009<\/a><\/p>\n<\/p>\n<p><p>\t\u00ab<em>L&rsquo;\u00e9ventuelle utilisation des radars ukrainiens dans l&rsquo;int\u00e9r\u00eat du bouclier antimissile US est en cours d&rsquo;\u00e9tude, a annonc\u00e9 jeudi lors d&rsquo;un point de presse \u00e0 Kiev l&rsquo;ambassadeur ukrainien aux Etats-Unis, Oleg Chamchour.<\/em> [] <em>Cette question<\/em> [de l&rsquo;utilisation des radars ukrainiens] <em>est au stade du d\u00e9bat pr\u00e9alable, a indiqu\u00e9 le diplomate cit\u00e9 par l&rsquo;agence ukrainienne UNIAN. De l&rsquo;avis de l&rsquo;ambassadeur, la possibilit\u00e9 de l&rsquo;engagement de l&rsquo;Ukraine dans ces processus est parfaitement naturelle et constructive, \u00e9tant donn\u00e9 le rapprochement constat\u00e9 entre les Etats-Unis et la Russie sur la question du bouclier antimissile.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes Russes ont aussit\u00f4t r\u00e9agi, \u00e0 la vitesse de l&rsquo;\u00e9clair, comme l&rsquo;indique Novosti toujours, le <a href=\"http:\/\/fr.rian.ru\/world\/20091015\/123518291.html\" class=\"gen\">15 octobre 2009<\/a> \u00e9galement. La revue des Folies-Berg\u00e8res est \u00e9galement une partie de tennis, service-vol\u00e9e, o\u00f9 les Russes ne sont pas les derniers \u00e0 r\u00e9agir avec vivacit\u00e9<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La Russie est pr\u00e9occup\u00e9e par les contacts des Etats-Unis avec des pays non membres de l&rsquo;OTAN dans le cadre de la r\u00e9vision de leurs projets de d\u00e9ploiement d&rsquo;\u00e9l\u00e9ments du bouclier antimissile (ABM) en Europe, a d\u00e9clar\u00e9 jeudi le vice-ministre russe des Affaires \u00e9trang\u00e8res Sergue\u00ef Riabkov. Nous n&rsquo;ignorons pas que, dans le cadre du renoncement auxdits projets, l&rsquo;administration am\u00e9ricaine entretient des contacts avec ses partenaires encore qu&rsquo;il ne s&rsquo;agisse pas uniquement des pays de l&rsquo;OTAN, a indiqu\u00e9 M.Riabkov, en commentant la d\u00e9claration de Kiev sur ses n\u00e9gociations avec Washington concernant une \u00e9ventuelle utilisation de radars ukrainiens dans le cadre du programme ABM am\u00e9ricain. Nous suivons de pr\u00e8s cette situation<\/em> [&#8230;] <em>qui nous pr\u00e9occupe, a not\u00e9 le diplomate.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Dans cet \u00e9trange tourbillon de d\u00e9clarations fort peu coordonn\u00e9es et tr\u00e8s souvent contradictoires dans l&rsquo;esprit et dans l&rsquo;interpr\u00e9tation qu&rsquo;on en fait, il faut d&rsquo;abord se garder d&rsquo;\u00e9carter l&rsquo;explication la plus simple. D&rsquo;une part et effectivement, l&rsquo;utilisation des installations radar ukrainiennes (ex-sovi\u00e9tiques) peuvent tr\u00e8s bien s&rsquo;ins\u00e9rer dans le cadre d&rsquo;un r\u00e9seau russo-am\u00e9ricain, autant contr\u00f4l\u00e9 par les Russes que par les Am\u00e9ricains, tel qu&rsquo;Hillary Clinton en a pr\u00f4n\u00e9 les vertus lors de sa visite de mardi-mercredi \u00e0 Moscou, avec le soutien enthousiaste des Russes; d&rsquo;autre part, on peut envisager que les Russes sur-r\u00e9agissent aux nouvelles venues soit de l&rsquo;Ukraine soit du Pentagone, \u00e0 la fois par tactique et par une sorte de crainte obsessionnelle, dont on comprend les fondements, d&rsquo;\u00eatre flou\u00e9s par les Am\u00e9ricains et par leurs voisins imm\u00e9diats.<\/p>\n<\/p>\n<p><p>\tCela \u00e9tant dit, il reste que toute affaire, m\u00eame politique et strat\u00e9gique, est, aujourd&rsquo;hui, une affaire de communication. En l&rsquo;occurrence, cette question des anti-missiles avec l&rsquo;incursion d&rsquo;un domaine ukrainien inattendu n&rsquo;est pas un mod\u00e8le du genre, question communication. Le Pentagone, lui aussi, joue au niveau tactique et au niveau obsessionnel, un peu comme les Russes, en m\u00eame temps qu&rsquo;au niveau technique. Le Pentagone estime que les radars ukrainiens sont \u00e9ventuellement n\u00e9cessaires \u00e0 un r\u00e9seau anti-missiles nouvelle formule (aspect technique); il y croit d&rsquo;autant plus que sa bureaucratie est, par substance pourrait-on dire, convaincue qu&rsquo;il faut r\u00e9unir le maximum de moyens pour opposer au r\u00e9seau infranchissable \u00e0 la terrifiante menace iranienne (aspect obsessionnel); il insiste d&rsquo;autant plus sur l&rsquo;affaire ukrainienne que cela lui permet, estime-t-il, de se placer un peu plus dans ce pays, pour affirmer sa position contre la Russie qui reste sur la liste des ennemis potentiels type-Guerre froide (aspect tactique, avec un zeste cons\u00e9quent d&rsquo;obsessionnel). On pourrait ajouter l&rsquo;hypoth\u00e8que ukrainienne o\u00f9 l&rsquo;on sait que r\u00e8gne un pouvoir au moins bic\u00e9phale (un pr\u00e9sident nettement anti-russe et unr premi\u00e8re ministre inclin\u00e9e \u00e0 un arrangement avec la Russie) et qu&rsquo;on ignore qui d\u00e9pend pr\u00e9cis\u00e9ment de qui (allusion aux ministre des affaires \u00e9trang\u00e8res et \u00e0 l&rsquo;ambassadeur de l&rsquo;Ukraine \u00e0 Washington).<\/p>\n<\/p>\n<p><p>\tLe probl\u00e8me reste pour l&rsquo;instant, pour l&rsquo;essentiel, du c\u00f4t\u00e9 US. La difficult\u00e9 de cette affaire des anti-missiles est qu&rsquo;elle m\u00e9lange l&rsquo;aspect politique et l&rsquo;aspect technique. L&rsquo;aspect politique affiche clairement, de ce c\u00f4t\u00e9 US, une volont\u00e9 d&rsquo;entente manifeste avec la Russie. C&rsquo;est peut-\u00eatre la seule <strong>certitude<\/strong> que l&rsquo;on puisse avancer, du c\u00f4t\u00e9 des USA o\u00f9 r\u00e9side l&rsquo;essentiel du probl\u00e8me. Mais il s&rsquo;agit d&rsquo;une volont\u00e9 de la direction politique (Obama et Clinton en l&rsquo;occurrence), qui n&rsquo;implique pas n\u00e9cessairement, du moins avec la rigueur qu&rsquo;il faudrait, les autres centres de pouvoir. L&rsquo;aspect technique permet au Pentagone de glisser r\u00e9guli\u00e8rement des obstacles divers qui ravivent la m\u00e9fiance russe et rendent plus difficile l&rsquo;\u00e9volution politique. On dirait, sans grande originalit\u00e9, que ce serait \u00e0 la direction de l&rsquo;administration Obama de faire le m\u00e9nage chez elle, et l&rsquo;on ajouterait, sans plus d&rsquo;originalit\u00e9, que ce n&rsquo;est pas demain la veille qu&rsquo;elle y parviendra. Plus que jamais, un mot caract\u00e9rise la situation washingtonienne, et nous dirons, avec politesse, que c&rsquo;est le mot d\u00e9sordre.<\/p>\n<\/p>\n<p><p>\tSurtout, l&rsquo;on doit observer combien l&rsquo;information se confirme \u00eatre d&rsquo;abord une question absolument et compl\u00e8tement relative, n\u00e9cessitant une enqu\u00eate permanente pour distinguer la r\u00e9alit\u00e9. (Voir notre <em>Note d&rsquo;analyse<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_l_enquete_pour_retrouver_la_realite_09_10_2009.html\" class=\"gen\">9 octobre 2009<\/a>.) Nous devons faire intervenir des facteurs ext\u00e9rieurs aux seules d\u00e9clarations, analyses, etc., des centres de pouvoir impliqu\u00e9s, auxquels il est <em>a priori<\/em> n\u00e9cessaire de n&rsquo;accorder <strong>aucune<\/strong> confiance. Nous devons juger des informations qu&rsquo;on nous dispense en faisant appel \u00e0 l&rsquo;exp\u00e9rience, au bon sens et \u00e0 l&rsquo;intuition, et en restant d\u00e9sormais convaincu que plus aucune r\u00e9f\u00e9rence ferme n&rsquo;existe en cette mati\u00e8re.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 octobre 2009 \u00e0 12H10<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La revue comme l&rsquo;on parle d&rsquo;une revue de music-hall ou de la revue des Folies-Berg\u00e8res continue dans l&rsquo;affaire des anti-missiles et de l&rsquo;Ukraine, avec la question d&rsquo;un radar qui pourrait servir au futur r\u00e9seau anti-missiles rempla\u00e7ant le d\u00e9funt BMDE. Il y a eu les d\u00e9clarations d&rsquo;Alexander Vershbow, du Pentagone, suivies de la visite euphorique d&rsquo;Hillary&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4940,2933,4314,3194,6332,2730,1296,8804],"class_list":["post-71175","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ambassadeur","tag-bases","tag-bmde","tag-pentagone","tag-radar","tag-russie","tag-ukraine","tag-ukrainien"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71175"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71175\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}