{"id":71185,"date":"2009-10-20T05:47:14","date_gmt":"2009-10-20T05:47:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/20\/en-attendant-le-f-35-godot\/"},"modified":"2009-10-20T05:47:14","modified_gmt":"2009-10-20T05:47:14","slug":"en-attendant-le-f-35-godot","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/20\/en-attendant-le-f-35-godot\/","title":{"rendered":"En attendant le F-35 <em>Godot<\/em>\u2026"},"content":{"rendered":"<p><p>Lorsqu&rsquo;on l&rsquo;interrogeait sur l&rsquo;identit\u00e9 de Godot, qu&rsquo;on attend tout au long de sa pi\u00e8ce <em>En attendant Godot<\/em>, et qui n&rsquo;arrive jamais, et qu&rsquo;on ne conna\u00eetra jamais jusqu&rsquo;\u00e0 ignorer s&rsquo;il existe d&rsquo;ailleurs  donc, \u00e0 la question mais qui est donc Godot? Samuel Beckett se r\u00e9criait: \u00ab<em>Je n&rsquo;en sais rien! Si je le savais je l&rsquo;aurais dit!<\/em>\u00bb. Ainsi introduirions-nous notre suggestion de d\u00e9baptiser le JSF\/F-35, de son nom assez conventionnel type-jeu vid\u00e9o de <em>Lightning<\/em> II, en <em>Godot<\/em> Le JSF\/F-35 <em>Godot<\/em>, non?<\/p>\n<\/p>\n<p><p>\tCertes  cela, pour taquiner un peu. Il faut dire qu&rsquo;il nous fait languir, le bougre. Bill Sweetman, qui semble prendre un malin plaisir \u00e0 suivre les d\u00e9clarations officielles sur l&rsquo;arriv\u00e9e des avions op\u00e9rationnels transform\u00e9s en protos ou l&rsquo;inverse, et la r\u00e9alit\u00e9 de ces arriv\u00e9es, et de secouer le tout pour mesurer l&rsquo;\u00e9trange chaos qui en sort  Sweetman, donc, r\u00e9cidive. Ainsi d\u00e9crit-il le processus \u00e9trange qui continue \u00e0 affecter le programme de Lockheed Martin qui ne cesse d&rsquo;annoncer, entre autres, les d\u00e9buts des essais en mode ADAC\/V (atterrissage et d\u00e9collage vertical) de l&rsquo;avion dit F-35 BF-1 apr\u00e8s son arriv\u00e9e au centre d&rsquo;essais en vol de Patuxent River. L&rsquo;ann\u00e9e derni\u00e8re, ces essais devaient commencer, apr\u00e8s d\u00e9j\u00e0 un consid\u00e9rable retard au d\u00e9but de 2009. En janvier 2009, l&rsquo;arriv\u00e9e \u00e0 Patuxent River fut annonc\u00e9e pour juin 2009, avec la pr\u00e9cision que le prototype BF-2 serait \u00e9galement de la partie; en f\u00e9vrier 2009, on annon\u00e7a que cette arriv\u00e9e \u00e9tait plut\u00f4t pr\u00e9vue pour la deuxi\u00e8me partie de l&rsquo;ann\u00e9e; au d\u00e9but septembre, on pr\u00e9cisa que cette arriv\u00e9e \u00e9tait annonc\u00e9e pour le d\u00e9but octobre, suivie d&rsquo;une annonce plus pr\u00e9cise que ce serait dans les quatre \u00e0 six semaines Sweetman constate que ce dernier d\u00e9lai, le cinqui\u00e8me successif retard annonc\u00e9 en huit mois est atteint et d\u00e9pass\u00e9 et qu&rsquo;on ne voit toujours par venir Godot \u00e0 Patuxent River.<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;il d\u00e9crit de la sorte sur son <em>blog<\/em> du <a href=\"http:\/\/www.aviationweek.com\/aw\/blogs\/defense\/index.jsp?plckController=Blog&#038;plckBlogPage=BlogViewPostUserId=27ec4a53-dcc8-42d0-bd3a-01329aef79a7&#038;plckPostId=Blog%3a27ec4a53-dcc8-42d0-bd3a-01329aef79a7Post%3a1826bdf5-46b1-4af4-9140-47479ac7d632&#038;plckScript=blogScript&#038;plckElementId=blogDest\" class=\"gen\">16 octobre 2009<\/a>, sur <em>AviationWeek.com<\/em>: \u00ab<em>and it is October 16, which means it&rsquo;s no longer early October&#8230; Which is when F-35 BF-1 was supposed to have arrived at Pax River to start its STOVL tests, which little more than a year ago were supposed to have started much earlier this year, were reset to June in January and to \u00ab\u00a0fall\u00a0\u00bb in February. The early October prediction is only five weeks old. Next week, the four to six weeks by which both BF-1 and BF-2 were expected at Pax is set to expire.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSweetman s&rsquo;explique de cette comptabilit\u00e9 que certains jugeraient tatillonne par le fait que le programme d&rsquo;essais en vol du JSF, qui a accumul\u00e9 un <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_une_merveille_a_10percent_30_09_2009.html\" class=\"gen\">retard ph\u00e9nom\u00e9nal<\/a> dans sa campagne dans l&rsquo;ann\u00e9e fiscale FY2009 se terminant le 1er octobre, est plac\u00e9 devant un calendrier intensif pour l&rsquo;ann\u00e9e fiscale FY2010 qui a commenc\u00e9 ce m\u00eame 1er octobre, pour essayer de rattraper un peu du retard de FY2009. Lockheed Martin a donn\u00e9 toutes les assurances que les r\u00e9cents consid\u00e9rables retards sont d\u00e9j\u00e0 du pass\u00e9, que de nouvelle m\u00e9thodes de gestion du programme vont montrer que, d\u00e8s le 1er octobre, tout a chang\u00e9. Et Sweetman  constate que ce 16 octobre, rien n&rsquo;a chang\u00e9, et l&rsquo;on attend toujours le d\u00e9marrage s\u00e9rieux du programme d&rsquo;essais du F-35 <em>Godot<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>This is not trivial, because at the same time the JSF program office set itself a tough to-do list for the end of CY 2009, including the first vertical landing and the flight of five more prototypes. And that is the first quarter of a fiscal year that &#8211; by the end of September 2010 &#8211; is supposed to see 12 development jets in the air flying 12 sorties a month each.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t Depuis les r\u00e9centes manifestations de Robert Gates, <a href=\"http:\/\/www.dedefensa.org\/article-gates_et_jet_fort-worth_aller-retour_03_09_2009.html\" class=\"gen\">soutenant<\/a> spectaculairement le programme mais <a href=\"http:\/\/www.dedefensa.org\/article-gates_et_le_jsf_prudence_de_sioux_et_quelques_avertissements_a_lm__17_09_2009.html\" class=\"gen\">avertissant<\/a> aussit\u00f4t que ce programme devait devenir s\u00e9rieux et se lancer dans sa campagne intensive d&rsquo;essais en vol, il n&rsquo;y a plus eu de nouvelles spectaculaires concernant le JSF, qui a disparu des communiqu\u00e9s officiels \u00e0 sensation. Sweetman, qui a d\u00e9cid\u00e9 de ne plus s&rsquo;en laisser compter, suit ses progr\u00e8s au jour le jour, et n&rsquo;en constate aucun. Il termine son billet par une \u00e9vocation sur le r\u00f4le de la d\u00e9sinformation au travers d&rsquo;une r\u00e9f\u00e9rence \u00e0 un livre sur la vie de Staline montrant comment Staline avait repouss\u00e9 une information vraie (celle d&rsquo;un officier de la Luftwaffe travaillant pour l&rsquo;URSS) sur l&rsquo;annonce de l&rsquo;attaque de l&rsquo;URSS par l&rsquo;Allemagne le 22 juin 1941 sous pr\u00e9texte de d\u00e9sinformation. Cela, \u00e9videmment, \u00e9voque le climat de d\u00e9sinformation g\u00e9n\u00e9ral qui caract\u00e9rise le programme JSF <em>Godot<\/em>, et une d\u00e9sinformation qui ressemble presque \u00e0 de la panique parce qu&rsquo;elle se caract\u00e9rise par une succession presque hebdomadaire d\u00e9sormais de fausses nouvelles concernant le d\u00e9but des essais en vol ADAC\/V du prototype BF-1, qui n&rsquo;est d&rsquo;ailleurs qu&rsquo;une illustration de la situation g\u00e9n\u00e9rale de la communication au sein de ce programme. L&rsquo;impression qu&rsquo;on en retire n&rsquo;est pas vraiment favorable&#8230; Le catastrophique retard de FY2009 semble en voie de se prolonger pour FY2010, confirmant que Lockheed Martin est incapable de reprendre le contr\u00f4le de cet \u00e9norme programme.<\/p>\n<\/p>\n<p><p>\tBien s\u00fbr, il est question de d\u00e9sinformation. Mais elle n&rsquo;est qu&rsquo;improvis\u00e9e, faite au jour le jour (ou, disons, semaine apr\u00e8s semaine). Elle se d\u00e9veloppe \u00e0 mesure que les promesses des services techniques qui r\u00e9pondent \u00e0 ce climat g\u00e9n\u00e9ral de communication qu&rsquo;on a d\u00e9j\u00e0 d\u00e9crit, qui est simplement qu&rsquo;aucun service n&rsquo;\u00e9chappe \u00e0 la n\u00e9cessit\u00e9, pour son domaine, d&rsquo;annoncer des pr\u00e9visions optimistes qu&rsquo;aucun service n&rsquo;est capable de tenir, ces diverses d\u00e9sinformations correspondant aux exigences internes de bonnes nouvelles aboutissent \u00e0 un flot permanent d&rsquo;informations fausses qui se traduit par ces annonces officielles qui sont aussit\u00f4t d\u00e9menties par les faits. Ce n&rsquo;est plus de la d\u00e9sinformation, c&rsquo;est une m\u00e9canique d&rsquo;une communication compl\u00e8tement prisonni\u00e8res de sources qui se couvrent les uns et les autres en annon\u00e7ant des pr\u00e9visions fausses, dont la responsabilit\u00e9 est renvoy\u00e9e d&rsquo;un service \u00e0 l&rsquo;autre, et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tLe programme JSF <em>Godot<\/em> continue sa descente aux enfers, avec le retard de ses essais en vol, pour des raisons \u00e0 la fois \u00e9videntes (les avions ne sont pas pr\u00eats pour leurs essais \u00e0 leur sortie d&rsquo;usine malgr\u00e9 les annonces officielles) et plus myst\u00e9rieuses (des difficult\u00e9s inattendues surgissent et s&rsquo;accumulent dans la pr\u00e9paration aux essais qui est en cours). Nous approchons de plus en plus des points de confrontation car le retard accumul\u00e9 des essais va se traduire bient\u00f4t, officiellement, en un retard g\u00e9n\u00e9ral du programme, des livraisons, des mises en service, etc.,  dans un programme d\u00e9j\u00e0 consid\u00e9rablement en retard. L&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_ombre_de_plus_en_plus_sombre_de_jet_sur_le_jsf_17_08_2009.html\" class=\"gen\">enqu\u00eate<\/a> de l&rsquo;\u00e9quipe JET, dont on attend le rapport (fin octobre?  Courant novembre?), et \u00e0 propos de laquelle certains ont voulu nous <a href=\"http:\/\/www.dedefensa.org\/article-_effectivement_jet_confirmera_le_jsf_21_08_2009.html\" class=\"gen\">rassurer<\/a>, sera-t-elle le d\u00e9tonateur de l&rsquo;explosion? Ou bien le rapport habituel du GAO, au printemps? La QDR en cours pour mettre en place les orientations strat\u00e9giques des 4 prochaines ann\u00e9es de programmation du Pentagone, pr\u00e9vu pour le d\u00e9but 2010, commencera-t-elle \u00e0 prendre en compte la catastrophe qu&rsquo;est d\u00e9sormais le JSF? En d&rsquo;autres termes, quand donc cette redoutable cacophonie communicationnelle se transformera-t-elle en une bombe politique qui, explosant, posera non seulement le probl\u00e8me du JSF <em>Godot<\/em> dans ses v\u00e9ritables termes, mais tout l&rsquo;avenir de la modernisation des forces a\u00e9riennes de combat des USA? (Sans compter les alli\u00e9s, dont les Britanniques, plong\u00e9s dans l&rsquo;angoisse d&rsquo;une programmation militaire menac\u00e9e d&rsquo;un cataclysme \u00e0 cause de la situation budg\u00e9taire du gouvernement.) <em>Godot<\/em> est une bombe \u00e0 retardement comme jamais le Pentagone n&rsquo;en a connue de pr\u00e9c\u00e9dente, d&rsquo;une telle intensit\u00e9. Il nous reste \u00e0 attendre le v\u00e9ritable scandale politico-militaire du JSF-<em>Godot<\/em>, qui va ouvrir la phase de la crise existentielle du programme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 20 octobre 2009 \u00e0 05H49<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu&rsquo;on l&rsquo;interrogeait sur l&rsquo;identit\u00e9 de Godot, qu&rsquo;on attend tout au long de sa pi\u00e8ce En attendant Godot, et qui n&rsquo;arrive jamais, et qu&rsquo;on ne conna\u00eetra jamais jusqu&rsquo;\u00e0 ignorer s&rsquo;il existe d&rsquo;ailleurs donc, \u00e0 la question mais qui est donc Godot? Samuel Beckett se r\u00e9criait: \u00abJe n&rsquo;en sais rien! Si je le savais je l&rsquo;aurais dit!\u00bb.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3015,3662,2662,8721,2969,6517,250,8815,5340,6770,8816,6769,4584],"class_list":["post-71185","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-communication","tag-desinformation","tag-en","tag-essais","tag-f-35","tag-godot","tag-jsf","tag-patuxent","tag-programme","tag-retard","tag-river","tag-sweetman","tag-vol"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71185"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71185\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}