{"id":71221,"date":"2009-10-29T09:39:02","date_gmt":"2009-10-29T09:39:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/29\/internet-et-la-presse-officielle-le-cas-du-jsf\/"},"modified":"2009-10-29T09:39:02","modified_gmt":"2009-10-29T09:39:02","slug":"internet-et-la-presse-officielle-le-cas-du-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/10\/29\/internet-et-la-presse-officielle-le-cas-du-jsf\/","title":{"rendered":"Internet et la \u201cpresse officielle\u201d: le cas du JSF"},"content":{"rendered":"<p><h2 class=\"common-article\">Internet et la presse officielle: le cas du JSF<\/h2>\n<\/p>\n<p><p>\t29 octobre 2009  Nous revenons une fois de plus sur le r\u00f4le jou\u00e9 par Internet dans certaines grandes affaires qui sont presque <strong>compl\u00e8tement<\/strong> ignor\u00e9e de la grande presse-<em>Pravda<\/em>, (ou presse officielle\/presse-papier, selon la m\u00e9sestime ou l&rsquo;estime qu&rsquo;on veut lui montrer). C&rsquo;est sans aucun doute le cas du programme JSF, dont nos lecteurs connaissent tout l&rsquo;int\u00e9r\u00eat que nous lui portons. Nous avons d\u00e9j\u00e0 parl\u00e9 de l&rsquo;action d&rsquo;Internet sur le cas du JSF (voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-le_net_contre_le_jsf_06_03_2009.html\" class=\"gen\">6 mars 2009<\/a>). Mais, dans ce cas, il faut relever un progr\u00e8s fort int\u00e9ressante avec une connexion grandissante entre Internet et cette presse officielle, connexion au d\u00e9part <strong>impos\u00e9e<\/strong> par Internet.<\/p>\n<\/p>\n<p><p>\tQuelques-unes des derni\u00e8res p\u00e9rip\u00e9ties du programme JSF t\u00e9moignent de cette \u00e9volution. (On peut les suivre notamment sur ce site le <a href=\"http:\/\/www.dedefensa.org\/article-jsf_versus_jet_euh_il_va_falloir_prendre_des_decisions_24_10_2009.html\" class=\"gen\">24 octobre 2009<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-la_mise_en_pieces_des_previsions_de_vente_du_jsf_27_10_2009.html\" class=\"gen\">27 octobre 2009<\/a>, et encore le m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-la_realite_contre_le_jsf_ostinato_27_10_2009.html\" class=\"gen\">27 octobre 2009<\/a>).<\/p>\n<\/p>\n<p><p>\tLes deux plus r\u00e9cents cas que nous pr\u00e9sentons sont particuli\u00e8rement r\u00e9v\u00e9lateurs.<\/p>\n<\/p>\n<p><p>\t Dans le cas de l&rsquo;\u00e9tude de l&rsquo;expert hollandais Johan Boeder, on observe que sa notori\u00e9t\u00e9 dans le domaine du JSF est pour l&rsquo;essentiel due \u00e0 son <a href=\"http:\/\/www.jsfnieuws.nl\/\" class=\"gen\">site<\/a> <em>JSFNieuws<\/em> (en hollandais avec traduction <em>Google<\/em> en <a href=\"http:\/\/translate.google.com\/translate?u=http%3A%2F%2Fwww.jsfnieuws.nl&#038;hl=fr&#038;ie=UTF-8&#038;sl=nl&#038;tl=fr\" class=\"gen\">fran\u00e7ais<\/a> notamment). Ce site, on l&rsquo;a d\u00e9j\u00e0 signal\u00e9 \u00e0 plusieurs reprises, a jou\u00e9 et joue un r\u00f4le \u00e9minent dans le d\u00e9bat politique et parlementaire qu&rsquo;est devenue, en Hollande, la question de l&rsquo;achat du JSF. Cette m\u00eame notori\u00e9t\u00e9 a entra\u00een\u00e9 la commande du rapport pour la commission de d\u00e9fense dont nous avons parl\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article-la_mise_en_pieces_des_previsions_de_vente_du_jsf_27_10_2009.html\" class=\"gen\">27 octobre 2009<\/a>, puis la publicit\u00e9 de ce rapport par la voie d&rsquo;Internet \u00e0 partir du 6 octobre, enfin son apparition dans la grande presse sp\u00e9cialis\u00e9e (<em>Defense News<\/em>), conduisant Lockheed Martin lui-m\u00eame \u00e0 r\u00e9agir de mani\u00e8re officielle. En Hollande m\u00eame, lorsque le d\u00e9bat sur le JSF rebondit, d&rsquo;une fa\u00e7on assez r\u00e9guli\u00e8re, Boeder tient un r\u00f4le central de r\u00e9f\u00e9rence pour la presse g\u00e9n\u00e9raliste. (La Hollande est le pays engag\u00e9 dans le programme le plus agit\u00e9 par cette question du JSF et le plus ouvert \u00e0 la pol\u00e9mique, malgr\u00e9, ou peut-\u00eatre \u00e0 cause de l&rsquo;engagement aveuglement pro-JSF de la Force A\u00e9rienne.) Le parcours est impeccable, montrant la position de force que peut acqu\u00e9rir une initiative de type-Internet, jusqu&rsquo;\u00e0 des interf\u00e9rences majeures dans les circuits officiels. La presse officielle elle-m\u00eame suit \u00e9pisodiquement l&rsquo;affaire quand cette presse est bonne (Hollande), pas du tout, sinon par la reproduction des communiqu\u00e9s LM, quand cette presse est \u00e9gale \u00e0 elle-m\u00eame (c&rsquo;est-\u00e0-dire ex\u00e9crable de m\u00e9diocrit\u00e9, sinon de complicit\u00e9). <\/p>\n<\/p>\n<p><p>\t Le cas du rapport JET (2009) est aussi exemplaire d&rsquo;une autre forme de parcours. La nouvelle est sortie, le 22 octobre, d&rsquo;un site payant, de la Lettre d&rsquo;Information <em>Inside the Air Force<\/em> (la m\u00eame qui, le 26 novembre 2008, avait r\u00e9v\u00e9l\u00e9 l&rsquo;information du premier rapport de l&rsquo;\u00e9quipe JET). La simple annonce sur le site, en acc\u00e8s libre, nous disait l&rsquo;essentiel \u00e0 cet \u00e9gard:  \u00ab<strong><em> Exclusive: New JSF Assessment Affirms Program Requires Billions More, Additional Time<\/em><\/strong><em>  DefenseAlert, Oct. 22, 2009  A new assessment of the Joint Strike Fighter program affirms earlier findings that substantially more money and time are required for the Pentagon&rsquo;s largest acquisition effort, a conclusion that could pose a formidable test of Defense Secretary Robert Gates&rsquo; recent support for the F-35 program and President Obama&rsquo;s pledge to terminate weapons with bloated price tags.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAussit\u00f4t, comme nous l&rsquo;avons signal\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article-jsf_versus_jet_euh_il_va_falloir_prendre_des_decisions_24_10_2009.html\" class=\"gen\">24 octobre 2009<\/a>, la nouvelle a \u00e9t\u00e9 largement r\u00e9pandue sur les sites d\u00e9sormais connus comme relais des nouvelles concernant le JSF. D\u00e8s le <a href=\"http:\/\/www.reuters.com\/article\/idUSN2312297620091023\" class=\"gen\">23 octobre<\/a>, la nouvelle tombait dans le domaine public, avec une longue d\u00e9p\u00eache de Reuters qui \u00e9tait reprise par de nombreux m\u00e9dias (ABC.News, MSNBC, etc.) Cette situation \u00e9tait impensable seulement en novembre 2008, o\u00f9 la nouvelle avait \u00e9t\u00e9 peine r\u00e9percut\u00e9e, uniquement  sur Internet, puis reprise de loin en loin jusqu&rsquo;\u00e0 ce qu&rsquo;elle soit pr\u00e9sent\u00e9e comme une nouvelle in\u00e9dite le 23 juillet 2009 par le <em>Congressional Quaterly Politics<\/em> (voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-jet_versus_jsf_25_07_2009.html\" class=\"gen\">25 juillet 2009<\/a>), en plein d\u00e9bat pol\u00e9mique sur l&rsquo;abandon du F-22. Rien de tout cela n&rsquo;e\u00fbt \u00e9t\u00e9 possible s&rsquo;il n&rsquo;y avait pas eu un site <em>InsidetheDefense.com<\/em>, lorsqu&rsquo;il n&rsquo;y avait que des Lettres d&rsquo;Information papier de ce groupe, et si Internet n&rsquo;avait pas impos\u00e9 la pol\u00e9mique autour du programme JSF, notamment en suivant de fort pr\u00e8s le d\u00e9veloppement du programme, souvent \u00e0 partir de ses propres investigations et ses propres sources, \u00e9galement en relayant et en exploitant certaines publications \u00e0 la diffusion tr\u00e8s sp\u00e9cifique et tr\u00e8s prot\u00e9g\u00e9e, comme les Lettres de <em>InsidetheDefense.com<\/em>.<\/p>\n<h3>Plus que jamais l&rsquo;ennemi du syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tCe que nous voulons \u00e9voquer d&rsquo;une mani\u00e8re g\u00e9n\u00e9rale \u00e0 partir de ces exemples particuliers est l&rsquo;apparition structur\u00e9e et durable d&rsquo;un nouveau champ d&rsquo;influence d&rsquo;Internet, tr\u00e8s diff\u00e9rent d&rsquo;un autre aspect d\u00e9j\u00e0 largement d\u00e9montr\u00e9 qui est l&rsquo;influence populaire directe passant par Internet (cas du r\u00e9f\u00e9rendum de mai 2005 en France). Il est vrai qu&rsquo;il existe une formidable hostilit\u00e9 entre la chronique et le commentaire politique d&rsquo;Internet et, au nom de leurs propres vertus professionnelles que les autres n&rsquo;auraient pas, le journalisme de la presse-<em>Pravda<\/em>. Le second sent bien qu&rsquo;il a un concurrent redoutable, voire mortel dans le premier; les arguments que le second oppose au premier pour le discr\u00e9diter sont path\u00e9tiques. S&rsquo;il y a sans aucun doute une majorit\u00e9 importante de chroniques et de commentaires politiques de pi\u00e8tre qualit\u00e9 sur Internet, le compliment peut \u00eatre retourn\u00e9, en encore plus accentu\u00e9 sans aucun doute, dans l&rsquo;autre sens. La presse-<em>Pravda<\/em>, plus proche des autorit\u00e9s officielles, est caract\u00e9ris\u00e9e par l&rsquo;\u00e9pouvantable poids du conformisme et de l&rsquo;alignement; les deux caract\u00e8re combin\u00e9s, la pr\u00e9tention au professionnalisme compl\u00e8tement contestable et d&rsquo;ailleurs d\u00e9mentie par le second caract\u00e8re, et le conformisme politique, forment une combinaison qu&rsquo;on pourrait qualifier de <strong>suffisance de la servilit\u00e9<\/strong>. C&rsquo;est la caract\u00e9ristique principale de la presse-<em>Pravda<\/em>, qu&rsquo;on retrouve en g\u00e9n\u00e9ral comme marque des milieux dirgeants et de la communication officielle qui les sert.<\/p>\n<\/p>\n<p><p>\tMais le cas du JSF brise d&rsquo;une fa\u00e7on syst\u00e9matique cet antagonisme entre Internet et la presse officielle, et le cloisonnement qui en r\u00e9sulte, peut-\u00eatre \u00e0 cause de sa position extr\u00eamement ambivalente (un cas tr\u00e8s sp\u00e9cialis\u00e9 d&rsquo;une part, en train de prendre une formidable dimension politique d&rsquo;autre part, pourtant d\u00e9gag\u00e9 de toutes r\u00e9f\u00e9rences id\u00e9ologiques <strong>en apparence<\/strong>). Pour la premi\u00e8re fois de fa\u00e7on affich\u00e9e, on voit des journalistes de la grande presse qui ont leurs propres <em>blogs<\/em> sur les sites de leurs journaux collaborer avec, citer, etc., des chroniqueurs et commentateurs d&rsquo;Internet. C&rsquo;est le cas, par exemple, de Bill Sweetman (<em>Defense &#038; Technologie International<\/em>\/groupe McGraw-Hill), de Stephen Trimble (<em>Flight International<\/em>), qui citent r\u00e9guli\u00e8rement des r\u00e9f\u00e9rences d&rsquo;Internet (Sweetman l&rsquo;a fait pour un article de <em>dedefensa.org<\/em>), la r\u00e9ciproque \u00e9tant d&rsquo;ailleurs vraie.<\/p>\n<\/p>\n<p><p>\tOn peut se demander, \u00e0 propos de ce type de journalistes qui parviennent \u00e0 conserver une libert\u00e9 d&rsquo;esprit et un esprit critique, dans quelle mesure ils se trouvent \u00e0 l&rsquo;aise, ou dans quelles limites ils peuvent intervenir dans les m\u00e9dias o\u00f9 ils \u00e9crivent. Notre appr\u00e9ciation est que certains jugements et remarques de Sweetman sur son <em>blog<\/em>, concernant le JSF, trouveraient difficilement leur place sur le support papier qu&rsquo;il dirige. C&rsquo;est tout de m\u00eame un cas fort int\u00e9ressant, parce que l&rsquo;inverse est vrai. A l&rsquo;inverse, en effet, un groupe comme Lockheed Marin peut difficilement faire trop de barrage aux <em>blogs<\/em> de cette sorte de journaliste, notamment en tentant de le discr\u00e9diter en tant que non professionnel d&rsquo;Internet, alors que le journaliste professionnel intervient \u00e9galement dans un m\u00e9dia-papier \u00e0 grande diffusion.<\/p>\n<\/p>\n<p><p>\tUn autre signe de l&rsquo;\u00e9volution de cette interconnexion entre grande presse et Internet se trouve dans l&rsquo;\u00e9cho rencontr\u00e9 sur Internet par le groupe <em>InsidetheDefense.com<\/em> (une cat\u00e9gorie de la grande presse-papier, mais tr\u00e8s confidentielle sous sa forme de lettre d&rsquo;information), tr\u00e8s faible lors des informations sur le premier rapport JET, mais qui a conduit \u00e0 une tr\u00e8s forte diffusion g\u00e9n\u00e9rale de l&rsquo;intervention de <em>Inside the Air Force<\/em>, \u00e0 propos du second rapport JET, dans tous les r\u00e9seaux, Internet et grande presse. Le cas du rapport sur le JSF de Johan Broeder b\u00e9n\u00e9ficie de ce m\u00eame ph\u00e9nom\u00e8ne, relativement nouveau, d&rsquo;interconnexion, avec une r\u00e9ussite certaine puisque son rapport a finalement fait l&rsquo;objet d&rsquo;une tr\u00e8s grande publicit\u00e9 dans l&rsquo;article de <em>Defense News<\/em>, d&rsquo;une r\u00e9action de Lockheed Martin, d&rsquo;une r\u00e9action favorable d&rsquo;un expert US. Dans d&rsquo;autres conditions, et notamment dans les conditions qui pr\u00e9valaient il y a encore trois ou quatre ans, ce rapport serait rest\u00e9 \u00e0 l&rsquo;\u00e9chelon national\/local de la seule Hollande.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 cet \u00e9gard, pour le point de vue que nous abordons aujourd&rsquo;hui, que le cas du JSF est du plus grand int\u00e9r\u00eat. Internet a jou\u00e9 un r\u00f4le essentiel pour faire sortir le programme de l&rsquo;abri de la bulle virtualiste o\u00f9 il se trouvait jusqu&rsquo;en 2007-2008. Il a montr\u00e9 qu&rsquo;Internet et une frange honorable de la grande presse peuvent collaborer. La position ambigu du programme (simple mati\u00e8re sp\u00e9cialis\u00e9e? Domaine id\u00e9ologique du syst\u00e8me de l&rsquo;am\u00e9ricanisme?) permet effectivement cette sorte d&rsquo;ambigu\u00eft\u00e9 dont un tr\u00e8s grand profit peut \u00eatre tir\u00e9, notamment par Internet, sans qu&rsquo;Internet ne sacrifie en rien sa sp\u00e9cificit\u00e9 d&rsquo;outil de r\u00e9sistance tout en accroissant de fa\u00e7on remarquable son cr\u00e9dit. Ces caract\u00e8res pourraient tr\u00e8s bien \u00eatre transf\u00e9r\u00e9s ensuite vers d&rsquo;autres domaines, plus politiques.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une perspective qu&rsquo;on ne peut ignorer. Internet est entr\u00e9 dans son deuxi\u00e8me \u00e2ge de force d&rsquo;information. De la phase purement alternative et dissidente, il commence \u00e0 mordre sur les marges les plus ouvertes de la presse officielle. Cela ne peut \u00eatre n\u00e9glig\u00e9, au contraire c&rsquo;est une perspective pleine de promesses. Il suffit de ne pas se perdre dans de mauvaises fr\u00e9quentations mais, plut\u00f4t, d&rsquo;attirer les autres vers les bonnes fr\u00e9quentations. Il faut devenir encore plus les <a href=\"http:\/\/www.dedefensa.org\/article-la_fable_des_termites_et_des_conduites_pourries_22_09_2008.html\" class=\"gen\">termites<\/a> qui contribueront \u00e0 pourrir un peu plus les fondations branlantes du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tD&rsquo;un autres point de vue, on peut \u00eatre assur\u00e9 que cette nouvelle extension de l&rsquo;influence d&rsquo;Internet dans le domaine des informations essentielles va rendre encore plus hostile et agressif le reste de la presse officielle, celle qui est plus que jamais presse-<em>Pravda<\/em>. Internet, devenu un acteur encore plus fondamental de l&rsquo;immense bataille de la communication, qui est la bataille centrale de la crise et de l&rsquo;affrontement avec le syst\u00e8me, est plus qu&rsquo;il n&rsquo;a jamais \u00e9t\u00e9, l&rsquo;ennemi prioritaire du syst\u00e8me. Dont acte.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet et la presse officielle: le cas du JSF 29 octobre 2009 Nous revenons une fois de plus sur le r\u00f4le jou\u00e9 par Internet dans certaines grandes affaires qui sont presque compl\u00e8tement ignor\u00e9e de la grande presse-Pravda, (ou presse officielle\/presse-papier, selon la m\u00e9sestime ou l&rsquo;estime qu&rsquo;on veut lui montrer). C&rsquo;est sans aucun doute le cas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3143,7247,3318,4931,60,8500,250,5446,3364,8861,6769,3050,8377],"class_list":["post-71221","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-air","tag-boeder","tag-force","tag-inside","tag-internet","tag-jet","tag-jsf","tag-officielle","tag-presse","tag-presse-pravda","tag-sweetman","tag-the","tag-trimble"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71221"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71221\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}