{"id":71260,"date":"2009-11-12T09:28:41","date_gmt":"2009-11-12T09:28:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/11\/12\/notes-sur-la-vertu-ultime-de-la-nation\/"},"modified":"2009-11-12T09:28:41","modified_gmt":"2009-11-12T09:28:41","slug":"notes-sur-la-vertu-ultime-de-la-nation","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/11\/12\/notes-sur-la-vertu-ultime-de-la-nation\/","title":{"rendered":"Notes sur la vertu ultime de la nation"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur la vertu ultime de la nation<\/h2>\n<\/p>\n<p><p>\tVoici un sujet par essence intemporel malgr\u00e9 l&rsquo;apparence, ou bien, jugeront certains, un peu trop durable dans le temporel. Il s&rsquo;agit du th\u00e8me de la nation, qui est un sujet toujours d&rsquo;actualit\u00e9, qui l&rsquo;est toujours aujourd&rsquo;hui. L&rsquo;id\u00e9e m\u00eame de nation semble toujours susciter une sorte de passion constante, une rage, un d\u00e9sespoir, une fureur et une haine, un amour jusqu&rsquo;au sacrifice. (Il m&rsquo;arrive parfois d&rsquo;en juger dans mes p\u00e9r\u00e9grinations de chroniqueur, devant telle ou telle r\u00e9action, o\u00f9 la chose, la nation, est parfois encombr\u00e9e d&rsquo;\u00e9pith\u00e8tes d\u00e9finitifs et d&rsquo;une pol\u00e9mique si excessive  et je m&rsquo;\u00e9bahis, devant l&rsquo;obsolescence de ces critiques d&rsquo;un autre temps, comme si l&rsquo;on d\u00e9battait de la question du sexe du Diable avec les barbares d\u00e9j\u00e0 l\u00e0, si pressants qu&rsquo;ils sont d\u00e9j\u00e0 en nous.)<\/p>\n<\/p>\n<p><p>\tS&rsquo;interroger sur la nation aujourd&rsquo;hui revient \u00e0 s&rsquo;interroger sur la situation de notre civilisation, c&rsquo;est-\u00e0-dire sur la crise que subit cette civilisation plus que sur le concept de nation. La question de la nation est un biais pour aborder les probl\u00e8mes qui nous hantent et nous assaillent \u00e0 la fois. Prenons garde \u00e0 ces deux verbes, pr\u00e9cis\u00e9ment choisis parce qu&rsquo;ensemble, ils relient notre m\u00e9moire historique \u00e0 notre situation contemporaine. Le probl\u00e8me de la nation nous hante parce qu&rsquo;il s&rsquo;agit d&rsquo;une question historique fondamentale; il nous assaille parce qu&rsquo;il se manifeste chaque jour dans notre esprit, comme facteur organisateur de la r\u00e9flexion sur la situation en cours. Les deux  l&rsquo;Histoire et la situation en cours  son ainsi \u00e9trangement li\u00e9s.<\/p>\n<\/p>\n<p><p>\tNous disons et redisons que le caract\u00e8re exceptionnel de notre temps historique, du \u00e0 la pression des \u00e9v\u00e9nements telle que nous la r\u00e9percute le ph\u00e9nom\u00e8ne fondamental de la communication, est bien de simultan\u00e9ment disposer d&rsquo;un regard imm\u00e9diatement historique sur la situation en cours. Nous suivons une actualit\u00e9 colossale au jour le jour et sommes en position, pour qui y pense et le veut et gr\u00e2ce \u00e0 la communication, d&rsquo;en distinguer aussit\u00f4t les caract\u00e8res historiques qui les relient \u00e0 ce que nous savons de notre pass\u00e9. Nous regardons et voyons sous nos yeux l&rsquo;Histoire se faire, et sommes \u00e0 m\u00eame d&rsquo;en tirer grand profit si nous faisons appel \u00e0 ce que nous savons de l&rsquo;Histoire. L\u00e0-dedans, la nation, qui hante notre histoire, est si pr\u00e9sente dans notre situation pr\u00e9sente que sa probl\u00e9matique ne cesse de nous assaillir.<\/p>\n<\/p>\n<p><h3>Notre m\u00e9thodologie<\/h3>\n<\/p>\n<p><p>\tNous d\u00e9finissons le cadre de notre r\u00e9flexion, volontairement d&rsquo;une fa\u00e7on structur\u00e9e, le plus rigoureusement possible, pour tenter d&rsquo;exprimer de la fa\u00e7on la plus rationnelle possible une situation o\u00f9 la pr\u00e9sence de forces qui d\u00e9passent l&rsquo;entendement de notre raison conduit \u00e0 des jugements d&rsquo;incompr\u00e9hension ou de d\u00e9sordre.<\/p>\n<\/p>\n<p><p>\tCet usage de la raison correspond \u00e0 ce que nous devrions en juger: la raison humaine n&rsquo;est pas une explication du monde, qui imposerait un rangement \u00e0 ce qui nous semble \u00eatre le chaos du monde mais un outil pour tenter de mieux appr\u00e9hender le chaos du monde et approcher de son explication. Cette approche m\u00e9thodologiquement rationnelle implique l&rsquo;acceptation de l&rsquo;existence de situations et de forces irrationnelles. Cette m\u00e9thode implique, selon le mot de Aron et Dandieu dans <em>La d\u00e9cadence de la nation fran\u00e7aise<\/em> (1931), un d\u00e9cha\u00eenement de la pens\u00e9e  la pens\u00e9e lib\u00e9r\u00e9e des cha\u00eenes de l&rsquo;interpr\u00e9tation de la raison comme explication du monde.<\/p>\n<h3>Bien entendu, structuration et d\u00e9structuration<\/h3>\n<\/p>\n<p><p>\tLa d\u00e9finition de notre situation pr\u00e9sente se d\u00e9compose, pour nous, en plusieurs points que nous tenons pour acquis ou \u00e9vidents. Ces affirmations sont de notre responsabilit\u00e9 intellectuelle.<\/p>\n<\/p>\n<p><p>\t Notre civilisation, en tant qu&rsquo;entit\u00e9 repr\u00e9sentant l&rsquo;organisation du monde globalis\u00e9, se trouve dans une crise profonde.<\/p>\n<\/p>\n<p><p>\t Cette crise n&rsquo;est pas n\u00e9cessairement transitoire ni n\u00e9cessairement explicable seulement par des facteurs humains sous le contr\u00f4le de notre raison.<\/p>\n<\/p>\n<p><p>\t  Il en r\u00e9sulte que cette crise peut ne pas \u00eatre transitoire, qu&rsquo;elle peut \u00eatre ultime pour notre civilisation; qu&rsquo;elle peut \u00eatre de type eschatologique, c&rsquo;est-\u00e0-dire d\u00e9pendant de facteurs qui ont \u00e9chapp\u00e9 au contr\u00f4le humain (crise des ressources naturelles, crise climatique, etc.). C&rsquo;est notre conviction qu&rsquo;elle est ceci (ultime) et cela (eschatologique).<\/p>\n<\/p>\n<p><p>\t Dans ce cadre se poursuit un affrontement entre des forces humaines, qui repr\u00e9sente la partie identifiable de la crise. Depuis la fin du communisme et l&rsquo;adoption de ce que nous nommons tr\u00e8s g\u00e9n\u00e9ralement le syst\u00e8me de l&rsquo;am\u00e9ricanisme, comprenant aussi bien des valeurs morales qu&rsquo;une organisation \u00e9conomique et politique sp\u00e9cifique, il n&rsquo;y a plus d&rsquo;affrontement id\u00e9ologique. (Nous mettons de c\u00f4t\u00e9 les arrangements de communication accessoire, que nous qualifions de virtualistes, tel la guerre contre la terreur, dont l&rsquo;arrangement rel\u00e8ve de la technique publicitaire et de <em>marketing<\/em>, dite de cr\u00e9ation d&rsquo;\u00e9v\u00e9nements.) Alors que le mod\u00e8le am\u00e9ricaniste subit une attaque (une contre-attaque) puissante et qu&rsquo;il donne tous les signes d&rsquo;un effondrement que nous qualifierions de subreptice derri\u00e8re l&#8217;empilement de crises diverses, aucun mod\u00e8le ne lui est oppos\u00e9.<\/p>\n<\/p>\n<p><p>\t Dans cette absence de bataille id\u00e9ologique et dans ce constat d&rsquo;une crise fondamentale, sinon terminale du mod\u00e8le de l&rsquo;am\u00e9ricanisme, nous proposons une autre d\u00e9finition de l&rsquo;affrontement en cours. Il s&rsquo;agit de l&rsquo;affrontement entre des forces d\u00e9structurantes et des forces structurantes  dans cet ordre, parce que les forces d\u00e9structurantes sont naturellement offensives et agressives, donc toujours les premi\u00e8res \u00e0 se signaler, et que les forces structurantes sont naturellement d\u00e9fensives et contre-offensives, donc secondes chronologiquement dans l&rsquo;affrontement.<\/p>\n<\/p>\n<p><p>\t Ce rangement n&rsquo;est pas accessoire ou d&rsquo;opportunit\u00e9, parce que nous n&rsquo;y comprendrions rien et fournirions une explication par d\u00e9faut. Au contraire, notre conviction est que nous touchons l\u00e0, par le biais de la crise, \u00e0 une v\u00e9rit\u00e9 qui est aussi l&rsquo;explication centrale de la crise, et une explication fondamentale de l&rsquo;histoire de notre civilisation. En quelque sorte, la crise, pour forcer notre compr\u00e9hension, nous oblige \u00e0 abandonner nos sch\u00e9mas habituels d&rsquo;explication (l&rsquo;id\u00e9ologie), qui s&rsquo;av\u00e9reraient pure construction d&rsquo;une raison faussaire pr\u00e9tendant \u00e0 l&rsquo;explication du monde.<\/p>\n<h3>Une autre vision de la nation<\/h3>\n<\/p>\n<p><p>\tC&rsquo;est imp\u00e9rativement dans ce cadre qu&rsquo;il faut placer notre appr\u00e9ciation de la nation. Il n&rsquo;est plus temps de plaider, de peser, d&rsquo;analyser, de juger et d&rsquo;ex\u00e9cuter la sentence. La nation n&rsquo;est plus en question s&rsquo;il y a toujours, \u00e9ternellement, une question de la nation. Elle est dans une situation historique et contemporaine inexpugnable, dans le sens que nous observons, parce qu&rsquo;elle est le seul concept politique de civilisation \u00e0 survivre, qui ait une vertu structurante; le seul concept qui entretient le dernier lien restant entre l&rsquo;individu perdu dans le d\u00e9sordre de l&rsquo;effondrement de la civilisation et une vertu politique collective qui soit autre que mercantile, de fortune ou de communaut\u00e9 accessoire  qui soit haute, en un mot, jusqu&rsquo;\u00e0 la m\u00e9tahistoire et la spiritualit\u00e9.<\/p>\n<\/p>\n<p><p>\tLa critique courante contre la nation est aussi obsol\u00e8te que le communisme, le fascisme (et, tr\u00e8s bient\u00f4t, si ce n&rsquo;est d\u00e9j\u00e0 fait, le lib\u00e9ralisme et la d\u00e9mocratie). Les proc\u00e8s sempiternels faits au nationalisme peuvent encore int\u00e9resser les salons, ils n&rsquo;ont plus aucune r\u00e9alit\u00e9. La question centrale qui s&rsquo;impose aujourd&rsquo;hui avec une force inou\u00efe est celle de la survie et, pour la seule et sublime raison de son existence obstin\u00e9e, la vertu fondamentale de la nation s&rsquo;impose comme le seul moteur politique disponible.<\/p>\n<\/p>\n<p><p>\tLa France, malgr\u00e9 un personnel politique stup\u00e9fiant de m\u00e9diocrit\u00e9, est plus que jamais capable d&rsquo;initier des liens qui p\u00e8seront vite d&rsquo;un poids consid\u00e9rable, par l&rsquo;attrait de la puissance de ses caract\u00e8res tels que la souverainet\u00e9 et l&rsquo;identit\u00e9. M\u00eame si notre \u00e9trange pr\u00e9sident trouve judicieux de d\u00e9cider la r\u00e9int\u00e9gration du commandement int\u00e9gr\u00e9 de l&rsquo;OTAN, ce qui ne fera pas vraiment de mal \u00e0 une mouche et ne rapportera rien, strictement rien \u00e0 son pays, la France garde assez d&rsquo;influence pour susciter des liens exceptionnels avec des pays d&rsquo;une grande importance, tels que ceux du BRIC (le Br\u00e9sil et la Russie), notamment par la force politique de certains march\u00e9s d&rsquo;armements, qui vont peser lourd contre le syst\u00e8me de l&rsquo;am\u00e9ricanisme d\u00e9structurant. C&rsquo;est la part exceptionnelle d&rsquo;une entit\u00e9 (la Grande Nation) qui conserve, sans doute au-del\u00e0 de l&rsquo;entendement de la raison du temps courant, ou de ce qu&rsquo;il reste de raison, les caract\u00e8res de l&rsquo;identit\u00e9, de la l\u00e9gitimit\u00e9 et de la souverainet\u00e9.<\/p>\n<\/p>\n<p><p>\tLa nation parle toujours Elle est la seule structure, la seule entit\u00e9, la seule r\u00e9f\u00e9rence \u00e0 avoir surv\u00e9cu \u00e0 l&rsquo;attaque d\u00e9structurante qui a pr\u00e9cipit\u00e9 la civilisation dans sa crise ultime. Sa vertu ultime est celle d&rsquo;\u00eatre un rempart et, \u00e9ventuellement, si la chose existe encore, une esp\u00e9rance suscitant une r\u00e9sistance. Rien d&rsquo;autre dans les cr\u00e9ations de cette civilisation que nous avons si parfaitement cochonn\u00e9e, ne peut pr\u00e9tendre \u00e0 une telle vertu. La vertu ultime de la nation est hors du champ de la discussion qu&rsquo;affectionne notre civilisation effondr\u00e9e parce qu&rsquo;elle est simplement un <em>diktat<\/em> de l&rsquo;Histoire qui a repris aujourd&rsquo;hui, \u00e0 l&rsquo;heure du r\u00e8glement des comptes, tous ses droits.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t(<em>Nota Bene<\/em>: ce texte est une intervention de Philippe Grasset dans un volume \u00e0 para\u00eetre sur le th\u00e8me de la Nation.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la vertu ultime de la nation Voici un sujet par essence intemporel malgr\u00e9 l&rsquo;apparence, ou bien, jugeront certains, un peu trop durable dans le temporel. Il s&rsquo;agit du th\u00e8me de la nation, qui est un sujet toujours d&rsquo;actualit\u00e9, qui l&rsquo;est toujours aujourd&rsquo;hui. L&rsquo;id\u00e9e m\u00eame de nation semble toujours susciter une sorte de passion&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3423,3015,8154,3460,3518,4194,8153,7160],"class_list":["post-71260","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-civilisation","tag-communication","tag-destructurantes","tag-forces","tag-histoire","tag-nation","tag-structurantes","tag-survie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71260"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71260\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}