{"id":71288,"date":"2009-11-24T06:36:25","date_gmt":"2009-11-24T06:36:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/11\/24\/le-jsf-va-tres-mal-tout-le-monde-veut-du-jsf\/"},"modified":"2009-11-24T06:36:25","modified_gmt":"2009-11-24T06:36:25","slug":"le-jsf-va-tres-mal-tout-le-monde-veut-du-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/11\/24\/le-jsf-va-tres-mal-tout-le-monde-veut-du-jsf\/","title":{"rendered":"Le JSF va tr\u00e8s mal \u2013 tout le monde veut du JSF!"},"content":{"rendered":"<p><p>En dix jours, on a annonc\u00e9 deux avis sur deux intentions nouvelles d&rsquo;achat \u00e9ventuel du JSF, de la part de deux pays qui, jusqu&rsquo;ici, ne s&rsquo;int\u00e9ressaient pas officiellement \u00e0 l&rsquo;avion.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.flightglobal.com\/articles\/2009\/11\/15\/334899\/dubai-09-uae-reveals-fifth-generation-fighter-ambitions.html\" class=\"gen\">15 novembre 2009<\/a>, Stephen Trimble annon\u00e7ait sur son <em>blog<\/em> que l&rsquo;adjoint au chef d&rsquo;\u00e9tat-major de la force a\u00e9rienne des Emirats Arabes Unis  avait exprim\u00e9 cette intention: \u00ab<em>A top United Arab Emirates military leader aspires to obtain a fifth-generation fighter in the very near term, suggesting a potential new sales coup for the Lockheed Martin F-35 Joint Strike Fighter. I hope that within a couple years the UAE, like many other countries, will have a fifth-generation fighter, says Brig Gen Ibrahim Naser Alalawi, deputy commander of the UAE Air Force and Air Defence. Alalawi was speaking at the Dubai International Air Chiefs.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Hier, <a href=\"http:\/\/www.defensenews.com\/story.php?i=4389389&#038;c=AME\" class=\"gen\">23 novembre 2009<\/a>, AFP (vie <em>Defense News<\/em>) citait des sources anonymes affirmant que le Japon voulait, tr\u00e8s vite, autour de 40 F-35. \u00ab<em>Japan is considering buying about 40 F-35 fighter jets as the future mainstay of the nation&rsquo;s air force, it was reported Monday.<\/em> [] <em>The defense ministry will likely seek funds in the fiscal 2011 budget for the fighters, Kyodo said, citing unnamed sources.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t On pourrait ajouter, pour le <em>fun<\/em> et pour justifier les \u00e9moluments courants, l&rsquo;annonce par le secr\u00e9taire \u00e0 la d\u00e9fense hollandais De Vries que les deux prototypes du JSF que la Hollande veut acheter vont co\u00fbter moins cher \u00e0 cause de la d\u00e9pr\u00e9ciation du dollar. M\u00eame le dollar confirme la valeur du JSF et le bon choix du ministre hollandais.<\/p>\n<\/p>\n<p><p>\tLe programme JSF est aujourd&rsquo;hui, <strong>officiellement<\/strong> depuis ce week-end, dans un \u00e9tat <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_du_jsf_inauguree_officiellement_24_11_2009.html?admin=1\" class=\"gen\">catastrophique<\/a> apr\u00e8s des <a href=\"http:\/\/www.reuters.com\/article\/marketsNews\/idUSN2326316620091123\" class=\"gen\">d\u00e9clarations<\/a> du n\u00b02 du Pentagone Ashton Carter sur des mesures d&rsquo;urgence \u00e0 prendre. Tout le monde se pr\u00e9cipite pour annoncer l&rsquo;intention de tr\u00e8s vite acheter cet avion. Il y a dans cet encha\u00eenement une r\u00e9elle logique  logique d&rsquo;\u00e9poque, \u00e0 front renvers\u00e9  plus \u00e7a va mal, plus \u00e7a va bien  sans aucun doute, logique largement sugg\u00e9r\u00e9e, avec les arguments convaincants qu&rsquo;il faut, par le comportement de Lockheed Martin.<\/p>\n<h4>Notre commentaire<\/h4>\n<p> On remarquera \u00e9videmment que ces deux d\u00e9clarations viennent de sources qui n&rsquo;engagent aucune autorit\u00e9 formelle. D&rsquo;une part, un vice-chef d&rsquo;\u00e9tat-major qui annonce la volont\u00e9 th\u00e9orique de sa force a\u00e9rienne d&rsquo;acqu\u00e9rir  et de disposer (dans deux ans! L&rsquo;homme a le sens de l&rsquo;humour ou bien il a mal traduit sa feuille de route) de l&rsquo;avion dont la r\u00e9putation internationale parmi ceux qui ont int\u00e9r\u00eat \u00e0 ce que cette r\u00e9putation soit maintenue est qu&rsquo;il s&rsquo;agit du meilleur avion du monde pour les d\u00e9cennies et les d\u00e9cennies \u00e0 venir. D&rsquo;autre part des sources anonymes proches des milieux de la d\u00e9fense japonaises qui annoncent l&rsquo;intention d&rsquo;acheter tr\u00e8s vite autour de 40 F-35, au moment o\u00f9 la tension est grande entre les USA et le Japon, au moment o\u00f9 le Japon veut plut\u00f4t r\u00e9duire son potentiel militaire pour se rapprocher des pays de la zone, au moment o\u00f9 le JSF entre <strong>officiellement<\/strong> dans une crise qui implique divers aspects  notamment la confirmation du rapport JET-II (au moins deux ans de d\u00e9lais pour le programme), un renforcement de la p\u00e9riode d&rsquo;essais \u00e0 partir d&rsquo;un budget auquel Lockheed Martin est invit\u00e9 \u00e0 participer, de nouveaux probl\u00e8mes techniques pour la version ADAC\/V (voir <em>DoDBuzz.com<\/em> du <a href=\"http:\/\/www.dodbuzz.com\/2009\/11\/23\/jsf-stovl-woes-strike-pax-river\/\" class=\"gen\">23 novembre 2009<\/a>), etc&#8230;. Tout cela fait beaucoup  cela fait m\u00eame un peu <em>too much<\/em>&#8230;<\/p>\n<\/p>\n<p><p>\tBien  il s&rsquo;agit d&rsquo;\u00eatre s\u00e9rieux. Lockheed Martin (LM) est aux abois. Il se d\u00e9fend avec ce qu&rsquo;il a de meilleur, c&rsquo;est-\u00e0-dire un remarquable r\u00e9seau d&rsquo;influence et de relations publiques, c&rsquo;est-\u00e0-dire  un r\u00e9seau de corruption de par le monde par les divers moyens du bord qui sont consid\u00e9rables. LM a donc donn\u00e9 la consigne de faire lancer au maximum des nouvelles diverses d&rsquo;intentions d&rsquo;achat du JSF hors des USA. Peu importe ce qu&rsquo;il restera de toutes ces intentions puisqu&rsquo;on est au niveau des vux th\u00e9oriques ou des sources anonymes, sans aucune d\u00e9cision officielle, dans des domaines (les forces a\u00e9riennes ou les minist\u00e8res de la d\u00e9fense des pays concern\u00e9s) o\u00f9 LM a ses hommes et ses canaux d&rsquo;informations dans le sens qui va bien. Pour l&rsquo;instant, LM n&rsquo;a qu&rsquo;une seule tactique possible: faire le maximum de pression sur le Pentagone par des relais ext\u00e9rieurs annon\u00e7ant la volont\u00e9 de divers pays d&rsquo;avoir du JSF, donc tenter de renforcer ce programme en lambeaux par des appuis ext\u00e9rieurs engageant la puissance US, l&rsquo;influence US, etc. Ce n&rsquo;est pas le Pentagone qui d\u00e9mentira toutes ces nouvelles diverses sur les vux d&rsquo;acquisition du JSF par les UAE et le Japon  m\u00eame les d\u00e9lais annonc\u00e9s pour l&rsquo;acquisition, voire la livraison, qui ont tout de m\u00eame l&rsquo;avantage d&rsquo;illlustrer indirectement le s\u00e9rieux des propos. Nous sommes en pleine offensive de d\u00e9fense des r\u00e9seaux d&rsquo;influence de LM. C&rsquo;est de bonne guerre.<\/p>\n<\/p>\n<p><p>\tTout de m\u00eame, en annon\u00e7ant toutes ces nouvelles, on devrait avoir l&rsquo;\u00e0-propos de pr\u00e9ciser de quoi l&rsquo;on parler, et dans quel \u00e9tat il se trouve la chose aujourd&rsquo;hui aux USA m\u00eame, juste pour informer&#8230; Tout de m\u00eame, retranscrire une telle d\u00e9claration d&rsquo;un officier g\u00e9n\u00e9ral responsable: <em>I hope that within a couple years the UAE, like many other countries, will have a fifth-generation fighter&#8230;<\/em>\u00bb (j&rsquo;esp\u00e8re que dans deux ans, les EAU, comme de nombreux autres pays, auront un chasseur de 5\u00e8me g\u00e9n\u00e9ration [le JSF, puisque c&rsquo;est le seul \u00e0 pr\u00e9tendre l&rsquo;\u00eatre]) alors que tous les gens <strong>un peu<\/strong> inform\u00e9s savant que si l&rsquo;on a un JSF op\u00e9rationnel en 2016, c&rsquo;est que le Bon Dieu aura pris partie pour lui  retranscrire cela et ne pas accompagner cette insanit\u00e9 d&rsquo;un commentaire \u00e0 propos de la r\u00e9alit\u00e9 du monde?<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 novembre 2009 \u00e0 06H36<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dix jours, on a annonc\u00e9 deux avis sur deux intentions nouvelles d&rsquo;achat \u00e9ventuel du JSF, de la part de deux pays qui, jusqu&rsquo;ici, ne s&rsquo;int\u00e9ressaient pas officiellement \u00e0 l&rsquo;avion. Le 15 novembre 2009, Stephen Trimble annon\u00e7ait sur son blog que l&rsquo;adjoint au chef d&rsquo;\u00e9tat-major de la force a\u00e9rienne des Emirats Arabes Unis avait exprim\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8959,3858,5134,3090,4662,250,2711,3501,3502,5579,8960,8961],"class_list":["post-71288","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-acheter","tag-corruption","tag-eau","tag-influence","tag-japon","tag-jsf","tag-le","tag-lockheed","tag-martin","tag-pression","tag-tres","tag-vite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71288"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71288\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}