{"id":71313,"date":"2009-12-04T07:25:01","date_gmt":"2009-12-04T07:25:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/04\/letrange-malaise-transatlantique\/"},"modified":"2009-12-04T07:25:01","modified_gmt":"2009-12-04T07:25:01","slug":"letrange-malaise-transatlantique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/04\/letrange-malaise-transatlantique\/","title":{"rendered":"L&rsquo;\u00e9trange malaise transatlantique"},"content":{"rendered":"<p><p>Le sommet entre l&rsquo;Union Europ\u00e9enne et les USA, le 3 novembre dernier \u00e0 Washington, a laiss\u00e9 une tr\u00e8s mauvaise impression \u00e0 Bruxelles, dans les milieux europ\u00e9ens. M\u00eame si personne n&rsquo;en parle officiellement  on s&rsquo;en doute tant le sujet est tabou  on peut sans la moindre h\u00e9sitation parler d&rsquo;un malaise.<\/p>\n<\/p>\n<p><p>\t Le pr\u00e9sident Obama, qui avait d&rsquo;autres occupations ce jour-l\u00e0, n&rsquo;a pass\u00e9 qu&rsquo;une petite heure au sommet du 3 novembre, le temps de quelques photos pour quelques poign\u00e9es de mains. Les officiels europ\u00e9ens ont \u00e9prouv\u00e9 une tr\u00e8s mauvaise impression et certaines notes de hauts fonctionnaires europ\u00e9ens appr\u00e9ciant la rencontre, diffus\u00e9es en interne, ont \u00e9t\u00e9 class\u00e9es confidentielles (la preuve) tant le langage employ\u00e9 \u00e9tait extr\u00eamement dur. Les Europ\u00e9ens ont \u00e9t\u00e9 effar\u00e9s des probl\u00e8mes de stagnation du pouvoir \u00e0 Washington, constatant notamment combien Obama est pieds et poings li\u00e9s par rapport au Congr\u00e8s, notamment sur les initiatives de lutte contre la crise climatique qui est un des th\u00e8mes favoris de l&rsquo;Europe institutionnelle.<\/p>\n<\/p>\n<p><p>\tLe malaise transatlantique prend une forme tr\u00e8s \u00e9trange. Devant les objurgations lanc\u00e9es pour tenter de revitaliser les relations transatlantiques entre l&rsquo;UE et les USA, certains fonctionnaires s&rsquo;avouent incapables de contr\u00f4ler un tel processus. \u00ab<em>Les fonctionnaires des services charg\u00e9s de ces relations \u00e0 la Commission reconnaissent qu&rsquo;ils ignorent combien de task forces, de comit\u00e9s, de groupes communs ou pas travaillent sur cette question dans l&rsquo;appareil bureaucratique transatlantique, <\/em>explique une source europ\u00e9enne. <em>On en arrive \u00e0 penser qu&rsquo;il est impossible de parvenir \u00e0 \u00e9tablir un contr\u00f4le du processus pour tenter de lui donner une orientation ou une impulsion. Les relations transatlantiques avec l&rsquo;UE stagnent et \u00e9touffent sous le poids d&rsquo;une sorte de bureaucratie de la coop\u00e9ration transatlantique.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDu c\u00f4t\u00e9 US, des interventions tr\u00e8s pressantes sont enregistr\u00e9es, notamment lors de s\u00e9minaires transatlantiques, pour une relance des relations transatlantiques, avec des propositions portant sur tous les domaines imaginables. \u00ab<em>On trouve de plus en plus d&rsquo;experts US pour insister sur la n\u00e9cessit\u00e9 de r\u00e9g\u00e9n\u00e9rer les relations transatlantiques, <\/em>dit notre source, <em>et l&rsquo;on a m\u00eame entendu, lors d&rsquo;un s\u00e9minaire cette semaine, l&rsquo;un d&rsquo;entre eux parler de la n\u00e9cessit\u00e9 d&rsquo;un G2, mais entre les USA et l&rsquo;Europe !<\/em>\u00bb Ces experts viennent des milieux tr\u00e8s classiques de l&rsquo;<em>establishment<\/em> US, du type Council of Foreign Relations.<\/p>\n<\/p>\n<p><p>\tDans ces rencontres, lorsque les experts US sont confront\u00e9s \u00e0 des remarques plus structur\u00e9es des Europ\u00e9ens, par exemple concernant le d\u00e9sordre \u00e9pouvantable (pour la r\u00e9f\u00e9rence aux dossiers de coop\u00e9ration transatlantique plus ou moins en cours) d&rsquo;affaires comme le JSF (avec des participants europ\u00e9ens qui sont priv\u00e9s de l&rsquo;acc\u00e8s aux codes sources) ou le ravitailleur en vol KC-45 de l&rsquo;USAF (o\u00f9 le concurrent EADS\/Northrop Grumman refuse d\u00e9sormais de participer \u00e0 la comp\u00e9tition \u00e0 cause de sp\u00e9cifications qui favorisent Boeing), ils ne r\u00e9pondent pas d&rsquo;une fa\u00e7on pr\u00e9cise sinon par une confusion in\u00e9vitable. \u00ab<em>L\u00e0 encore, <\/em>sugg\u00e8re notre source, <em>la sensation est de se trouver devant des experts qui, passant des souhaits aux r\u00e9alit\u00e9s, reconnaissent implicitement qu&rsquo;il s&rsquo;agit, avec le syst\u00e8me de l&rsquo;am\u00e9ricanisme, d&rsquo;un syst\u00e8me totalement bloqu\u00e9.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn r\u00e9alit\u00e9, tout cela ressemble plut\u00f4t \u00e0 un appel au secours, comme une reconnaissance implicite du c\u00f4t\u00e9 US que les USA ne contr\u00f4lent plus la situation de leur h\u00e9g\u00e9monie qui devient ainsi une coquille vide, ni m\u00eame leur propre situation int\u00e9rieure. Il semble que ces appels \u00e0 la coop\u00e9ration transatlantique, sur un tissu de coop\u00e9rations innombrables, d\u00e9j\u00e0 lanc\u00e9es et sans effets r\u00e9els, un tissu de plus en plus paralys\u00e9, satur\u00e9 de programmes et de structures bureaucratiques qu&rsquo;on ne parvient m\u00eame plus \u00e0 identifier, constitue une tentative de faire sortir le syst\u00e8me de l&rsquo;am\u00e9ricanisme de la l\u00e9thargie g\u00e9n\u00e9rale et mortelle o\u00f9 il s&rsquo;enfonce. En un sens, la situation europ\u00e9enne n&rsquo;est pas meilleure mais la diff\u00e9rence est \u00e9videmment que les Am\u00e9ricains viennent d&rsquo;une situation psychologique o\u00f9 ils croyaient dominer le monde et la gestion de leur propre puissance.<\/p>\n<\/p>\n<p><p>\t(Bien entendu, les r\u00e9sultats de l&rsquo;enqu\u00eate PEW Research, que nous commentons ce m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-l_epuisement_du_desespoir_04_12_2009.html?admin=1\" class=\"gen\">4 d\u00e9cembre 2009<\/a>, ont tout \u00e0 voir avec ce malaise transatlantique.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 d\u00e9cembre 2009 \u00e0 07H17<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le sommet entre l&rsquo;Union Europ\u00e9enne et les USA, le 3 novembre dernier \u00e0 Washington, a laiss\u00e9 une tr\u00e8s mauvaise impression \u00e0 Bruxelles, dans les milieux europ\u00e9ens. M\u00eame si personne n&rsquo;en parle officiellement on s&rsquo;en doute tant le sujet est tabou on peut sans la moindre h\u00e9sitation parler d&rsquo;un malaise. Le pr\u00e9sident Obama, qui avait d&rsquo;autres&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2623,1463,3435,3079,8279,3446,4608,1205,8984,5150],"class_list":["post-71313","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bureaucratie","tag-commission","tag-cooperation","tag-europeenne","tag-g2","tag-malaise","tag-paralysie","tag-transatlantique","tag-transtatlantique","tag-usa-europe"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71313"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71313\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}