{"id":71318,"date":"2009-12-07T08:04:46","date_gmt":"2009-12-07T08:04:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/07\/bernanke-face-au-senat-avec-un-brin-de-contestation\/"},"modified":"2009-12-07T08:04:46","modified_gmt":"2009-12-07T08:04:46","slug":"bernanke-face-au-senat-avec-un-brin-de-contestation","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/07\/bernanke-face-au-senat-avec-un-brin-de-contestation\/","title":{"rendered":"Bernanke face au S\u00e9nat, avec un brin de contestation"},"content":{"rendered":"<p><p>Quatre s\u00e9nateurs ont d\u00e9cid\u00e9 de tenter de s&rsquo;opposer \u00e0 la d\u00e9cision de Barack Obama de prolonger Bernanke pour un deuxi\u00e8me mandat \u00e0 la t\u00eate de la Federal Reserve. Ces quatre parlementaires forment une \u00e9trange coalition, bon reflet de la situation de d\u00e9sordre \u00e0 Washington. On y trouve trois r\u00e9publicains, en g\u00e9n\u00e9ral plut\u00f4t class\u00e9s \u00e0 droite et pourfendeur de tout ce qui ressemble au socialisme et un ind\u00e9pendant, et le seul s\u00e9nateur \u00e0 se r\u00e9clamer de l&rsquo;appellation de socialiste.<\/p>\n<\/p>\n<p><p>\tLes trois r\u00e9publicains sont Jim Bunning, du Kentucky, Jim DeMint, de la Caroline du Sud, et David Vitter, de la Louisiane (le dernier \u00e0 avoir rejoint le groupe). Le quatri\u00e8me est Bernie Sanders, du Vermont, un ind\u00e9pendant qui vote en g\u00e9n\u00e9ral avec les d\u00e9mocrates et qui s&rsquo;intitule lui-m\u00eame socialiste d\u00e9mocrate. (<a href=\"http:\/\/www.dedefensa.org\/article-a_washington_un_senateur_socialiste_a_l_assaut_de_la_fed_15_05_2009.html\" class=\"gen\">Sanders<\/a> a lanc\u00e9 au S\u00e9nat un mouvement pour obtenir une loi proche de celle que <a href=\"http:\/\/www.dedefensa.org\/article-_et_ron_paul_en_rock_star_du_congres_01_12_2009.html\" class=\"gen\">Ron Paul<\/a> a lanc\u00e9 \u00e0 la Chambre, pour la mise \u00e0 jour du fonctionnement et des d\u00e9cisions de la <em>Fed<\/em>.) <\/p>\n<\/p>\n<p><p>\t<em>RAW Story<\/em>, notamment, rapporte, le <a href=\"http:\/\/rawstory.com\/2009\/12\/bernanke-trouble-confirmation\/\" class=\"gen\">4 d\u00e9cembre 2009<\/a> les divers d\u00e9tails de cette initiative. Voici quelques d\u00e9clarations de trois de ces quatre s\u00e9nateurs.<\/p>\n<\/p>\n<p><p>\t Sanders: \u00ab<em>The American people overwhelmingly voted last year for a change in our national priorities to put the interests of ordinary people ahead of the greed of Wall Street and the wealthy few. What the American people did not bargain for was another four years for one of the key architects of the Bush economy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Bunning a publi\u00e9 une d\u00e9claration \u00e9crite adress\u00e9e directement \u00e0 Bernanke pour expliquer sa d\u00e9cision (le terme <em>moral hazard<\/em> d\u00e9signe l&rsquo;attitude des banques prenant n&rsquo;importe quel risque parce qu&rsquo;elle se savent couvertes par l&rsquo;aide du gouvernement en cas de besoin). \u00ab<em>You are the definition of moral hazard. Instead of taking that money and lending to consumers and cleaning up their balance sheets, the banks started to pocket record profits and pay out billions of dollars in bonuses. Because you bowed to pressure from the banks and refused to resolve them or force them to clean up their balance sheets and clean out the management, you have created zombie banks that are only enriching their traders and executives.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Vitter a lui aussi publi\u00e9 une d\u00e9claration \u00e9crite: \u00ab<em>Over the past year or so, the Fed has doled out several trillion dollars to any number of troubled institutions through a series of programs that were supposed to turn our economy around. These programs have worsened our economic crisis by making too big to fail a permanent government policy and created further debt that will now be the burden of our children and grandchildren. His endorsement of these unsound fiscal policies gives me great pause.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, il est g\u00e9n\u00e9ralement admis qu&rsquo;il n&rsquo;y a aucune chance pour que la confirmation de la nomination de Bernanke soit repouss\u00e9e par le S\u00e9nat. Mais l&rsquo;activisme de ces quatre dissidents, qui peuvent \u00eatre soutenus par d&rsquo;autres, va rendre le processus plus long et plus difficile et, surtout, susciter des questions et des pol\u00e9miques dans son cours, qui mettront un peu plus \u00e0 jour les turpitudes diverses du processus de lutte contre la crise, et du r\u00f4le de la <em>Fed<\/em>. Pour l&rsquo;instant, la r\u00e9ponse standard de Bernanke lorsqu&rsquo;on lui demande si la <em>Fed<\/em> a commis des fautes est tout le monde a commis des fautes (\u00ab<em>There were mistakes made all around<\/em>\u00bb).<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Alors que la Chambre des Repr\u00e9sentants a la position qu&rsquo;on sait vis-\u00e0-vis de la <em>Fed<\/em> (voir Ron Paul), le S\u00e9nat est une citadelle du conservatisme standard \u00e0 cet \u00e9gard. A cette lumi\u00e8re, la manifestation des quatre s\u00e9nateurs est int\u00e9ressante (en plus du fait de l&rsquo;activisme anti-<em>Fed<\/em> de Sanders, parall\u00e8le \u00e0 celui de Paul, et qui n&rsquo;a pas \u00e9t\u00e9 compl\u00e8tement \u00e9touff\u00e9 bien que cela se passe au S\u00e9nat). L&rsquo;int\u00e9r\u00eat est d&rsquo;abord de constater l&rsquo;h\u00e9t\u00e9roclisme d&rsquo;une si petite coalition, qui r\u00e9unit ce qui est pour les USA un extr\u00e9miste de gauche et trois r\u00e9publicains de la droite plut\u00f4t radicale, sinon extr\u00e9miste, puisque nettement d&rsquo;orientation populiste, et d&rsquo;avoir ainsi le rappel qu&rsquo;on peut trouver au S\u00e9nat de telles positions, malgr\u00e9 le filtre impitoyable de l&rsquo;appareil des partis et du syst\u00e8me lui-m\u00eame. (M\u00eame remarque, bien s\u00fbr, pour Ron Paul et la Chambre des Repr\u00e9sentants. Le mouvement y est certes beaucoup plus vaste, tenant \u00e0 la structure et \u00e0 la tradition beaucoup plus populaire de la Chambre.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;action des dissidents n&rsquo;a donc gu\u00e8re de chance, non, plut\u00f4t aucune chance d&rsquo;aboutir  cela jug\u00e9 et \u00e9crit pour l&rsquo;\u00e9tat actuel de la situation. Mais, effectivement, elle permet d&rsquo;alimenter la pol\u00e9mique autour de la <em>Fed<\/em> et du r\u00f4le de Bernanke, elle accentue le mouvement g\u00e9n\u00e9ral de contestation larv\u00e9e des institutions telles qu&rsquo;elles se sont r\u00e9v\u00e9l\u00e9es durant la crise. Mais le mot r\u00e9v\u00e9l\u00e9 est inappropri\u00e9, sinon pour les circonstances. La crise a simplement confirm\u00e9 l&rsquo;esprit et le fonctionnement des institutions et l&rsquo;originalit\u00e9 de la situation est la poursuite de cette contestation, sur le terme durable, alors que les conditions dramatiques de la crise n&rsquo;existent plus, et cette contestation au cur m\u00eame de ces institutions (et, dans ce cas, le S\u00e9nat, la plus institutionnelle de toutes ces institutions). La contestation n&rsquo;est pas ridiculis\u00e9e, elle n&rsquo;est pas marginalis\u00e9e, m\u00eame quand elle vient d&rsquo;un tr\u00e8s petit nombre. Elle correspond \u00e9videmment \u00e0 un climat de malaise g\u00e9n\u00e9ral, r\u00e9pondant \u00e0 la perception diffuse mais puissante de la crise du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tEncore une fois, notre hypoth\u00e8se est qu&rsquo;il ne faut rien attendre de constructif dans cette contestation. Cette appr\u00e9ciation continue \u00e0 \u00eatre la n\u00f4tre m\u00eame dans le cas d&rsquo;un Ron Paul, certainement l&rsquo;\u00e9l\u00e9ment le plus puissant, le mieux arm\u00e9 et appuy\u00e9 sur une incontestable popularit\u00e9 dans ce mouvement de contestation. Il nous para\u00eet que la puissance du syst\u00e8me, son caract\u00e8re monolithique, sont trop grands pour permettre une p\u00e9n\u00e9tration constructive de la contestation, jusqu&rsquo;\u00e0 une r\u00e9forme fondamentale. Par contre, ni cette puissance, ni ce monolithisme ne sont garantes de l&rsquo;absolue solidit\u00e9, ni de l&rsquo;\u00e9tanch\u00e9it\u00e9 de ce m\u00eame syst\u00e8me. Les machines les plus puissantes et les plus monolithiques, d\u00e8s lors qu&rsquo;elles sont de la complexit\u00e9 de ce syst\u00e8me, pr\u00e9sentent des points de vuln\u00e9rabilit\u00e9, qu&rsquo;il est d&rsquo;ailleurs en g\u00e9n\u00e9ral impossibles de d\u00e9terminer par avance et le plus souvent avec des surprises \u00e0 cet \u00e9gard. La contestation actuelle, dont la <em>Fed<\/em> est un objectif \u00e9vident pour toutes les raisons du monde, est un mouvement disparate et peu coordonn\u00e9 mais remarquable par sa dur\u00e9e et son alacrit\u00e9, dans un syst\u00e8me qui s&rsquo;y entend pour faire dispara\u00eetre sous les pressions de l&rsquo;actualit\u00e9, de la communication et des int\u00e9r\u00eats divers cette sorte de r\u00e9action.<\/p>\n<\/p>\n<p><p>\tL&rsquo;effet de la contestation, consid\u00e9r\u00e9 objectivement et sans consid\u00e9ration des intentions des contestataires, m\u00eame si ces intentions sont honorables et constructives, est de poursuivre un travail de sape contre le syst\u00e8me, d&rsquo;une certaine fa\u00e7on aveugl\u00e9ment (m\u00eame si l&rsquo;objectif est identifi\u00e9 dans un cas ou l&rsquo;autre), simplement pour maintenir une pression d\u00e9structurante contre ce syst\u00e8me lui-m\u00eame d\u00e9structurant (la pression devenant ainsi indirectement structurante). Le r\u00e9sultat possible est qu&rsquo;\u00e0 un moment, quelque chose c\u00e8de, un de ces points de vuln\u00e9rabilit\u00e9 dont on ne sait rien pour l&rsquo;instant. Le r\u00e9sultat objectif est l&rsquo;\u00e9largissement du d\u00e9sordre \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me; le r\u00e9sultat objectif, si un de ces points de vuln\u00e9rabilit\u00e9 est touch\u00e9, sera un d\u00e9sordre plus grand encore, mais surtout devenant plus grand avec une telle brutalit\u00e9 et une telle rapidit\u00e9 que sa substance changera. Le d\u00e9sordre encore rampant deviendra soudain \u00e9clatant et tonitruant, et cette hypoth\u00e8se justifie effectivement que l&rsquo;on parle d&rsquo;un changement de substance. C&rsquo;est alors que les choses ne seront plus ce qu&rsquo;elles \u00e9taient jusqu&rsquo;alors, et ce qu&rsquo;elles sont encore. Elles ne seront pas pr\u00e9visibles pour autant, et m\u00eame au contraire, mais il nous semble impossible que la possible destruction de ce syst\u00e8me ne passe pas par des phases de tr\u00e8s profonde incertitude dans un d\u00e9sordre g\u00e9n\u00e9ralis\u00e9 par rapport aux normes de ce syst\u00e8me. (Cela ne signifie pas n\u00e9cessairement un d\u00e9sordre au sens commun o\u00f9 on l&rsquo;entend, impliquant par exemple la violence; il s&rsquo;agit d&rsquo;un d\u00e9sordre par antinomie avec l&rsquo;ordre du syst\u00e8me, donc plus d\u00e9structurant que violent  la d\u00e9structuration d&rsquo;un syst\u00e8me lui-m\u00eame d\u00e9structurant n&rsquo;impliquant pas n\u00e9cessairement la violence, tant s&rsquo;en faut)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 d\u00e9cembre 2009 \u00e0 08H12<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatre s\u00e9nateurs ont d\u00e9cid\u00e9 de tenter de s&rsquo;opposer \u00e0 la d\u00e9cision de Barack Obama de prolonger Bernanke pour un deuxi\u00e8me mandat \u00e0 la t\u00eate de la Federal Reserve. Ces quatre parlementaires forment une \u00e9trange coalition, bon reflet de la situation de d\u00e9sordre \u00e0 Washington. On y trouve trois r\u00e9publicains, en g\u00e9n\u00e9ral plut\u00f4t class\u00e9s \u00e0 droite&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8987,8086,5592,5393,3140,4207,3310,8327,3531,3014],"class_list":["post-71318","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-benanke","tag-confirmation","tag-contestation","tag-federal","tag-paul","tag-reserve","tag-ron","tag-sanders","tag-senat","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71318"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71318\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}