{"id":71322,"date":"2009-12-08T09:48:56","date_gmt":"2009-12-08T09:48:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/08\/qui-commande-ici\/"},"modified":"2009-12-08T09:48:56","modified_gmt":"2009-12-08T09:48:56","slug":"qui-commande-ici","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/08\/qui-commande-ici\/","title":{"rendered":"Qui commande ici?"},"content":{"rendered":"<p><p>Question \u00e0 nouveau pos\u00e9e: qui commande \u00e0 Washington? Les g\u00e9n\u00e9raux ou Obama? Question \u00e0 propos du discours du 1er d\u00e9cembre sur l&rsquo;envoi de troupes US en Afghanistan, et \u00e0 propos des interpr\u00e9tations notablement divergentes sur la question du retrait en 2011. (Voir notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-vous_avez_bien_dit_juillet_2011_07_12_2009.html\" class=\"gen\">7 d\u00e9cembre 2009<\/a> et notre <em>Notes d&rsquo;analyse<\/em> du m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_guerre_personnelle_du_president_obama_07_12_2009.html\" class=\"gen\">7 d\u00e9cembre 2009<\/a>.)<\/p>\n<\/p>\n<p><p>\tIl y a un long et tr\u00e8s int\u00e9ressant texte de <em>Politico-Com<\/em> du <a href=\"http:\/\/www.politico.com\/news\/stories\/1209\/30268_Page3.html\" class=\"gen\">6 d\u00e9cembre 2009<\/a> sur le sujet, et une synth\u00e8se d&rsquo;<em>Antiwar.com<\/em> du <a href=\"http:\/\/news.antiwar.com\/2009\/12\/07\/senate-dems-fear-generals-undermining-july-2011-target\/\" class=\"gen\">8 d\u00e9cembre 2009<\/a>.<\/p>\n<\/p>\n<p><p>\tMcChrystal doit t\u00e9moigner ces jours prochains au S\u00e9nat sur la d\u00e9cision prise par Obama. (On entendra aussi l&rsquo;ambassadeur \u00e0 Kaboul Karl Eikenberry, ancien g\u00e9n\u00e9ral et ancien chef des forces US en Afghanistan, qui s&rsquo;est violemment oppos\u00e9 \u00e0 l&rsquo;augmentation des forces US en Afghanistan. Du sport en perspective ou bien des litanies conformistes pour \u00e9touffer un dissentiment trop voyant?) Des s\u00e9nateurs ont fait savoir leurs pr\u00e9occupations de la situation des rapports entre Obama et ses g\u00e9n\u00e9raux sur le terrain. C&rsquo;est notamment le cas des s\u00e9nateurs Inouye et Levin, tous deux d\u00e9mocrates, tous deux occupant des positions tr\u00e8s puissantes dans deux commissions s\u00e9natoriales, dont celle des forces arm\u00e9es qui va entendre McChrystal.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>I&rsquo;ve always believed that the president of the United States is the commander in chief, said Senate Appropriations Committee Chairman Daniel Inouye (D-Hawaii), who was awarded the Medal of Honor in World War II. It concerns me when I see my president, the commander in chief, having to debate with generals. They can do that privately, but he should be able to say to General A, This is the way we&rsquo;re going to do our business.&rsquo; &#8230; I would expect generals to advise the president but not to go public.<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The pace<\/em> [<em>of withdrawal<\/em>] <em>is condition-based. The location is condition-based. But what wasn&rsquo;t condition-based is the beginning, Levin said of the July 2011 date. I want to see if McChrystal says, yes, he understands that. Second, does he support it? He&rsquo;s not obligated to. I&rsquo;m asking for his honest personal opinion. If he has a different opinion, he should tell us. He&rsquo;s obligated to tell us. &#8230; Their advice should be private, &#8230; with the one caveat [that] if they are asked by a congressional committee for their best professional opinion, they are duty bound to give it to us.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est ce climat qui fait surgir la th\u00e8se d&rsquo;Obama prisonnier des g\u00e9n\u00e9raux et des g\u00e9n\u00e9raux menant la politique US en Afghanistan, voire Washington D. C. par le bout du nez. Notre analyse sur ces hypoth\u00e8ses est pour le moins nuanc\u00e9e, tenant compte de la situation du syst\u00e8me et de la m\u00e9diocrit\u00e9 g\u00e9n\u00e9rale qui le caract\u00e9rise.<\/p>\n<h4>Notre commentaire<\/h4>\n<p> M\u00e9diocrit\u00e9, en effet. D&rsquo;abord, celle des g\u00e9n\u00e9raux. McChrystal est la brute standard de notre \u00e9poque, rayon op\u00e9rations sp\u00e9ciales, commandos de la mort, philosophie Rumsfeld et ainsi de suite, mais avec une pr\u00e9tention \u00e0 l&rsquo;intellectualisme des th\u00e9ories en vogue li\u00e9e \u00e0 une bonne dose de trouille du c\u00f4t\u00e9 de l&rsquo;image et des relations publiques; reconnaissons-lui \u00e9galement une certaine habilet\u00e9 pour ses r\u00e9seaux dans la presse (<a href=\"http:\/\/www.dedefensa.org\/article-le_president_et_quelques_generaux_25_09_2009.html\" class=\"gen\">Woodward<\/a>, du <em>Post<\/em>, la gloire de la presse US pour les intellectuels europ\u00e9ens dans son r\u00f4le d&rsquo;agent et de relais des militaires qu&rsquo;il tient depuis avant le Watergate). Petraeus, sup\u00e9rieur et complice de McChrystal, est une cr\u00e9ature de pure relations publiques avec, para\u00eet-il, des ambitions politiques qui lui feraient r\u00eaver d&rsquo;\u00eatre un nouveau MacArthur. On a d\u00e9j\u00e0 vu <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_bho_et_ses_generaux_et_ses_amiraux_29_09_2009.html\" class=\"gen\">cette th\u00e8se<\/a>. Plus habile politiquement que MacArthur  dans ce cas, la maladresse de MacArthur \u00e9tait plut\u00f4t une vertu   Petraeus est un nain grotesque \u00e0 c\u00f4t\u00e9 de la stature de soldat de son soi-disant mod\u00e8le. McChrystal et Petraeus font partie de la nouvelle g\u00e9n\u00e9ration des militaires US, celle qui est <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_desinteret_pour_la_victoire_27_10_2009.html\" class=\"gen\">vilipend\u00e9e<\/a> par Andrew Bacevich et qui applique la philosophie <em>post<\/em>-9\/11 de la guerre (guillemets utiles) pour la guerre  parfaitement \u00e0 la mesure de la m\u00e9diocrit\u00e9 abyssale de cette pens\u00e9e. <\/p>\n<\/p>\n<p><p>\tCette m\u00e9diocrit\u00e9, qui s&rsquo;exprime notamment dans le go\u00fbt byzantin des manuvres de bas-empire et dans un respect au garde-\u00e0-vous du conformisme du syst\u00e8me, fait de ces g\u00e9n\u00e9raux des intrigants mais le contraire de putschistes ou d&rsquo;aventuriers qui auraient le courage de bouleverser les structures du syst\u00e8me pour s&rsquo;affirmer de fa\u00e7on formelle et puissante. Autrement dit, l&rsquo;actuelle phase o\u00f9 l&rsquo;on s&rsquo;interroge \u00e0 nouveau pour savoir si les g\u00e9n\u00e9raux ne dirigent pas la politique US correspond surtout \u00e0 un recul d&rsquo;Obama, \u00e0 son incapacit\u00e9 d&rsquo;affirmer autre chose qu&rsquo;une politique conforme, la poursuite sous <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_guerre_personnelle_du_president_obama_07_12_2009.html\" class=\"gen\">le masque<\/a> de la politique de la raison de la politique de l&rsquo;id\u00e9ologie et de l&rsquo;instinct. Depuis la phase de vacillement d&rsquo;ao\u00fbt-d\u00e9but septembre, Obama avait repris le contr\u00f4le de la situation en concentrant la d\u00e9cision sur son propre processus d&rsquo;\u00e9valuation, mais ce fut pour accoucher de l&rsquo;esp\u00e8ce de monstre du discours du 1er d\u00e9cembre 2009 (engagement mais promesse de d\u00e9sengagement) qui cr\u00e9e, avec l&rsquo;impression d&rsquo;une capitulation devant le parti de la guerre ajout\u00e9e \u00e0 la confusion des interpr\u00e9tations de la promesse de d\u00e9sengagement, un vide du pouvoir dont l&rsquo;\u00e9valuation profite aux g\u00e9n\u00e9raux.<\/p>\n<\/p>\n<p><p>\tEn v\u00e9rit\u00e9, ceux-ci ne dirigent rien du tout, ils n&rsquo;en ont ni la capacit\u00e9 ni l&rsquo;originalit\u00e9. Ils se trouvent dans ce cas du c\u00f4t\u00e9 de la machinerie du syst\u00e8me et les r\u00e9flexes de communication font le reste. Dans trois mois, lorsqu&rsquo;on commencera \u00e0 \u00e9valuer les r\u00e9sultats de la strat\u00e9gie McChrystal (malgr\u00e9 les d\u00e9n\u00e9gations de ce dernier qui affirmera que c&rsquo;est encore trop t\u00f4t pour juger), qu&rsquo;on constatera que rien ne s&rsquo;am\u00e9liore, les g\u00e9n\u00e9raux seront vilipend\u00e9s autant qu&rsquo;ils sont aujourd&rsquo;hui consid\u00e9r\u00e9s comme les ma\u00eetres du jeu. Puisqu&rsquo;Obama ne fait rien de marquant pour tenter de mettre en cause le contr\u00f4le du syst\u00e8me, cela signifie alors que personne ne dirige rien et que le syst\u00e8me, lui, dirige tout, continue son chemin \u00e0 son rythme, en baptisant pour une semaine, un mois ou un an, pour telle campagne ou telle catastrophe, tel ou tel groupe ma\u00eetre du jeu et manipulateur du reste (successivement ou en d\u00e9sordre, et cit\u00e9s \u00e0 la queue-leu-leu, les p\u00e9troliers, Wall Street, le Complexe militaro-industriel, les grands groupes pharmaceutiques, les g\u00e9n\u00e9raux et ainsi de suite). Les g\u00e9n\u00e9raux pour l&rsquo;instant? Vu leur calibre, ce ne sont que de pi\u00e8tres ex\u00e9cutants de la dynamique du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tPour terminer, observons que la v\u00e9ritable d\u00e9ception de l&rsquo;\u00e9pisode est la d\u00e9faite compl\u00e8te du g\u00e9n\u00e9ral James Jones, directeur du NSC, qui \u00e9tait oppos\u00e9 \u00e0 l&rsquo;envoi de troupes et qui n&rsquo;a rien pu faire finalement. Il a affirme m\u00eame d\u00e9sormais, avec tout le monde, que la pr\u00e9sence US en Afghanistan sera tr\u00e8s longue \u00e0 cause des int\u00e9r\u00eats g\u00e9ostrat\u00e9giques US dans la r\u00e9gion, ce qui est \u00e9pouser les th\u00e8ses du parti de la guerre dont il semblait plut\u00f4t l&rsquo;adversaire. C&rsquo;est une v\u00e9ritable d\u00e9ception parce que Jones, au contraire de McChrystal et de Petraeus, est un homme de qualit\u00e9. Cela n&#8217;emp\u00eache qu&rsquo;il faut garder son nom \u00e0 l&rsquo;esprit et observer son \u00e9volution parce qu&rsquo;il pourrait retrouver sa position initiale si la situation tourne mal en Afghanistan malgr\u00e9 les renforts, ce qui est apr\u00e8s tout une hypoth\u00e8se sp\u00e9culative particuli\u00e8rement acceptable. Comme chacun sait, cet \u00e9pisode-l\u00e0 de la partie, qui n&rsquo;est \u00e9videmment pas jou\u00e9e, ne fait que commencer.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 d\u00e9cembre 2009 \u00e0 09H49<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Question \u00e0 nouveau pos\u00e9e: qui commande \u00e0 Washington? Les g\u00e9n\u00e9raux ou Obama? Question \u00e0 propos du discours du 1er d\u00e9cembre sur l&rsquo;envoi de troupes US en Afghanistan, et \u00e0 propos des interpr\u00e9tations notablement divergentes sur la question du retrait en 2011. (Voir notre Bloc-Notes du 7 d\u00e9cembre 2009 et notre Notes d&rsquo;analyse du m\u00eame 7&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,2631,4390,5160,8376,8360,8361,4780,7887,8321,6264,4607,5713,2766,3531],"class_list":["post-71322","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-de","tag-et","tag-generaux","tag-inouye","tag-lideologie","tag-linstinct","tag-levin","tag-macarthur","tag-mcchrystal","tag-petraeus","tag-politique","tag-publiques","tag-relations","tag-senat"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71322"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71322\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}