{"id":71371,"date":"2009-12-24T08:15:32","date_gmt":"2009-12-24T08:15:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/24\/la-poussee-britannique-autour-de-ashton\/"},"modified":"2009-12-24T08:15:32","modified_gmt":"2009-12-24T08:15:32","slug":"la-poussee-britannique-autour-de-ashton","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2009\/12\/24\/la-poussee-britannique-autour-de-ashton\/","title":{"rendered":"La pouss\u00e9e britannique autour de Ashton"},"content":{"rendered":"<p><p>Les \u00e9chos ne cessent de se confirmer d&rsquo;une pouss\u00e9e bureaucratique colossale des Britanniques dans l&rsquo;appareil qui est mis en place autour de la Haute Repr\u00e9sentante, la baronne Ashton. Ces appr\u00e9ciations poursuivent et compl\u00e8tent en quelque sorte celles que nous donnions hier, le <a href=\"http:\/\/www.dedefensa.org\/article-ashton_en_derapage_incontrole_et_van_rompuy_en_embuscade_23_12_2009.html\" class=\"gen\">23 d\u00e9cembre 2009<\/a>, sur la m\u00eame baronne Ashton.<\/p>\n<\/p>\n<p><p>\t Des indications venues des milieux fran\u00e7ais proches des institutions europ\u00e9ennes indiquent que les Fran\u00e7ais estiment avoir \u00e9t\u00e9 battus dans le processus d&rsquo;installation des structures autour de la baronne Ashton, dans tout ce qui repr\u00e9sente la mise en place de l&rsquo;\u00e9norme bureaucratie europ\u00e9enne de politique ext\u00e9rieure et de bureaucratie. \u00ab<em>Les Fran\u00e7ais sont furieux, <\/em>nous indique une source europ\u00e9enne, <em>de l&rsquo;action des Britanniques, conduite sans le moindre scrupule et avec le plus complet cynisme, et \u00e9galement, on s&rsquo;en doute, d&rsquo;une fa\u00e7on tr\u00e8s efficace. Il se pourrait bien, d&rsquo;ailleurs, que cette mauvaise humeur se manifeste officiellement.<\/em>\u00bb Mais le constat ne doit pas s&rsquo;arr\u00eater l\u00e0, s\u00fbrement pas \u00e0 une concurrence franco-anglaise. Notre source poursuit: \u00ab<em>Mais ils <\/em>[les Fran\u00e7ais] <em>ne sont pas les seuls. Cette r\u00e9action de rancur et de col\u00e8re est partag\u00e9e par d&rsquo;autres pays de l&rsquo;UE. On a un peu l&rsquo;impression que, cette fois, les Anglais en ont fait vraiment trop, que tout le monde commence \u00e0 en avoir assez.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe paradoxe est que, du c\u00f4t\u00e9 britannique, la perception est qu&rsquo;il s&rsquo;agit d&rsquo;abord d&rsquo;une pouss\u00e9e presque de contre-attaque. Les Britanniques ont \u00e9t\u00e9 fortement secou\u00e9s par la nomination de Barnier \u00e0 la Commission sur les mati\u00e8res financi\u00e8res et de r\u00e9gulation des march\u00e9s, et que les Fran\u00e7ais se sont ainsi acquis des pouvoirs exorbitants, tout cela dramatis\u00e9 par <a href=\"http:\/\/www.dedefensa.org\/article-sarkozy_et_la_city_rencontre_du_troisieme_type_03_12_2009.html\" class=\"gen\">la passe d&rsquo;armes<\/a> Sarko-la <em>City<\/em>. De leur point de vue, leur offensive autour d&rsquo;Ashton est d&rsquo;abord une riposte. Mais cette vision est loin d&rsquo;\u00eatre partag\u00e9e, comme on l&rsquo;a vu, et demeure l&rsquo;\u00e9valuation d\u00e9crite plus haut de r\u00e9actions tr\u00e8s d\u00e9favorables devant le comportement britannique.<\/p>\n<\/p>\n<p><p>\tCe n&rsquo;est pas la premi\u00e8re fois qu&rsquo;on observe de telles r\u00e9actions devant le comportement britannique, qui a toujours \u00e9t\u00e9 semblable au sein des institutions europ\u00e9ennes. Mais cette fois, le moment est extr\u00eamement important parce que de nouvelles forces se mettent en place et que les diff\u00e9rents nouveaux postes dirigeants vont ainsi marquer leurs territoires. D&rsquo;autre part, l&rsquo;effondrement britannique avec la crise du 15 septembre 2008, cette crise elle-m\u00eame d\u00e9clench\u00e9e \u00e0 partir de pratiques dont les Britanniques sont les promoteurs, rend d&rsquo;autant plus difficile \u00e0 accepter cet imp\u00e9rialisme bureaucratique.<\/p>\n<\/p>\n<p><p>\tPlus que jamais, nous confirmons notre analyse d&rsquo;hier, o\u00f9 nous mettions en \u00e9vidence le poids potentiel de Van Rompuy. S&rsquo;il y a une riposte \u00e0 l&rsquo;entrisme britannique, elle se fera en recherchant un renforcement du poids du nouveau pr\u00e9sident de l&rsquo;UE, qui dispose en th\u00e9orie de forces bureaucratiques tr\u00e8s r\u00e9duites \u00e0 sa disposition. S&rsquo;il y a une riposte Van Rompuy, elle devra se faire autour du personnage, qui a devant lui la possibilit\u00e9 de jouer un r\u00f4le de sage, d\u00e9fendant fermement une sp\u00e9cificit\u00e9 europ\u00e9enne contre les manuvres bureaucratiques. S&rsquo;il joue ce jeu, Van Rompuy aura des soutiens dans les Etats membres.<\/p>\n<\/p>\n<p><p>\tCe qui permet de conclure, en passant, que l&rsquo;Europe <em>post<\/em>-Lisbonne, soi-disant acte de la mise en place de la vraie Europe, conduit surtout \u00e0 \u00e9largir notablement le champ de la bataille entre les diff\u00e9rentes forces antagonistes caract\u00e9risant cette Europe. En un mot, le contraire de l&rsquo;Europe dont ils disent poursuivre l&rsquo;accomplissement.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 d\u00e9cembre 2009 \u00e0 08H21<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9chos ne cessent de se confirmer d&rsquo;une pouss\u00e9e bureaucratique colossale des Britanniques dans l&rsquo;appareil qui est mis en place autour de la Haute Repr\u00e9sentante, la baronne Ashton. Ces appr\u00e9ciations poursuivent et compl\u00e8tent en quelque sorte celles que nous donnions hier, le 23 d\u00e9cembre 2009, sur la m\u00eame baronne Ashton. Des indications venues des milieux&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8150,4347,4875,4609,5513,2927,2687,3293,8948,4590,4164],"class_list":["post-71371","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ashton","tag-barnier","tag-britannique","tag-bureaucratique","tag-city","tag-colere","tag-france","tag-imperialisme","tag-rompuy","tag-sarkozy","tag-van"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71371"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71371\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}