{"id":71441,"date":"2010-01-18T00:47:03","date_gmt":"2010-01-18T00:47:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/01\/18\/le-camouflet-a-peine-camoufle-de-medvedev-a-washington\/"},"modified":"2010-01-18T00:47:03","modified_gmt":"2010-01-18T00:47:03","slug":"le-camouflet-a-peine-camoufle-de-medvedev-a-washington","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/01\/18\/le-camouflet-a-peine-camoufle-de-medvedev-a-washington\/","title":{"rendered":"Le camouflet \u00e0 peine camoufl\u00e9 de Medvedev \u00e0 Washington"},"content":{"rendered":"<p><p>Les n\u00e9gociations pour le trait\u00e9 START-II de limitation des armes strat\u00e9giques entre les USA et la Russie ont repris \u00e0 Moscou.<\/p>\n<\/p>\n<p><p>\t Du c\u00f4t\u00e9 US, l&rsquo;optimisme est de rigueur sinon pressant. Les d\u00e9clarations du chef de la d\u00e9l\u00e9gation US sont caract\u00e9ristiques \u00e0 cet \u00e9gard (Novosti, le <a href=\"http:\/\/fr.rian.ru\/world\/20100114\/185831089.html\" class=\"gen\">14 janvier 2010<\/a>).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La Russie et les Etats-Unis parach\u00e8veront la r\u00e9solution du reste des questions relatives au nouveau trait\u00e9 de r\u00e9duction des armes strat\u00e9giques offensives (START) dans les prochaines semaines, a annonc\u00e9 jeudi le sous-secr\u00e9taire d&rsquo;Etat am\u00e9ricain William Burns en visite \u00e0 Moscou. Il nous reste \u00e0 r\u00e9soudre encore quelques questions, cela prendra quelques semaines, a estim\u00e9 le haut responsable am\u00e9ricain. Selon lui, il est normal que l&rsquo;\u00e9laboration de ce nouveau trait\u00e9 ait pris du temps: Ce retard est dans l&rsquo;int\u00e9r\u00eat des deux parties. Depuis le sommet qui a r\u00e9uni en juillet \u00e0 Moscou les pr\u00e9sidents Medvedev et Obama, nous avons fait des progr\u00e8s consid\u00e9rables et nous sommes \u00e0 la veille de la signature d&rsquo;un nouveau trait\u00e9.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Du c\u00f4t\u00e9 russe, optimisme \u00e9galement, mais plus de forme et assorti de d\u00e9clarations pr\u00e9cises sur certaines conditions. Les d\u00e9clarations de Medvedev, du <a href=\"http:\/\/fr.rian.ru\/world\/20100116\/185846785.html\" class=\"gen\">16 janvier 2010<\/a> (Novosti), sont caract\u00e9ristiques \u00e0 cet \u00e9gard. La condition qu&rsquo;\u00e9nonce le pr\u00e9sident russe de la n\u00e9cessit\u00e9 d&rsquo;une ratification simultan\u00e9e du trait\u00e9 par les deux pays repr\u00e9sente une r\u00e9serve s\u00e9rieuse et, <em>in fine<\/em>, un camouflet en douceur pour le pouvoir politique washingtonien.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La ratification du nouveau trait\u00e9 START doit s&rsquo;op\u00e9rer simultan\u00e9ment \u00e0 Moscou et \u00e0 Washington, sinon ce processus n&rsquo;aura pas lieu, a d\u00e9clar\u00e9 samedi le pr\u00e9sident russe Dmitri Medvedev. Il s&rsquo;agit d&rsquo;une entente paritaire qui r\u00e9pond aux int\u00e9r\u00eats des deux Etats: soit nous ratifierons simultan\u00e9ment ce document qui refl\u00e8tera notre vision commune de l&rsquo;avenir des forces strat\u00e9giques nucl\u00e9aires, soit ce processus n&rsquo;aura pas lieu, a-t-il soulign\u00e9. Nos partenaires am\u00e9ricains ne doivent pas l&rsquo;ignorer, a ajout\u00e9 le chef de l&rsquo;Etat.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Camouflet, sans aucun doute, parce que cette condition implique le peu de cas qu&rsquo;on fait \u00e0 Moscou de la signature du pr\u00e9sident des USA. Le trait\u00e9, s&rsquo;il est conclu, sera paraph\u00e9 par les deux chefs d&rsquo;Etat puis devra \u00eatre ratifi\u00e9 par les deux Parlements. La condition \u00e9mise par la Russie s&rsquo;adresse directement au pouvoir US, pour lui dire: Nous n&rsquo;avons aucune confiance dans la signature du pr\u00e9sident Obama, non pas parce que nous l&rsquo;estimons indigne de confiance mais parce que nous estimons qu&rsquo;il n&rsquo;est pas le pouvoir US \u00e0 lui seul, qu&rsquo;en cette mati\u00e8re des trait\u00e9s il n&rsquo;est m\u00eame qu&rsquo;une partie mineure du pouvoir. Le\u00e7on des choses par les Russes<\/p>\n<\/p>\n<p><p>\tLa Russie a la m\u00e9moire tenace, f\u00fbt-ce celle de l&rsquo;URSS. Elle se rappelle que le trait\u00e9 SALT-II fut sign\u00e9 en juillet 1979 (Brejnev-Carter \u00e0 Moscou) et qu&rsquo;il ne fut jamais ratifi\u00e9 par le S\u00e9nat US apr\u00e8s deux ans d&rsquo;auditions et de pol\u00e9miques interminables (alors que le Soviet Supr\u00eame, toujours arrangeant, s&rsquo;\u00e9tait ex\u00e9cut\u00e9 pour ratifier du c\u00f4t\u00e9 de l&rsquo;URSS). L&rsquo;administration Reagan abandonna le trait\u00e9 SALT-II (portant sur la limitation des armes strat\u00e9giques  Strategic Arms Limitation Talks) et passa \u00e0 la formule START (portant sur la r\u00e9duction des armes strat\u00e9giques  STrategic Arms Reduction Talks). START-I fut sign\u00e9 en juillet 1991 et ratifi\u00e9 en janvier 1996, alors qu&rsquo;il \u00e9tait entr\u00e9 en vigueur par accord des deux gouvernements en 1994. (Mais ces d\u00e9lais avaient, dans ce cas, plus \u00e0 voir avec la situation de l&rsquo;URSS, qui disparut, se fractionna en plusieurs Etats nouvellement ind\u00e9pendants, avec d&rsquo;autres pays que la Russie poss\u00e9dant <em>de facto<\/em> des armes nucl\u00e9aires de l&rsquo;ex-URSS dont il fallut n\u00e9gocier le transfert vers la Russie.) Encore les d\u00e9g\u00e2ts de la non ratification de SALT-II de juillet 1979, qui reste la principale r\u00e9f\u00e9rence n\u00e9gative \u00e0 cet \u00e9gard, avaient-ils \u00e9t\u00e9 limit\u00e9s par le s\u00e9rieux des administrations US \u00e0 cette \u00e9poque de Guerre froide: le pr\u00e9sident Carter avait ordonn\u00e9 que les forces strat\u00e9giques US s&rsquo;alignassent sur les chiffres de limitation du trait\u00e9, en attendant la ratification.<\/p>\n<\/p>\n<p><p>\tMais aujourd&rsquo;hui? Qui peut dire si le S\u00e9nat ne va pas s&rsquo;ab\u00eemer dans un d\u00e9bat interminable  alors que tout nous <a href=\"http:\/\/www.dedefensa.org\/article-nucleaire_le_pentagone_le_cmi_contre_bho_05_01_2010.html\" class=\"gen\">annonce<\/a> d\u00e9j\u00e0 qu&rsquo;il va le faire? Qui peut dire si le trait\u00e9 sera jamais ratifi\u00e9 avant la fin du mandat de BHO, si celui-ci sera r\u00e9\u00e9lu, s&rsquo;il ne sera pas remplac\u00e9 par une Sarah Palin ou un g\u00e9n\u00e9ral Petraeus d\u00e9non\u00e7ant le trait\u00e9 paraph\u00e9 mais non ratifi\u00e9? La condition \u00e9mise par Medvedev constitue donc une s\u00e9rieuse mise en cause du pouvoir d&rsquo;Obama et une non moins s\u00e9rieuse hypoth\u00e8se portant sur le d\u00e9sordre du pouvoir aujourd&rsquo;hui \u00e0 Washington. Si ce n&rsquo;est un camouflet<\/p>\n<\/p>\n<p><p>\tLes Russes sont des r\u00e9alistes, c&rsquo;est bien connu, mais avec un sens historique propre \u00e0 la culture que donne une v\u00e9ritable nation. Ils ont senti \u00e0 la fin 2008 qu&rsquo;Obama repr\u00e9sentait une chance d&rsquo;un tournant radical aux USA, et ils lui ont fait confiance. Cela a dur\u00e9 jusqu&rsquo;\u00e0 la fin de l&rsquo;\u00e9t\u00e9 et cela \u00e9tait judicieux  effectivement, BHO avait encore un potentiel d&rsquo;action, selon l&rsquo;audace qu&rsquo;il montrerait. Tout cela s&rsquo;est \u00e9vanoui en fum\u00e9e dans les quatre derniers mois, parce qu&rsquo;Obama a d\u00e9cid\u00e9, ou s&rsquo;est convaincu devant les pressions du syst\u00e8me de jouer le jeu de la politique du syst\u00e8me conduite par la seule m\u00e9canique des forces bureaucratiques en action. Sa d\u00e9cision sur l&rsquo;Afghanistan marque <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_descente_aux_enfers__30_12_2009.html\" class=\"gen\">sa capitulation<\/a> g\u00e9n\u00e9rale, et les Russes ont senti cela. (Voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-les_russes_se_doutent_de_quelque_chose_06_01_2010.html\" class=\"gen\">6 janvier 2010<\/a>.) Depuis, ils sont sur leur garde et consid\u00e8rent Obama dans toute sa faiblesse, d&rsquo;une part prisonnier du syst\u00e8me, d&rsquo;autre part confront\u00e9 \u00e0 une opposition int\u00e9rieure multiple. Dans sa situation, Obama a besoin de START-II, alors qu&rsquo;un d\u00e9bat f\u00e9roce devrait d\u00e9marrer \u00e0 Washington d\u00e8s l&rsquo;accord sign\u00e9  s&rsquo;il est sign\u00e9. Alors, il lui impose une condition \u00e9galement f\u00e9roce  f\u00e9rocit\u00e9 contre f\u00e9rocit\u00e9: imposer START-II au syst\u00e8me. Si Obama accepte, il deviendra un pr\u00e9sident doublement, triplement prisonnier: du syst\u00e8me, de l&rsquo;opposition washingtonienne, des Russes (Chaque fois, encha\u00eenement des situations, des int\u00e9r\u00eats contradictoires, avec tous les probl\u00e8mes qui naissent de ces situations.)<\/p>\n<\/p>\n<p><p>\tObama pourrait-il ne pas accepter? Il n&rsquo;envisage sans doute pas le probl\u00e8me dans les termes o\u00f9 nous l&rsquo;exposons. Il est d&rsquo;ores et d\u00e9j\u00e0 un pr\u00e9sident assi\u00e9g\u00e9 par les multiples pressions auxquelles son attitude politique l&rsquo;a conduit \u00e0 devenir vuln\u00e9rable. Il tente de r\u00e9pondre au coup par coup parce qu&rsquo;il n&rsquo;a plus de ligne g\u00e9n\u00e9rale et il est conduit de plus en plus \u00e0 traiter les probl\u00e8mes qui s&rsquo;accumulent pour ce qu&rsquo;ils sont dans l&rsquo;imm\u00e9diat, sans les int\u00e9grer dans une vision g\u00e9n\u00e9rale. Son d\u00e9sir \u00e9vident de parvenir \u00e0 un accord START-II tient \u00e0 sa volont\u00e9 de sauver sa politique de r\u00e9duction des armes nucl\u00e9aires, qui constitue une affaire essentielle pour lui. De ce point de vue, il en a plus besoin que les Russes et l&rsquo;on ne peut ignorer que l&rsquo;accord qui devrait finalement en r\u00e9sulter, si c&rsquo;est le cas, sera un immense sujet de controverse et de pol\u00e9mique \u00e0 Washington, o\u00f9 des forces diff\u00e9rentes s&rsquo;appr\u00eatent \u00e0 le contester  de l&rsquo;opposition pol\u00e9mique et syst\u00e9matique des r\u00e9publicains aux critiques expertes d&rsquo;un syst\u00e8me tout entier domin\u00e9 par le poids et les exigences du Pentagone. La personnalit\u00e9 d&rsquo;Obama, dont la brillante intelligence a comme revers une trop grande confiance en lui et une assurance de pouvoir convaincre sinon vaincre ses adversaires par le seul brio de sa dialectique, le pousse effectivement \u00e0 ne pas s&rsquo;attarder aux cons\u00e9quences lointaines de ses actes pour s&rsquo;en remettre aux circonstances qu&rsquo;il est trop s\u00fbr de ma\u00eetriser. L&rsquo;exp\u00e9rience de ces derniers mois montre qu&rsquo;il n&rsquo;y parvient plus gu\u00e8re, et de moins en moins; il n&rsquo;y a aucune raison que l&rsquo;affaire START-II \u00e9chappe \u00e0 cette nouvelle r\u00e8gle en train de s&rsquo;imposer.<\/p>\n<\/p>\n<p><p>\tLes Russes sont des r\u00e9alistes (<em>bis<\/em>). Ils ont \u00e9t\u00e9 d\u00e9\u00e7us par Obama, par rapport \u00e0 la confiance qu&rsquo;ils mettaient en lui, mais sans lui faire le proc\u00e8s de mauvaises intentions. Ils constatent simplement un consid\u00e9rable affaiblissement de son pouvoir et exigent des garanties. Du coup, ils font <em>de facto<\/em> d&rsquo;Obama un homme li\u00e9 \u00e0 leur propre politique aux yeux de l&rsquo;opposition au pr\u00e9sident US, l&rsquo;affaiblissant d&rsquo;autant. Ils ont, vis-\u00e0-vis d&rsquo;Obama, une attitude compl\u00e8tement diff\u00e9rente de celles qu&rsquo;ils eurent avec Nixon (voir l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-bho-nixon_une_analogie_feconde_28_12_2009.html\" class=\"gen\">analogie<\/a> Nixon-BHO), qu&rsquo;ils soutinrent et aid\u00e8rent jusqu&rsquo;au bout malgr\u00e9 sa position d\u00e9sesp\u00e9r\u00e9e \u00e0 Washington. Cette fois, ils s&rsquo;en lavent les mains. Les temps sont bien diff\u00e9rents, o\u00f9 toutes les grandes choses ne passent plus par Washington, o\u00f9 le pr\u00e9sident US n&rsquo;est plus un partenaire privil\u00e9gi\u00e9, o\u00f9 le syst\u00e8me am\u00e9ricaniste en voie de d\u00e9sint\u00e9gration appara\u00eet de plus en plus comme une contrainte qui r\u00e9duit \u00e0 peu de choses les capacit\u00e9s d&rsquo;intervention des hommes d\u00e8s lors qu&rsquo;ils ont \u00e9cart\u00e9, comme l&rsquo;a fait BHO, la voie de l&rsquo;affrontement frontal et de la rupture avec le syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 18 janvier 2010 \u00e0 00H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les n\u00e9gociations pour le trait\u00e9 START-II de limitation des armes strat\u00e9giques entre les USA et la Russie ont repris \u00e0 Moscou. Du c\u00f4t\u00e9 US, l&rsquo;optimisme est de rigueur sinon pressant. Les d\u00e9clarations du chef de la d\u00e9l\u00e9gation US sont caract\u00e9ristiques \u00e0 cet \u00e9gard (Novosti, le 14 janvier 2010). \u00abLa Russie et les Etats-Unis parach\u00e8veront la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2858,2697,6208,6859,9150,2730,9149,3531,9097,5770,3014],"class_list":["post-71441","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-medvedev","tag-negociations","tag-obama","tag-prisonnier","tag-ratification","tag-russie","tag-salt","tag-senat","tag-start-ii","tag-strategiques","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71441"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71441\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}