{"id":71521,"date":"2010-02-04T07:52:45","date_gmt":"2010-02-04T07:52:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/04\/usa-retour-a-la-case-depart\/"},"modified":"2010-02-04T07:52:45","modified_gmt":"2010-02-04T07:52:45","slug":"usa-retour-a-la-case-depart","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/04\/usa-retour-a-la-case-depart\/","title":{"rendered":"USA, retour \u00e0 la case d\u00e9part"},"content":{"rendered":"<p><p>Tous les chefs du renseignement et des services de s\u00e9curit\u00e9 US sont d&rsquo;accord. Le terrorisme est (re)devenu la premi\u00e8re menace contre les USA. Al Qa\u00efda va frapper, certainement dans les six mois qui viennent. Cette \u00e9volution mesure l&rsquo;extraordinaire recul des \u00e9valuations am\u00e9ricanistes de la situation du monde, apr\u00e8s une br\u00e8ve am\u00e9lioration, au d\u00e9but du mandat d&rsquo;Obama, qui avait fait croire \u00e0 la possibilit\u00e9 que la nouvelle administration rompe avec la <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct qui domine les USA depuis 9\/11.<\/p>\n<\/p>\n<p><p>\tUn article du New York <em>Times<\/em> du <a href=\"http:\/\/www.nytimes.com\/2010\/02\/03\/us\/politics\/03intel.html ?\" class=\"gen\">3 f\u00e9vrier 2010<\/a> nous fait appr\u00e9cier cette \u00e9volution.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>America&rsquo;s top intelligence official told lawmakers on Tuesday that Al Qaeda and its affiliates had made it a high priority to attempt a large-scale attack on American soil within the next six months.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The assessment by Dennis C. Blair, the director of national intelligence, was much starker than his view last year, when he emphasized the considerable progress in the campaign to debilitate Al Qaeda and said that the global economic meltdown, rather than the prospect of a major terrorist attack, was the primary near-term security concern of the United States.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At Tuesday&rsquo;s hearing, Senator Dianne Feinstein, Democrat of California and chairwoman of the Senate Intelligence Committee, asked Mr. Blair to assess the possibility of an attempted attack in the United States in the next three to six months. He replied, The priority is certain, I would say  a response that was reaffirmed by the top officials of the C.I.A. and the F.B.I.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Citing a recent wave of terrorist plots, including the failed Dec. 25 attempt to blow up an airliner as it approached Detroit, Mr. Blair and other intelligence officials told a Senate panel that Al Qaeda had adjusted its tactics to more effectively strike American targets domestically and abroad. The biggest threat is not so much that we face an attack like 9\/11, said Leon E. Panetta, the C.I.A. director. It is that Al Qaeda is adapting its methods in ways that oftentimes make it difficult to detect.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As the C.I.A. continues its drone attacks aimed at Qaeda operatives in Pakistan, the officials also said that the network&rsquo;s splinter groups in Yemen and Somalia were taking on more importance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But Mr. Blair began his annual threat testimony before Congress by saying that the threat of a crippling attack on telecommunications and other computer networks was growing, as an increasingly sophisticated group of enemies had severely threatened the sometimes fragile systems undergirding the country&rsquo;s information infrastructure. Malicious cyberactivity is occurring on an unprecedented scale with extraordinary sophistication, he told the committee.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>His emphasis on the threat points up the growing concerns among American intelligence officials about the potentially devastating results of a coordinated attack on the nation&rsquo;s technology apparatus, sometimes called a cyber-Pearl Harbor.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Le d\u00e9sarroi am\u00e9ricaniste, bien plus que la perspective du ni\u00e8me complot recommenc\u00e9, n&rsquo;a jamais paru aussi fort qu&rsquo;aujourd&rsquo;hui. Les USA r\u00e9veillent une menace terroriste majeure \u00e0 partir d&rsquo;\u00e9valuations qu&rsquo;ils font eux-m\u00eames comme cons\u00e9quence, per\u00e7u inconsciemment et sans faire de rapport de cause \u00e0 effet, de leurs diverses actions d\u00e9stabilisatrices au Pakistan, au Yemen et ailleurs. En quelque sorte, ils justifient ainsi <em>a posteriori<\/em> une action g\u00e9n\u00e9rale de relance des interventions ext\u00e9rieures qui est elle-m\u00eame la cause de leur perception d&rsquo;une menace qu&rsquo;ils supposent soudain terrible et pressante, jusqu&rsquo;\u00e0 la certitude d&rsquo;une attaque terroriste contre les USA d&rsquo;ici juillet prochain (la date exacte n&rsquo;est pas donn\u00e9e, sans doute class\u00e9e secret d\u00e9fense).<\/p>\n<\/p>\n<p><p>\tDans notre texte que nous citons souvent sur la <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct, nous faisons \u00e9videmment r\u00e9f\u00e9rence \u00e0 Harlan Ullman, dans son texte du <a href=\"http:\/\/www.spacewar.com\/reports\/Outside_View_Top_national_security_threat_999.html\" class=\"gen\">27 mai 2009<\/a>, qui d\u00e9signait comme la plus grave menace pour la s\u00e9curit\u00e9 nationale US l&rsquo;incapacit\u00e9 \u00e9ventuelle de l&rsquo;administration Obama d&rsquo;abandonner cette politique. D\u00e9j\u00e0, Ullman n&rsquo;\u00e9tait pas optimiste. On voit qu&rsquo;il ne s&rsquo;est pas tromp\u00e9. L&rsquo;amiral Dennis C. Blair, qui avait <a href=\"http:\/\/www.dedefensa.org\/article-deconstruction_de_9_11_13_02_2009.html\" class=\"gen\">correctement<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-evaluation_apocalyptique_14_02_2009.html\" class=\"gen\">identifi\u00e9<\/a> il y a un an le changement n\u00e9cessaire dans l&rsquo;\u00e9valuation des menaces et des dangers, en fonction notamment de la crise financi\u00e8re mais aussi des autres crises syst\u00e9miques, revient compl\u00e8tement sur cette \u00e9valuation et retrouve la perception 9\/11. C&rsquo;est un formidable retour en arri\u00e8re, qui montre essentiellement la scl\u00e9rose extraordinaire du syst\u00e8me qui a repouss\u00e9 en six mois toute possibilit\u00e9 de r\u00e9forme radicale de son fonctionnement, de sa perception, de la force de sa pathologie psychologique.<\/p>\n<\/p>\n<p><p>\tIl est certain que la perception catastrophique que nous signalions le <a href=\"http:\/\/www.dedefensa.org\/article-la_dimension_catastrophique_de_l_attaque_contre_la_cia_en_afghanistan_13_01_2010.html\" class=\"gen\">13 janvier 2010<\/a> de l&rsquo;attaque du 29 d\u00e9cembre 2009 contre la base de la CIA en Afghanistan, a jou\u00e9 un r\u00f4le essentiel dans ce revirement de la perception de la menace. Les services de s\u00e9curit\u00e9 nationale ont surtout \u00e9t\u00e9 marqu\u00e9s par le fait que cette attaque a montr\u00e9 combien ils \u00e9taient eux-m\u00eames p\u00e9n\u00e9tr\u00e9s par des agents doubles ou triples et, en g\u00e9n\u00e9ral, par l&rsquo;habilet\u00e9 du renseignement de diverses organisations terroristes, dont le mythique Al Qa\u00efda bien entendu, avec sa capacit\u00e9 aujourd&rsquo;hui compar\u00e9e \u00e0 celle d&rsquo;une sorte de super-KGB postmoderniste. Cette d\u00e9stabilisation du renseignement US, qui est d&rsquo;abord le produit du d\u00e9sarroi du syst\u00e8me de s\u00e9curit\u00e9 nationale am\u00e9ricaniste entre ses certitudes de puissance et les \u00e9checs qu&rsquo;il essuie, est en soi une \u00e9norme victoire de ces diverses organisations et d&rsquo;Al Qa\u00efda pris comme nom g\u00e9n\u00e9rique de cette n\u00e9buleuse terroriste. Il peut \u00e9videmment se concevoir que ce m\u00eame renseignement terroriste, profitant de la voie ouverte dans la psychologie am\u00e9ricaniste, se lance d\u00e9sormais dans des op\u00e9rations d&rsquo;intoxication majeure, comme pourrait l&rsquo;\u00eatre cette annonce de la certitude d&rsquo;une attaque terroriste contre les USA d&rsquo;ici juillet 2010.<\/p>\n<\/p>\n<p><p>\tLe cas est \u00e9tonnant: ayant eu la preuve humiliante de la faiblesse et de la d\u00e9stabilisation de leurs propres services avec l&rsquo;attaque du 29 d\u00e9cembre 2009 contre la CIA, et par cons\u00e9quent de leur incapacit\u00e9 o\u00f9 ils se trouvent d&rsquo;\u00e9valuer pr\u00e9cis\u00e9ment les intentions et les capacit\u00e9s des terroristes, les m\u00eames services de renseignement US r\u00e9agissent par des affirmations presque fantasmagoriques de certitude et de pr\u00e9vision, particuli\u00e8rement dans l&rsquo;annonce d&rsquo;un \u00e9v\u00e9nement aussi al\u00e9atoire qu&rsquo;une attaque terroriste contre les USA. En quelque sorte, l&rsquo;\u00e9chec complet de leurs capacit\u00e9s d&rsquo;\u00e9valuation serait l&rsquo;argument supr\u00eame pour avancer une certitude compl\u00e8te de l&rsquo;annonce d&rsquo;un tel \u00e9v\u00e9nement. C&rsquo;est le signe le plus convaincant du d\u00e9sarroi proche de la panique d&rsquo;un syst\u00e8me qui ne peut accepter l&rsquo;id\u00e9e m\u00eame qu&rsquo;il puisse \u00eatre faillible, apr\u00e8s la d\u00e9monstration cuisante et sanglante qu&rsquo;il l&rsquo;est comme il ne l&rsquo;a jamais \u00e9t\u00e9 (Dieu sait si les r\u00e9f\u00e9rences ne manquent pas en mati\u00e8re d&rsquo;\u00e9checs de leur c\u00f4t\u00e9).<\/p>\n<\/p>\n<p><p>\tDu coup et devant de telles affirmations, on imagine qu&rsquo;il faudra bien que quelque chose de tr\u00e8s s\u00e9rieux se passe d&rsquo;ici juillet, sauf disons si Wall Street s&rsquo;effondre \u00e0 nouveau ou si Gates d\u00e9cide d&rsquo;abandonner le JSF. A la limite, bien entendu, il faudra bien qu&rsquo;on se d\u00e9cide \u00e0 organiser quelque chose dans ce sens, par exemple une nouvelle pantalonnade type <a href=\"http:\/\/www.dedefensa.org\/article-le_vol_253_et_le_paradoxe_du_complot_31_12_2009.html\" class=\"gen\">vol 253<\/a>\/<em>PantaBomber<\/em>, d&rsquo;autant qu&rsquo;il para\u00eet que le jeune terroriste captur\u00e9 a donn\u00e9 beaucoup de renseignement \u00e0 ses interrogateurs. Il y a peut-\u00eatre eu un <a href=\"http:\/\/www.dedefensa.org\/article-le_vol_253_est-il_un_coup_tordu_hypotheses_13_01_2010.html\" class=\"gen\">coup mont\u00e9<\/a> US avec cette affaire, mais on imaginerait plus volontiers, si l&rsquo;on avait l&rsquo;esprit fol\u00e2tre et malgr\u00e9 les circonstances rocambolesques de l&rsquo;affaire dont certaines \u00e9taient impr\u00e9visibles, un coup mont\u00e9 du c\u00f4t\u00e9 d&rsquo;Al Qa\u00efda pour faire capturer un apprenti-terroriste charg\u00e9 d&rsquo;intoxiquer les services US en leur annon\u00e7ant la grande attaque de juillet 2010, une sorte de ni\u00e8me Pearl Harbor l\u00e0 o\u00f9 on ne l&rsquo;attend pas du tout. Ces gens rendraient fou le syst\u00e8me, si ce n&rsquo;\u00e9tait d\u00e9j\u00e0 fait.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 f\u00e9vrier 2010 \u00e0 07H56<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les chefs du renseignement et des services de s\u00e9curit\u00e9 US sont d&rsquo;accord. Le terrorisme est (re)devenu la premi\u00e8re menace contre les USA. Al Qa\u00efda va frapper, certainement dans les six mois qui viennent. Cette \u00e9volution mesure l&rsquo;extraordinaire recul des \u00e9valuations am\u00e9ricanistes de la situation du monde, apr\u00e8s une br\u00e8ve am\u00e9lioration, au d\u00e9but du mandat&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[9068,4747,705,3104,2631,7482,8109,4390,4220,8360,8361,9237,4607,1267,8174,4584],"class_list":["post-71521","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-9068","tag-9-11","tag-blair","tag-cia","tag-de","tag-deconstruction","tag-dennis","tag-et","tag-evaluation","tag-lideologie","tag-linstinct","tag-pantabomber","tag-politique","tag-terrorisme","tag-ullman","tag-vol"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71521"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71521\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}