{"id":71527,"date":"2010-02-05T09:32:22","date_gmt":"2010-02-05T09:32:22","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/05\/nachetez-pas-la-camelote-us\/"},"modified":"2010-02-05T09:32:22","modified_gmt":"2010-02-05T09:32:22","slug":"nachetez-pas-la-camelote-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/05\/nachetez-pas-la-camelote-us\/","title":{"rendered":"N&rsquo;achetez pas la camelote US&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">N&rsquo;achetez pas la camelote US&#8230;<\/h2>\n<\/p>\n<p><p>On appr\u00e9ciera l&rsquo;ironie de la situation. Les USA annoncent qu&rsquo;ils vont livrer aux \u00e9mirats du Golfe des armements suppl\u00e9mentaires importants, essentiellement des missiles <em>Patriot<\/em>, pour leur d\u00e9fense contre l&rsquo;Iran. L&rsquo;Iran intervient (AFP, relay\u00e9e par <em>Spacewar.com<\/em>, le <a class=\"gen\" href=\"http:\/\/www.spacewar.com\/reports\/Iran_tells_Gulf_states_not_to_buy_ineffective_US_missiles_999.html\">5 f\u00e9vrier 2010<\/a>), par les voix de plusieurs de ses militaires, pour \u00ab\u00a0conseiller\u00a0\u00bb aux pays du Golfe: n&rsquo;achetez pas la quincaillerie US, elle ne marche pas. Les <em>Patriot<\/em> abattent en priorit\u00e9 les avions amis, et nous avons des syst\u00e8mes qui neutralisent les h\u00e9licopt\u00e8res US d&rsquo;attaque <em>Apache<\/em>. Pour un peu, les g\u00e9n\u00e9raux et autres autres Gardes R\u00e9volutionnaires iraniens ajouteraient: si vous voulez vous d\u00e9fendre contre nous, faites comme nous, essayez d&rsquo;acheter des S-300 russes, tellement plus efficaces que les <em>Patriot<\/em>&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>A senior Iranian military official told Gulf states on Thursday not to squander money on US missiles, boasting that Iran can render them useless, the state news agency IRNA reported. Tehran had on Wednesday slammed plans by the United States to beef up defences in the Gulf against potential Iranian missile attacks, with the Islamic republic insisting it posed no threat to its neighbours.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0Installing anti-missile Patriot missiles is a new trick to empty the pockets of rich Persian Gulf countries,\u00a0\u00bb said General Hassan Firuzabadi, the joint chief of staff of Iran&rsquo;s armed forces. \u00ab\u00a0Patriot missiles can be rendered ineffective by simple tactics, and I advise the regional countries, especially Islamic states, not to waste their money on these missiles which have not worked anywhere,\u00a0\u00bb he said.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>US President Barack Obama&rsquo;s administration is reportedly placing ships with missile-targeting capabilities off Iran&rsquo;s coast, and anti-missile systems in at least four Gulf states &ndash; Bahrain, Kuwait, Qatar and the United Arab Emirates.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>An Iranian Revolutionary Guards official also said on Wednesday that Iran had developed anti-armor weapons which can combat US Apache helicopters and armored tanks.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0The enemy should not think their Apache helicopters can have the same power that they have in Iraq and Afghanistan in Iran,\u00a0\u00bb Naser Arab-beigi, who heads the self-sufficiency organization of the Revolutionary Guards, told Fars news agency. \u00ab\u00a0We will end Apache power by our measures. Their armored tanks will be met with the firm response of our weapons,\u00a0\u00bb he said.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Les pays du Golfe, qui se voient ainsi impos\u00e9s par les USA un surarmement suppl\u00e9mentaire, tentent d\u00e9sesp\u00e9r\u00e9ment et assez comiquement de convaincre l&rsquo;Iran que ce surarmement n&rsquo;est pas pour se d\u00e9fendre contre lui. (&laquo;<em>US ally Bahrain acknowledged on Wednesday that Gulf military defences were being upgraded but urged Iran not to see them as plans for attack.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>L&rsquo;attaque (dialectique, s&rsquo;entend) est malicieuse, m\u00eame si elle l&rsquo;est involontairement. En effet, les USA \u00ab\u00a0imposent\u00a0\u00bb, pas d&rsquo;autres mots, un lot suppl\u00e9mentaires pour une pinc\u00e9e de $milliards (autour de 7, plus dit-on) d&rsquo;un missile sol-air dont <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-d_une_guerre_du_golfe_l_autre_le_roman_et_virtualiste_du_patriot_21_04_2003.html?admin=1\">l&rsquo;inefficacit\u00e9<\/a>, sauf contre les avions amis, semble l&rsquo;un des titres de sa gloire promotionnelle les plus constants. L&rsquo;attaque est d&rsquo;autant plus malicieuse que, pendant ce temps, le principal pays et alli\u00e9 des USA dans la r\u00e9gion, l&rsquo;Arabie Saoudite, est en train de n\u00e9gocier avec les Russes un achat important de missiles sol-air S-300, et peut-\u00eatre S-400, r\u00e9put\u00e9s comme les meilleurs du monde &ndash; envisageant de ce fait d&rsquo;effectuer un changement important de sa politique d&rsquo;armement (jusqu&rsquo;alors \u00e0 orientation fondamentale US, sinon anglo-saxonne), aussi bien \u00e0 signification politique que technique. Les Saoudiens sont de plus en plus convaincus de l&rsquo;inefficacit\u00e9 des <em>Patriot<\/em>, et cette attitude rend d&rsquo;autant plus malais\u00e9 l&rsquo;\u00e9tat d&rsquo;esprit des pays du Golfe qui vont devoir \u00e0 nouveau se gaver de <em>Patriot<\/em>. (Car, tout le monde, dans ce riche univers schizophr\u00e9nique, continue tout de m\u00eame \u00e0 avoir peur de son ombre, notamment iranienne.)<\/p>\n<\/p>\n<p><p>Les Iraniens, eux, ne cachent pas non plus toute l&rsquo;estime qu&rsquo;ils ont pour les S-300 et S-400 russes. Il y a depuis trois ans une course-poursuite \u00e9pique autour de la vente \u00e9ventuelle de ces syst\u00e8mes \u00e0 l&rsquo;Iran, que les Russes d\u00e9mentent \u00e0 intervalles r\u00e9guliers, avant de laisser aller des fuites sur une possible livraison malgr\u00e9 tout. Les Isra\u00e9liens sont affol\u00e9s par cette perspective, eux qui ne r\u00eavent que d&rsquo;attaquer l&rsquo;Iran par les airs et jugent les S-300 redoutables d&rsquo;efficacit\u00e9; Netanyahou, qui va en Russie ce mois-ci, implorera une fois de plus les Russes de ne pas vendre des S-300 \u00e0 l&rsquo;Iran. On dit que le soudain <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-securite_europeenne_mode_defensif_agressif_05_02_2010.html\">refroidissement<\/a> USA-Russie, et la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_traitement_des_usa_par_la_russie_27_01_2010.html\">hargne<\/a> des Russes contre les USA, pourraient bien ramener dans l&rsquo;actualit\u00e9 la possibilit\u00e9 de la vente de S-300 \u00e0 l&rsquo;Iran. Que ne dit-on pas&hellip;<\/p>\n<\/p>\n<p><p>Cette affaire de quincaillerie est aussi un fort enjeu politique. On voit bien les enjeux directement politiques sur les relations et attitudes des divers pays concern\u00e9s, mais nous voulons surtout parler des effets politiques de la question m\u00eame, technique et op\u00e9rationnelle, autour de ces syst\u00e8mes d&rsquo;arme. Il est vrai que la pr\u00e9tendue qualit\u00e9 quasi surhumaine des armements US commence \u00e0 \u00eatre redoutablement mise en question. Nous parlons souvent du JSF, bien s&ucirc;r, mais il y a d&rsquo;autres domaines affect\u00e9s du m\u00eame d\u00e9sordre, qui commence \u00e0 faire d\u00e9sordre &ndash; et la mauvaise r\u00e9putation du <em>Patriot<\/em> commence \u00e0 \u00eatre prise au mot. Ce syst\u00e8me, notoirement inefficace et m\u00eame dangereux (il a d\u00e9j\u00e0 abattu un nombre assez cons\u00e9quent d&rsquo;avions amis), est pourtant le fer de lance des pressions diplomatico-militaires US, soutenus par les actionnaires des firmes US concern\u00e9s (particuli\u00e8rement Raytheon), aupr\u00e8s des pays \u00ab\u00a0alli\u00e9s\u00a0\u00bb qu&rsquo;il s&rsquo;agit de d\u00e9fendre contre les multiples attaques qu&rsquo;on pr\u00e9voit depuis des d\u00e9cennies. Le <em>Patriot<\/em> est le st\u00e9r\u00e9otype de cette diplomatie militaris\u00e9e du syst\u00e8me de l&rsquo;am\u00e9ricanisme qui prend en compte syst\u00e9matiquement les int\u00e9r\u00eats de l&rsquo;industrie d&rsquo;armement concern\u00e9e. Aujourd&rsquo;hui, notamment gr\u00e2ce \u00e0 la r\u00e9putation des nouveaux syst\u00e8mes russes, la r\u00e9putation catastrophique du <em>Patriot<\/em> commence \u00e0 \u00eatre un handicap assez lourd. Bien entendu, les USA ne sont pas au courant.<\/p>\n<\/p>\n<p><p>Il est certain que les d\u00e9clarations iraniennes seront entendues, autant par les pays du Golfe que par les Russes, et il n&rsquo;est pas assur\u00e9 que la vente \u00ab\u00a0impos\u00e9e\u00a0\u00bb par Washington soit r\u00e9alis\u00e9e sans complication, dans tous les cas dans son enti\u00e8ret\u00e9. Il n&rsquo;est pas assur\u00e9 que l&rsquo;un ou l&rsquo;autre pays du Golfe, se pr\u00e9valant de l&rsquo;exemple saoudien et estimant qu&rsquo;un accord avec les Russes aurait l&rsquo;avantage de se rapprocher politiquement d&rsquo;un pays qui a de l&rsquo;influence sur l&rsquo;Iran, ne rechigne finalement \u00e0 cet achat forc\u00e9 et commence \u00e0 envisager de se tourner vers la Russie. L&rsquo;avantage th\u00e9orique serait celui d&rsquo;une d\u00e9fense plus s&ucirc;re, cette fois approuv\u00e9e par les Iraniens (!) qui trouvent bien du charme au S-300, et de l&rsquo;esp\u00e9rance que la Russie fasse montre de son influence pour freiner les ardeurs offensives des Iraniens contre les pays du Golfe &ndash; \u00ab\u00a0ardeurs offensives\u00a0\u00bb qui sont, par ailleurs, de la pure imagination des strat\u00e8ges du Pentagone et des directeurs de la communication de Raytheon &ndash; \u00e0 moins, bien s&ucirc;r, qu&rsquo;entre temps, il prenne \u00e0 Isra\u00ebl ou aux USA la fine id\u00e9e d&rsquo;attaquer l&rsquo;Iran. Bien entendu, ce genre d&rsquo;h\u00e9sitation vis-\u00e0-vis du <em>Patriot<\/em> qu&rsquo;on \u00e9voque ici n&rsquo;est que du domaine de la supputation des int\u00e9ress\u00e9s et aura surtout pour effet imm\u00e9diat d&rsquo;introduire le doute et le trouble dans les relations entre ces pays \u00ab\u00a0alli\u00e9s\u00a0\u00bb du Golfe et les USA.<\/p>\n<\/p>\n<p><p>La mise en cause des capacit\u00e9s de l&rsquo;<em>Apache<\/em> inqui\u00e9tera aussi les \u00ab\u00a0clients\u00a0\u00bb des USA dans la r\u00e9gion, qui regorgent de cet h\u00e9licopt\u00e8re d&rsquo;attaque extr\u00eamement cher, dont la technologie remonte aux ann\u00e9es 1980 et qui est, pour cette raison, constamment alourdie de modernisation co&ucirc;teuses et peu int\u00e9gr\u00e9es. Tout cela implique une offensive de communication contre la qualit\u00e9 des armements US, qui peut constituer un \u00e9l\u00e9ment important tant une part tr\u00e8s grande de l&rsquo;influence et des restes de la \u00ab\u00a0diplomatie\u00a0\u00bb des USA repose effectivement sur le prestige de la quincaillerie militaire de cette puissance. La paralysie des forces arm\u00e9es US autant que les avatars sans nombre du Pentagone dans le d\u00e9veloppement des syst\u00e8mes commencent \u00e0 peser lourd dans la perception qu&rsquo;on a de la puissance de cette quincaillerie, cela coupl\u00e9 bien entendu avec le d\u00e9clin g\u00e9n\u00e9ral de la puissance US depuis la crise du 15 septembre 2008.<\/p>\n<\/p>\n<p><p>Mis en ligne le 5 f\u00e9vrier 2010 \u00e0 09H34<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N&rsquo;achetez pas la camelote US&#8230; On appr\u00e9ciera l&rsquo;ironie de la situation. Les USA annoncent qu&rsquo;ils vont livrer aux \u00e9mirats du Golfe des armements suppl\u00e9mentaires importants, essentiellement des missiles Patriot, pour leur d\u00e9fense contre l&rsquo;Iran. L&rsquo;Iran intervient (AFP, relay\u00e9e par Spacewar.com, le 5 f\u00e9vrier 2010), par les voix de plusieurs de ses militaires, pour \u00ab\u00a0conseiller\u00a0\u00bb aux&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4989,3259,3723,2773,2970,3950,8636,2730,8446,8289,3558,3959],"class_list":["post-71527","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-apache","tag-arabie","tag-golfe","tag-iran","tag-missiles","tag-patriot","tag-quincaillerie","tag-russie","tag-s-300","tag-s-400","tag-saoudite","tag-sol-air"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71527"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71527\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}