{"id":71562,"date":"2010-02-15T16:57:36","date_gmt":"2010-02-15T16:57:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/15\/une-blitzkrieg-bavarde\/"},"modified":"2010-02-15T16:57:36","modified_gmt":"2010-02-15T16:57:36","slug":"une-blitzkrieg-bavarde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/15\/une-blitzkrieg-bavarde\/","title":{"rendered":"Une <em>blitzkrieg<\/em> bavarde"},"content":{"rendered":"<p><h2 class=\"common-article\">Une <em>blitzkrieg<\/em> bavarde<\/h2>\n<\/p>\n<p><p>\t15 f\u00e9vrier 2010  L&rsquo;offensive baptis\u00e9e <em>Operation Moshtarak<\/em>,  cela voudrait dire, para\u00eet-il, quelque chose comme Op\u00e9ration Ensemble, habile clin d&rsquo;il \u00e0 l&rsquo;Afghan moyen, vous en conviendrez,  se d\u00e9roule conform\u00e9ment au plan pr\u00e9vu. Cette formule rituelle de l&rsquo;URSS des ann\u00e9es brejn\u00e9viennes et de l&rsquo;Arm\u00e9e Rouge en Afghanistan fait parfaitement l&rsquo;affaire de nos vaillantes phalanges am\u00e9ricanistes, otaniennes et occidentalistes.<\/p>\n<\/p>\n<p><p>\t Pour commencer, on citera une d\u00e9p\u00eache de Novosti du <a href=\"http:\/\/fr.rian.ru\/world\/20100214\/186055310.html\" class=\"gen\">14 f\u00e9vrier 2010<\/a> qui pourrait para\u00eetre assez comique,  ironie volontaire, qui sait,  dans sa concision et les termes employ\u00e9s qui t\u00e9moignent \u00e0 la fois, du chef des \u00e9normes moyens mis en uvre et du battage autour de l&rsquo;affaire, d&rsquo;une lenteur extr\u00eame d&rsquo;une ex\u00e9cution dont le rythme semblerait pourtant aussi ambitieux qu&rsquo;un \u00e9clair, de r\u00e9sultats proches de l&rsquo;enfoncement des portes ouvertes et d&rsquo;une activit\u00e9 guerri\u00e8re approchant l&rsquo;accouchement d&rsquo;une souris malingre par l&rsquo;Himalaya am\u00e9ricaniste<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le deuxi\u00e8me stade de l&rsquo;op\u00e9ration anti taliban Mushtarak (Ensemble, en dari) qui r\u00e9unit plus de 14.000 militaires \u00e9trangers et afghans, se d\u00e9roule sans succ\u00e8s particuliers de la coalition, annonce dimanche le correspondant de RIA Novosti sur place. Le premier stade de l&rsquo;op\u00e9ration, lanc\u00e9e mardi, s&rsquo;est achev\u00e9 vendredi pour permettre de commencer le deuxi\u00e8me stade. A part les militaires afghans, les troupes am\u00e9ricaines, britanniques, canadiennes, danoises et estoniennes prennent part \u00e0 l&rsquo;op\u00e9ration, \u00e9tant soutenues par plus de 60  h\u00e9licopt\u00e8res et chasseurs. L&rsquo;objectif du premier stade \u00e9tait d&rsquo;encercler les villes Marjah et Nad Ali de la province du Helmand, le deuxi\u00e8me stade consistant \u00e0 les occuper. Le troisi\u00e8me stade pr\u00e9voit la cr\u00e9ation d&rsquo;organes du pouvoir sur place.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t D&rsquo;une fa\u00e7on assez r\u00e9v\u00e9latrice, le <em>Times<\/em>, pourtant bien prompt \u00e0 applaudir la soldatesque de la libert\u00e9, montre dans un petit billet du <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/afghanistan\/article7026984.ece\" class=\"gen\">15 f\u00e9vrier 2010<\/a> de sa correspondante pour les questions de d\u00e9fense Deborah Haynes, un r\u00e9el scepticisme qui a des allures de d\u00e9senchantement. La bataille a \u00e9t\u00e9 gagn\u00e9e puisque les m\u00e9dias ont annonc\u00e9 la victoire avant m\u00eame que la bataille ait commenc\u00e9, et se pose d\u00e9sormais la question de savoir si la bataille sera gagn\u00e9e au bout du compte, et si d&rsquo;ailleurs la bataille est vraiment une bataille D&rsquo;ailleurs, tout ce charabia redondant n&rsquo;est pas nouveau.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>American commanders in Iraq used similar tactics before large-scale offensives with the Iraqi Army against al-Qaeda strongholds in Diyala, northeast of Baghdad. The pre-emptive warnings, followed by impressive shows of combat power, would typically be met with minimal resistance and result in hundreds of arrests  although many detainees would be released subsequently. Declarations of success would be made and the operation would drop off the headlines<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, effectivement, tout se d\u00e9roule conform\u00e9ment au plan pr\u00e9vu, y compris la victoire: \u00ab<em>Afghan civilians know what is coming, the public at home know to expect fresh casualties and the Taleban, who were always going to be outgunned, are beaten in a very public way. The key, however, is what happens next.<\/em> [] <em>Back in Helmand, the true test of Operation Moshtarak will come a year from now when Nato and Afghan forces will have had time to secure the territory, talk to local people and start reconstruction work. It remains to be seen whether anyone will be watching.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Il y a eu, bien entendu, l&rsquo;habituelle bavure, avec 12 civils tu\u00e9s par un tir qu&rsquo;on suppose affreusement malencontreux. <em>The Independent<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/feb\/14\/nato-rockets-kill-afghan-civilians<D\" class=\"gen\">15 f\u00e9vrier 2010<\/a> nous fait part de la d\u00e9vastation et de la tristesse des chefs militaires am\u00e9ricanistes et occidentalistes, et puis l&rsquo;amusante et opportune je m&rsquo;en lave les mains du type c&rsquo;est pas moi, c&rsquo;est le cousin des Britanniques : \u00ab<em>A Ministry of Defence spokeswoman said the rockets, which were fired by a sophisticated missile system, were a US responsibility.<\/em> [] <em>News of the deaths overshadowed cautiously optimistic reports from US commanders in nearby Marjah, a major hub of insurgents and drug smugglers<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Hier, <a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/feb\/14\/coalition-forces-taliban-retreat\" class=\"gen\">14 f\u00e9vrier 2010<\/a>, le <em>Guardian<\/em> parlait de retraite des talibans, comme si on jouait \u00e0 la vraie guerre : \u00ab<em>Coalition troops force Taliban retreat from key stronghold. Meticulous operation achieves its military objectives with minimal casualties<\/em>\u00bb. Certes, mais certains s&rsquo;\u00e9tonnaient, dans le cours de l&rsquo;offensive, comme Steve Clemons le <a href=\"http:\/\/www.thewashingtonnote.com\/archives\/2010\/02\/like_the_viet_c\/\" class=\"gen\">13 f\u00e9vrier 2010<\/a>, sur <em>The Washington Note<\/em>, en citant un article du New York <em>Times<\/em> du m\u00eame <a href=\"http:\/\/www.nytimes.com\/2010\/02\/14\/world\/asia\/14afghan.html?pagewanted=print\" class=\"gen\">13 f\u00e9vrier 2010<\/a>, de la tactique suivie et des r\u00e9sultats obtenus (\u00ab<em>Like the Viet Cong? Where Did Taliban Disappear To?<\/em>\u00bb). <\/p>\n<\/p>\n<p><p>\t\u00ab<em>There is a potentially eery, disconcerting passage in Dexter Filkins&rsquo; interesting report on the Afghan, British and American push into the Taliban stronghold of Marja in Helmand Province. Filkins notes that the opposition didn&rsquo;t really materialize, despite reports that they had recently received reinforcements. This may mean that the Taliban are tactically disappearing into the population, a move that the US also saw when fighting in Vietnam.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On the first full day of operations, much of the expected Taliban resistance failed to materialize. Afghan and NATO troops discovered some bombs, narcotics and weapons caches, but the fighting itself was relatively desultory. There was certainly none of the eyeball-to-eyeball fighting that typified the battle for Falluja in Iraq in 2004, to which the invasion of Marja had been compared.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Abdul Rahim Wardak, the Afghan defense minister, said in a news conference in Kabul that the Afghan Army had suffered no dead at all, and only a handful of wounded. He seemed a little surprised at the day&rsquo;s events. Actually, the resistance is not there,&rsquo; Mr. Wardak said. Based on our intelligence reports, some of the Taliban have left the area. But we still expected there to be several hundred in the area. Just yesterday, we received reports that reinforcements had arrived from neighboring provinces.&rsquo;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Tout de m\u00eame, le <em>Guardian<\/em> cit\u00e9 plus haut a, ce <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2010\/feb\/15\/afghanistan-offensive-obama-strategy-flawed\" class=\"gen\">15 f\u00e9vrier 2010<\/a>, un \u00e9ditorial appropri\u00e9, qui commence par ce paragraphe sur la nouvelle recette miracle du maitre queux (*) McChrystal (quatre \u00e9toiles, plus qu&rsquo;au Michelin), vous offrant un gouvernement d\u00e9mocratique en poudre qu&rsquo;il suffit d&rsquo;arroser d&rsquo;un peu d&rsquo;eau pour l&rsquo;installer \u00e0 Marjah: \u00ab<em>It is difficult to have confidence in a general who sets himself up so obviously for a fall. Among the many nonsenses uttered about the long-heralded offensive against the walled town of Marjah in Helmand yesterday was the claim by the US commander, General Stanley McChrystal, that he had an Afghan administration that would be brought to life in the newly liberated areas in a box, ready to roll in. From the army that gave us meals ready to eat, comes a new product. It is called governments ready to govern. All you do is add water. If such a thing did exist, it has got unlimited potential in a global market of failed states.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Il est tristement ironique, \u00e9crivons-nous <a href=\"http:\/\/www.dedefensa.org\/article-ce_que_pense_de_nous_celle_pour_laquelle_nous_nous_battons__15_02_2010.html?admin=1\" class=\"gen\">par ailleurs<\/a> dans notre rubrique <em>Ouverture libre<\/em> de lire ce que pense Malalai Joya, d\u00e9put\u00e9e afghane et f\u00e9ministe, en un mot la personne embl\u00e9matique pour laquelle tous les salons parisiens et adjacents sont partis en croisade en Afghanistan \u00ab<em>It is ridiculous<\/em>\u00bb dit-elle, cela \u00e0 propos de la strat\u00e9gie de l&rsquo;OTAN, de notre grande guerre et du g\u00e9nial g\u00e9n\u00e9ral McChrystal. <\/p>\n<\/p>\n<p><p>\t Que dire l\u00e0-dessus, du point de vue de la guerre, de l&rsquo;aspect op\u00e9rationnel, de cette doctrine-miracle du g\u00e9n\u00e9ral McChrystal, nomm\u00e9e contre-insurrection? R\u00e9inventent-il la roue, ou bien inventent-ils le fil \u00e0 couper le beurre? Pas du tout, car la roue est de forme pentagonale (5 c\u00f4t\u00e9s, comme le Pentagone, et non un cercle), et le beurre est ind\u00e9tectable par les <em>drones<\/em> \u00e0 quelques dizaines de $millions l&rsquo;unit\u00e9 (barda compris), en attendant les JSF. Que dire l\u00e0-dessus sinon qu&rsquo;on reste sans voix devant le d\u00e9roulement des op\u00e9rations, la pompe et l&#8217;emphase de la chose militaire qui se maquille en humanitaire, les th\u00e9ories compass\u00e9es et tr\u00e8s philosophiquement arrang\u00e9es qui accompagnent les explications. L&rsquo;offensive finale du g\u00e9n\u00e9ral McChrystal ayant abouti pour l&rsquo;instant \u00e0 la mort r\u00e9pertori\u00e9 de quelques dizaines de talibans ou baptis\u00e9s tels, de quelques soldats des forces coalis\u00e9es de la libert\u00e9, en plus des 12 civils de la bavure qui appara\u00eet comme le minimum syndical de la circonstance, on cherche d\u00e9sesp\u00e9r\u00e9ment un mot \u00e0 accoler \u00e0 cette chose informe que d&rsquo;aucuns osent nommer (nous aussi, parfois, c\u00e9dant \u00e0 la facilit\u00e9) la guerre en Afghanistan.<\/p>\n<\/p>\n<p><p>\tMcChrystal et l&rsquo;OTAN ont donc repris, ou sont en train de le faire, une ville, voire une r\u00e9gion que personne ne tenait \u00e0 d\u00e9fendre vraiment selon le sens militaire conventionnel du terme d\u00e9fendre, pour y installer une administration qui doit d\u00e9j\u00e0 figurer sur les listes des donations habituelles pour r\u00e9pondre aux normes de la corruption de ce chaos, et o\u00f9, sans doute, des talibans seront tr\u00e8s vite int\u00e9gr\u00e9s sous peine de repr\u00e9sailles, tout cela apr\u00e8s que les forces occidentalistes, am\u00e9ricanistes et victorieuses auront quitt\u00e9 les lieux,  justice ainsi faite. Jusqu&rsquo;ici, selon certaines \u00e9valuations, l&rsquo;op\u00e9ration lanc\u00e9e par le g\u00e9n\u00e9ral McChrystal depuis moins d&rsquo;une semaine a largement d\u00e9pass\u00e9 le $milliard en frais de fonctionnement. On ne l\u00e9sine pas avec la d\u00e9mocratie en poudre.<\/p>\n<\/p>\n<p><p>\tLa nouvelle tactique de la contre-insurrection, \u00e0 ne pas confondre avec la contre-gu\u00e9rilla, combine curieusement la d\u00e9monstration de l&rsquo;utilit\u00e9 de tous les mat\u00e9riels ultra-sophistiqu\u00e9s que commande r\u00e9guli\u00e8rement le Pentagone,  car la sophistication a jou\u00e9 un grand r\u00f4le dans la d\u00e9termination et la surveillance d&rsquo;objectifs nombreux et importants, et de toutes les fa\u00e7ons d\u00e9sert\u00e9s par un ennemi qui ne se soucie gu\u00e8re d&rsquo;un affrontements en terrain d\u00e9couvert o\u00f9 il est surclass\u00e9 par la puissance de feu,  et l&rsquo;affirmation que les forces arm\u00e9es US ma\u00eetrisent parfaitement la guerre psychologique consistant \u00e0 gagner, si possible en dialecte local, les curs et les esprits des populations locales. Cette nouvelle tactique est d&rsquo;ailleurs remarquablement \u00e9prouv\u00e9e, ce qui fait s&rsquo;interroger sur sa nouveaut\u00e9,  comme le montre le court billet du <em>Times<\/em> qui nous rapporte avec minutie combien tout cela a d\u00e9j\u00e0 ex\u00e9cut\u00e9 en Irak, avec l&rsquo;incontestable succ\u00e8s qu&rsquo;il est interdit de contester (\u00ab<em>American commanders in Iraq used similar tactics before large-scale offensives with the Iraqi Army against al-Qaeda strongholds in Diyala, northeast of Baghdad<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tQuant au comportement des talibans, il \u00e9tait non seulement \u00e9ventuellement pr\u00e9visible mais quasiment programm\u00e9 dans la fa\u00e7on dont l&rsquo;offensive a \u00e9t\u00e9 pr\u00e9par\u00e9e et annonc\u00e9. Il renvoie bien \u00e9videmment au mod\u00e8le dit asym\u00e9trique, aussi vieux qu&rsquo;existe cette sorte de guerre de partisan contre des arm\u00e9es conventionnelles. Le parall\u00e8le que Clemons fait avec le Vietnam pourrait valoir pour de nombreux autres conflits, en remontant tr\u00e8s loin dans l&rsquo;histoire. L&rsquo;\u00e9tat-major des forces coalis\u00e9es explique que c&rsquo;\u00e9tait le but recherch\u00e9 par l&rsquo;offensive, comme nul n&rsquo;en a jamais dout\u00e9. Il s&rsquo;agissait donc de monter, non pas une offensive militaire, mais un sc\u00e9nario cin\u00e9matographique, ou bien disons hollywoodien, qui puisse d\u00e9sormais figurer dans les rapports internes du Pentagone comme la victoire de Marjah.<\/p>\n<\/p>\n<p><p>\tPour autant, on ne peut pas pr\u00e9tendre que cette offensive ne marque pas un temps nouveau important de ce qu&rsquo;on doit \u00e9videmment refuser d\u00e9sormais de nommer l&rsquo;art de la guerre, de ce qu&rsquo;on doit m\u00eame h\u00e9siter \u00e0 nommer encore la science de la guerre,  de ce que l&rsquo;on nommerait donc plut\u00f4t d\u00e9sormais les relations publiques de la guerre, du terme anglo-saxon de <em>public relations<\/em>, ou PR, ou la publicit\u00e9 de la guerre,  mais non sans une certaine g\u00eane, avec ces deux derni\u00e8res expressions. L&rsquo;expression la publicit\u00e9 de la guerre pourrait faire croire qu&rsquo;il s&rsquo;agit de faire la publicit\u00e9 de la guerre; ce n&rsquo;est pas le cas; il s&rsquo;agit de signifier que la guerre est elle-m\u00eame devenue une activit\u00e9 de publicit\u00e9, relevant de la publicit\u00e9 (<em>advertising<\/em>) <\/p>\n<h3>La strat\u00e9gie devenue publicit\u00e9 pure<\/h3>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de cette offensive se trouve donc dans tout ce qui a pr\u00e9c\u00e9d\u00e9, tout ce qui l&rsquo;a accompagn\u00e9, dans la pr\u00e9sentation qui en a \u00e9t\u00e9 faite, dans la pr\u00e9sentation qui sera faite de la suite, tout cela sans aucun rapport avec la r\u00e9alit\u00e9 op\u00e9rationnelle. On peut m\u00eame aller jusqu&rsquo;\u00e0 se demander si quelque chose comme la r\u00e9alit\u00e9 op\u00e9rationnelle existe encore, et si tout cet environnement, avant, pendant et autour, ne repr\u00e9sente pas l&rsquo;essentiel de la r\u00e9alit\u00e9 op\u00e9rationnelle,  avec au terme, effectivement, l&rsquo;op\u00e9ration elle-m\u00eame, comme simple concr\u00e9tisation du reste,  en esp\u00e9rant qu&rsquo;aucun incident f\u00e2cheux ne survienne en chemin faisant.<\/p>\n<\/p>\n<p><p>\tL&rsquo;offensive a \u00e9t\u00e9 annonc\u00e9e et v\u00e9ritablement lanc\u00e9e, en termes d&rsquo;annonce, comme l&rsquo;est une campagne publicitaire. Nous parlons bien du lancement d&rsquo;une campagne publicitaire, qu&rsquo;il faut bien entendu et imp\u00e9rativement diff\u00e9rencier du lancement de l&rsquo;offensive sur le terrain, le premier lancement ayant pr\u00e9c\u00e9d\u00e9 de deux \u00e0 trois semaines l&rsquo;op\u00e9ration sur le terrain. D&rsquo;une certaine fa\u00e7on, il \u00e9tait implicitement demand\u00e9 aux talibans et aux autres groupes de r\u00e9sistance d&rsquo;agir comme ils l&rsquo;ont fait, et comme ils le font toujours dans cette sorte de circonstances,  c&rsquo;est-\u00e0-dire d&rsquo;abandonner l&rsquo;essentiel du terrain qui leur \u00e9tait conc\u00e9d\u00e9 (sans qu&rsquo;ils l&rsquo;occupassent vraiment). L&rsquo;important, en termes de relations publiques, \u00e9tait qu&rsquo;il exist\u00e2t une circonstance que l&rsquo;on pourrait d\u00e9signer comme l&rsquo;attaque et la prise de la ville de Marjah, puis, tr\u00e8s vite, renomm\u00e9e comme la victoire de Marjah. Effectivement, l&rsquo;id\u00e9e devrait tr\u00e8s vite s&rsquo;installer qu&rsquo;il y a eu l&rsquo;attaque et la prise de la ville de Marjah, c&rsquo;est-\u00e0-dire la victoire de Marjah.<\/p>\n<\/p>\n<p><p>\tCette offensive a donc \u00e9t\u00e9 pr\u00e9par\u00e9e essentiellement par les services de communication et de relations publiques des forces arm\u00e9es, et essentiellement du Pentagone. Le facteur tactique de l&rsquo;op\u00e9ration, le d\u00e9placement et les objectifs des unit\u00e9s, etc., n&rsquo;ont eu qu&rsquo;\u00e0 s&rsquo;adapter aux consignes des services de communication qui avaient planifi\u00e9 l&rsquo;offensive publicitaire et de relations publiques de Marjah.<\/p>\n<\/p>\n<p><p>\tDe ce point de vue, on pourrait commencer \u00e0 se demander si une v\u00e9ritable guerre conventionnelle est aujourd&rsquo;hui encore possible, surtout sinon essentiellement dans le contexte du syst\u00e8me de l&rsquo;am\u00e9ricanisme o\u00f9 la communication joue un r\u00f4le absolument essentiel. La diff\u00e9rence, pour l&rsquo;instant, c&rsquo;est-\u00e0-dire la s\u00e9curit\u00e9 fondamentale des forces engag\u00e9es pour faire la figuration de l&rsquo;offensive publicitaire et de communication, est assur\u00e9e par l&rsquo;\u00e9norme sup\u00e9riorit\u00e9 en puissance de feu brute (<em>brute force<\/em>) des forces arm\u00e9es am\u00e9ricanistes. Pour autant, cette garantie n&rsquo;est pas absolue, et un incident pourrait survenir un jour, prenant en d\u00e9faut ce dispositif de s\u00e9curit\u00e9 par la force brute, et infligeant une r\u00e9elle et sanglante d\u00e9faite op\u00e9rationnelle \u00e0 la force brute. Il n&rsquo;en faudrait d&rsquo;ailleurs pas beaucoup, selon les normes massacreuses de la guerre que nous avons l&rsquo;habitude de solliciter: une compagnie tombant dans une embuscade, trois ou quatre h\u00e9licopt\u00e8res d\u00e9truits, entre 50 et 100 morts et ce serait toute la strat\u00e9gie de relations publiques qui s&rsquo;effondrerait, et une crise telle \u00e0 Washington qu&rsquo;on pourrait arriver \u00e0 un point de rupture de la guerre (c&rsquo;est-\u00e0-dire, essentiellement, la possibilit\u00e9 d&rsquo;un retrait en d\u00e9bandade).<\/p>\n<\/p>\n<p><p>\tLa deuxi\u00e8me guerre du Liban de juillet-ao\u00fbt 2006 o\u00f9 la brillantissime <em>Tsahal<\/em> isra\u00e9lienne avait essuy\u00e9, selon ses propres normes et sa sup\u00e9riorit\u00e9 de feu et de manuvre conventionnelle, une s\u00e9v\u00e8re correction de la part du Hezbollah, \u00e9tait le premier signe de la d\u00e9g\u00e9n\u00e9rescence entr\u00e9e en phase active de la puissance militaire occidentaliste, d&rsquo;inspiration directement am\u00e9ricaniste. (Dans ce cas, effectivement, nous consid\u00e9rons <em>Tsahal<\/em>, alors plus justement d\u00e9sign\u00e9e comme l&rsquo;<em>Israelian Defense Force<\/em>, ou IDF, comme une <a href=\"http:\/\/www.dedefensa.org\/article-qui_commande_en_israel_et_8747_17_07_2006.html\" class=\"gen\">annexe<\/a> du <a href=\"http:\/\/www.dedefensa.org\/article-l_ombre_civilisatrice_de_curtiss_lemay_02_08_2006.html?admin=1\" class=\"gen\">Pentagone<\/a> et rien d&rsquo;autre.) L&rsquo;enseignement valait pour le volet op\u00e9rationnel pur, et il \u00e9tait particuli\u00e8rement pr\u00e9occupant. L&rsquo;offensive de Marjah en Afghanistan tend \u00e0 constituer un deuxi\u00e8me volet de cette d\u00e9g\u00e9n\u00e9rescence, sans doute largement influenc\u00e9 par les cons\u00e9quences induites du premier (IDF <em>versus<\/em> Hezbollah), qui est celui du refus de l&rsquo;op\u00e9rationnalit\u00e9 de la guerre, o\u00f9 la strat\u00e9gie et la tactique sont transmises aux services publicitaires et de relations publiques. On comprend qu&rsquo;en combinant ces deux \u00e9l\u00e9ments, un accident inattendu du fonctionnement de ces non-arm\u00e9es surpuissantes engag\u00e9es dans des guerres marqu\u00e9es par le refus du fondement de la guerre qu&rsquo;est le combat, peut tr\u00e8s vite se transformer en un d\u00e9sastre qui aurait d&rsquo;\u00e9normes r\u00e9percussions politiques.<\/p>\n<\/p>\n<p><p>\tEn attendant, et plus fondamentalement, constatons que la strat\u00e9gie, en \u00e9tant transf\u00e9r\u00e9e aux services de publicit\u00e9 et de PR (communications), h\u00e9rite du caract\u00e8re de ces activit\u00e9s: le nihilisme. La vente \u00e0 l&rsquo;opinion publique de la guerre, ou d&rsquo;une image de la guerre sous la forme d&rsquo;une <em>narrative<\/em>, est une chose, qui peut \u00eatre men\u00e9e \u00e0 bien ou pas. Le but politique de cette situation, l&rsquo;\u00e9volution politique qui y conduit, les conditions politiques qui l&rsquo;accompagnent sont une autre chose, qui n&rsquo;est aujourd&rsquo;hui plus trait\u00e9e par rien ni par personne. Selon le t\u00e9moignage de diplomates europ\u00e9ens qui ont eu r\u00e9cemment des entretiens avec leurs interlocuteurs US \u00e0 ce sujet, il n&rsquo;y a actuellement, au National Security Council de Washington autant que dans les services de l&rsquo;envoy\u00e9 personnel du pr\u00e9sident pour le secteur Afghanistan-Pakistan Richard Holbrooke, personne qui sache <strong>pourquoi<\/strong> les forces arm\u00e9es US se trouvent en Afghanistan. C&rsquo;est d&rsquo;ailleurs la raison principale pour laquelle Holbrooke, \u00e0 qui il reste encore un peu de cerveau pour \u00e9laborer une pens\u00e9e logique, est un partisan acharn\u00e9 quoique discret de la participation \u00e0 tout prix et par tous les moyens des talibans \u00e0 une nouvelle \u00e9quipe de direction afghane, \u00e0 Kaboul. Le projet est d&rsquo;une originalit\u00e9 confondante.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t(*) &#8230;Orthographi\u00e9 dans la version initiale ma\u00eetre queue, et modifi\u00e9 \u00e0 la suite d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/forum-une_blitzkrieg_bavarde_15_02_2010.html\" class=\"gen\">intervention<\/a> fort \u00e0 propos d&rsquo;un lecteur. Cela pour observer qu&rsquo;avec McChrystal, l&rsquo;explication est plut\u00f4t la coquille, qui implique nos excuses, que la lubricit\u00e9.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une blitzkrieg bavarde 15 f\u00e9vrier 2010 L&rsquo;offensive baptis\u00e9e Operation Moshtarak, cela voudrait dire, para\u00eet-il, quelque chose comme Op\u00e9ration Ensemble, habile clin d&rsquo;il \u00e0 l&rsquo;Afghan moyen, vous en conviendrez, se d\u00e9roule conform\u00e9ment au plan pr\u00e9vu. Cette formule rituelle de l&rsquo;URSS des ann\u00e9es brejn\u00e9viennes et de l&rsquo;Arm\u00e9e Rouge en Afghanistan fait parfaitement l&rsquo;affaire de nos vaillantes phalanges&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,9274,2892,5300,7973,2766],"class_list":["post-71562","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-marjah","tag-offensive","tag-public","tag-publicite","tag-relations"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71562"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71562\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}