{"id":71612,"date":"2010-02-27T13:06:03","date_gmt":"2010-02-27T13:06:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/27\/lamentations-ce-nest-plus-thatcher-reagan\/"},"modified":"2010-02-27T13:06:03","modified_gmt":"2010-02-27T13:06:03","slug":"lamentations-ce-nest-plus-thatcher-reagan","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/02\/27\/lamentations-ce-nest-plus-thatcher-reagan\/","title":{"rendered":"Lamentations: ce n&rsquo;est plus Thatcher-Reagan"},"content":{"rendered":"<p><p>La fausse-vraie querelle, <em>remake<\/em> de la premi\u00e8re guerre et sorte de Guerre des Malouines  le retour, permet \u00e0 nouveau d&rsquo;exprimer quelques lamentations de circonstance sur l&rsquo;\u00e9tat des <em>special relationships<\/em>. Il s&rsquo;agit de la nouvelle querelle entre l&rsquo;Argentine et le Royaume-Uni \u00e0 propos des Malouines, et des champs p\u00e9troliers qui r\u00f4dent autour de ces iles, qui \u00e9veillent des int\u00e9r\u00eats. A nouveau est pos\u00e9e la question de la souverainet\u00e9 sur ces \u00eeles, ou sur leurs alentours navals et p\u00e9troliers, qui nous valut la guerre des Malouines du printemps 1982, et avec elle l&rsquo;heure de gloire churchillienne de Margaret Thatcher.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est James Corum qui, dans <em>The Daily Telegraph<\/em> du <a href=\"http:\/\/blogs.telegraph.co.uk\/news\/jamescorum\/100027451\/american-neutrality-on-the-falklands-is-a-symptom-of-us-foreign-policy-drift\/\" class=\"gen\">26 f\u00e9vrier 2010<\/a>, soul\u00e8ve cette question, qui ne soul\u00e8ve pas, elle, les passions dans le monde. Il aborde la chose du point de vue particulier des <em>special relationships<\/em> entre UK et USA. Professeur (US) d&rsquo;histoire militaire, Corum est actuellement d\u00e9tach\u00e9 au Coll\u00e8ge de D\u00e9fense de la Baltique, en Estonie; cette assignation dans ce pays, autant que le journal o\u00f9 il \u00e9crit et ce qu&rsquo;il \u00e9crit montre \u00e0 suffisance que l&rsquo;homme n&rsquo;est pas \u00e9tranger au r\u00e9seau d&rsquo;inspiration <em>neocons<\/em> qui courent de Washington aux pays d&rsquo;Europe de l&rsquo;Est.<\/p>\n<\/p>\n<p><p>\tSon propos est une d\u00e9nonciation s\u00e9v\u00e8re de l&rsquo;attitude prise par les USA dans cette querelle<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Bush administration got a lot of things wrong  but at least they usually had some idea of who America&rsquo;s adversaries were and who America&rsquo;s friends were. For example, Bush&rsquo;s policy of maintaining the special relationship with Britain was a simple recognition of the close bonds of alliance, friendship and interests that the British and Americans have had since World War I<\/em> [] <em>The declaration of neutrality on the issue of the sovereignty of the Falklands issued by the US State Department is clear proof of the uselessness of the Obama administration.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the grand scheme of things it makes little sense for America to give moral support to the Kirchner government in Argentina. Kirchner is no friend of the US and Kirchner&rsquo;s government is in deep domestic trouble for its gross mismanagement of the economy and its attempts to suppress the press criticism of the regime at home. One has to wonder what benefit America gets out of hurting Britain on this issue. Perhaps Obama thinks that the more Leftist Latin American regimes will somehow approve of the US. If that is the case, he is truly mistaken, as most Latin American nations dislike the Argentineans, and have little sympathy for the mess Argentina got into over the Falklands.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>On assuming office, Obama&rsquo;s vision of foreign policy was simple: he would repudiate past American policies and the whole world would melt before the president&rsquo;s charm. The administration somehow thought that we really didn&rsquo;t have enemies with agendas completely hostile to our own  there were just countries that had become offended by US actions and they would happily cooperate with America as soon as the evil Republicans were gone. Well, it hasn&rsquo;t worked  and there was no Plan B.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>With a president overwhelmed by domestic problems, Hillary Clinton has failed to step in and set a foreign policy vision. Simply put, she does not have the brains or the experience to develop a coherent foreign policy vision for America. This is how we get policy mistakes on issues such as the sovereignty of the Falklands.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Lorsque, en mars 1982, l&rsquo;Argentine prit possession des \u00eeles Malouines, ouvrant une crise majeure avec le Royaume-Uni, les USA se trouv\u00e8rent imm\u00e9diatement dans l&#8217;embarras. Il y avait d&rsquo;un c\u00f4t\u00e9 la politique panam\u00e9ricaine de Washington, bas\u00e9e sur l&rsquo;interventionnisme ill\u00e9gal et la violence par les actions clandestines ou maquill\u00e9es, et une politique de communication officielle de solidarit\u00e9 panam\u00e9ricaine. D&rsquo;un autre c\u00f4t\u00e9, il y avait les habituelles <em>special relationships<\/em> avec le Royaume-Uni, renforc\u00e9es par les int\u00e9r\u00eats puissants de maintenir une coh\u00e9sion \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;OTAN bas\u00e9e sur l&rsquo;axe anglo-saxon. Le d\u00e9bat fut s\u00e9v\u00e8re \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;administration Reagan. La faction pro-argentine et panam\u00e9ricaine \u00e9tait men\u00e9e par l&rsquo;ambassadeur US \u00e0 l&rsquo;ONU, Jeane Kirkpatrick, la faction pro-UK et transatlantique par le secr\u00e9taire d&rsquo;Etat Alexander Haig. La seconde l&#8217;emporta finalement et les USA se proclam\u00e8rent aux c\u00f4t\u00e9s des Britanniques, avant m\u00eame que le conflit n&rsquo;entre dans sa phase op\u00e9rationnelle effective.<\/p>\n<\/p>\n<p><p>\t(Ensuite, durant le conflit lui-m\u00eame, les USA vinrent en aide aux Britanniques d&rsquo;une fa\u00e7on discr\u00e8te, notamment en assurant un soutien logistique et op\u00e9rationnel avec des ravitailleurs en vol, des avions de surveillance et de contr\u00f4le AWACS, etc.; les USA \u00e9taient m\u00eame pr\u00eats \u00e0 fournir un porte-avions sorti de leurs r\u00e9serves, si l&rsquo;un des deux porte-avions britanniques envoy\u00e9s aux Malouines avec la force a\u00e9ronavale avait \u00e9t\u00e9 touch\u00e9 ou d\u00e9truit. De leur c\u00f4t\u00e9, les Fran\u00e7ais aid\u00e8rent d&rsquo;une fa\u00e7on indirecte mais importante les Britanniques en leur donnant, notamment par des informations et des essais op\u00e9rationnels lors d&rsquo;intervention vers la force britannique en route vers les Malouines, des indications cruciales pour contrer les missiles air-mer MM39 <em>Exocet<\/em> que les Fran\u00e7ais avaient vendus aux Argentins.) <\/p>\n<\/p>\n<p><p>\tLa diff\u00e9rence est frappante avec la situation actuelle. Certes, la situation est diff\u00e9rente, dans la mesure o\u00f9 il semble bien qu&rsquo;on doive envisager d&rsquo;\u00e9carter la possibilit\u00e9 d&rsquo;un conflit, notamment avec l&rsquo;affirmation de l&rsquo;Argentine qu&rsquo;il n&rsquo;y aura pas de tentative d&rsquo;intervention contre les Malouines. (On trouve \u00e0 cette occasion, largement et justement pos\u00e9e, la question de savoir si les Britanniques seraient encore capables aujourd&rsquo;hui de monter une op\u00e9ration de projection de force, op\u00e9ration navale, avec une composante a\u00e9rienne importante et une composante terrestre cons\u00e9quente, comme celle qu&rsquo;ils men\u00e8rent en 1982. Dans le <em>Daly Mail<\/em> du <a href=\"http:\/\/www.dailymail.co.uk\/debate\/article-1252149\/Its-bitter-truth-We-send-task-force-Falklands-today.html#\" class=\"gen\">19 f\u00e9vrier 2010<\/a>, le capitaine de vaisseau Michael Clapp, qui fait partie de la National Defence Association, publie une analyse pour montrer que les Britanniques n&rsquo;ont plus aujourd&rsquo;hui cette capacit\u00e9: \u00ab<em>It&rsquo;s the bitter truth: We couldn&rsquo;t send a task force to the Falklands today.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tN\u00e9anmoins, cette probabilit\u00e9 d&rsquo;absence de conflit ne supprime nullement la valeur analogique de la situation, puisqu&rsquo;il s&rsquo;agit en l&rsquo;occurrence, comme en 1982 lorsque Washington prit la position qu&rsquo;on a rappel\u00e9e, d&rsquo;abord d&rsquo;une position diplomatique de principe. Le fait est qu&rsquo;aucun d\u00e9bat r\u00e9el n&rsquo;a eu lieu au sein de l&rsquo;administration Obama. D&rsquo;une part, la question n&rsquo;a pas \u00e9t\u00e9 jug\u00e9e importante pour Washington, m\u00eame si elle l&rsquo;est pour Londres, d&rsquo;o\u00f9 l&rsquo;absence de d\u00e9bat strat\u00e9gique. D&rsquo;autre part, la d\u00e9cision du d\u00e9partement d&rsquo;Etat, prise sans gu\u00e8re de consultations internes, n&rsquo;a soulev\u00e9e aucune opposition d&rsquo;aucun autre d\u00e9partement, y compris du Pentagone. La position de neutralit\u00e9 du d\u00e9partement d&rsquo;Etat revient en fait, par rapport \u00e0 ce que les Britanniques attendaient des Am\u00e9ricains apr\u00e8s pr\u00e8s d&rsquo;une d\u00e9cennie d&rsquo;engagement intense aupr\u00e8s des USA en Irak et en Afghanistan, \u00e0 un camouflet donn\u00e9 \u00e0 ces m\u00eames Britanniques. Effectivement, de ce point de vue, les <em>special relationships<\/em> ne soul\u00e8vent plus gu\u00e8re d&rsquo;int\u00e9r\u00eat \u00e0 Washington, sinon pour exiger de Londres des efforts partout o\u00f9 les USA en ont besoin<\/p>\n<\/p>\n<p><p>\tLe point int\u00e9ressant \u00e0 observer est qu&rsquo;il s&rsquo;agit plus, de la part des USA, d&rsquo;une position de retraite que d&rsquo;une position effective de politique ext\u00e9rieure. Cette neutralit\u00e9 dans le conflit n&rsquo;implique pas n\u00e9cessairement une prise de position implicite en faveur de l&rsquo;Argentine, comme le probl\u00e8me \u00e9tait pos\u00e9 en 1982. A cette \u00e9poque, le choix \u00e9tait pour ou contre (pour ou contre les Britanniques, pour ou contre l&rsquo;Argentine). Dans ce cas, la position de neutralit\u00e9 est une v\u00e9ritable d\u00e9claration de d\u00e9sint\u00e9r\u00eat du probl\u00e8me, essentiellement due \u00e0 l&rsquo;affaiblissement consid\u00e9rable de la puissance US et \u00e0 la crise interne US, \u00e0 Washington m\u00eame. Corum laisse entendre le constat de cette situation lorsqu&rsquo;il \u00e9crit \u00ab<em>With a president overwhelmed by domestic problems<\/em>\u00bb, mais il n&rsquo;en tire pas la v\u00e9ritable cons\u00e9quence puisqu&rsquo;il encha\u00eene sur la mise en question des capacit\u00e9s d&rsquo;Hillary Clinton dans cette affaire, en m\u00eame temps qu&rsquo;il met l&rsquo;accent sur sa faiblesse et son inexp\u00e9rience. Quoi qu&rsquo;il en soit de l&rsquo;exp\u00e9rience ou non de Clinton, le fait de sa faiblesse ne correspond pas \u00e0 une sp\u00e9cificit\u00e9 de son action, ou de sa position \u00e0 l&rsquo;int\u00e9rieur du cabinet, mais il est plut\u00f4t un reflet de la faiblesse des moyens dont dispose la diplomatie US en g\u00e9n\u00e9ral, et d&rsquo;une politique g\u00e9n\u00e9rale partout sur la d\u00e9fensive et sur le repli.<\/p>\n<\/p>\n<p><p>\tPour le reste de l&rsquo;article de Corum, on retrouve une r\u00e9crimination classique des factions n\u00e9o-conservatrices \u00e0 l&rsquo;encontre de la politique de l&rsquo;administration Obama, sans beaucoup d&rsquo;int\u00e9r\u00eat. Aucun compte n&rsquo;est tenu de la situation r\u00e9elle de la puissance US aujourd&rsquo;hui, \u00e0 la d\u00e9gradation de laquelle le courant n\u00e9o-conservateur a si puissamment contribu\u00e9 depuis 2001.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 27 f\u00e9vrier 2010 \u00e0 13H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fausse-vraie querelle, remake de la premi\u00e8re guerre et sorte de Guerre des Malouines le retour, permet \u00e0 nouveau d&rsquo;exprimer quelques lamentations de circonstance sur l&rsquo;\u00e9tat des special relationships. Il s&rsquo;agit de la nouvelle querelle entre l&rsquo;Argentine et le Royaume-Uni \u00e0 propos des Malouines, et des champs p\u00e9troliers qui r\u00f4dent autour de ces iles, qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3261,934,9334,9333,3831,3215,3345,7437,5462,3344,3174],"class_list":["post-71612","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-argentine","tag-clinton","tag-corum","tag-malouines","tag-neo-conservateurs","tag-reagan","tag-relationships","tag-repli","tag-retraite","tag-special","tag-thatcher"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71612"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71612\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}