{"id":71677,"date":"2010-03-19T04:36:02","date_gmt":"2010-03-19T04:36:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/19\/cooperation-nucleaire-france-uk-variations\/"},"modified":"2010-03-19T04:36:02","modified_gmt":"2010-03-19T04:36:02","slug":"cooperation-nucleaire-france-uk-variations","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/19\/cooperation-nucleaire-france-uk-variations\/","title":{"rendered":"Coop\u00e9ration nucl\u00e9aire France-UK : variations"},"content":{"rendered":"<p><h4>Coop\u00e9ration nucl\u00e9aire France-UK : variations<\/h4>\n<p>Le <em>Guardian<\/em> publie un article assez significatif, \u00e0 la fois par l&rsquo;\u00e9vocation de possibilit\u00e9s et l&rsquo;absence de pr\u00e9cisions, sur une coop\u00e9ration franco-britannnique en mati\u00e8re de nucl\u00e9aire. L&rsquo;article parle de coop\u00e9ration en mati\u00e8re de patrouille de sous-marins nucl\u00e9aires et \u00e9voque d&rsquo;autres possibilit\u00e9s. Il insiste sur le fait que les propositions viennent des Fran\u00e7ais (cette affirmation doit \u00eatre prise avec un certain scepticisme, signifiant plut\u00f4t que les Britanniques sont actifs mais ne veulent pas qu&rsquo;on le sache trop); qu&rsquo;il y a eu des discussions \u00e0 diverses occasions depuis 2008 sur un <em>deterrent-sharing scheme<\/em>; que le Royaume-Uni <em>has so far opposed the idea<\/em> (le <em>so far<\/em> \u00e9tant le mot important).<\/p>\n<\/p>\n<p><p>\tL&rsquo;article, de ce <a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/mar\/19\/france-britain-shared-nuclear-deterrent\" class=\"gen\">19 mars 2010<\/a>, sign\u00e9 de deux sp\u00e9cialistes du journal (Julian Borger et Richard Norton-Taylor), n&rsquo;est pas innocent. C&rsquo;est le type m\u00eame d&rsquo;une publication destin\u00e9e \u00e0 t\u00e2ter le terrain, pour faire savoir qu&rsquo;il existe des possibilit\u00e9s s\u00e9rieuses dans le domaine envisag\u00e9 sans en dire plus. Une place importante est faite aux intentions possibles des conservateurs, dont on attend qu&rsquo;ils acc\u00e8dent au pouvoir \u00e0 la suite des \u00e9lections de la fin du printemps. S&rsquo;ils n&rsquo;ont pas de majorit\u00e9 absolue, les conservateurs pourraient \u00eatre soutenus au Parlement par les d\u00e9mocrates-lib\u00e9raux, qui sont tr\u00e8s pro-europ\u00e9ens et partisans d&rsquo;une coop\u00e9ration militaire avec les Fran\u00e7ais.<\/p>\n<\/p>\n<p><p>\tVoici ce que l&rsquo;article du <em>Guardian<\/em> dit des positions des conservateurs sur le sujet.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Liam Fox, the shadow defence secretary, has spelled out the possibilities of closer co-operation on a number of occasions recently. Our most important bilateral relationship in Europe is with France, he said in a keynote speech. Most importantly, we are Europe&rsquo;s only two nuclear powers and we contribute greatly to Nato&rsquo;s security because of this. A future Conservative government will continue and strengthen this relationship.&rsquo;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He added that if the Conservatives formed the next government, the Ministry of Defence would invite France to make a formal submission to the promised Strategic Defence and Security Review stating what they expect from their relationship with the United Kingdom.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Fox told the Commons earlier this week: We will need to be able to project power on a strategic level alongside the US and France.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He is expected today to point to the advantages of closer defence procurement co-operation with France  on a bilateral basis, he will emphasise.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.org<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coop\u00e9ration nucl\u00e9aire France-UK : variations Le Guardian publie un article assez significatif, \u00e0 la fois par l&rsquo;\u00e9vocation de possibilit\u00e9s et l&rsquo;absence de pr\u00e9cisions, sur une coop\u00e9ration franco-britannnique en mati\u00e8re de nucl\u00e9aire. L&rsquo;article parle de coop\u00e9ration en mati\u00e8re de patrouille de sous-marins nucl\u00e9aires et \u00e9voque d&rsquo;autres possibilit\u00e9s. Il insiste sur le fait que les propositions viennent&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9393,3435,3288,5052,8599,3004],"class_list":["post-71677","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-conservzteurs","tag-cooperation","tag-fox","tag-france-uk","tag-liam","tag-nucleaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71677"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71677\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}