{"id":71686,"date":"2010-03-22T05:47:27","date_gmt":"2010-03-22T05:47:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/moins-de-prisonniers-aux-usa-pour-cause-deconomie\/"},"modified":"2010-03-22T05:47:27","modified_gmt":"2010-03-22T05:47:27","slug":"moins-de-prisonniers-aux-usa-pour-cause-deconomie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/moins-de-prisonniers-aux-usa-pour-cause-deconomie\/","title":{"rendered":"Moins de prisonniers aux USA\u2026 pour cause d&rsquo;\u00e9conomie"},"content":{"rendered":"<p><h4>Moins de prisonniers aux USA pour cause d&rsquo;\u00e9conomie<\/h4>\n<p>Une sorte de miracle Pour la premi\u00e8re fois depuis 1972, il y a eu une diminution en 2009 dans le nombre de personnes emprisonn\u00e9es dans les prisons des Etats de l&rsquo;Union aux USA. (En 1972, il y avait 174.000 personnes en prison dans ce r\u00e9seau, en 2009 il y en avait 1.403.091.) La r\u00e9duction par rapport \u00e0 2008 est minime (0,4%), mais tout de m\u00eame c&rsquo;est une r\u00e9duction.<\/p>\n<\/p>\n<p><p>\tQuoique Comme on peut lire l&rsquo;explication, dans <em>The Observer<\/em> du 21 mars (<a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/mar\/21\/america-jail-population-down-economy\" class=\"gen\">http:\/\/www.guardian.co.uk\/world\/2010\/mar\/21\/america-jail-population-down-economy<\/a>), c&rsquo;est plus une affaire de gros sous qu&rsquo;un changement d&rsquo;attitude des autorit\u00e9s.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>What is it that has finally stopped the onward charge to lock up as many people as possible for as long as possible? Sadly for reformers, it is not much to do with their campaigns to have America&rsquo;s laws changed on moral, humanitarian or, indeed, effectiveness grounds. It is instead mainly economic: the recession has simply meant that many states can no longer afford to lock up so many people. In cash-strapped Michigan, for example, the prison population has been slashed by 6,000 in three years as prisoners are released for serving their minimum sentence and parole violation rules are loosened.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, le loi et l&rsquo;ordre veillent toujours, comme le montre le cas de cette personne jug\u00e9e en Californie au d\u00e9but mars, et condamn\u00e9e \u00e0 huit ans de prison ferme pour avoir d\u00e9rob\u00e9 un morceau de fromage emball\u00e9 valant $3,99. La propri\u00e9t\u00e9 priv\u00e9e, \u00e7a ne se vole pas. D&rsquo;ailleurs, si on fait les calculs et si on ajoute les prisonniers dans les prisons f\u00e9d\u00e9rales aux prisonniers dans les prisons d&rsquo;Etat, la tradition est heureusement renou\u00e9e : il y a augmentation.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>So, too, does the fact that at the federal level the number of prisoners is still increasing, up by 6,838 to an all-time high of 208,118. Indeed when the two populations are added together there are still more prisoners in American jails this year than last year.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jacques Laubion<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moins de prisonniers aux USA pour cause d&rsquo;\u00e9conomie Une sorte de miracle Pour la premi\u00e8re fois depuis 1972, il y a eu une diminution en 2009 dans le nombre de personnes emprisonn\u00e9es dans les prisons des Etats de l&rsquo;Union aux USA. (En 1972, il y avait 174.000 personnes en prison dans ce r\u00e9seau, en 2009&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9110,6183,2804],"class_list":["post-71686","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-laubion","tag-prisons","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71686"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71686\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}