{"id":71688,"date":"2010-03-22T09:28:57","date_gmt":"2010-03-22T09:28:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/krugman-est-il-un-fauteur-de-guerre\/"},"modified":"2010-03-22T09:28:57","modified_gmt":"2010-03-22T09:28:57","slug":"krugman-est-il-un-fauteur-de-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/krugman-est-il-un-fauteur-de-guerre\/","title":{"rendered":"Krugman est-il un fauteur de guerre?"},"content":{"rendered":"<p><p>La prise de position de l&rsquo;\u00e9conomiste Prix Nobel Paul Krugman, dans le New York <em>Times<\/em> le <a href=\"http:\/\/www.nytimes.com\/2010\/03\/15\/opinion\/15krugman.html\" class=\"gen\">15 mars 2010<\/a>, en faveur de mesures contre les importations chinoises (25% de surcharge puisqu&rsquo;il se refuse \u00e0 employer l&rsquo;expression tr\u00e8s protectionniste de taxe \u00e0 l&rsquo;importation), lui vaut des attaques aussi violentes que la gravit\u00e9 de ces mesures. Jeremy Warner, un des \u00e9diteurs du <em>Daily Telegraph<\/em> et l&rsquo;un des sp\u00e9cialistes \u00e9conomiques du quotidien, et un partisan intraitable de la politique libre-\u00e9changiste, r\u00e9sume son propos (le <a href=\"http:\/\/www.telegraph.co.uk\/finance\/comment\/jeremy-warner\/7483177\/Paul-Krugman-the-Nobel-prize-winner-who-threatens-the-world.html \" class=\"gen\">19 mars 2010<\/a>) par la formule de son titre,  Krugman, le Prix Nobel qui menace le monde. Le texte de Warner, suivant la prise de position de Krugman qui traduit un puissant courant aux USA parce qu&rsquo;il est de plus en plus le seul point \u00e0 rapprocher s\u00e9rieusement d\u00e9mocrates et r\u00e9publicains, et \u00e0 r\u00e9concilier les \u00e9lus washingtoniens et leurs \u00e9lecteurs, t\u00e9moigne d&rsquo;une fracture int\u00e9ressante dans le front jusqu&rsquo;ici uni des Anglo-Saxons en faveur du libre-\u00e9change.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>When the self-proclaimed conscience of liberal America and a one-time free trader to boot starts arguing for protectionism, you know that things have come to a pretty pass. But that&rsquo;s what&rsquo;s happened over the past week.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Paul Krugman, a Nobel Prize-winning economist, has taken to advocating a 25 per cent \u00ab\u00a0surcharge\u00a0\u00bb  he refuses to use the more descriptive term of \u00ab\u00a0import tariff\u00a0\u00bb  on goods from China as a way of bringing the Chinese leadership to heel over currency reform. So potentially dangerous and out of character is this idea that when I first read it, I assumed he was being ironic. But sometimes the cleverest of people can also be the most stupid, and he&rsquo;s now said it so often that you have to believe he&rsquo;s serious.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What he&rsquo;s advocating is trade retaliation so extreme that it would make the 1930s look like a stroll in the park. Contrary to Professor Krugman&rsquo;s na\u00efve assumption that the Chinese would soon cave in and allow their currency to float if confronted by such hard-ball tactics, I am certain that nothing is more guaranteed to produce the opposite response.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Professor Krugman&rsquo;s suggestion mines a rich seam of populist US thinking and rhetoric which grows ever more vocal and worrying as the recession persists. What makes Krugman and other highly regarded economists who toe the same line so dangerous is that they give intellectual respectability to a fundamentally disreputable idea.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Unlike Britain, America doesn&rsquo;t really do free-traders. Even progressives, though they may pretend otherwise, are protectionists at heart. And there is a good reason for it. The US is still a largely internalised, self-reliant economy for which trade with the outside world is relatively unimportant. Many Americans have long thought they don&rsquo;t much benefit from globalisation and that they would be better off behind high, protectionist walls. When times are tough, these arguments find ever more traction.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> C&rsquo;est effectivement un \u00e9change int\u00e9ressant, notamment par la violence des prises de position, dans un domaine et entre gens (Anglais et Am\u00e9ricains) o\u00f9 l&rsquo;on \u00e9vite en g\u00e9n\u00e9ral les antagonismes violents parce que l&rsquo;on esp\u00e8re toujours se retrouver au bout du compte. Warner attaque Krugman avec la violence qu&rsquo;on lui voit parce que le prestige d&rsquo;un Krugman proposant de telles mesures donne un cr\u00e9dit consid\u00e9rable \u00e0 un mouvement tr\u00e8s puissant en cours aux USA,  non pas sp\u00e9cifiquement protectionniste, mais mouvement populiste dont l&rsquo;un des effets est effectivement de pr\u00f4ner le protectionnisme, sinon l&rsquo;isolationnisme. L&rsquo;habitude \u00e9tait de consid\u00e9rer que l&rsquo;<em>establishment<\/em>, dont Krugman fait partie quelles que soient ses positions, ne pouvait en aucun cas cautionner un tel mouvement, lui donnant ainsi le cr\u00e9dit de la respectabilit\u00e9.<\/p>\n<\/p>\n<p><p>\tDevant ce qu&rsquo;il juge \u00eatre un tel d\u00e9sastre, Warner a des mots emport\u00e9s mais qui vont tr\u00e8s loin jusqu&rsquo;\u00e0 r\u00e9v\u00e9ler des v\u00e9rit\u00e9s en g\u00e9n\u00e9ral dissimul\u00e9es; ceci, par exemple: \u00ab<em>Unlike Britain, America doesn&rsquo;t really do free-traders. Even progressives, though they may pretend otherwise, are protectionists at heart.<\/em>\u00bb Mis \u00e0 part le <em>Unlike Britain<\/em>, parce que les Britanniques ont d\u00e9j\u00e0 su \u00eatre protectionnistes, notamment avec leur Commonwealth, lorsque leur int\u00e9r\u00eat le commandait, l&rsquo;analyse psychologique est d&rsquo;une justesse historique incontestable. Les Am\u00e9ricains sont protectionnistes dans l&rsquo;\u00e2me, de la m\u00eame fa\u00e7on qu&rsquo;ils sont isolationnistes, \u00e9galement dans l&rsquo;\u00e2me puisqu&rsquo;il s&rsquo;av\u00e8re qu&rsquo;ils en auraient une, c&rsquo;est-\u00e0-dire non pas d&rsquo;un point de vue du choix \u00e9conomique mais du point de vue plus fondamental du r\u00e9flexe profond, de l&rsquo;attitude naturelle. Bien entendu, lorsque des hommes aussi mesur\u00e9s et d&rsquo;un statut aussi important qu&rsquo;un Krugman c\u00e8dent \u00e0 ce r\u00e9flexe, on peut \u00eatre assur\u00e9 que c&rsquo;est un signe de la gravit\u00e9 de la situation aux USA. Dans ce cas, Krugman ne s&rsquo;est pas engag\u00e9 seul, il est la voix d&rsquo;une partie grandissante de l&rsquo;<em>intelligentsia<\/em>. Il s&rsquo;agit bien d&rsquo;une prise de position fondamentale, qui vient du cur de la crise.<\/p>\n<\/p>\n<p><p>\tKrugman a chang\u00e9. Jusqu&rsquo;au printemps dernier, il pilonnait sans arr\u00eat le syst\u00e8me, demandant sa r\u00e9forme, la mise au pas de Wall Street, l&rsquo;interventionnisme public sans restriction, etc. Il n&rsquo;a rien obtenu de l&rsquo;essentiel qu&rsquo;il r\u00e9clamait. Il en a \u00e9prouv\u00e9 bien du d\u00e9pit, qui s&rsquo;est traduit dans certaines attaques contre Obama, o\u00f9 ce Prix Nobel de l&rsquo;Economie 2008 s&rsquo;est d\u00e9clar\u00e9 quasiment en \u00e9tat de rupture avec le Prix Nobel de la Paix 2009. Cette fois, il change compl\u00e8tement d&rsquo;attitude, retrouve la solidarit\u00e9 de survie du syst\u00e8me et exige une mesure qui contredit fondamentalement toute la philosophie du syst\u00e8me, sans plus se soucier des causes fondamentales qui conduisent \u00e0 demander cette sorte de mesure, o\u00f9 les USA ont \u00e9videmment la part principale en tant qu&rsquo;organisateurs de la situation actuelle du monde avec un dollar dont ils ont jou\u00e9 \u00e0 leur avantage durant des d\u00e9cennies, selon leur comportement d&rsquo;une pure piraterie. Mais c&rsquo;est bien s\u00fbr sur le fond de la protection de la doctrine sacr\u00e9e que vient l&rsquo;accusation de trahison, sinon de simple d\u00e9mence du jugement, chez Warner.<\/p>\n<\/p>\n<p><p>\tLe symbolisme de l&rsquo;\u00e9v\u00e9nement est d&rsquo;importance, symbolisme parce qu&rsquo;impliquant des personnalit\u00e9s justement d&rsquo;une telle importance dans la r\u00e9putation et l&rsquo;influence, des gardiens du temple si l&rsquo;on veut. Il d\u00e9montre la continuelle d\u00e9gradation de la situation, notamment dans les pays anglo-saxons et entre les pays du front anglo-saxons. La crise ne cesse de s&rsquo;approfondir pour toucher les psychologies jusqu&rsquo;\u00e0 susciter des choix de survie. Face \u00e0 cela, les th\u00e9ories fondamentales qui tiennent le syst\u00e8me sont trait\u00e9es avec la plus extr\u00eame l\u00e9g\u00e8ret\u00e9, et d&rsquo;une fa\u00e7on cat\u00e9gorique. Demander l&rsquo;\u00e9rection d&rsquo;un mur protectionniste aussi puissant contre la Chine, comme le fait Krugman, c&rsquo;est effectivement absolument <strong>r\u00e9habiliter<\/strong> le protectionnisme dans toute sa p\u00e9rennit\u00e9.<\/p>\n<\/p>\n<p><p>\tAinsi Krugman, en d\u00e9fendant ce qu&rsquo;il reste du pays qui imposa au monde le syst\u00e8me qui a engendr\u00e9 la crise, et cela en r\u00e9clamant une politique qui est l&rsquo;antith\u00e8se de ce syst\u00e8me, vient-il au secours de ceux qui s&rsquo;opposent \u00e0 ce syst\u00e8me, notamment quelques-uns en Europe, surtout en France. La r\u00e9habilitation du protectionnisme est un point <strong>politique<\/strong> essentiel de la bataille contre le syst\u00e8me, dans la mesure o\u00f9 il accompagne une r\u00e9affirmation de l&rsquo;identit\u00e9 et de la souverainet\u00e9. Ce n&rsquo;est pas l&rsquo;intention de Krugman, puisqu&rsquo;il raisonne, lui, en mode de survie et en \u00e9conomiste, et que l&rsquo;identit\u00e9 et la souverainet\u00e9 ne sont pas des vertus pr\u00e9cis\u00e9ment am\u00e9ricanistes et \u00e9conomistes. Mais c&rsquo;est l&rsquo;effet \u00e0 terme qu&rsquo;il obtiendra, et c&rsquo;est l&rsquo;essentiel.<\/p>\n<\/p>\n<p><p>\tOn sait que les jugements sur le protectionnisme sont divers. Pour Warner, c&rsquo;est le moteur des guerres et le Diable incarn\u00e9. On se permettra d&rsquo;en douter, jugeant au contraire que c&rsquo;est le syst\u00e8me lui-m\u00eame, avec ses pressions d\u00e9structurantes et ses conceptions de production et de comp\u00e9tition pr\u00e9datrices, et d&rsquo;exigence chez les puissances inspiratrices de l&rsquo;absence d&rsquo;un protectionnisme diabolis\u00e9 chez les autres, qui a engendr\u00e9 les conflits les plus sanglants. Mieux encore, le protectionnisme n&rsquo;est pas qu&rsquo;un simple coup de hache qui rompt toutes les choses, mais une doctrine souple et adaptable. Quoi qu&rsquo;il en soit, la prise de position de Krugman, qui va \u00eatre encore plus spectaculaire et cons\u00e9quente avec ceux qui, comme Warner, l&rsquo;accusent de trahir, rencontre un mouvement puissant aux USA, qui a le soutien populaire. Il est possible, sinon probable que les USA deviennent protectionnistes, et la victoire d&rsquo;Obama dans l&rsquo;affaire des soins de sant\u00e9, qui a d\u00e9montr\u00e9 au pr\u00e9sident la vertu d&rsquo;une certaine fermet\u00e9 et d&rsquo;un certain engagement contre la recherche du consensus, devrait effectivement d\u00e9velopper l&rsquo;\u00e9tat d&rsquo;esprit qui conduit au protectionnisme; raisonnement d&rsquo;autant plus \u00e0 consid\u00e8re que (rengaine) la crise au lieu de finir, ne cesse de s&rsquo;aggraver.<\/p>\n<\/p>\n<p><p>\tCette discorde chez l&rsquo;ennemi, une de plus, une fois de plus entre les deux alli\u00e9s anglo-saxons par l&rsquo;interm\u00e9diaire de quelques-unes de leurs grand&rsquo;pr\u00eatres de l&rsquo;\u00e9conomie, est une excellente nouvelle. Elle confirme la d\u00e9gradation acc\u00e9l\u00e9r\u00e9e du syst\u00e8me, avec le d\u00e9sarroi et les r\u00e9actions d&rsquo;une violence incontr\u00f4l\u00e9e de ces m\u00eames grand&rsquo;pr\u00eatres. On ne rigole plus, m\u00eame si le Diable en rit d\u00e9j\u00e0.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 mars 2010 \u00e0 09H32<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prise de position de l&rsquo;\u00e9conomiste Prix Nobel Paul Krugman, dans le New York Times le 15 mars 2010, en faveur de mesures contre les importations chinoises (25% de surcharge puisqu&rsquo;il se refuse \u00e0 employer l&rsquo;expression tr\u00e8s protectionniste de taxe \u00e0 l&rsquo;importation), lui vaut des attaques aussi violentes que la gravit\u00e9 de ces mesures. Jeremy&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3977,3617,3067,898,1097,7160,4199,3470],"class_list":["post-71688","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chine","tag-daily","tag-doctrine","tag-krugman","tag-protectionnisme","tag-survie","tag-telegraph","tag-warner"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71688"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71688\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}