{"id":71694,"date":"2010-03-22T19:52:00","date_gmt":"2010-03-22T19:52:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/le-crepuscule-de-la-sainte-alliance\/"},"modified":"2010-03-22T19:52:00","modified_gmt":"2010-03-22T19:52:00","slug":"le-crepuscule-de-la-sainte-alliance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/22\/le-crepuscule-de-la-sainte-alliance\/","title":{"rendered":"Le cr\u00e9puscule de la Sainte Alliance"},"content":{"rendered":"<p><h2 class=\"common-article\">Le cr\u00e9puscule de la Sainte Alliance<\/h2>\n<\/p>\n<p><p>\t22 mars 2010  Quelque part, disons entre 1990 et 1999, s&rsquo;\u00e9tablit fermement et \u00e0 d\u00e9couvert une alliance qui, dans sa potentialit\u00e9, vient de beaucoup plus loin qu&rsquo;on ne croit,  qui vient, par exemple, de ce jour de 1825 sans doute, o\u00f9 Stendhal bondit d&rsquo;horreur et abandonna aussit\u00f4t son engagement de lib\u00e9ral pro-am\u00e9ricaniste, en entendant ce mot du d\u00e9nomm\u00e9 Gouhier: \u00ab<em>Les Lumi\u00e8res c&rsquo;est d\u00e9sormais l&rsquo;industrie.<\/em>\u00bb (*) Lequel mot, quoi qu&rsquo;il en soit de Stendhal et de ses divers \u00e9crits, annon\u00e7ait un destin qui n&rsquo;a cess\u00e9 de se renforcer et qui est devenue une r\u00e9alit\u00e9 criante dans les ann\u00e9es 1990. La Sainte Alliance dont nous parlons, c&rsquo;est l&rsquo;alliance entre les deux descendants des acteurs nouveaux identifi\u00e9s en 1825:<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, le parti intellectuel lib\u00e9ral au sens politique, c&rsquo;est-\u00e0-dire les intellectuels avanc\u00e9s, ou progressistes (\u00e9ventuellement progressistes mod\u00e9r\u00e9s), qui se r\u00e9clament tous \u00e0 un moment ou l&rsquo;autre, d&rsquo;une fa\u00e7on ou l&rsquo;autre, des Lumi\u00e8res. (Nous avons appris \u00e0 les baptiser, pour ce qui concerne les deux rives de la Seine, le parti des salonards.) On pourrait les renommer d&rsquo;une fa\u00e7on plus avantageuse et conforme aux murs du temps le parti de la communication en identifiant cette classe intellectuelle au moyen qui la fait vivre, qui la fait s&rsquo;\u00e9couter et se plaire \u00e9norm\u00e9ment, au moyen qui lui permet de disposer des consignes \u00e0 suivre.<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, le parti de la puissance \u00e9conomique moderniste, industrielle et technologique,  et militaire, par cons\u00e9quent, dans la mesure o\u00f9 l&rsquo;armement est devenu l&rsquo;une des expression les plus avanc\u00e9es et les plus violentes de la technologie. Actualisons l&rsquo;expression de parti de l&rsquo;industrie sugg\u00e9r\u00e9e par l&rsquo;exclamation de Gouhier ci-dessus, et nommons-le, plus conform\u00e9ment \u00e0 nos normes, le parti du technologisme. Nous avons ainsi les deux branches, les deux dynamiques qui animent la politique de l&rsquo;id\u00e9al de puissance.<\/p>\n<\/p>\n<p><p>\tCette alliance fut fermement affich\u00e9e \u00e0 diverses occasions mais elle devint quasiment institutionnalis\u00e9e durant les ann\u00e9es 1990, notamment \u00e0 l&rsquo;occasion du conflit de l&rsquo;ex-Yougoslavie. Les jeux de r\u00f4les et les \u00e9volutions relatives firent que le parti de l&rsquo;obscurantisme, qui est en g\u00e9n\u00e9ral assign\u00e9 \u00e0 des acteurs diff\u00e9rents, selon les int\u00e9r\u00eats changeants de la coalition, fut attribu\u00e9 aux Serbes. Le conflit du Kosovo fut l&rsquo;arch\u00e9type de cette alliance, les intellectuels progressistes du parti de la communication soutenant avec enthousiasme l&rsquo;action des forces qui repr\u00e9sentaient \u00e9videmment le parti du technologisme, et qui \u00e9taient principalement repr\u00e9sent\u00e9s par les escadres a\u00e9riennes du Pentagone (USAF et Navy). Le bon mot de l&rsquo;\u00e9poque, le slogan de l&rsquo;esprit de la chose, fut r\u00e9sum\u00e9 par Vaclav Havel, sous la d\u00e9nomination de \u00ab<em>bombardements humanitaires<\/em>\u00bb,  qui l&rsquo;\u00e9taient effectivement, dans la mesure o\u00f9 ils touchaient avec une assez grande g\u00e9n\u00e9rosit\u00e9 la population et les infrastructures civiles. Il faut ajouter qu&rsquo;\u00e0 cette m\u00eame \u00e9poque, la droite conservatrice US, celle qui allait s&rsquo;engager \u00e0 fond dans la politique belliciste de l&rsquo;administration Bush, se tenait fermement dans une position de retrait, sinon d&rsquo;hostilit\u00e9 pour ces op\u00e9rations ext\u00e9rieures. Les r\u00e9publicains observ\u00e8rent tout au long du conflit du Kosovo une position passivement hostile qu&rsquo;on pouvait juger comme proche du courant isolationniste traditionnel.<\/p>\n<\/p>\n<p><p>\t Avec le 11 septembre 2001, il y eut un consid\u00e9rable reclassement. Il y en eut pour juger que l&rsquo;\u00e9v\u00e9nement tombait fort bien pour certains, au point qu&rsquo;on pouvait s&rsquo;interroger sur la fa\u00e7on dont ces m\u00eames certains ne l&rsquo;auraient pas favoris\u00e9 d&rsquo;une fa\u00e7on ou l&rsquo;autre. En d&rsquo;autres mots fort transparents, Isra\u00ebl fut le grand b\u00e9n\u00e9ficiaire de l&rsquo;affaire. Pour la premi\u00e8re fois, dans ce grand mouvement qu&rsquo;on d\u00e9crit, une entit\u00e9 rassemblait en elle-m\u00eame la puissance du parti de la communication et celle du parti du technologisme. Isra\u00ebl \u00e9tait \u00e0 la fois la victime de toutes les barbaries et tous les obscurantisme r\u00e9unies en une <em>narrative<\/em> colossale, si colossale qu&rsquo;elle interdit toute approche critique en \u00e9tant class\u00e9 dans une cat\u00e9gorie nouvelle, dite indicible. Le parti de la communication avait sa poule aux ufs d&rsquo;or. En m\u00eame temps, Isra\u00ebl ne s&rsquo;en laissait pas compter, devenu l&rsquo;avant-bras arm\u00e9 du Pentagone, et sachant cogner, et cogner dur. Le parti du technologisme avait son champion r\u00e9gional, avec la caract\u00e9ristique d&rsquo;un prestige, d&rsquo;un <em>diktat<\/em> moral pr\u00e9tendant ais\u00e9ment \u00e0 l&rsquo;universel.<\/p>\n<\/p>\n<p><p>\tMais il \u00e9tait admis par-dessus tout, au propre et au figur\u00e9, qu&rsquo;il y avait un patron, dans les deux partis concern\u00e9s. Les USA \u00e9taient ce patron, avec une puissante machine de communication, et une machine de technologisme encore plus puissante, les deux \u00e9tant li\u00e9es. D&rsquo;une certaine fa\u00e7on, le Pentagone, qui s&rsquo;\u00e9tait adapt\u00e9 avec une stup\u00e9fiante habilet\u00e9 aux exigences, us et coutumes du parti de la communication, notamment en exploitant la r\u00e9v\u00e9rence et le prestige de la chose militaire dans l&rsquo;<em>establishment<\/em>, tenait toutes les cartes. Cela n&rsquo;\u00e9tait pas un probl\u00e8me. Les <em>neocons<\/em>, relais oblig\u00e9s d&rsquo;Isra\u00ebl \u00e0 Washington, avaient adopt\u00e9 au centuple la politique britannique d\u00e9finie en 1944 par une circulaire du Foreign Office, mais en la retournant avec une impudence qui laisse \u00e0 penser.<\/p>\n<\/p>\n<p><p>\tJohn Charmley \u00e9crivait en 1996 (voir son livre <em>La Passion de Churchill<\/em>) : \u00ab<em>En tentant d&rsquo;exposer l&rsquo;essence d&rsquo;une politique am\u00e9ricaine en 1944, un diplomate d\u00e9finit parfaitement cette attitude. La politique traditionnelle du Royaume-Uni de chercher \u00e0 emp\u00eacher qu&rsquo;une puissance exer\u00e7\u00e2t une position dominante \u00e9tait \u00e9cart\u00e9e : Notre but ne doit pas \u00eatre de chercher \u00e0 \u00e9quilibrer notre puissance contre celle des \u00c9tats-Unis, mais d&rsquo;utiliser la puissance am\u00e9ricaine pour des objectifs que nous consid\u00e9rons comme b\u00e9n\u00e9fiques. La politique britannique devrait \u00eatre d\u00e9sormais consid\u00e9r\u00e9e comme un moyen d&rsquo; orienter cette \u00e9norme p\u00e9niche maladroite<\/em> [les USA] <em>vers le port qui convient. L&rsquo;id\u00e9e d&rsquo;utiliser la puissance am\u00e9ricaine pour prot\u00e9ger le Commonwealth et l&rsquo;Empire avait beaucoup de charme en soi, en fonction de ce que l&rsquo;on sait des attitudes de Roosevelt concernant l&rsquo;Europe. Elle \u00e9tait \u00e9galement un parfait exemple de la fa\u00e7on dont les Britanniques parvenaient \u00e0 se tromper eux-m\u00eames \u00e0 propos de l&rsquo;Am\u00e9rique.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes <em>neocons<\/em> (et Isra\u00ebl, par cons\u00e9quent) avaient-ils r\u00e9ussi ce que les Britanniques ne r\u00e9ussirent jamais malgr\u00e9 leur finesse tactique? Cela sembla \u00eatre le cas tout au long de l&rsquo;aventure irakienne. Mais le jugement contenait une forte dose d&rsquo;ambigu\u00eft\u00e9: dans quelle mesure la manipulation en \u00e9tait-elle une, si le Pentagone avait d\u00e9cid\u00e9 de lui-m\u00eame que l&rsquo;aventure irakienne, assortie d&rsquo;une offensive g\u00e9n\u00e9rale de conflits, d&rsquo;implantations et d&rsquo;influence accompagnant la guerre contre la terreur, \u00e9tait de son int\u00e9r\u00eat?<\/p>\n<\/p>\n<p><p>\tLa suite montra que cette ambigu\u00eft\u00e9 rec\u00e9lait une contradiction. A partir de 2005-2006, le Pentagone commen\u00e7a \u00e0 \u00e9voluer, selon le constat que les aventures ext\u00e9rieures pouvaient lui co\u00fbter plus qu&rsquo;elles ne lui rapportaient. Face aux gains apparents de la politique expansionniste, on constatait une usure interne extraordinairement puissante, qui touchait toutes les structures de cette entit\u00e9, r\u00e9duisait le volume des forces, plongeait dans le chaos les processus d&rsquo;acquisition et de modernisation, transformait la gestion de l&rsquo;ensemble en un cauchemar. Il est vite apparu que ces maux n&rsquo;\u00e9taient pas comptables mais eux-m\u00eames profond\u00e9ment structurels: l&rsquo;augmentation incessante du budget de la d\u00e9fense ne r\u00e9solvait rien, au contraire il apparut d&rsquo;ann\u00e9e en ann\u00e9e comme un facteur de d\u00e9sordre de plus, en favorisant les maux structurels du syst\u00e8me (gaspillage, errance bureaucratique, gestion chaotique, corruption, etc.).<\/p>\n<\/p>\n<p><p>\tLes diff\u00e9rents services concurrents eurent une attitude conjoncturelle diff\u00e9rente selon leurs int\u00e9r\u00eats,  l&rsquo;U.S. Navy \u00e9tant la plus rapidement inqui\u00e8te de la situation, l&rsquo;USAF occupant une position oppos\u00e9e,  mais tr\u00e8s vite ils en arriv\u00e8rent \u00e0 une conclusion commune. Aujourd&rsquo;hui, la crise du Pentagone est per\u00e7ue avec une \u00e9gale acuit\u00e9 par toute la direction militaire et tous les services. Le conflit en Afghanistan illustre bien cette situation. Certes, les militaires sont engag\u00e9s \u00e0 fond dans ce conflit parce qu&rsquo;il existe, que le pouvoir politique s&rsquo;y est engag\u00e9, parce que le statut du Pentagone est lui-m\u00eame en jeu. Mais tout le reste, autour de l&rsquo;Afghanistan, doit \u00eatre r\u00e9duit, contr\u00f4l\u00e9, voire pacifi\u00e9 le plus possible. Le but est double: effectivement favoriser une \u00e9ventuelle et rapide victoire en Afghanistan pour pouvoir souffler; par cons\u00e9quent et surtout, \u00e9viter un autre engagement redoublant celui de l&rsquo;Afghanistan ou lui succ\u00e9dant (un peu comme l&rsquo;Afghanistan relanc\u00e9e avec Obama a pris le relais de l&rsquo;Irak).<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 <a href=\"http:\/\/www.dedefensa.org\/article-moby_dick_contre_israel_19_03_2010.html\" class=\"gen\">l&rsquo;intervention<\/a> de Petraeus, dont on a beaucoup parl\u00e9. Elle a \u00e9t\u00e9 extr\u00eamement pes\u00e9e, calcul\u00e9e, concert\u00e9e avec le Joint Chiefs of Staff. En raison de la popularit\u00e9 et de l&rsquo;influence du g\u00e9n\u00e9ral, de sa puissance de communication vis-\u00e0-vis du Congr\u00e8s, elle a constitu\u00e9 un \u00e9v\u00e9nement de communication particuli\u00e8rement puissant. Elle a marqu\u00e9 une rupture en s&rsquo;adressant brutalement \u00e0 Isra\u00ebl pour signifier \u00e0 ce pays que le Pentagone ne soutenait plus sa politique. La puissance de l&rsquo;\u00e9v\u00e9nement est notamment marqu\u00e9e par <a href=\"http:\/\/www.dedefensa.org\/article-le_lobby_s_affole_que_faire_de_petraeus_20_03_2010.html\" class=\"gen\">le d\u00e9sarroi<\/a> du parti isra\u00e9lien, notamment et principalement vis-\u00e0-vis de Petraeus lui-m\u00eame,  parce que Petraeus \u00e9tait jusqu&rsquo;alors tenu comme le plus ferme alli\u00e9 indirect de ce m\u00eame parti isra\u00e9lien, puisqu&rsquo;il \u00e9tait l&rsquo;homme qui avait transform\u00e9 l&rsquo;affreuse r\u00e9alit\u00e9 irakienne en une <em>narrative<\/em> victorieuse qui rencontrait absolument les conceptions des n\u00e9oconservateurs.<\/p>\n<h3>Discorde chez l&rsquo;ennemi (suite)<\/h3>\n<\/p>\n<p><p>\tOn comprend que ce n&rsquo;est pas une question de personne, et r\u00e9duire le probl\u00e8me aux intentions et ambitions de Petraeus, c&rsquo;est le priver de sa vraie dimension. Nous parlons en termes d&rsquo;entit\u00e9s, en termes de syst\u00e8mes anthropotechniques lorsqu&rsquo;on parle du Pentagone, si l&rsquo;on veut selon une vision anthropomorphiste des forces qui sont \u00e0 l&rsquo;uvre. Dans ce cas, Petraeus est bien, en l&rsquo;occurrence et pour le temps pr\u00e9sent qui nous int\u00e9resse, le d\u00e9l\u00e9gu\u00e9 du Pentagone; il est la voix du Pentagone, il exprime la politique du Pentagone, il <strong>est<\/strong> le Pentagone. L&rsquo;habilet\u00e9 est d&rsquo;avoir utilis\u00e9 un homme tr\u00e8s puissant du point de vue de la communication, donc d&rsquo;avoir affirm\u00e9 une position du parti du technologisme en \u00f4tant au parti de la communication certaines de ses armes favorites.<\/p>\n<\/p>\n<p><p>\tToutes ces consid\u00e9rations de pure tactique ne doivent pas nous \u00e9carter du constat essentiel. L&rsquo;intervention de Petraeus est la marque puissante et \u00e9clatante de la rupture de la Sainte Alliance scell\u00e9e avec \u00e9clat lors de la guerre du Kosovo et qui fonctionna \u00e0 plein depuis 9\/11. Le parti du technologisme, essentiellement repr\u00e9sent\u00e9 par le Pentagone, se sent fondamentalement en danger, non pas \u00e0 cause d&rsquo;un adversaire ext\u00e9rieur mais \u00e0 cause de ses propres faiblesses. C&rsquo;est l&rsquo;illustration typique de la <a href=\"http:\/\/www.dedefensa.org\/article-la_fable_des_termites_et_des_conduites_pourries_22_09_2008.html\" class=\"gen\">fable<\/a> des loups et des termites, lorsqu&rsquo;on s&rsquo;oppose \u00e0 des loups qui n&rsquo;existent gu\u00e8re, et qu&rsquo;on se trouve min\u00e9 par l&rsquo;action interne des termites dont l&rsquo;efficacit\u00e9 est multipli\u00e9e par les effets de l&rsquo;effort fait pour combattre les loups qui n&rsquo;existent pas.<\/p>\n<\/p>\n<p><p>\tIl y a donc rupture dans l&rsquo;air, d\u00e9j\u00e0 act\u00e9, et qui va se concr\u00e9tiser sur le terme des mois qui viennent, peut-\u00eatre des deux ann\u00e9es \u00e0 venir jusqu&rsquo;\u00e0 des cons\u00e9quences importantes. Cette rupture est fondamentale puisque c&rsquo;est celle de la Sainte Alliance. Le parti de la communication, regroupant notamment tous les moyens de communications officiels et les communaut\u00e9s intellectuelles du syst\u00e8me occidentaliste-am\u00e9ricaniste, dont notre parti des salonards parisien, et regroup\u00e9 autour d&rsquo;Isra\u00ebl en tant qu&rsquo;entit\u00e9 id\u00e9ologique et politique aussi bien qu&rsquo;en tant que symbole, se trouve brusquement priv\u00e9 du moteur de puissance qu&rsquo;\u00e9tait pour lui le parti du technologisme avec lequel s&rsquo;\u00e9tait nou\u00e9e la Sainte Alliance.<\/p>\n<\/p>\n<p><p>\tSch\u00e9ma classique, que nous avons souvent signal\u00e9, de la discorde chez l&rsquo;ennemi, affectant cette fois les deux grandes forces du syst\u00e8me. Isra\u00ebl est au centre du propos, ce qui est une chose importante parce qu&rsquo;il s&rsquo;agit d&rsquo;un acteur particuli\u00e8rement turbulent, qui ne cessera plus de poser sur la table des cas d\u00e9licats qui alimenteront les conflits. Avec Isra\u00ebl, les militaires se trouvent sur leur terrain de pr\u00e9dilection des manipulations strat\u00e9giques, et les intellectuels de la communication sur leur terrain de pr\u00e9dilection des manipulations morales. La situation, qui d\u00e9multipliait cette double puissance du temps de l&rsquo;entente, risque d\u00e9sormais d&rsquo;\u00e9voluer vers un d\u00e9sordre profond et un affrontement d\u00e9chirant de deux puissances aussi impressionnante l&rsquo;une que l&rsquo;autre.<\/p>\n<\/p>\n<p><p>\tSi les bombes de l&rsquo;U.S. Air Force ne sont plus humanitaires, la morale du parti des salonards se trouvera confront\u00e9 \u00e0 l&rsquo;horrible perspective de devoir envisager la critique de l&rsquo;am\u00e9ricanisme au nom des habituels <em>ukases<\/em> (Petraeus est-il antis\u00e9mite? Etc.) Cette perspective n&rsquo;est certainement pas suffisante pour d\u00e9courager le parti du technologisme. Le Pentagone n&rsquo;a gu\u00e8re d&rsquo;\u00e9tats d&rsquo;\u00e2me, m\u00eame s&rsquo;il s&rsquo;av\u00e9rait qu&rsquo;il a une conscience et une politique. Son alliance avec le parti de la communication ne fut jamais qu&rsquo;une rencontre de circonstance.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cr\u00e9puscule de la Sainte Alliance 22 mars 2010 Quelque part, disons entre 1990 et 1999, s&rsquo;\u00e9tablit fermement et \u00e0 d\u00e9couvert une alliance qui, dans sa potentialit\u00e9, vient de beaucoup plus loin qu&rsquo;on ne croit, qui vient, par exemple, de ce jour de 1825 sans doute, o\u00f9 Stendhal bondit d&rsquo;horreur et abandonna aussit\u00f4t son engagement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2996,2734,3015,6200,9404,3206,2774,3085,4679,5905,8727,3194,6264,9405,9403,4268],"class_list":["post-71694","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alliance","tag-charmley","tag-communication","tag-discorde","tag-gouhier","tag-hawks","tag-israel","tag-kosovo","tag-liberal","tag-liberaux","tag-lumieres","tag-pentagone","tag-petraeus","tag-sainte","tag-stendhal","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71694"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71694\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}