{"id":71713,"date":"2010-03-29T07:55:36","date_gmt":"2010-03-29T07:55:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/29\/un-traite-au-gout-incertain\/"},"modified":"2010-03-29T07:55:36","modified_gmt":"2010-03-29T07:55:36","slug":"un-traite-au-gout-incertain","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/29\/un-traite-au-gout-incertain\/","title":{"rendered":"Un trait\u00e9 au go\u00fbt incertain"},"content":{"rendered":"<p><p>L&rsquo;annonce que le trait\u00e9 START-II est conclu entre les USA et la Russie et sera paraph\u00e9 par les deux pr\u00e9sidents (Obama et Medvedev) le 8 avril \u00e0 Prague a \u00e9t\u00e9 l&rsquo;occasion de r\u00e9actions tr\u00e8s diff\u00e9rentes. Triomphantes \u00e0 Washington, presque indiff\u00e9rentes \u00e0 Moscou. Comme l&rsquo;\u00e9crit le New York <em>Times<\/em> le <a href=\"http:\/\/www.nytimes.com\/2010\/03\/27\/world\/europe\/27russia.html\" class=\"gen\">26 mars 2010<\/a>: \u00ab<em>On a Friday that began in Washington with a triumphant presidential news conference about the conclusion of arms talks with Russia, Moscow seemed to have its mind on other things.<\/em>\u00bb Medvedev \u00e9tait \u00e0 Sochi, pour discuter des futurs Jeux Olympiques. Poutine faisait un discours sur les dangers des inondations courantes au printemps.<\/p>\n<\/p>\n<p><p>\tLe point central, qui \u00e9tait le lien que voulaient \u00e9tablir les Russes entre les armes offensives et les armes d\u00e9fensives (anti-missiles), semble n&rsquo;\u00eatre rencontr\u00e9 que d&rsquo;une mani\u00e8re extr\u00eamement \u00e9vasive. \u00ab<em>In recent months Russian leaders  notably Mr. Putin  have pushed openly for a pact that explicitly links reductions in strategic weapons to limits on the American missile-defense program. Aleksei K. Pushkov, the host of the political talk show Post-Scriptum, said he feared that the text of the treaty included only a soft linkage between offense and defense. For many Russians, the first question will be, Where have we made concessions to the United States? he said, and they will look for the answer in those phrases.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa seule pr\u00e9cision \u00e0 propos du lien est venue du ministre russe des affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov. \u00ab<em>Mr. Lavrov called the agreement real progress in the relationship between Russia and the United States, but added that Russia could pull out if it concluded that the American missile defense plans had compromised its nuclear deterrent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDu c\u00f4t\u00e9 am\u00e9ricain, donc, un air triomphant. C&rsquo;est la grande semaine de renaissance du pr\u00e9sident BHO. Un texte de <em>ABC.News<\/em>, du <a href=\"http:\/\/blogs.abcnews.com\/politicalpunch\/2010\/03\/nuke-treaty-talks-almost-fell-apart-last-month-after-russians-kept-insisting-on-linking-missile-defe.html\" class=\"gen\">26 mars 2010<\/a>, nous rapporte diverses anecdotes, venues d&rsquo;officiels de la Maison-Blanche, montrant un Obama r\u00e9sistant aux pressions des Russes. \u00ab<em>At the end of the day it was a pivotal moment, the official said, suggesting that the Russians saw President Obama as someone who wasn&rsquo;t going to cave.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn autre texte, peut-\u00eatre le plus significatif apr\u00e8s tout, de <em>The Voice of America<\/em>, du <a href=\"http:\/\/www1.voanews.com\/english\/news\/usa\/Missile-Defense-Controversy-Remains-After-START-Accord-89287027.html\" class=\"gen\">26 mars 2010<\/a>, affirme que le trait\u00e9 ne cl\u00f4t nullement la controverse des anti-missiles. Le texte d\u00e9taille au contraire combien le syst\u00e8me anti-missiles est devenu essentiel dans la programmation du Pentagone, qu&rsquo;il s&rsquo;agit d\u00e9sormais d&rsquo;un domaine non n\u00e9gociable.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Friday&rsquo;s announcement of a new U.S.-Russia strategic arms reduction treaty was achieved partly because the negotiators agreed to separate the issue from the controversy over the U.S. missile defense program.  Russia has strongly opposed the program, but U.S. officials say missile defense has become<\/em> <strong><em>an integral part of security<\/em><\/strong> <em>for the United States and its allies, and they predict significant advances during the next two years.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> L&rsquo;issue de cette affaire, le trait\u00e9 START-II, est assez inattendue, au point o\u00f9 l&rsquo;on se dit qu&rsquo;il ne s&rsquo;agit pas d&rsquo;un v\u00e9ritable trait\u00e9, dans le sens o\u00f9 il serait fondateur d&rsquo;une nouvelle politique et de nouvelles relations. Le contraste entre l&rsquo;attitude US et l&rsquo;attitude russe est remarquable. Le New York <em>Times<\/em>, dans l&rsquo;article cit\u00e9, avance l&rsquo;hypoth\u00e8se que la r\u00e9serve des Russes est notamment justifi\u00e9e par la crainte qu&rsquo;un certain triomphalisme de leur part pourrait compromettre la ratification du trait\u00e9 au S\u00e9nat US (\u00ab<em>One reason for Russian caution is the looming ratification vote in the United States Senate, where any note of Russian triumphalism might play badly<\/em>\u00bb). Le m\u00eame argument est prolong\u00e9 par l&rsquo;affirmation que l&rsquo;opposition au trait\u00e9 en Russie, notamment \u00e0 la <em>Douma<\/em>, est n\u00e9gligeable. Tout cela semble contredire ce qui devrait \u00eatre un r\u00e9el d\u00e9sappointement russe de l&rsquo;absence d&rsquo;un lien solide entre armements offensifs et d\u00e9fensifs,  quoique il faudrait voir dans quelle mesure la remarque de Lavrov n&rsquo;est pas extr\u00eamement s\u00e9rieuse (le trait\u00e9 donnant la possibilit\u00e9 \u00e0 la Russie de s&rsquo;en retirer si la question des anti-missiles devenait trop br\u00fblante). Mais toutes ces remarques restent tr\u00e8s conditionnelles, tant que le texte d\u00e9finitif n&rsquo;est pas connu.<\/p>\n<\/p>\n<p><p>\tSi l&rsquo;attitude russe reste incertaine, l&rsquo;attitude de la partie am\u00e9ricaniste, elle, est beaucoup plus pr\u00e9cise. Elle se d\u00e9compose en deux points essentiels, \u00e0 notre sens, qui brossent un tableau peu encourageant pour ce qui concerne les espoirs de stabilit\u00e9 qu&rsquo;aurait pu et du amener ce trait\u00e9 START-II.<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, il y a la situation politique de Barak Obama. Le triomphalisme de la Maison-Blanche dans cette affaire fait manifestement partie d&rsquo;une tr\u00e8s forte op\u00e9ration de relations publiques pour rehausser la stature d&rsquo;un pr\u00e9sident incroyablement diminu\u00e9, op\u00e9ration d\u00e9j\u00e0 commenc\u00e9e avec le vote de la loi sur les soins de sant\u00e9. De m\u00eame, le but du pr\u00e9sident est \u00e9galement de remporter tr\u00e8s vite une nouvelle victoire au Congr\u00e8s avec la ratification du trait\u00e9, et son triomphalisme fait partie de cet autre aspect de l&rsquo;op\u00e9ration. De ce point de vue, la position de l&rsquo;administration Obama appara\u00eet suspecte et nous dit fort peu de choses sur la pens\u00e9e profonde du pr\u00e9sident et de son \u00e9quipe sur le trait\u00e9, s&rsquo;il y a d&rsquo;ailleurs une pens\u00e9e profonde.<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, et c&rsquo;est peut-\u00eatre le plus important, l&rsquo;affirmation tonitruante de l&rsquo;importance du syst\u00e8me anti-missiles par toute la communaut\u00e9 de s\u00e9curit\u00e9 nationale, telle que l&rsquo;expose le texte de <em>The Voice of America<\/em>. Il s&rsquo;agit d&rsquo;une affirmation impressionnante, qui est la proclamation que le syst\u00e8me anti-missiles est d\u00e9sormais class\u00e9 dans la cat\u00e9gorie des intouchables du Pentagone, un de ces syst\u00e8mes non n\u00e9gociable qu&rsquo;il ne peut \u00eatre question d&rsquo;abandonner, voire d&rsquo;alt\u00e9rer. (D\u00e9claration triomphante du n\u00b02 du Pentagone, William Lynn, la semaine derni\u00e8re: <em>The high-pitched partisan debate over whether to invest in missile defense is no longer with us. Ballistic missile defense is without question an important part of our current and future strategy.  We are committed to developing new missile technologies to their fullest.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tCe deuxi\u00e8me point est de loin le plus important parce qu&rsquo;il nous situe peut-\u00eatre d&rsquo;une fa\u00e7on pr\u00e9cise le climat dans lequel se sont d\u00e9roul\u00e9es, du c\u00f4t\u00e9 US, les tractations pour d\u00e9terminer une position dans l&rsquo;affaire START-II. Le point central serait que le groupe de pression sur les anti-missiles a pris une importance consid\u00e9rable apr\u00e8s les d\u00e9cisions de l&rsquo;\u00e9t\u00e9 dernier d&rsquo;abandon des plans de d\u00e9ploiement en Pologne et en Tch\u00e9quie, et en r\u00e9action \u00e0 ces d\u00e9cisions. Le groupe de pression des anti-missiles a r\u00e9agi, semble-t-il, avec une force consid\u00e9rable, et il semble \u00e9galement qu&rsquo;Obama ait du reculer devant ces pressions. Les Russes ont-ils compris qu&rsquo;il n&rsquo;y avait rien \u00e0 faire contre cette pression et que le trait\u00e9 START-II les arrangeait en l&rsquo;\u00e9tat en limitant les capacit\u00e9s offensives US alors qu&rsquo;eux-m\u00eames ont un arsenal offensif en mauvais \u00e9tat, qu&rsquo;ils sont ainsi dispens\u00e9s d&rsquo;efforts budg\u00e9taires ruineux tandis que les USA sont emp\u00each\u00e9s d&rsquo;\u00e9largir leur arsenal?<\/p>\n<\/p>\n<p><p>\tUne hypoth\u00e8se qui semblerait donc devoir se pr\u00e9ciser, c&rsquo;est bien que la question des anti-missiles n&rsquo;est pas close et qu&rsquo;elle va certainement \u00eatre l&rsquo;occasion d&rsquo;autres crises et d&rsquo;autres tensions entre la Russie et les USA. La conclusion que nous serions tent\u00e9s de tirer, conclusion temporaire tant il reste d&rsquo;\u00e9l\u00e9ments \u00e0 \u00e9claircir, est que la question des rapports strat\u00e9giques entre la Russie et les USA est loin, tr\u00e8s loin d&rsquo;\u00eatre r\u00e9gl\u00e9e par START-II. De ce point de vue, START-II n&rsquo;a nullement l&rsquo;importance historique que les services du syst\u00e8me de la communication \u00e0 Washington voudraient lui attribuer, \u00e0 la gloire d&rsquo;un pr\u00e9sident Obama r\u00e9g\u00e9n\u00e9r\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 mars 2010 \u00e0 07H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;annonce que le trait\u00e9 START-II est conclu entre les USA et la Russie et sera paraph\u00e9 par les deux pr\u00e9sidents (Obama et Medvedev) le 8 avril \u00e0 Prague a \u00e9t\u00e9 l&rsquo;occasion de r\u00e9actions tr\u00e8s diff\u00e9rentes. Triomphantes \u00e0 Washington, presque indiff\u00e9rentes \u00e0 Moscou. Comme l&rsquo;\u00e9crit le New York Times le 26 mars 2010: \u00abOn a Friday&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5541,3453,2830,3816,2858,6208,916,6975,5713,9420,2766,9097],"class_list":["post-71713","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-abm","tag-anti-missiles","tag-lavrov","tag-lobby","tag-medvedev","tag-obama","tag-poutine","tag-pressions","tag-publiques","tag-regenere","tag-relations","tag-start-ii"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71713"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71713\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}