{"id":71719,"date":"2010-03-30T12:26:41","date_gmt":"2010-03-30T12:26:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/30\/voila-qui-plairait-a-de-gaulle\/"},"modified":"2010-03-30T12:26:41","modified_gmt":"2010-03-30T12:26:41","slug":"voila-qui-plairait-a-de-gaulle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/03\/30\/voila-qui-plairait-a-de-gaulle\/","title":{"rendered":"Voil\u00e0 qui plairait \u00e0 de Gaulle"},"content":{"rendered":"<p><h4>Voil\u00e0 qui plairait \u00e0 de Gaulle<\/h4>\n<p>La d\u00e9claration de James Sternberg, du d\u00e9partement d&rsquo;Etat, ferait plaisir \u00e0 de Gaulle et \u00e0 sa politique d&rsquo;ind\u00e9pendance nationale. Sternberg dit que les USA et l&rsquo;OTAN doivent \u00eatre impliqu\u00e9s dans les n\u00e9gociations de la vente du <em>Mistral<\/em> \u00e0 la Russie ! Comme Sarko d\u00e9jeune aujourd&rsquo;hui avec Obama (je crois), il va pouvoir lui dire tout le bien qu&rsquo;il pense du j&rsquo;ai mon mot \u00e0 dire de Washington dans la vente du <em>Mistral<\/em> aux Russes.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est Novosti qui rapporte la nouvelle, aujourd&rsquo;hui (lien : <a href=\"http:\/\/fr.rian.ru\/defense\/20100330\/186350990.html\" class=\"gen\">http:\/\/fr.rian.ru\/defense\/20100330\/186350990.html<\/a>).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La d\u00e9cision de la France de vendre \u00e0 la Russie des porte-h\u00e9licopt\u00e8res de classe Mistral doit faire l&rsquo;objet d&rsquo;une analyse d\u00e9taill\u00e9e, a d\u00e9clar\u00e9 lundi aux journalistes le secr\u00e9taire d&rsquo;Etat adjoint am\u00e9ricain James Steinberg.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le pr\u00e9sident a accord\u00e9 une certaine attention \u00e0 cette question mais je crois que la meilleure solution est de discuter avec nos coll\u00e8gues fran\u00e7ais des moyens de renforcer la stabilit\u00e9 sur le territoire de l&rsquo;ex-URSS, a indiqu\u00e9 M. Steinberg.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il a soulign\u00e9 que chaque pays \u00e9tait en droit de prendre seul des d\u00e9cisions de ce genre, mais qu&rsquo;il \u00e9tait important pour les Etats-Unis d&rsquo;\u00eatre s\u00fbr qu&rsquo;elles \u00e9taient m\u00fbrement r\u00e9fl\u00e9chies. Il est important que toutes les cons\u00e9quences possibles aient \u00e9t\u00e9 pes\u00e9es, a dit le diplomate.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Selon lui, les Etats-Unis et l&rsquo;OTAN doivent \u00eatre impliqu\u00e9s dans les discussions sur ce contrat.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>Ulysse<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voil\u00e0 qui plairait \u00e0 de Gaulle La d\u00e9claration de James Sternberg, du d\u00e9partement d&rsquo;Etat, ferait plaisir \u00e0 de Gaulle et \u00e0 sa politique d&rsquo;ind\u00e9pendance nationale. Sternberg dit que les USA et l&rsquo;OTAN doivent \u00eatre impliqu\u00e9s dans les n\u00e9gociations de la vente du Mistral \u00e0 la Russie ! Comme Sarko d\u00e9jeune aujourd&rsquo;hui avec Obama (je crois),&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2631,2685,8635,584,2730,9424,9141],"class_list":["post-71719","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-de","tag-gaulle","tag-mistral","tag-otan","tag-russie","tag-sternberg","tag-ulysse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71719"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71719\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}