{"id":71749,"date":"2010-04-07T09:14:49","date_gmt":"2010-04-07T09:14:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/07\/loutil-supreme-de-la-revolte-generale\/"},"modified":"2010-04-07T09:14:49","modified_gmt":"2010-04-07T09:14:49","slug":"loutil-supreme-de-la-revolte-generale","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/07\/loutil-supreme-de-la-revolte-generale\/","title":{"rendered":"\u00ab\u2026L&rsquo;outil   supr\u00eame de la r\u00e9volte g\u00e9n\u00e9rale<D>\u00bb"},"content":{"rendered":"<p><h2 class=\"common-article2\">\u00abL&rsquo;outil   supr\u00eame de la r\u00e9volte g\u00e9n\u00e9rale<D>\u00bb<\/h2>\n<\/p>\n<p><p>\tIl y a quelques jours, un de nos lecteurs a demand\u00e9 une interview \u00e0 Philippe Grasset, \u00e0 partir du th\u00e8me trait\u00e9 dans <em>dde.crisis<\/em> du <a href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_25_mars_2010.html\" class=\"gen\">25 mars 2010<\/a> sur l&rsquo;annihilation et la dissolution des hommes politiques par le syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>\tCette interview a \u00e9t\u00e9 publi\u00e9e hier <a href=\"http:\/\/owni.fr\/2010\/04\/06\/reseaux-sociaux-les-outils-supremes-de-la-revolte-generale\/comment-page-1\/#comment-16989\" class=\"gen\">6 avril 2010<\/a> sur le site <em>OWNI.fr<\/em>. Nous la reproduisons aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t<strong>Question : Nicolas Sarkozy et Barack Obama ont tous deux \u00e9t\u00e9 \u00e9lus sur un fort espoir de changement auquel a succ\u00e9d\u00e9 une d\u00e9ception et un essoufflement rapide. En quoi leurs parcours similaires sont ils symptomatiques de l&rsquo;\u00e9tat de notre syst\u00e8me politique?<\/strong><\/p>\n<\/p>\n<p><p>\tPhilippe Grasset : Nous ne vivons <strong>plus<\/strong> dans un monde diversifi\u00e9, ni m\u00eame dans un monde globalis\u00e9, ni m\u00eame dans un monde tout court. Nous vivons sous l&#8217;empire d&rsquo;un syst\u00e8me qui a acquis, gr\u00e2ce \u00e0 sa puissance, une compl\u00e8te autonomie, \u00e0 un point o\u00f9 l&rsquo;on peut se demander s&rsquo;il ne s&rsquo;agit pas d&rsquo;un ph\u00e9nom\u00e8ne en soi, d&rsquo;un artefact universel, qu&rsquo;aucune entit\u00e9 humaine ne ma\u00eetrise et qui dispose sans doute d&rsquo;une pens\u00e9e automatique, voire peut-\u00eatre plus, au demeurant tout \u00e0 fait nihiliste dans ses ambitions. Deux forces r\u00e9gissent ce syst\u00e8me: l&rsquo;une est le syst\u00e8me du technologisme, cette dynamique d&rsquo;une puissance extraordinaire qui est dispens\u00e9e par les technologies et anime l&rsquo;essentiel de ces choses qu&rsquo;on persiste \u00e0 nommer des politiques. L&rsquo;autre est le syst\u00e8me de la communication, qui r\u00e9git un flot d&rsquo;informations qui ont le plus souvent la forme de consignes dont le but est d&rsquo;habiller d&rsquo;une mani\u00e8re convenable pour l&rsquo;esprit les effets du syst\u00e8me du technologisme, de fa\u00e7on \u00e0 le pr\u00e9server de toute attaque et critique fondamentales.<\/p>\n<\/p>\n<p><p>\tDans cet ensemble, les hommes politiques, ceux qui parlent et semblent \u00eatre l\u00e0 pour accr\u00e9diter l&rsquo;id\u00e9e qu&rsquo;il existe encore des politiques diversifi\u00e9es, sont n\u00e9cessairement des cr\u00e9atures du syst\u00e8me de communication, sinon ils ne seraient pas l\u00e0 o\u00f9 ils sont. Ils ne sont pas pour autant homog\u00e9n\u00e9is\u00e9s; certains sont intelligents, d&rsquo;autres cyniques, d&rsquo;autres sentimentaux, certains sont tr\u00e8s corrompus et d&rsquo;autres beaucoup moins, et ainsi de suite. Mais une chose les r\u00e9unit au moment de l&rsquo;examen de passage (l&rsquo;\u00e9lection, ou la nomination \u00e0 un poste de direction, etc.): la n\u00e9cessit\u00e9 d&rsquo;en passer par le syst\u00e8me de communication.<\/p>\n<\/p>\n<p><p>\tLe syst\u00e8me de la communication est tr\u00e8s divers et tr\u00e8s habile. Ainsi peut-il susciter des apparences de critique contre certains effets du syst\u00e8me du technologisme en brouillant le circuit de cause \u00e0 effet, de fa\u00e7on \u00e0 \u00e9viter la critique centrale. Ainsi les hommes politiques peuvent-ils utiliser, en mati\u00e8re de communication, des arguments d&rsquo;une critique extr\u00eamement forte de la situation pr\u00e9sente, mais qui doit rester extr\u00eamement vague pour ne pas aller \u00e0 la critique fondamentale du syst\u00e8me. C&rsquo;est donc la r\u00e9forme implicitement radicale pour Sarkozy, le changement implicitement r\u00e9volutionnaire pour Obama.<\/p>\n<\/p>\n<p><p>\tMais nous avons d\u00e9crit le syst\u00e8me dans sa situation id\u00e9ale. A c\u00f4t\u00e9 de cela existe la r\u00e9alit\u00e9, et la r\u00e9alit\u00e9 est caract\u00e9ris\u00e9e par deux faits : d&rsquo;une part, ce syst\u00e8me est en crise profonde, parce qu&rsquo;il arrive au maximum de sa puissance, c&rsquo;est-\u00e0-dire au maximum de l&rsquo;oppression qu&rsquo;il exerce sur nous alors qu&rsquo;il a besoin de nous pour faire subsister une apparence de l\u00e9gitimit\u00e9 (\u00e9lections, d\u00e9mocratie, libert\u00e9 de parole, etc.) ; et, d&rsquo;autre part, le nous, c&rsquo;est-\u00e0-dire vous, moi, les peuples, etc., subsistent, subissent cette oppression syst\u00e9mique et la supportent de moins en moins. C&rsquo;est pourquoi les candidats pr\u00f4nant la r\u00e9forme implicitement radicale et le changement implicitement r\u00e9volutionnaire sont \u00e9lus, et qu&rsquo;ils sont aussit\u00f4t l&rsquo;objet d&rsquo;une profonde d\u00e9saffection. La promesse autoris\u00e9e tactiquement par le syst\u00e8me de la communication ne peut \u00eatre tenue une seule seconde lorsque l&rsquo;homme politique, install\u00e9 au pouvoir, se trouve sous l&#8217;empire du syst\u00e8me du technologisme.<\/p>\n<\/p>\n<p><p>\tPour arriver \u00e0 rompre cet encha\u00eenement infernal, \u00e0 l&rsquo;instant o\u00f9 nous sommes, il faudrait un Gorbatchev, c&rsquo;est-\u00e0-dire un homme qui joue le jeu du syst\u00e8me pour arriver au pouvoir et qui, \u00e0 un moment donn\u00e9, alors qu&rsquo;il est au pouvoir, entre en dissidence, prend la maquis si vous voulez, et attaque le syst\u00e8me par l&rsquo;ext\u00e9rieur, hors du syst\u00e8me, en utilisant des moyens de l&rsquo;int\u00e9rieur que lui donne le pouvoir qu&rsquo;il d\u00e9tient, exactement comme a fait Gorbatchev. Parce que Gorbatchev, consciemment ou pas pour son but final peu importe, a agi exactement comme \u00e7a, d\u00e8s l&rsquo;automne 1985, six mois apr\u00e8s son \u00e9lection comme secr\u00e9taire g\u00e9n\u00e9ral du PC de l&rsquo;URSS en mars 1985, apr\u00e8s avoir plac\u00e9 ses premiers hommes \u00e0 lui (Chevardnadze \u00e0 la place de Gromyko aux affaires \u00e9trang\u00e8res) d\u00e8s mai 1985. Tous ceux qui vous font une description institutionnelle de l&rsquo;action de Gorbatchev, seulement \u00e0 partir de 1987, n&rsquo;ont rien compris \u00e0 l&rsquo;essence historique de son action, en g\u00e9n\u00e9ral parce qu&rsquo;ils sont rest\u00e9s anti-communiste m\u00eame apr\u00e8s la mort du communisme et ne peuvent s&rsquo;imaginer qu&rsquo;un communiste puisse en avoir marre du communisme jusqu&rsquo;\u00e0 envisager de lui faire la peau. Encore une fois, qu&rsquo;il ait voulu ou non l&rsquo;effet final de son action n&rsquo;importe pas ; Gorbatchev a \u00e9t\u00e9 un instrument formidable de l&rsquo;Histoire contre le syst\u00e8me sovi\u00e9tique, un dissident du syst\u00e8me, un maquisard entreprenant des actions de d\u00e9stabilisation compl\u00e8tement hors des normes du syst\u00e8me, intervenant aupr\u00e8s de groupes de citoyens et les incitant \u00e0 mettre en cause puis en accusation la bureaucratie,  pour cela, grand homme, sans aucun doute. On a cru qu&rsquo;Obama pourrait \u00eatre cet <em>American<\/em> Gorbatchev, mais, jusqu&rsquo;ici, on a \u00e9t\u00e9 notablement, sinon irr\u00e9m\u00e9diablement d\u00e9\u00e7u.<\/p>\n<\/p>\n<p><p>\tNotez que je parle en temps constant, \u00e0 l&rsquo;instant o\u00f9 nous sommes, car j&rsquo;estime que la situation \u00e9volue \u00e0 une rapidit\u00e9 absolument confondante, qui prend le syst\u00e8me lui-m\u00eame par surprise, sans parler de ces choses anim\u00e9es qu&rsquo;on nomme les hommes politiques. La pression du syst\u00e8me de la communication sur les psychologies, notamment, est consid\u00e9rable, et comme elle s&rsquo;exerce souvent dans le sens d&rsquo;une critique tactique pour \u00e9viter la critique fondamentale, elle joue constamment avec le danger pour le syst\u00e8me d&rsquo;ouvrir le champ \u00e0 une \u00e9chapp\u00e9e incontr\u00f4l\u00e9e de la psychologie vers cette critique fondamentale. Des agitations comme le mouvement <em>Tea Party<\/em> aux USA, les d\u00e9gringolades dans les sondages d&rsquo;un Sarko, etc., sont aussi bien les effets pervers (pour lui) du syst\u00e8me de la communication. Il est bien possible, sinon probable, qu&rsquo;en 2012,  ce sera une fameuse ann\u00e9e parce que, outre le calendrier des Mayas, nous aurons les pr\u00e9sidentielles russe, fran\u00e7aise et US en quelques mois,  la situation sera notablement diff\u00e9rente, et des choses tr\u00e8s diff\u00e9rentes pourront se manifester. La v\u00e9rit\u00e9 est que nous sommes dans tous les domaines dans une situation de tension maximale, et du syst\u00e8me, et des psychologies collectives contraintes par le syst\u00e8me. Il est absolument impossible de pr\u00e9voir de quoi demain,  disons 2012, pour le cas,  sera fait.<\/p>\n<\/p>\n<p><p>\t<strong>Question : Comment expliquez-vous que leur ma\u00eetrise des m\u00e9dias, si forte pendant leurs campagnes, ait sembl\u00e9 les abandonner d\u00e8s l&rsquo;\u00e9lection pass\u00e9e?<\/strong><\/p>\n<\/p>\n<p><p>\tPhilippe Grasset : Les m\u00e9dias que je nomme officiels, les m\u00e9dias classiques, r\u00e9pondant au conformisme des puissances \u00e9conomiques, suivent certes les consignes du syst\u00e8me ; mais ils r\u00e9pondent essentiellement, dans ce syst\u00e8me, beaucoup plus au minist\u00e8re du syst\u00e8me de la communication qu&rsquo;au minist\u00e8re du syst\u00e8me du technologisme. On a vu que les candidats vainqueurs r\u00e9pondent au syst\u00e8me de la communication et qu&rsquo;en plus ils ont le r\u00f4le flatteur du r\u00e9formiste, voire du r\u00e9volutionnaire, donc ils sont soutenus. Ce sont les candidats du changement. Une fois au pouvoir, ils d\u00e9pendent du syst\u00e8me du technologisme, ce sont les ex\u00e9cutants de la ligne du Parti. Les m\u00e9dias, qui d\u00e9pendent toujours du minist\u00e8re de la communication, se mettent \u00e0 tirer \u00e0 boulets rouges contre les candidats devenus pr\u00e9sidents.<\/p>\n<\/p>\n<p><p>\tCertes, il y a de temps en temps des corrections, mais d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, dans le contexte de crise, la tendance est de plus en plus marqu\u00e9e. Les journalistes du syst\u00e8me n&rsquo;\u00e9chappent pas au vertige que leur donne le syst\u00e8me de la communication, dont le r\u00f4le est d&rsquo;une pression constante sur la psychologie, en g\u00e9n\u00e9ral dans le sens de la ligne du Parti, mais qui implique aussi une excitation de la psychologie en g\u00e9n\u00e9ral pour les am\u00e9nagements tactiques dont j&rsquo;ai parl\u00e9 plus haut. Cela leur donne, \u00e0 ces belles \u00e2mes qui portent haut leur vertu, l&rsquo;excitation de la croyance qu&rsquo;ils peuvent \u00e9crire librement. Chaque fois, ils sont comme des adolescents puceaux qui vont \u00e0 un premier rendez-vous amoureux.<\/p>\n<\/p>\n<p><p>\tLe syst\u00e8me est certes au sommet de sa puissance d\u00e9chain\u00e9e, mais c&rsquo;est aussi, parall\u00e8lement, comme je l&rsquo;ai signal\u00e9 plus haut, le paroxysme de la crise g\u00e9n\u00e9r\u00e9e par cette puissance qui d\u00e9structure tout. Ce n&rsquo;est pas l&rsquo;ordre qui en r\u00e9sulte, mais de plus en plus le d\u00e9sordre. Les psychologies excit\u00e9es des journalistes du syst\u00e8me perdent de plus en plus souvent le sens des consignes, \u00e0 mesure de l&rsquo;affaiblissement, de l&rsquo;usure des candidats triomphants devenus pr\u00e9sidents en phase acc\u00e9l\u00e9r\u00e9e de dissolution. Alors, ces psychologies c\u00e8dent de plus en plus souvent \u00e0 l&rsquo;ivresse de la plume, et passent de plus en plus volontiers \u00e0 la critique de ceux qu&rsquo;elles ont \u00e9t\u00e9 contraints par leur propre psychologie \u00e0 adorer. D&rsquo;autant que tout cela pla\u00eet au public, qui est tout de m\u00eame le facteur qui fait rentrer des b\u00e9n\u00e9ficies.<\/p>\n<\/p>\n<p><p>\tSi je vous d\u00e9cris cette situation comme pleine de contradictions et de paradoxes, c&rsquo;est que les choses bougent \u00e0 une vitesse extraordinairement rapide, et que la puissance de la crise du syst\u00e8me contrarie de plus en plus l&rsquo;explosion de puissance du syst\u00e8me. Il s&rsquo;agit, sous nos yeux, d&rsquo;une bataille titanesque. Mon interpr\u00e9tation g\u00e9n\u00e9rale est que cette crise est due \u00e0 l&rsquo;affrontement du syst\u00e8me au terme de son explosion de puissance avec les grandes forces de l&rsquo;Histoire qui s&rsquo;\u00e9l\u00e8vent de plus en plus contre le syst\u00e8me. Je d\u00e9finis en g\u00e9n\u00e9ral, dans la situation pr\u00e9sente qui est celle d&rsquo;un affrontement ultime, les forces du syst\u00e8me comme d\u00e9structurantes, les forces de l&rsquo;Histoire comme structurantes.<\/p>\n<\/p>\n<p><p>\t<strong>Question : Cette situation qui touche d\u00e9j\u00e0 plusieurs pays consid\u00e9r\u00e9s comme des d\u00e9mocraties avanc\u00e9es s&rsquo;\u00e9tendra t-elle \u00e0 d&rsquo;autres pays ?<\/strong><\/p>\n<\/p>\n<p><p>\tPhilippe Grasset : Ce temps-l\u00e0 est pass\u00e9. Les situations d&rsquo;extension sont accomplies. L&rsquo;invasion du syst\u00e8me est globalis\u00e9e, sa crise l&rsquo;est aussi. Tous les pays sont plus ou moins dans cette situation d\u00e9crite, d&rsquo;affrontement grandissant et de chaos \u00e0 mesure dans la bataille de la communication, et l&rsquo;on ne peut plus analyser la situation en termes nationaux parce que c&rsquo;est une situation g\u00e9n\u00e9ral et transversale ; mais il y a des diff\u00e9rences nationales selon les pays, plus ou moins conscients de leur situation, de la situation de crise g\u00e9n\u00e9rale, plus ou moins pr\u00eats \u00e0 la r\u00e9volte.<\/p>\n<\/p>\n<p><p>\tLe concept de d\u00e9mocraties avanc\u00e9es est d\u00e9pass\u00e9 et je parlerais plut\u00f4t, justement, de d\u00e9mocraties d\u00e9pass\u00e9es, o\u00f9 l&rsquo;id\u00e9e de d\u00e9mocratie est devenue une sorte de bouillie pour les chats, qui n&rsquo;est ni syst\u00e8me de laxisme g\u00e9n\u00e9ral ni syst\u00e8me de pouvoir policier, mais un m\u00e9lange chaotique de tout cela et de tentatives dans tous les sens, tout cela bouillonnant dans la d\u00e9risoire proclamation par les derniers perroquets du syst\u00e8me des valeurs morales r\u00e9duites au rang de d\u00e9tritus destin\u00e9s aux poubelles de ce qu&rsquo;il reste d&rsquo;histoire. La situation d\u00e9crite pour la France et les USA touche de diverses fa\u00e7ons tous les pays du bloc central am\u00e9ricaniste-occidentaliste, avec le cur bouillonnant de la chose aux USA m\u00eame, dont plus personne ne sait plus quoi penser de pr\u00e9cis pour la raison imp\u00e9rative que ce monstre est en train de se transformer sous nos yeux en quelque chose d&rsquo;autre,  nul ne sait encore en quoi (Mon id\u00e9e est que le monstre va se d\u00e9composer, le fameux danger de la s\u00e9cession, de l&rsquo;\u00e9clatement, mais je dis aussit\u00f4t que c&rsquo;est plus une conviction intuitive qu&rsquo;une pr\u00e9vision rationnelle. Pourtant, il y a des signes. Si cela survient, ce sera le plus grand \u00e9v\u00e9nement depuis les R\u00e9volution am\u00e9ricaine (et pour cause) et fran\u00e7aise, quelque chose qui bouleversa nos psychologies comme peut le faire un tremblement de terre cosmique avec la mort de l&rsquo;influence mal\u00e9fique de l&rsquo;<em>American Dream<\/em>, qui oriente et police tout notre imaginaire politique depuis deux si\u00e8cles.)<\/p>\n<\/p>\n<p><p>\t<strong>Question : A contrario, dans des pays qui ne sont pas forc\u00e9ment consid\u00e9r\u00e9es comme des d\u00e9mocratie en bonne et due forme, la Russie par exemple, la classe politique continue \u00e0 se pr\u00e9occuper de l\u00e9gitimit\u00e9&#8230;<\/strong><\/p>\n<\/p>\n<p><p>\tPhilippe Grasset : Effectivement, il y a des pays que je d\u00e9signe comme \u00e0 la fois en dedans et \u00e0 la fois en dehors (du syst\u00e8me). Les pays qui gardent certains attributs de r\u00e9gimes politiques forts, comme la Russie et la Chine, conservent \u00e0 la fois une certaine identit\u00e9 et une certaine l\u00e9gitimit\u00e9. Ils ne sont pas infect\u00e9s par cette maladie ultime de notre civilisation finissante, qui se nomme d\u00e9mocratie, comme on parle de Guignol ou d&rsquo;une organisation mafieuse, ou plut\u00f4t comme l&rsquo;organisation du crime organis\u00e9, la <em>Cosa Nostra<\/em> aux USA, qui serait d\u00e9chir\u00e9e par une guerre entre gangs, ou entre Familles diff\u00e9rentes selon le vocabulaire de cette sorte d&rsquo;organisation.<\/p>\n<\/p>\n<p><p>\tCes pays comme la Russie et la Chine ne sont pas des alternatives, ils ne pr\u00e9sentent pas un syst\u00e8me alternatif. Ils pr\u00e9servent ce qui peut l&rsquo;\u00eatre pour affronter ce qui est l&rsquo;in\u00e9luctable crise g\u00e9n\u00e9rale de la civilisation occidentale qui est incontestablement globale. Ils ont une certaine lucidit\u00e9. C&rsquo;est certainement chez les Russes, instruits par l&rsquo;effondrement de l&rsquo;URSS et avec un sens inn\u00e9 de l&rsquo;apocalypse, que l&rsquo;on trouve les analyses les plus pr\u00e9cises de l&rsquo;effondrement des USA et du syst\u00e8me occidentaliste.<\/p>\n<\/p>\n<p><p>\tCurieusement, et malgr\u00e9 ce qu&rsquo;on voit de la situation actuelle, je pense que la France est assez proche de ces pays, parce que c&rsquo;est aussi un pays \u00e0 la fois en dedans et \u00e0 la fois en dehors, gr\u00e2ce \u00e0 sa puissance tradition historique de la Grande Nation, son identit\u00e9 transcendantale tr\u00e8s forte. La population, les Fran\u00e7ais, et un certain nombre de politiciens savent tr\u00e8s bien, mieux qu&rsquo;en aucun autre pays du syst\u00e8me occidentaliste, que ce syst\u00e8me est une calamit\u00e9 qu&rsquo;il faut d\u00e9truire.<\/p>\n<\/p>\n<p><p>\t<strong>Question : Pensez vous que les m\u00e9dias hors syst\u00e8me comme les sites d&rsquo;analyse ou les r\u00e9seaux sociaux, puissent infl\u00e9chir cette \u00e9volution?<\/strong><\/p>\n<\/p>\n<p><p>\tPhilippe Grasset : Sans le moindre doute, la r\u00e9ponse est archi positive. Ils ont d\u00e9j\u00e0 eu des effets d&rsquo;une extraordinaire puissance, bien que cela ne puisse \u00eatre encore comptabilis\u00e9. La phobie des th\u00e9ories complotistes de 9\/11, d&rsquo;ailleurs largement aliment\u00e9es par des \u00e9l\u00e9ments pr\u00e9cis, est un cancer qui d\u00e9vore le syst\u00e8me de communication du syst\u00e8me g\u00e9n\u00e9ral. L&rsquo;important n&rsquo;est pas de prouver le complot mais qu&rsquo;existe, depuis 9\/11, le doute d\u00e9vastateur sur cette affaire,  et je dirais, le doute est encore plus d\u00e9vastateur que s&rsquo;il y avait preuve reconnue du complot, qui exp\u00e9dierait quelques lampistes \u00e0 la lanterne et donnerait un surcro\u00eet de vertu au syst\u00e8me pour s&rsquo;\u00eatre d\u00e9barrass\u00e9 lui-m\u00eame de ses branches pourries. (Op\u00e9ration de cette sorte r\u00e9ussie avec le Watergate en 1974.) Ce sont les r\u00e9seaux alternatifs qui ont cr\u00e9\u00e9 ce cancer-l\u00e0 du doute, qui d\u00e9vore le syst\u00e8me et lui \u00f4te toute l\u00e9gitimit\u00e9.<\/p>\n<\/p>\n<p><p>\tIl y a une multitude d&rsquo;autres cas, encore plus pr\u00e9cis et, eux, men\u00e9s \u00e0 bien. Je suis de pr\u00e8s depuis toujours l&rsquo;affaire de l&rsquo;avion de combat Joint Strike Fighter (JSF), ce programme de plus de $300 milliards qui est le plus grand scandale de l&rsquo;histoire de l&rsquo;aviation militaire et de la puissance militaire tout court, qui est parfaitement un artefact du syst\u00e8me, et qui est en train d&rsquo;\u00e9branler la puissance du Pentagone lui-m\u00eame, \u00e0 un point qui peut conduire \u00e0 l&rsquo;effondrement de ce syst\u00e8me-l\u00e0. Internet, les r\u00e9seaux alternatifs sont la cause \u00e0 100%, sans aucun doute, de l&rsquo;\u00e9clatement du scandale comme une affaire publique d\u00e8s 2008, alors que la r\u00e9alit\u00e9 serait apparue sans doute 2 ou 3 ans plus tard, avec un effet infiniment moins d\u00e9vastateur pour le syst\u00e8me. Les r\u00e9seaux ont emp\u00each\u00e9 le syst\u00e8me, qui ne s&rsquo;\u00e9tait encore aper\u00e7u de rien, de prendre des mesures de <em>cover up<\/em>, de dissimulation du scandale. On peut tracer les jalons de l&rsquo;intervention des r\u00e9seaux dans cette affaire aux articles m\u00eame, dat\u00e9s, sur les r\u00e9seaux, et on peut retrouver les moments o\u00f9 ils ont oblig\u00e9 les autorit\u00e9s, l&rsquo;industrie et le Pentagone, \u00e0 reconna\u00eetre qu&rsquo;il y avait un formidable probl\u00e8me, en septembre 2008 pr\u00e9cis\u00e9ment,  tiens, au moment o\u00f9 Wall Street s&rsquo;effondrait Aujourd&rsquo;hui, le syst\u00e8me, affol\u00e9, impuissant, se d\u00e9chire \u00e0 propos du JSF. Ils y laisseront leurs culottes, \u00e9toil\u00e9es cela va de soi.<\/p>\n<\/p>\n<p><p>\tLa trouille formidable que les r\u00e9seaux alternatifs cr\u00e9ent au cur du syst\u00e8me est un facteur \u00e9galement formidable de pression sur le syst\u00e8me. Il impose des limites terribles \u00e0 l&rsquo;action du syst\u00e8me de communication, de crainte d&rsquo;erreurs exploit\u00e9es par les r\u00e9seaux alternatifs ; le syst\u00e8me en craint les r\u00e9v\u00e9lations, les hypoth\u00e8ses, les accusations. La haine des journalistes officiels vis-\u00e0-vis des r\u00e9seaux est quelque chose de formidable et de fascinant \u00e0 la fois, comme la haine de la m\u00e9diocrit\u00e9 institutionnalis\u00e9e face \u00e0 l&rsquo;attaque ext\u00e9rieure. Les r\u00e9seaux jouent le r\u00f4le des <em>samizdat<\/em> de l&rsquo;opposition clandestine en URSS \u00e0 partir des ann\u00e9es 1970, qui particip\u00e8rent largement \u00e0 l&rsquo;effondrement du r\u00e9gime. Mais ils sont mille fois, un million de fois plus puissants que les <em>samizdat<\/em> ; il faut dire que, dans l&rsquo;ignominie et l&rsquo;imposture, notre syst\u00e8me est mille fois, un million de fois pire que celui de l&rsquo;URSS, si on a le courage de d\u00e9compter les choses en termes historiques, de causes, de cons\u00e9quences, d&rsquo;effets indirects, de d\u00e9vastation d&rsquo;une civilisation enti\u00e8re, d&rsquo;abaissement et d&rsquo;intoxication de l&rsquo;esprit, de la culture&#8230;<\/p>\n<\/p>\n<p><p>\tAutre point de force des r\u00e9seaux, le fait que certaines forces du syst\u00e8me se servent des r\u00e9seaux pour d\u00e9fendre leurs propres int\u00e9r\u00eats, au d\u00e9triment de l&rsquo;\u00e9quilibre g\u00e9n\u00e9ral du syst\u00e8me. Les r\u00e9seaux ont jou\u00e9 ce r\u00f4le avec le g\u00e9n\u00e9ral Petraeus durant la r\u00e9cente et, \u00e0 mon avis, tr\u00e8s durable brouille entre Obama et Netanyahou. Ils ont jou\u00e9 un r\u00f4le essentiel dans ce qui pourrait \u00eatre l&rsquo;\u00e9v\u00e9nement formidable de l&rsquo;\u00e9branlement de l&rsquo;influence d&rsquo;Isra\u00ebl sur la politique US, surtout sur les militaires US.<\/p>\n<\/p>\n<p><p>\tDu point de vue de l&rsquo;\u00e9tat d&rsquo;esprit, les Am\u00e9ricains sont en avance sur nous, je veux dire les Europ\u00e9ens et surtout les Fran\u00e7ais. Eux, qui sont au cur du syst\u00e8me oppressif, ils croient \u00e0 la puissance des r\u00e9seaux comme seule arme de r\u00e9sistance s\u00e9rieuse. Avec les r\u00e9seaux, ils sont capables de monter un \u00e9norme truc comme le mouvement <em>Tea Party<\/em>, qui a d\u00e9j\u00e0 provoqu\u00e9 la d\u00e9faite des d\u00e9mocrates dans l&rsquo;\u00e9lection partielle du Massachusetts en janvier et qui a provoqu\u00e9 un d\u00e9sordre formidable \u00e0 Washington, et autant pour les r\u00e9publicains que pour les d\u00e9mocrates. Les Fran\u00e7ais n&rsquo;y croient pas assez, alors qu&rsquo;ils ont bless\u00e9 \u00e0 mort l&rsquo;Europe institutionnelle avec leur r\u00e9f\u00e9rendum de mai 2005, o\u00f9 le non fran\u00e7ais l&rsquo;a emport\u00e9 gr\u00e2ce \u00e0 Internet. Ils prennent trop peu au s\u00e9rieux les r\u00e9seaux, les consid\u00e9rant du point de vue citoyen, vaguement anarchiste, simplement comme un moyen d&rsquo;expression avec le romantisme de la d\u00e9mocratie citoyenne, une fa\u00e7on d&rsquo;exprimer son humeur, son d\u00e9go\u00fbt, etc. Pas du tout, c&rsquo;est bien plus que \u00e7a, c&rsquo;est une force d&rsquo;influence, une vraie ! Et c&rsquo;est peut-\u00eatre la plus grande force d&rsquo;influence aujourd&rsquo;hui !  C&rsquo;est sur les r\u00e9seaux qu&rsquo;on trouve aujourd&rsquo;hui les meilleurs journalistes, les meilleurs commentateurs, et de loin,  aux USA, c&rsquo;est absolument indiscutable, les noms et les exemples fourmillent. Les \u00e9crivains peuvent se lib\u00e9rer du syst\u00e8me, sur les r\u00e9seaux, et les historiens aussi, et m\u00eame les scientifiques. La seule chose qui manque aux r\u00e9seaux, en Europe et surtout en France, c&rsquo;est la prise de conscience de leur puissance g\u00e9n\u00e9rale, constante, organis\u00e9e, et non pas seulement comme un moyen o\u00f9 l&rsquo;on peut faire parfois des coups. Aux USA, c&rsquo;est d\u00e9j\u00e0 fait. Ils savent bien que le seul moyen de d\u00e9molir le syst\u00e8me, la seule v\u00e9ritable dissidence, ce sont les r\u00e9seaux alternatifs. C&rsquo;est l&rsquo;\u00e9quivalent des barricades et de l&rsquo;\u00e9meute devenant r\u00e9volution au XIX\u00e8me et au XX\u00e8me si\u00e8cles, de cette \u00e9meute et de cette r\u00e9volution qu&rsquo;on ne peut plus faire dans les rues aujourd&rsquo;hui. C&rsquo;est l&rsquo;outil supr\u00eame et le seul outil de la r\u00e9volte g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abL&rsquo;outil supr\u00eame de la r\u00e9volte g\u00e9n\u00e9rale\u00bb Il y a quelques jours, un de nos lecteurs a demand\u00e9 une interview \u00e0 Philippe Grasset, \u00e0 partir du th\u00e8me trait\u00e9 dans dde.crisis du 25 mars 2010 sur l&rsquo;annihilation et la dissolution des hommes politiques par le syst\u00e8me de la communication. Cette interview a \u00e9t\u00e9 publi\u00e9e hier 6 avril&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3015,2631,3125,5270,2622,9445,3997,3014],"class_list":["post-71749","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-communication","tag-de","tag-grasset","tag-interview","tag-la","tag-owni-fr","tag-philippe","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71749"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71749\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}