{"id":71781,"date":"2010-04-16T07:02:31","date_gmt":"2010-04-16T07:02:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/16\/bho-et-les-usa-prisonniers-du-systeme-de-leur-puissance-militaire\/"},"modified":"2010-04-16T07:02:31","modified_gmt":"2010-04-16T07:02:31","slug":"bho-et-les-usa-prisonniers-du-systeme-de-leur-puissance-militaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/16\/bho-et-les-usa-prisonniers-du-systeme-de-leur-puissance-militaire\/","title":{"rendered":"BHO et les USA prisonniers du syst\u00e8me de leur puissance militaire"},"content":{"rendered":"<p><p>Quelques m\u00e9dias de la droite radicale US et l&rsquo;un ou l&rsquo;autre commentateur, ou homme politique, y compris le s\u00e9nateur McCain, ont relev\u00e9 un propos pass\u00e9 d&rsquo;abord inaper\u00e7u de Barack Obama durant son discours de cl\u00f4ture du sommet de Washington sur la prolif\u00e9ration nucl\u00e9aire. Cela a \u00e9t\u00e9 pour r\u00e9agir brutalement, ce propos \u00e9tant interpr\u00e9t\u00e9 comme mettant en cause l&rsquo;avantage et la vertu pour les USA d&rsquo;\u00eatre une\/la superpuissance militaire du monde.<\/p>\n<\/p>\n<p><p>\tLe propos est le suivant (soulign\u00e9 en gras): \u00ab<em>It is a vital national security interest of the United States to reduce these conflicts because<\/em> <strong><em>whether we like it or not, we remain a dominant military superpower<\/em><\/strong><em>, and when conflicts break out, one way or another we get pulled into them. And that ends up costing us significantly in terms of both blood and treasure.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe site <em>WarNews<\/em> rel\u00e8ve, le <a href=\"http:\/\/warnewsupdates.blogspot.com\/2010\/04\/president-obama-whether-we-like-it-or.html\" class=\"gen\">15 avril 2010<\/a> diff\u00e9rentes r\u00e9actions, dont il donne les liens. C&rsquo;est <em>Fox.News<\/em> qui a lanc\u00e9 l&rsquo;affaire, le <a href=\"http:\/\/www.foxnews.com\/politics\/2010\/04\/15\/obama-america-superpower-like\/\" class=\"gen\">15 avril 2010<\/a>. Parmi ceux qui on relay\u00e9 le commentaire, Nile Gardiner, n\u00e9oconservateur britannique notoire bas\u00e9 \u00e0 Washington et directement connect\u00e9 aux milieux de la droite radicale US, dans <em>The Daily Telegraph<\/em> du <a href=\"http:\/\/blogs.telegraph.co.uk\/news\/nilegardiner\/100034746\/barack-obama-should-be-proud-america-is-a-superpower\/\" class=\"gen\">15 avril 2010<\/a>, avec une v\u00e9h\u00e9mence extr\u00eame. (Gardiner cite \u00e9galement McCain.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Fox News.com has a revealing story about some extraordinary remarks by President Obama at the close of the Nuclear Security Summit in Washington this week in response to questions about America&rsquo;s role in the Middle East peace process. The video can be viewed here. In the video the president is clearly uncomfortable with the notion of America as a superpower, as though it were a millstone round his neck, rather than a source of pride.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Obama&rsquo;s former presidential rival John McCain has issued a stinging rebuke of President Obama&rsquo;s remarks, calling them a direct contradiction to everything America believes in.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That&rsquo;s one of the more incredible statements I&rsquo;ve ever heard a president of the United States make in modern times, McCain, a Vietnam veteran and former prisoner of war, told Fox News. We are the dominant superpower, and we&rsquo;re the greatest force for good in the history of this country (sic), and I thank God every day that we are a dominant superpower.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEgalement sur <em>Fox.News<\/em>, le 13 avril 2010, Dick Morris, ancien conseiller de Clinton pass\u00e9 aux r\u00e9publicains, avait critiqu\u00e9 la nouvelle doctrine nucl\u00e9aire de BHO apportant certaines restrictions \u00e0 l&rsquo;usage de l&rsquo;arme nucl\u00e9aire avec ces mots : \u00ab<em>We may have the first anti-American president we&rsquo;ve ever had.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuels que soit la v\u00e9h\u00e9mence et le parti-pris des interpr\u00e9tations, qui sont rest\u00e9es cantonn\u00e9es \u00e0 quelques organes et commentateurs de la droite radicale et interventionniste, le propos d&rsquo;Obama restitue effectivement le malaise d&rsquo;un dirigeant politique qui para\u00eet conduit dans sa politique par un syst\u00e8me militaro-industriel. Il s&rsquo;agit d&rsquo;un cas pr\u00e9cis d&rsquo;une r\u00e9f\u00e9rence implicite au ph\u00e9nom\u00e8ne d&#8217;emprisonnement dans des syst\u00e8mes anthropotechniques o\u00f9 nous nous trouvons aujourd&rsquo;hui (voir notre <a href=\"http:\/\/www.dedefensa.org\/section-dialogues.html\" class=\"gen\">s\u00e9rie<\/a> <em>DIALOGUES<\/em>).<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Les r\u00e9actions \u00e0 ces propos d&rsquo;Obama sont parcellaires, tr\u00e8s v\u00e9h\u00e9mentes quand il y en a comme il est de coutume dans le jeu washingtonien syst\u00e9matique de la mont\u00e9e dialectique aux extr\u00eames. Par exemple, les commentaires de McCain sont d&rsquo;une bouffonnerie, d&rsquo;une pompe et d&rsquo;une brutalit\u00e9 primaire bien illustratives du niveau du commentaire de l&rsquo;homme politique moyen aux USA, en constante recherche de la radicalisation de ses propos dans l&rsquo;espoir d&rsquo;un effet \u00e9lectoral. Pour autant, nous ne devons absolument pas \u00e9carter la signification du propos, qui rend effectivement un ton de contrainte incontestable (\u00e9galement pour la fin de la citation donn\u00e9e par Gardiner, le <em>that<\/em> signifiant la d\u00e9pendance des USA de cette puissance militaire: \u00ab<em>And that ends up costing us significantly in terms of both blood and treasure.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tIl y a plusieurs commentaires \u00e0 faire autour de cet extrait du discours d&rsquo;Obama, qui appara\u00eet comme r\u00e9ellement significatif. Le ton rendu dans les mots et les phrases n&rsquo;est certainement pas indiff\u00e9rent. Il est effectivement illustratif d&rsquo;un malaise de l&rsquo;homme, comme ses adversaires le lui reprochent. Dans ce cas, et si l&rsquo;on se place de leur point de vue et du point de vue de leurs croyances, leur v\u00e9h\u00e9mence est justifi\u00e9e<\/p>\n<\/p>\n<p><p>\t En effet, la tonalit\u00e9 de l&rsquo;intervention d&rsquo;Obama montre que, du point de vue de ces critiques, BHO n&rsquo;est pas un homme s\u00fbr, que c&rsquo;est potentiellement un ennemi dans la place. Dick Morris s&rsquo;exclame : c&rsquo;est le premier pr\u00e9sident anti-am\u00e9ricaniste que nous ayons jamais eu! D&rsquo;un c\u00f4t\u00e9, propos excessif, d&rsquo;un autre point de vue, qui est celui du syst\u00e8me (on verra plus loin),  oui, jugement justifi\u00e9, car si Obama ne semble pas pouvoir faire grand&rsquo;chose, il le regrette manifestement. Obama nous dit personnellement qu&rsquo;il est lui-m\u00eame prisonnier des m\u00e9canismes et des contraintes de la puissance militaire US et il nous laisse entendre,  c&rsquo;est l\u00e0 la tonalit\u00e9 la plus remarquable du propos,  qu&rsquo;il semble avoir abdiqu\u00e9 tout espoir de changer cela. Si vous voulez, la teneur du message, en se r\u00e9f\u00e9rant \u00e0 notre langage propre, \u00e0 <em>dedefensa.org<\/em>, c&rsquo;est ceci: D\u00e9sol\u00e9, je n&rsquo;ai pas la moindre chance d&rsquo;\u00eatre l&rsquo;<em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a>&lsquo; que certains pouvaient esp\u00e9rer que je sois. Il s&rsquo;agit d&rsquo;un constat d&rsquo;\u00e9chec par rapport \u00e0 ce que l&rsquo;on attendait de lui, peut-\u00eatre par rapport \u00e0 ce qu&rsquo;il esp\u00e9rait secr\u00e8tement \u00eatre (les 6-8 premiers mois de sa pr\u00e9sidence montr\u00e8rent effectivement des tentatives dans ce sens).  <\/p>\n<\/p>\n<p><p>\t D&rsquo;un autre point de vue pour notre compte, ces d\u00e9clarations confirment bien que les puissances occidentalistes-am\u00e9ricanistes, et la principale d&rsquo;entre elles au premier rang et d&rsquo;une fa\u00e7on massive, sont totalement entre les griffes des divers syst\u00e8mes anthropotechniques dont l&rsquo;\u00e9tude nous int\u00e9resse tant en ce moment. L&rsquo;int\u00e9r\u00eat de l&rsquo;intervention d&rsquo;Obama est que cela est dit d&rsquo;une fa\u00e7on si publique, \u00e0 un tel moment de sa pr\u00e9sidence, et que cela para\u00eet comme un \u00e9cho lointain du discours de Eisenhower du <a href=\"http:\/\/www.dedefensa.org\/article-un_general-president_nous_parle_du_complexe_militaro-industriel_10_08_2005.html\" class=\"gen\">16 janvier 1961<\/a> sur le complexe militaro-industriel,  mais dans des circonstances infiniment diff\u00e9rentes, infiniment plus dramatiques et pressantes, infiniment plus explosives, alors que les USA sont en pleine crise de leur puissance (et, notamment et principalement, le complexe militaro-industriel lui-m\u00eame). Tout cela nous invite \u00e0 explorer avec encore plus d&rsquo;audace intellectuelle la situation de notre civilisation, dans ses parties les plus repr\u00e9sentatives, ce qui est \u00e9videmment le cas des USA; notamment et principalement, la r\u00e9alit\u00e9 puissante, voire autonome dans cette puissance jusqu&rsquo;\u00e0 la manifestation d&rsquo;une sp\u00e9cificit\u00e9 politique active et imp\u00e9rative, de ces syst\u00e8mes anthropotechniques, et certainement du plus puissant d&rsquo;entre tous que sont le Pentagone et le complexe militaro-industriel.<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;avenir, qu&rsquo;est-ce que nous signifient les remarques d&rsquo;Obama? Certes, qu&rsquo;il est conscient de cette situation d&#8217;emprisonnement et qu&rsquo;il laisse entendre qu&rsquo;il n&rsquo;y peut rien. N\u00e9anmoins, l&rsquo;aveu de la conscience de la situation est plus int\u00e9ressant que l&rsquo;aveu d&rsquo;impuissance. En effet, il peut survenir des situations compl\u00e8tement impr\u00e9visibles pour nous, dans la situation g\u00e9n\u00e9rale de crise o\u00f9 nous nous trouvons, o\u00f9 le syst\u00e8me se trouverait confront\u00e9 \u00e0 une soudaine et extr\u00eame difficult\u00e9, et o\u00f9 la conscience qu&rsquo;a Obama de cette toute-puissance du syst\u00e8me pourrait lui sugg\u00e9rer de profiter de cette opportunit\u00e9 pour agir contre lui. C&rsquo;est la seule hypoth\u00e8se o\u00f9 l&rsquo;on voit une possibilit\u00e9 de r\u00e9action et de changement. Elle est extr\u00eamement mince mais la volatilit\u00e9 de la situation g\u00e9n\u00e9rale nous dit qu&rsquo;elle existe tout de m\u00eame. Dans ce cas, la conscience que montre Obama de cet emprisonnement dans un syst\u00e8me constitue une information importante d&rsquo;une situation qui, dans des cas extr\u00eames et urgents, peut soudainement jouer un r\u00f4le tr\u00e8s important.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 avril 2010 \u00e0 07H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelques m\u00e9dias de la droite radicale US et l&rsquo;un ou l&rsquo;autre commentateur, ou homme politique, y compris le s\u00e9nateur McCain, ont relev\u00e9 un propos pass\u00e9 d&rsquo;abord inaper\u00e7u de Barack Obama durant son discours de cl\u00f4ture du sommet de Washington sur la prolif\u00e9ration nucl\u00e9aire. Cela a \u00e9t\u00e9 pour r\u00e9agir brutalement, ce propos \u00e9tant interpr\u00e9t\u00e9 comme mettant&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3612,9389,6132,3012,7921,9472,9473,4619,3483,3123,9474,6208,3194,3014],"class_list":["post-71781","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-american","tag-anthropotechnique","tag-anti-americaniste","tag-complexe","tag-dick","tag-emprisonnement","tag-foxnews","tag-gardiner","tag-gorbatchev","tag-militaro-industriel","tag-morris","tag-obama","tag-pentagone","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71781"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71781\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}