{"id":71788,"date":"2010-04-19T06:55:40","date_gmt":"2010-04-19T06:55:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/19\/american-gorbatchev-etait-dans-sa-tombe-et-remuait-encore\/"},"modified":"2010-04-19T06:55:40","modified_gmt":"2010-04-19T06:55:40","slug":"american-gorbatchev-etait-dans-sa-tombe-et-remuait-encore","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/19\/american-gorbatchev-etait-dans-sa-tombe-et-remuait-encore\/","title":{"rendered":"\u201c<em>American<\/em> Gorbatchev\u201d \u00e9tait dans sa tombe et remuait encore"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>American<\/em> Gorbatchev \u00e9tait dans sa tombe et remuait encore<\/h2>\n<\/p>\n<p><p>\t19 avril 2010  Barack Obama existe-t-il encore? BHO a-t-il laiss\u00e9 au vestiaire toutes ses vell\u00e9it\u00e9s, perceptibles dans les 8-9 premiers mois de son mandat, de tenter de r\u00e9former l&rsquo;irr\u00e9formable syst\u00e8me de l&rsquo;am\u00e9ricanisme dont nous d\u00e9pendons tous, lui-m\u00eame avec nous? Ou bien, non, existe-t-il encore quelque possibilit\u00e9 d&rsquo;une \u00e9volution radicale?<\/p>\n<\/p>\n<p><p>\tMentionnons quelques signes montrant que la seconde question n&rsquo;est pas inutile. <\/p>\n<\/p>\n<p><p>\t D&rsquo;abord, l&rsquo;on dit,  certes, de suspectes origines, l&rsquo;information, mais qui a \u00e9t\u00e9 prise au s\u00e9rieux du c\u00f4t\u00e9 US,  que Sarkozy juge Obama comme un <a href=\"http:\/\/www.dedefensa.org\/article-sarko_versus_bho_l_aliene__12_04_2010.html \" class=\"gen\">ali\u00e9n\u00e9<\/a>. Ce n&rsquo;est pas que la diff\u00e9rence de taille qui lui ferait dire cela, mais bien la position jug\u00e9e par Sarko extr\u00eamement mod\u00e9r\u00e9e d&rsquo;Obama vis-\u00e0-vis du mouvement islamiste et de l&rsquo;Iran. Si Sarko pense qu&rsquo;Obama est un ali\u00e9n\u00e9, alors c&rsquo;est qu&rsquo;Obama reste un homme tr\u00e8s int\u00e9ressant, par la simple \u00e9vidence de la logique antagoniste. <\/p>\n<\/p>\n<p><p>\t L&rsquo;on entend aussi BHO dire des choses pendables, qui font \u00e9ructer de rage plus d&rsquo;un ex-<em>neocon<\/em> de service. Nous dire, comme s&rsquo;il s&rsquo;agissait d&rsquo;un <a href=\"http:\/\/www.dedefensa.org\/article-bho_et_les_usa_prisonniers_du_systeme_de_leur_puissance_militaire_16_04_2010.html\" class=\"gen\">fardeau<\/a>, que les USA sont prisonniers d&rsquo;un syst\u00e8me de puissance militaire qui semble, dans sa pens\u00e9e, leur co\u00fbter plus qu&rsquo;il ne leur rapporte, n&rsquo;est pas du type habituel de la pens\u00e9e conforme.<\/p>\n<\/p>\n<p><p>\t Voil\u00e0 que la SEC, le gendarme habituellement bon enfant de la bourse US, entend se payer Goldman Sachs \u00e0 hauteur d&rsquo;$1 milliard au moins (c&rsquo;est l&rsquo;amende coquette qu&rsquo;il r\u00e9clame, qui pourrait m\u00eame monter \u00e0 $4 milliards, selon certaines \u00e9valuations). Exclamation d&rsquo;un mauvais esprit, cit\u00e9 par un \u00e9dito du <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/cifamerica\/2010\/apr\/17\/goldman-sachs-lawsuit-banking\" class=\"gen\">17 avril 2010<\/a> : \u00ab<em>How can the<\/em> [US] <em>government sue Goldman Sachs? I thought Goldman Sachs ran the government.<\/em>\u00bb Effectivement, si la SEC entend aligner Goldman Sachs, qui a perdu sur les march\u00e9s 13% de sa valeur \u00e0 la nanoseconde o\u00f9 l&rsquo;on a appris l&rsquo;intention du digne organisme gouvernemental, c&rsquo;est que Washington-Obama a mis le feu vert. Ainsi court le bruit que Goldman Sachs ne dirige pas le gouvernement des Etats-Unis. Singulier.<\/p>\n<\/p>\n<p><p>\t Dans des d\u00e9clarations ce week-end, Obama a sonn\u00e9 le signal d&rsquo;alarme. Il veut une r\u00e9forme du syst\u00e8me bancaire de Wall Street, sans quoi il craint une nouvelle crise. Sur la route de cette r\u00e9forme, il trouvera le Congr\u00e8s et les r\u00e9publicains, qui s&rsquo;y opposent. Associated Press et <em>ABC.News<\/em> pr\u00e9sentaient la chose le <a href=\"http:\/\/news.yahoo.com\/s\/ap\/20100417\/ap_on_bi_ge\/us_obama_financial_reform;_ylt=AmbYKwaP_8JVOOTFlQx76RFv24cA;_ylu=X3oDMTNlMXZuMGg5BGFzc2V0A2FwLzIwMTAwNDE3L3VzX29iYW1hX2ZpbmFuY2lhbF9yZWZvcm0EY2NvZGUDbW9zdHBvcHVsYXIEY3BvcwMzBHBvcwMzBHNlYwN5bl90b3Bfc3RvcmllcwRzbGsDb2JhbWFmcmVzaGNy\" class=\"gen\">17 avril 2010<\/a>, selon le reportage de Jake Tapper. La r\u00e9forme financi\u00e8re sera la deuxi\u00e8me grande bataille int\u00e9rieure \u00e0 Washington cette ann\u00e9e, apr\u00e8s la bataille des soins de sant\u00e9. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The U.S. is destined to endure a new economic crisis that sticks taxpayers with the bill unless Congress tightens oversight of the financial industry, President Barack Obama said Saturday. The overhaul is the next major piece of legislation that Obama wants to sign into law this year, but solid GOP opposition in the Senate is jeopardizing that goal.<\/em><\/p>\n<\/p>\n<p><p>\t\u00ab\u00a0\u00bb<em>Every day we don&rsquo;t act, the same system that led to bailouts remains in place, with the exact same loopholes and the exact same liabilities, Obama said in his weekly radio and Internet address. And if we don&rsquo;t change what led to the crisis, we&rsquo;ll doom ourselves to repeat it. <\/em> [] <em>Opposing reform will leave taxpayers on the hook if a crisis like this ever happens again, the president said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Et dans ce m\u00eame ordre d&rsquo;id\u00e9e, il ne surprendra personne d&rsquo;apprendre que Goldman Sachs est persuad\u00e9 d&rsquo;\u00eatre victime d&rsquo;un complot, cette banque qu&rsquo;on accuse en g\u00e9n\u00e9ral d&rsquo;\u00eatre comploteuse-en-chef pour ce qui concerne la manipulation du gouvernement de Washington. <em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/americas\/a-goldplated-scandal-hits-the-bonus-bank-1947722.html\" class=\"gen\">18 avril 2010<\/a> \u00e9crit : \u00ab<em>The blue-chip bank, which traces its history back to 1869, intends to fight the action and vigorously defend its reputation. Executives believe the bank is being victimised as part of a political move by Barack Obama to gain support for his financial reform policies. President Obama&rsquo;s weekly video address was yesterday entitled Holding Wall Street accountable, and promised shareholders additional powers in a more heavily regulated financial system.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Jim Lobe, commentateur s\u00e9rieux et mesur\u00e9 pas pr\u00e9cis\u00e9ment ami des <em>neocons<\/em>, mais qui fait son m\u00e9tier avec conscience, pond un assez long article pour nous confirmer que la crise entre les USA et Isra\u00ebl est diablement s\u00e9rieuse et que, litt\u00e9ralement, BHO en a vraiment assez de Netanyahou. Lobe \u00e9crit cela le <a href=\"http:\/\/www.lobelog.com\/israel-lobby-leadership-losing-it\/\" class=\"gen\">17 avril 2010<\/a>, sur son <em>blog<\/em>. Apr\u00e8s avoir explicit\u00e9 son propos, Lobe conclut : \u00ab<em>It&rsquo;s pretty clear that the right-wing leadership of the organized Jewish community believes that a major crisis in U.S.-Israeli relations  perhaps the most important in 35 years, as Amb. Oren himself reportedly warned (and then unconvincingly denied) last month  is really upon us.<\/em>\u00bb L&rsquo;affaire dure maintenant depuis cinq semaines et l&rsquo;on dit BHO d\u00e9termin\u00e9.<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Le fait est que dans des temps o\u00f9 l&rsquo;on serait tent\u00e9 d&rsquo;abandonner les derniers espoirs que Barack Obama puisse \u00eatre l&rsquo;<em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a> qu&rsquo;on esp\u00e9rait qu&rsquo;il soit, voil\u00e0 que divers signes font penser qu&rsquo;il pourrait \u00eatre pouss\u00e9 \u00e0 l&rsquo;\u00eatre tout de m\u00eame. Plut\u00f4t, et pour \u00eatre plus explicite, observons que divers fronts sont en train de s&rsquo;ouvrir simultan\u00e9ment, dans le cours de la bataille desquels existent de s\u00e9rieuses potentialit\u00e9s de d\u00e9stabilisation, notamment venant du pr\u00e9sident qui d\u00e9ciderait, ou serait conduit \u00e0 d\u00e9cider certaines mesures conduisant \u00e0 des situations de rupture. On peut admettre que l&rsquo;actuelle phase s&rsquo;est esquiss\u00e9e avec l&rsquo;affaire isra\u00e9lienne, dont le d\u00e9but remonte au 9-10 mars et au voyage du vice-pr\u00e9sident Joe Biden en Isra\u00ebl, tout cela suivi d&rsquo;un encha\u00eenement de circonstances f\u00e2cheuses o\u00f9 la situation qui, selon le sc\u00e9nario classique, aurait d\u00fb s&rsquo;arranger, n&rsquo;a fait qu&#8217;empirer.<\/p>\n<\/p>\n<p><p>\tNous n&rsquo;avons nullement l&rsquo;impression d&rsquo;un Barack Obama qui aurait le vent en poupe, notamment apr\u00e8s ses victoires des soins de sant\u00e9, de SALT-II et du sommet anti-prolif\u00e9ration nucl\u00e9aires vers le terrorisme,  qui sont autant de victoires \u00e0 la Pyrrhus, qui n&rsquo;ont apais\u00e9 personne, qui n&rsquo;ont nullement renforc\u00e9 la stature d&rsquo;Obama contre ses adversaires ou face \u00e0 ses partenaires, qui ont souvent marqu\u00e9 surtout le genre de victoires que le syst\u00e8me permet entre les bornes \u00e9troites qu&rsquo;il place dans le parcours des cr\u00e9atures qui \u00e9voluent dans les sch\u00e9mas qu&rsquo;il autorise. (Quant au sommet de Washington des 12-13 avril, l&rsquo;\u00e9v\u00e9nement le plus unanimement salu\u00e9 comme une victoire, la <a href=\"http:\/\/www.dedefensa.org\/article-bho_et_les_usa_prisonniers_du_systeme_de_leur_puissance_militaire_16_04_2010.html\" class=\"gen\">phrase<\/a> d\u00e9sormais fameuse qu&rsquo;il a gliss\u00e9e dans son discours de cl\u00f4ture marque bien, non seulement la conscience qu&rsquo;il a des limites de l&rsquo;exercice, mais plus encore la r\u00e9alit\u00e9 objective de ces limites.)<\/p>\n<\/p>\n<p><p>\tNous avons plut\u00f4t l&rsquo;impression d&rsquo;un Barack Obama qui se trouve, apr\u00e8s plus de quatorze mois de tentatives diverses suivies ou accompagn\u00e9es de capitulations diverses dans le cadre du syst\u00e8me, <strong>accul\u00e9<\/strong> \u00e0 envisager de devoir se battre r\u00e9ellement. Il ne s&rsquo;agit pas d&rsquo;une bataille normale, ici contre Isra\u00ebl, ou bien l\u00e0 contre Wall Street, mais contre le syst\u00e8me en g\u00e9n\u00e9ral, alors que le m\u00eame Obama est press\u00e9 par ailleurs par une situation int\u00e9rieure de plus en plus volatile et insaisissable. <\/p>\n<\/p>\n<p><p>\tObama le dos au mur? Si l&rsquo;on veut, malgr\u00e9 les applaudissements ind\u00e9cents de satisfaction de circonstance de ses soutiens lib\u00e9raux (s&rsquo;intitulant politiquement progressistes), qui ne parviennent pas \u00e0 prendre pour du comptant la faiblesse de l&rsquo;action r\u00e9formiste de celui qu&rsquo;ils avaient soutenu comme un r\u00e9formiste radical. Ce soutien-l\u00e0, des lib\u00e9raux, du centre-gauche politique qui se satisfait si ais\u00e9ment d&rsquo;am\u00e9nagements de fa\u00e7ade et de discours sonnant et tromp\u00e9tant, sont finalement les pires alli\u00e9s d&rsquo;Obama, et les pires parmi les divers centres politiques en activit\u00e9. Ils n&rsquo;ont pas protest\u00e9 et ont m\u00eame applaudi lorsqu&rsquo;on leur a annonc\u00e9 l&rsquo;intensification de la guerre en Afghanistan, montrant ainsi qu&rsquo;ils ne valaient gu\u00e8re mieux, et m\u00eame qu&rsquo;ils valaient pire puisqu&rsquo;ils ont l&rsquo;hypocrisie en plus, que la droite radicale qui a soutenu Bush du temps de l&rsquo;Irak.<\/p>\n<\/p>\n<p><p>\tD&rsquo;ailleurs, sont-ils encore les alli\u00e9s d&rsquo;Obama? Depuis la brouille avec Isra\u00ebl, leurs rangs sont secou\u00e9s d&rsquo;incertitudes \u00e0 cet \u00e9gard. Pour eux, l&rsquo;alliance avec Isra\u00ebl est une <a href=\"http:\/\/www.dedefensa.org\/article-le_crepuscule_de_la_sainte_alliance_22_03_2010.html?admin=1\" class=\"gen\">Sainte Alliance<\/a> qui est le fondement m\u00eame de leurs conceptions politiques. Autant ces lib\u00e9raux peuvent assurer leur soutien \u00e0 Obama lorsque celui-ci parle d&rsquo;une r\u00e9forme financi\u00e8re de Wall Street, autant ils le lui retirent de plus en plus lorsqu&rsquo;il s&rsquo;agit de la question isra\u00e9lienne. Cet exemple, qui se r\u00e9p\u00e8te pour divers autres groupes, mesure la difficult\u00e9 du probl\u00e8me pour le pr\u00e9sident US.<\/p>\n<h3>La nature du syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tToutes ces consid\u00e9rations ne r\u00e9solvent pas le probl\u00e8me de Barack Obama, qui n&rsquo;est pas le probl\u00e8me d&rsquo;une politique, d&rsquo;un choix, d&rsquo;une orientation,  mais, plus que jamais, le probl\u00e8me d&rsquo;une <strong>\u00e9nigme<\/strong>. Quoi qu&rsquo;on veuille, quoi qu&rsquo;on fasse, quelque d\u00e9ception qu&rsquo;on exprime, quelque certitude qu&rsquo;on avance, Obama reste une \u00e9nigme. Ce qui nous appara\u00eet peu \u00e0 peu, c&rsquo;est que cet homme reste une \u00e9nigme, nullement pour ce qu&rsquo;il est lui-m\u00eame comme nous pouvions le penser d&rsquo;abord, nullement <em>per se<\/em>, mais \u00e0 cause de ses rapports et de sa confrontation larv\u00e9e avec le syst\u00e8me. Etant un homme d&rsquo;une r\u00e9elle intelligence, il est n\u00e9cessairement plus confront\u00e9 aux inerties et aux obstacles du syst\u00e8me et ainsi n&rsquo;est-il une \u00e9nigme qu&rsquo;en fonction de cet affrontement avec le syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9nigme est la suivante. Malgr\u00e9 toutes les garanties qu&rsquo;il a d\u00e9j\u00e0 donn\u00e9es, malgr\u00e9 les r\u00e9alignements, les capitulations, Obama, \u00e0 cause de sa personnalit\u00e9, continue \u00e0 rester en situation d&rsquo;affrontement latent avec le syst\u00e8me. L&rsquo;\u00e9nigme est de savoir s&rsquo;il continuera \u00e0 c\u00e9der comme il l&rsquo;a fait jusqu&rsquo;ici ou si, tout de m\u00eame, \u00e0 un moment ou l&rsquo;autre, il se d\u00e9cidera, comme nous l&rsquo;\u00e9crivions dans notre <em>F&#038;C<\/em> pr\u00e9c\u00e9dent du  <a href=\"http:\/\/www.dedefensa.org\/article-spirale_et_peril_interieurs_17_04_2010.html\" class=\"gen\">17 avril 2010<\/a>, \u00ab<em>\u00e0 franchir son Rubicon personnel<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tLa situation qu&rsquo;il affronte ne cesse de se compliquer \u00e0 mesure qu&rsquo;il avance dans sa pr\u00e9sidence, moins tant \u00e0 cause des difficult\u00e9s innombrables qu&rsquo;\u00e0 cause de la multiplicit\u00e9 des axes que suivent ces difficult\u00e9s. Il n&rsquo;y a aucune coh\u00e9rence, aucune coh\u00e9sion, dans les attaques venues de <em>Tea Party<\/em>, l&rsquo;affrontement qui s&rsquo;esquisse et qui pourrait \u00eatre sanglant avec Wall Street, l&rsquo;opposition sauvage des r\u00e9publicains, la pression montante des courants anti-guerres, etc. Il s&rsquo;agit r\u00e9ellement d&rsquo;une situation d&rsquo;antagonisme g\u00e9n\u00e9ral avec les diverses pressions allant dans tous les sens, n\u00e9es du syst\u00e8me et des forces antisyst\u00e8mes, qui passent n\u00e9cessairement par le relais de heurts ou de frictions avec lui-m\u00eame, Obama, qui repr\u00e9sente la figure centrale de l&rsquo;ensemble, au moins symboliquement. Son absence d&rsquo;orientation nette, son refus jusqu&rsquo;ici de toute option se rapprochant de l&rsquo;option <em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a>, le place effectivement dans cette position inconfortable o\u00f9 s&rsquo;accumulent d\u00e9faites et fausses victoires, o\u00f9 rien de d\u00e9cisif ne s&rsquo;affirme. Obama est une \u00e9nigme mais il est aussi une sorte de <em>punching ball<\/em> o\u00f9 tout le monde frappe \u00e0 son tour, sous la pression de l&rsquo;exacerbation de la crise. M\u00eame ceux qui ont honteusement profit\u00e9 de la crise, comme Goldman Sachs et Wall Street, sont de la partie, car eux-m\u00eames ressentent la pression de la crise.<\/p>\n<\/p>\n<p><p>\tMais ce qu&rsquo;on a \u00e9num\u00e9r\u00e9 plus haut montre qu&rsquo;Obama lui-m\u00eame est de plus en plus proche d&rsquo;un point o\u00f9 il ne pourrait plus supporter cette position inconfortable de centre magn\u00e9tique de toutes les contestations et de toutes les r\u00e9criminations. Dans un tel climat de comp\u00e9tition et de contestation, aucune de ses victoires ne peut \u00eatre d\u00e9cisive tandis que tous ses revers l&rsquo;affaiblissent. Il serait ainsi conduit irr\u00e9m\u00e9diablement \u00e0 s&rsquo;affaiblir en progressant vers la fin de son terme,  \u00e0 moins d&rsquo;une r\u00e9action. C&rsquo;est en cela qu&rsquo;on peut \u00eatre tent\u00e9, \u00e0 relever les signes \u00e9pars mentionn\u00e9s ci-dessus, de pr\u00e9senter l&rsquo;hypoth\u00e8se qu&rsquo;Obama pourrait tr\u00e8s bien consid\u00e9rer, \u00e0 un moment d&rsquo;ici 2012, que la seule issue raisonnable serait d&rsquo;\u00eatre <strong>d\u00e9raisonnable<\/strong> et de tenter un coup de force, une radicalisation d&rsquo;ici l\u00e0. Dans quel sens? De quelle fa\u00e7on? Pas de r\u00e9ponse.<\/p>\n<\/p>\n<p><p>\tDe m\u00eame, pas de r\u00e9ponse \u00e0 la question qu&rsquo;on serait tent\u00e9 de poser sur les cons\u00e9quence d&rsquo;une telle \u00e9ventuelle initiative, qui reste en plus du domaine de l&rsquo;hypoth\u00e8se. Elle s&rsquo;imposerait comme un facteur de plus de d\u00e9sordre \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un syst\u00e8me lui-m\u00eame sans cesse secou\u00e9 par l&rsquo;accentuation r\u00e9guli\u00e8re du d\u00e9sordre. Il devient absolument impossible de faire quelque pr\u00e9vision que ce soit sur l&rsquo;orientation des choses, sinon de proposer le constat que de plus en plus d&rsquo;actes d\u00e9stabilisants de l&rsquo;actuelle situation sont en pr\u00e9paration ou se pr\u00e9sentent comme autant d&rsquo;initiatives tentantes. Le climat est d&rsquo;une telle lourdeur, la tension d&rsquo;une telle force Ainsi peut-on compl\u00e9ter notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-observations_techniques_sur_l_effondrement_du_modele__15_04_2010.html\" class=\"gen\">15 avril 2010<\/a> sur l&rsquo;extension du domaine de la crise, avec ce domaine englobant d\u00e9sormais l&rsquo;\u00e9nigme Obama elle-m\u00eame. La crise de ce syst\u00e8me anthropotechnique, ou anthropotechnologique si l&rsquo;on veut actualiser sa substance, ne laisse personne indemne. C&rsquo;est d&rsquo;ailleurs dans sa nature m\u00eame.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>American Gorbatchev \u00e9tait dans sa tombe et remuait encore 19 avril 2010 Barack Obama existe-t-il encore? BHO a-t-il laiss\u00e9 au vestiaire toutes ses vell\u00e9it\u00e9s, perceptibles dans les 8-9 premiers mois de son mandat, de tenter de r\u00e9former l&rsquo;irr\u00e9formable syst\u00e8me de l&rsquo;am\u00e9ricanisme dont nous d\u00e9pendons tous, lui-m\u00eame avec nous? Ou bien, non, existe-t-il encore quelque possibilit\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3612,9389,6648,8477,3483,2774,6208,8478,3372,3014,3132],"class_list":["post-71788","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-american","tag-anthropotechnique","tag-enigme","tag-goldman","tag-gorbatchev","tag-israel","tag-obama","tag-sachs","tag-street","tag-systeme","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71788"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71788\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}