{"id":71830,"date":"2010-04-30T17:29:33","date_gmt":"2010-04-30T17:29:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/30\/le-katrina-de-bho\/"},"modified":"2010-04-30T17:29:33","modified_gmt":"2010-04-30T17:29:33","slug":"le-katrina-de-bho","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/04\/30\/le-katrina-de-bho\/","title":{"rendered":"Le <em>Katrina<\/em> de BHO ?"},"content":{"rendered":"<p><p>Nous avons en communication d&rsquo;un document d&rsquo;analyse g\u00e9n\u00e9rale, bien entendu sans classification restrictive, qui donne une appr\u00e9ciation tr\u00e8s bien document\u00e9e de la catastrophe dite mar\u00e9e noire en cours sur les c\u00f4tes de la Louisiane, avec ses cons\u00e9quences politiques. Nous signalons nous-m\u00eames en gras les passages qui nous paraissent significatifs.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>For days, as an oil spill spread in the Gulf of Mexico, BP assured the government the plume was manageable, not catastrophic. U.S. Federal authorities were content to let the company handle the mess while keeping an eye on the operation. Then government scientists realized the leak was five times larger than they had been led to believe, and days of lulling statistics and reassuring words gave way Thursday to an all-hands-on-deck emergency response. Now questions are sure to be raised about a self-policing system<\/em> <strong><em>that trusted a commercial operator<\/em><\/strong> <em>to take care of its own mishap even as it grew into a menace imperiling Gulf Coast nature and livelihoods from Florida to Texas. The pivot point had come Wednesday night, at a news conference at an oil research center in the tiny community of Robert, Louisiana. That is when the nation learned the earlier estimates were far too small, and an additional leak had been found. On Thursday, President Barack Obama set in motion a larger federal mobilization, pledging to deploy every single available resource to the area and ordering his disaster and environmental leaders to get down there in person. Only a few days after the Coast Guard assured the country there was<\/em> <strong><em>ample time<\/em><\/strong> <em>to protect the coast if oil came ashore, warnings from the government were newly alarming. I am frightened for the country, for the environment, David Kennedy, assistant chief of the National Ocean Service at the National Oceanic and Atmospheric Administration, told The Associated Press. This is a very, very big thing, and the efforts that are going to be required to do anything about it, especially if it continues on, are just mind-boggling.\u00bb<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The political subtext of the crisis was clear and increasingly on people&rsquo;s minds, whether from a federal office deploying oil-containment booms or from a Louisiana parish awaiting yet another sucker punch from the sea. Will this be<\/em> <strong><em>Obama&rsquo;s Katrina<\/em><\/strong><em>? Should the federal and state governments have done more, and earlier? Did they learn the lessons of the devastating 2005 hurricane? Political calculations vied with the increasingly scary Gulf reality  hundreds of thousands of gallons of oil and its progression to landfall as early as Thursday night. Obama spokesman Robert Gibbs said that sometimes accidents happen, and the loss of the Deepwater Horizon was no reason to back off on the president&rsquo;s recent decision to support expanded offshore drilling. On Thursday, that policy was challenged by some Democratic lawmakers, now that the fuller extent of the spill was known, and Gibbs acknowledged that details might be revisited. Throughout last week and into this one, the government was<\/em> <strong><em>deferring to BP<\/em><\/strong> <em>on what was being done at the site and on assessments of progress. The Coast Guard was<\/em> <strong><em>not doing<\/em><\/strong> <em>its own independent, firsthand assessment of the seabed rupture. By Thursday afternoon, the White House had assembled a team of top advisers to showcase the administration&rsquo;s determination to head off the damage posed by the oil slick. And Gibbs acknowledged details of the president&rsquo;s drilling proposal might be<\/em> <strong><em>revisited<\/em><\/strong><em>, depending on the investigation into the rig explosion and spill. The equation had changed, like a hurricane setting a new course<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Il y a une remarquable continuit\u00e9 ces derni\u00e8res semaines, ces derniers mois, dans la succession d&rsquo;accidents, d&rsquo;origine naturelle ou humaine, qui, <strong>tous<\/strong>, portent implicitement une accusation contre notre syst\u00e8me g\u00e9n\u00e9ral et mettent en \u00e9vidence sa fragilit\u00e9, sa vuln\u00e9rabilit\u00e9, sa nocivit\u00e9 et l&rsquo;absence de contr\u00f4le humain qui les caract\u00e9rise. Certains y verront le signe du Ciel. De toutes les fa\u00e7ons, et c&rsquo;est peut-\u00eatre la  m\u00eame chose, on y verra le signe de l&rsquo;intensification des pressions de diverses origines contre le syst\u00e8me anthropotechnique qui conduit et r\u00e9git les affaires du monde.<\/p>\n<\/p>\n<p><p>\tPlus aucun r\u00e9pit ne nous est accord\u00e9, et, de plus en plus, c&rsquo;est la surprise, en g\u00e9n\u00e9ral g\u00e9n\u00e9r\u00e9e par l&rsquo;impr\u00e9vision des autorit\u00e9s ou des diverses puissances (en g\u00e9n\u00e9ral priv\u00e9es) en place qui sont \u00e0 l&rsquo;origine de l&rsquo;in\u00e9luctable aggravation de tous ces incidents. On retrouve, notamment dans cette affaire de Louisiane comme dans d&rsquo;autres incidents et catastrophes qui se succ\u00e8dent, tous les \u00e9l\u00e9ments fautifs du syst\u00e8me, que ce soit le blanc-seing accord\u00e9 aux forces priv\u00e9es, que ce soit l&rsquo;impr\u00e9vision et l&rsquo;irresponsabilit\u00e9 des forces repr\u00e9sentant la puissance publique. Il y a la r\u00e9alit\u00e9 d&rsquo;un esprit d\u00e9sormais majoritaire, sinon exclusif, d&rsquo;absence de vigilance, de pr\u00e9vision, d&rsquo;attention et de responsabilit\u00e9 face aux missions dont ces divers services sont charg\u00e9es d&rsquo;une part; la structure extr\u00eamement tendue de ce syst\u00e8me en crise et aux abois, qui transforme in\u00e9luctablement tout incident ou catastrophe en incident grave et en catastrophe incontr\u00f4lable d&rsquo;autre part. Ce sont les caract\u00e9ristiques m\u00eame d&rsquo;un syst\u00e8me \u00e0 bout de souffle, d&rsquo;une civilisation dont l&rsquo;organisation est compl\u00e8tement d\u00e9pass\u00e9e par les cons\u00e9quences des situations de puissance aveugle qu&rsquo;elle engendre et qu&rsquo;elle est incapable de contr\u00f4ler.<\/p>\n<\/p>\n<p><p>\tPour ce qui est de l&rsquo;<em>Obama&rsquo;s Katrina<\/em>, bien entendu ce sera le <em>Katrina<\/em> d&rsquo;Obama, car rien n&rsquo;est \u00e9pargn\u00e9 dans le sens du spectaculaire et de l&rsquo;aggravation du diagnostic par un syst\u00e8me de communication lui-m\u00eame aux abois et qui ne sait faire que foncer en aveugle dans le sens de la dramatisation de tout ce qu&rsquo;il commente et communique. Il est inutile d&rsquo;en appeler \u00e0 la raison et \u00e0 la mesure du jugement car ce ne sont ni la raison ni le jugement que touche le syst\u00e8me de communication, mais la psychologie elle-m\u00eame, qui s&rsquo;impr\u00e8gne, exactement comme les superbes c\u00f4tes de Louisiane s&rsquo;impr\u00e8gnent de l&rsquo;immonde mazout, de la perception automatique de cette aggravation incessante de tous les \u00e9v\u00e9nements, et une aggravation qui est port\u00e9e au d\u00e9bit du syst\u00e8me. D&rsquo;ores et d\u00e9j\u00e0, Obama songe \u00e0 revoir sa d\u00e9cision sur les forages <em>off-shore<\/em> d&rsquo;Alaska, sous la pression de certains \u00e9lus d\u00e9mocrates, montrant par l\u00e0 que le r\u00e9sultat final de tous ces \u00e9v\u00e9nements n&rsquo;est pas la r\u00e9flexion politique mais le d\u00e9sordre, encore le d\u00e9sordre et toujours le d\u00e9sordre. La d\u00e9gradation syst\u00e9matique de l&rsquo;environnement contribue enfin, pour ce cas pr\u00e9cis de la Louisiane, \u00e0 exposer une fois de plus les cons\u00e9quences du syst\u00e8me du technologisme pouss\u00e9 \u00e0 son extr\u00eame, hors de contr\u00f4le, lanc\u00e9 dans l&rsquo;exploitation de mati\u00e8res qui ne sont pas in\u00e9puisables, avec comme cons\u00e9quence la destruction d&rsquo;un environnement qui est la pi\u00e8ce ma\u00eetresse de l&rsquo;\u00e9quilibre de la psychologie humaine. Les deux composants de la politique de l&rsquo;id\u00e9al de puissance, le syst\u00e8me de la communication et le syst\u00e8me du technologisme, se rejoignent pour attaquer la psychologie humaine et acc\u00e9l\u00e9rer encore un peu plus la crise du syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 avril 2010 \u00e0 17H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons en communication d&rsquo;un document d&rsquo;analyse g\u00e9n\u00e9rale, bien entendu sans classification restrictive, qui donne une appr\u00e9ciation tr\u00e8s bien document\u00e9e de la catastrophe dite mar\u00e9e noire en cours sur les c\u00f4tes de la Louisiane, avec ses cons\u00e9quences politiques. Nous signalons nous-m\u00eames en gras les passages qui nous paraissent significatifs. \u00abFor days, as an oil spill&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7781,3015,3228,2631,2651,7884,9547,2888,9548,3600,3014,4268],"class_list":["post-71830","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bp","tag-communication","tag-crise","tag-de","tag-du","tag-louisiane","tag-maree","tag-noire","tag-off-shore","tag-petrole","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71830"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71830\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}