{"id":71834,"date":"2010-05-01T09:52:00","date_gmt":"2010-05-01T09:52:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/01\/dialogues-4-de-lindividu-dans-lhistoire\/"},"modified":"2010-05-01T09:52:00","modified_gmt":"2010-05-01T09:52:00","slug":"dialogues-4-de-lindividu-dans-lhistoire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/01\/dialogues-4-de-lindividu-dans-lhistoire\/","title":{"rendered":"<em>DIALOGUES<\/em>-4 : De l&rsquo;individu dans l&rsquo;Histoire"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-4 : De l&rsquo;individu dans l&rsquo;Histoire<\/h2>\n<h4>Pr\u00e9alable sur le darwinisme<\/h4>\n<p>Je voudrais d&rsquo;abord revenir sur le darwinisme et plus pr\u00e9cis\u00e9ment sur l&rsquo;\u00e9volution darwinienne. Selon moi et je pense pour la plupart des darwinistes, il n&rsquo;est pas possible d&rsquo;imaginer que cette \u00e9volution  soit orient\u00e9e dans le sens d&rsquo;une finalit\u00e9 quelconque, accomplissement de la vie, de l&rsquo;humain, de l&rsquo;esprit, voire pour les mystique mont\u00e9e vers la panspiritualit\u00e9 de Teilhard de Chardin. L&rsquo;\u00e9volution est ce qu&rsquo;elle est et donne ce qu&rsquo;elle donne. Il est toujours possible a post\u00e9riori de d\u00e9crire la succession des formes et les succ\u00e8s ou impasses auxquelles celles-ci ont donn\u00e9 lieu, mais ce travail est fait par un observateur qui projette sur le monde ses propres grilles mentales d&rsquo;analyse, lesquelles ont \u00e9t\u00e9 construites dans son cerveau par les types de contraintes \u00e9volutives que ce cerveau lui-m\u00eame a  pr\u00e9c\u00e9demment subi. <\/p>\n<\/p>\n<p><p>\tOr un cerveau comme le n\u00f4tre a r\u00e9ifi\u00e9 l&rsquo;hypoth\u00e8se selon laquelle les organismes vivants complexes (le tigre par exemple) ne se r\u00e9sument pas aux forces brutes qu&rsquo;ils manifestent \u00e0 premi\u00e8re vue. Ils peuvent aussi ressentir des affects, peurs  ou attachements \u00e0 l&rsquo;\u00e9gard  d&rsquo;autres animaux voire \u00e0 l&rsquo;\u00e9gard d&rsquo;humains. D&rsquo;o\u00f9 d\u00e9coule dans certains cas la possibilit\u00e9 vitale de coexister avec eux. Cette hypoth\u00e8se a \u00e9t\u00e9 souvent v\u00e9rifi\u00e9e par l&rsquo;exp\u00e9rience. Elle est donc devenue loi implicite nous permettant de survivre face non seulement aux animaux sauvages mais aux autres humains o\u00f9 nous ne verrions sans cette hypoth\u00e8se que d&rsquo;autres forces brutes acharn\u00e9es \u00e0 nous d\u00e9truire. <\/p>\n<\/p>\n<p><p>\tOn peut donc faire l&rsquo;hypoth\u00e8se que dans le cadre de l&rsquo;\u00e9volution darwinienne, la plupart des humains ont int\u00e9gr\u00e9 le fait que les cerveaux de leurs contemporains et comp\u00e9titeurs peuvent dans certaines conditions commander des comportements altruistes auxquels il est souhaitable de faire appel. Par le mot altruiste, tr\u00e8s utilis\u00e9 en biologie, je mettrais ici tout ce qui d\u00e9passe l&rsquo;\u00e9go\u00efsme imm\u00e9diat de l&rsquo;individu cherchant \u00e0 se procurer sans r\u00e9fl\u00e9chir les ressources dont il pense avoir besoin pour survivre. Tout les symboles  de l&rsquo;altruisme, du d\u00e9passement, des valeurs dites mystiques permettant de prendre du recul par rapport aux pressions mat\u00e9rielles imm\u00e9diates,  sont selon moi un des r\u00e9sultats de cette forme d&rsquo;\u00e9volution darwinienne. Ces valeurs inspirent indiscutablement les grands  monuments du pass\u00e9, Stonehenge, T\u00e9otihuacan ou les cath\u00e9drales. <\/p>\n<\/p>\n<p><p>\tMais on peut aussi voir dans ces symboles architecturaux le produit d&rsquo;un autre d\u00e9terminisme social pr\u00e9sent chez la plupart des esp\u00e8ces sup\u00e9rieures: le besoin pour des dominants, dominants du sexe ou du pouvoir (pouvoir des armes ou pouvoir de l&rsquo;esprit) d&rsquo;afficher les marques de leur puissance pour impressionner les foules. Les Tours de Duba\u00ef sont para\u00eet-il pour le monde arabe le symbole de la renaissance de l&rsquo;islam conqu\u00e9rant, la tour p\u00e9nienne relayant le minaret dans cette forme d&rsquo;imaginaire. Qu&rsquo;elles se cassent la figure plus t\u00f4t que ne le pr\u00e9voyaient leurs promoteurs ne sera \u00e0 cet \u00e9gard qu&rsquo;un incident dans la lutte multis\u00e9culaire entre religions monoth\u00e9istes. La lutte se poursuit et se poursuivra sur bien d&rsquo;autres plans.<\/p>\n<\/p>\n<p><p>\tCeci dit, pour en revenir \u00e0 un point fondamental de votre dernier propos, je ne crois pas qu&rsquo;il faille faire du complexe anthropotechnique tel que je le d\u00e9finis une machine uniquement guid\u00e9e par l&rsquo;<em>ubris<\/em> technologique. Mon postulat fondamental est que l&rsquo;anthropotechnique allie des technologies elles-m\u00eames \u00e9volutionnaires \u00e0 une grande vari\u00e9t\u00e9 de structures ou soci\u00e9t\u00e9s bioanthropologiques. On peut y trouver le Pentagone, dont l&rsquo;aspect militaire fera peur, mais on y trouvera aussi des syst\u00e8mes extr\u00eamement riches en cons\u00e9quences scientifico-philosophiques altruistes dont on parle peu, par exemple l&rsquo;Observatoire europ\u00e9en austral (<a href=\"http:\/\/fr.wikipedia.org\/wiki\/Observatoire_europ%C3%A9en_austral\" class=\"gen\">lien<\/a>). Pour moi, l&rsquo;ESO, puisque tel est son sigle, est aussi un syst\u00e8me anthropotechnique, tout autant que ceux utilisant d&rsquo;autres grands \u00e9quipements scientifiques, associant des technologies et des humains. Ces humains, sans \u00eatre de petits anges, sont certainement moins potentiellement destructeurs et d\u00e9structurants que ceux du lobby militaro-industriel am\u00e9ricain ou de son homologue chinois.<\/p>\n<\/p>\n<p><p>\tPour moi donc, la richesse du concept de syst\u00e8me anthropotechnique est qu&rsquo;elle permet de prolonger par l&rsquo;analyse de leurs relations symbiotiques avec des technologies foisonnantes l&rsquo;\u00e9tude de toutes les formes existantes d&rsquo;organisations humaines, sans porter sur celles-ci a priori de regards d\u00e9finitifs. <\/p>\n<h4>Les cerveaux des homo sapiens<\/h4>\n<p>Mais revenons au r\u00f4le des individus humains dans l&rsquo;\u00e9volution et l&rsquo;altruisme que certains d&rsquo;entre eux manifestent p\u00e9riodiquement au risque d&rsquo;y laisser la vie, alors que la grande masse se comporte de fa\u00e7on moutonni\u00e8re. C&rsquo;est un point auquel vous tenez beaucoup, \u00e0 juste titre : signaler, quand il y a lieu, le r\u00f4le de l&rsquo;individu humain dans  ces conflits entre structures. Les humains, homo sapiens, sont ind\u00e9niablement \u00e9quip\u00e9s d&rsquo;un cerveau qui en fait des syst\u00e8mes cognitifs individuels (pour reprendre mon expression)  capables d&rsquo;une  prise d&rsquo;autonomie au regard des d\u00e9terminismes biologiques et culturels au sein desquels ils se forment, bien sup\u00e9rieure \u00e0 celle des syst\u00e8mes cognitifs animaux. Dans <em>Les \u00c2mes de Verdun<\/em>, vous \u00eates all\u00e9 jusqu&rsquo;\u00e0 parler de l&rsquo;homme contre la machine, c&rsquo;est-\u00e0-dire de la r\u00e9sistance inattendue des fantassins fran\u00e7ais face aux pr\u00e9parations d&rsquo;artillerie allemande qui, dans l&rsquo;esprit du Haut Etat-Major prussien, devaient tout an\u00e9antir. L&rsquo;histoire est \u00e9videmment pleine de tels exemples, o\u00f9 des humains en petit nombre se dressent contre des forces susceptibles de les \u00e9craser, r\u00e9ussissant parfois \u00e0 les d\u00e9tourner. <\/p>\n<\/p>\n<p><p>\tC&rsquo;est une des grandes questions que se posent les biologistes et les psychologues \u00e9volutionnaires. L&rsquo;altruisme est constamment \u00e9voqu\u00e9, de m\u00eame que les tendances \u00e0 la coop\u00e9ration, pour expliquer que la comp\u00e9tition darwinienne ne favorise pas toujours le plus fort. Mais pourquoi certains individus courent-ils le risque de se sacrifier et pas le plus grand nombre. Chez les insectes sociaux, comme dans les autres formes plus \u00e9volu\u00e9es d&rsquo;altruisme, celui de la m\u00e8re, par exemple,  des d\u00e9terminismes \u00e9pig\u00e9n\u00e9tiques assez stricts font que l&rsquo;individu altruiste fait si l&rsquo;on peut dire partie  du syst\u00e8me. Il contribue \u00e0 sa survie. Dans les soci\u00e9t\u00e9s humaines, le h\u00e9ros individuel para\u00eet relever d&rsquo;un m\u00e9canisme beaucoup plus al\u00e9atoire. Il appara\u00eet ou n&rsquo;appara\u00eet pas, et l&rsquo;\u00e9volution globale des syst\u00e8mes en conflit en est chang\u00e9e.  <\/p>\n<\/p>\n<p><p>\tAdmettons donc qu&rsquo;il y ait une question \u00e0 traiter en termes syst\u00e9mique: pourquoi ce que l&rsquo;on nomme des valeurs de d\u00e9passement inspirent-elles certains individus et non d&rsquo;autres? Les premiers s&rsquo;adonnent alors \u00e0 des activit\u00e9s n&rsquo;ayant plus grand chose \u00e0 voir avec l&rsquo;int\u00e9r\u00eat \u00e9conomique ni l&rsquo;<em>ubris<\/em> technologique.  Pour les spiritualistes, ceci tient au fait que l&rsquo;esprit ne se laisse pas r\u00e9duire \u00e0 la mati\u00e8re. Pour les mat\u00e9rialistes comme moi, il faut r\u00e9fl\u00e9chir au  fondement biologiques des valeurs morales et \u00e0 la fa\u00e7on dont, \u00e0 certains moments, elles s&rsquo;expriment sur le mode al\u00e9atoire, en d\u00e9viant le cours des forces plus brutales. <\/p>\n<\/p>\n<p><p>\tEn termes \u00e9volutionnaires, on pourrait admettre que l&rsquo;individualit\u00e9 des individus, surtout quant elle s&rsquo;exprime d&rsquo;une fa\u00e7on qui les fait \u00e9chapper aux contraintes d&rsquo;ensemble, repr\u00e9sente la variable al\u00e9atoire mutante n\u00e9cessaire \u00e0 l&rsquo;\u00e9volution darwinienne des groupes. Si tous les individus se comportaient et raisonnaient de la m\u00eame fa\u00e7on, le groupe se reproduirait \u00e0 l&rsquo;identique et aucune mutation ne pourrait survenir. Or ces mutations sont indispensables pour que la s\u00e9lection de groupe d\u00e9termine ensuite quels sont les variants les mieux adapt\u00e9s aux nouvelles conditions que rencontre le groupe. <\/p>\n<\/p>\n<p><p>\tMais je ne vous \u00e9nonce pas ces banalit\u00e9s pour le plaisir d&rsquo;aligner des mots. J&rsquo;en arrive \u00e0 l&rsquo;id\u00e9e que j&rsquo;avais en t\u00eate depuis le d\u00e9but de nos relations intellectuelles. Vous \u00eates pr\u00e9cis\u00e9ment vous-m\u00eame un de ces individus (au sens d&rsquo;individualit\u00e9) qui ne se laissent pas embrigader dans le convenu des repr\u00e9sentations dominantes. Vous percevez de ce fait l&rsquo;existence de r\u00e9alit\u00e9s sous-jacentes que les autres ne voient pas. Vous les d\u00e9veloppez sous la forme de ce que les Am\u00e9ricains nomment des visions. On parle aussi  de grands r\u00e9cits. Ces visions, je crois l&rsquo;avoir \u00e9crit pr\u00e9c\u00e9demment, sont indispensables aussi bien aux grands inventeurs de la science qu&rsquo;aux grands artistes. Les premiers les mettent tout de suite \u00e0 l&rsquo;\u00e9preuve de l&rsquo;exp\u00e9rience et les seconds ne se soucient pas de les mettre \u00e0 l&rsquo;\u00e9preuve. Ils se bornent \u00e0 les faire conna\u00eetre comme ils le peuvent. L&rsquo;historien se situe en g\u00e9n\u00e9ral parmi les scientifiques. Il recherche les faits pouvant v\u00e9rifier ses th\u00e8ses et hypoth\u00e8ses. Mais si celles-ci prennent la forme de grands r\u00e9cits, de visions, elles sont difficilement v\u00e9rifiables (sauf peut-\u00eatre \u00e0 tr\u00e8s long terme). L&rsquo;historien se comporte donc aussi dans une certaine mesure en artiste. <\/p>\n<\/p>\n<p><p>\tJe vous dirais que moi-m\u00eame et sans doute la majorit\u00e9 de vos lecteurs, nous ne vous demandons  pas d&rsquo;\u00eatre un historien scientifique, compilant les donn\u00e9es statistiques et les r\u00e9f\u00e9rences. Nous nous int\u00e9ressons plut\u00f4t en vous \u00e0 l&rsquo;historien visionnaire, fut-il proche de l&rsquo;artiste dans certaines de ses cr\u00e9ations. Car cette cat\u00e9gorie  d&rsquo;historien et de chroniqueur rel\u00e8ve pr\u00e9cis\u00e9ment du r\u00f4le de l&rsquo;individu qui se dresse seul contre les forces mat\u00e9rielles, dont je parlais pr\u00e9c\u00e9demment. C&rsquo;est le r\u00f4le que vous jouez, d&rsquo;une certaine fa\u00e7on,  et que vos lecteurs continuent de vous demander \u00e0 jouer, tant que vous en aurez les forces. Le succ\u00e8s est l\u00e0 d&rsquo;ailleurs. Sans doute pas en monnaie sonnante et tr\u00e9buchante mais en renom sur le <em>Web<\/em>, le seul qui compte aujourd&rsquo;hui en terme de contribution \u00e0 un <em>global brain<\/em> en train peut-\u00eatre d&rsquo;\u00e9merger sans que nous ne nous en rendions compte. Je viens en effet de constater que depuis quelques semaines, votre Goggle Page Rank est pass\u00e9 de 4 \u00e0 5. Petite chose direz-vous. Mais vu les mati\u00e8res que vous traitez, et la forme aust\u00e8re de votre site, c&rsquo;est l\u00e0 un compliment du technologisme \u00e0 ne pas sous-estimer.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-4 : De l&rsquo;individu dans l&rsquo;Histoire Pr\u00e9alable sur le darwinisme Je voudrais d&rsquo;abord revenir sur le darwinisme et plus pr\u00e9cis\u00e9ment sur l&rsquo;\u00e9volution darwinienne. Selon moi et je pense pour la plupart des darwinistes, il n&rsquo;est pas possible d&rsquo;imaginer que cette \u00e9volution soit orient\u00e9e dans le sens d&rsquo;une finalit\u00e9 quelconque, accomplissement de la vie, de l&rsquo;humain,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[15],"tags":[9389,7895,4745,5153,3125,3014],"class_list":["post-71834","post","type-post","status-publish","format-standard","hentry","category-dialogues","tag-anthropotechnique","tag-baquiast","tag-darwinisme","tag-doubai","tag-grasset","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71834"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71834\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}