{"id":71863,"date":"2010-05-12T05:30:46","date_gmt":"2010-05-12T05:30:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/12\/dialogues-5-de-lhistorien-face-a-lhistoire\/"},"modified":"2010-05-12T05:30:46","modified_gmt":"2010-05-12T05:30:46","slug":"dialogues-5-de-lhistorien-face-a-lhistoire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/12\/dialogues-5-de-lhistorien-face-a-lhistoire\/","title":{"rendered":"<em>DIALOGUES<\/em>-5 : De l&rsquo;historien face \u00e0 l&rsquo;Histoire"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-5 : De l&rsquo;historien face \u00e0 l&rsquo;Histoire<\/h2>\n<\/p>\n<p><p>\tPuisque nous avons conclu que ces <em>DIALOGUES<\/em> commenceraient par une s\u00e9rie d&rsquo;\u00e9changes sur nos livres respectifs, trois textes pour chacun d&rsquo;eux, et que nous venons d&rsquo;\u00e9changer des consid\u00e9rations autour de votre livre (trois textes effectivement), alors passons au mien. Pour cette raison, je laisserais de c\u00f4t\u00e9 l&rsquo;essentiel de votre texte <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-4_de_l_individu_dans_l_histoire_01_05_2010.html\" class=\"gen\">pr\u00e9c\u00e9dent<\/a> qui r\u00e9pondait lui-m\u00eame \u00e0 mon intervention <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-3_le_grain_de_sable_divin__25_04_2010.html\" class=\"gen\">pr\u00e9c\u00e9dente<\/a>, mais sur lequel, j&rsquo;en suis assur\u00e9 pour mon compte, nous reviendrons. Je m&rsquo;attache \u00e0 la derni\u00e8re partie de votre texte, celle o\u00f9 vous parlez de mon r\u00f4le en tant qu&rsquo;historien (les guillemets sont mis ici,  pour la premi\u00e8re et la derni\u00e8re fois).<\/p>\n<\/p>\n<p><p>\tVous avez pour moi des mots que je consid\u00e8re comme flatteurs, pour lesquels, je l&rsquo;avoue, j&rsquo;aurais pu tomber dans le travers horrible de la vanit\u00e9. Mais je l&rsquo;ai \u00e9cart\u00e9e, je le jure, et elle ne se manifestera pas. Il y a des choses plus int\u00e9ressantes car ces m\u00eames mots abordent un probl\u00e8me absolument fondamental qui m\u00e9rite un d\u00e9bat, qui est celui, non seulement du r\u00f4le de l&rsquo;historien, mais de sa nature m\u00eame. Je vous cite et, par cons\u00e9quent, ces mots ne sont rappel\u00e9s que pour nos dialogues et rien d&rsquo;autre : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>L&rsquo;historien se situe en g\u00e9n\u00e9ral parmi les scientifiques. Il recherche les faits pouvant v\u00e9rifier ses th\u00e8ses et hypoth\u00e8ses. Mais si celles-ci prennent la forme de grands r\u00e9cits, de visions, elles sont difficilement v\u00e9rifiables (sauf peut-\u00eatre \u00e0 tr\u00e8s long terme). L&rsquo;historien se comporte donc aussi dans une certaine mesure en artiste.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nous nous int\u00e9ressons plut\u00f4t en vous \u00e0 l&rsquo;historien visionnaire, fut-il proche de l&rsquo;artiste dans certaines de ses cr\u00e9ations. Car cette cat\u00e9gorie  d&rsquo;historien et de chroniqueur rel\u00e8ve pr\u00e9cis\u00e9ment du r\u00f4le de l&rsquo;individu qui se dresse seul contre les forces mat\u00e9rielles, dont je parlais pr\u00e9c\u00e9demment. C&rsquo;est le r\u00f4le que vous jouez, d&rsquo;une certaine fa\u00e7on,  et que vos lecteurs continuent de vous demander \u00e0 jouer, tant que vous en aurez les forces.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes deux id\u00e9es sont bien l\u00e0 : l&rsquo;historien \u00e0 classer parmi les scientifiques d&rsquo;une part ; l&rsquo;historien dans une certaine mesure [] artiste. Manifestement, il vous pla\u00eet de me mettre dans l&rsquo;historien proche de l&rsquo;artiste, dans la cat\u00e9gorie que vous nommez historien visionnaire. (Je dirais aussi historien proph\u00e9tique, qui est, apr\u00e8s tout, une cat\u00e9gorie reconnue comme telle, qui fut longtemps florissante en France, qui est, je pense, le pays par excellence de l&rsquo;histoire, peut-\u00eatre plus encore que de la litt\u00e9rature,  ou bien, disons, de l&rsquo;histoire quand elle est <strong>aussi<\/strong> la litt\u00e9rature, c&rsquo;est-\u00e0-dire l&rsquo;historien n\u00e9cessairement artiste.) <\/p>\n<\/p>\n<p><p>\tComment vous dire autrement que d&rsquo;admettre que vous comblez tous mes vux et que vous rencontrez \u00e9videmment ma conviction profonde Je m&rsquo;explique : combler tous mes vux, cela est bien rencontrer ma secr\u00e8te esp\u00e9rance et ma conviction que je fais mon travail d&rsquo;historien d&rsquo;abord comme un artiste, gouvern\u00e9 par l&rsquo;intuition pour mieux utiliser mes connaissances techniques et mon exp\u00e9rience ; c&rsquo;est aussi nourrir ma conviction que l&rsquo;historien <strong>n\u00e9cessaire<\/strong> aujourd&rsquo;hui est bien l&rsquo;artiste, car lui seul \u00e9chappe au syst\u00e8me anthropotechnique qui nous d\u00e9vore, s&rsquo;en d\u00e9tache, l&rsquo;observe de l&rsquo;ext\u00e9rieur et le d\u00e9crit pour ce qu&rsquo;il est. C&rsquo;est cet historien-l\u00e0 qui s&rsquo;est lanc\u00e9 dans <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> en ignorant <strong>compl\u00e8tement<\/strong> ce qui l&rsquo;attendait (on le verra plus loin) D&rsquo;une certaine fa\u00e7on, c&rsquo;\u00e9tait la condition <em>sine qua non<\/em> ; aurais-je su ce qui m&rsquo;attendait, jusqu&rsquo;\u00e0 quelle extr\u00e9mit\u00e9 j&rsquo;allais faire avancer mon travail, pouss\u00e9 et \u00e9clair\u00e9 par l&rsquo;intuition, que je ne l&rsquo;aurais jamais entrepris. D&rsquo;abord, je n&rsquo;aurais pas os\u00e9 y croire,  je veux dire, aux hypoth\u00e8ses auxquelles j&rsquo;aboutis, et ma conviction sinc\u00e8re \u00e0 cet \u00e9gard est qu&rsquo;elles ne sont pas <strong>de moi<\/strong>, qu&rsquo;elles se sont form\u00e9es d&rsquo;elles-m\u00eames, hors de ma volont\u00e9 et, peut-\u00eatre, de mon esprit lui-m\u00eame. L\u00e0-dessus, puisqu&rsquo;il faut toujours songer \u00e0 une cause premi\u00e8re,  d&rsquo;o\u00f9 tout cela vient-il ? Nous laissons la r\u00e9ponse pour plus tard, s&rsquo;il y a un plus tard<\/p>\n<h3>Un seul th\u00e8me s&rsquo;impose \u00e0 l&rsquo;historien<\/h3>\n<\/p>\n<p><p>\tIl est vrai qu&rsquo;<strong>un seul<\/strong> th\u00e8me s&rsquo;impose, devrait s&rsquo;imposer au v\u00e9ritable historien aujourd&rsquo;hui : comment une telle civilisation, marqu\u00e9e de tant d&rsquo;efforts, de tant d&rsquo;esprits prodigieux, de tant de d\u00e9couvertes, est-elle parvenue \u00e0 un fonctionnement qui engendre d&rsquo;une fa\u00e7on aussi <strong>syst\u00e9matique<\/strong> la laideur, la b\u00eatise et la destruction ? Comment est-il possible qu&rsquo;un tel rassemblement d&rsquo;esprits \u00e9lev\u00e9s et d&rsquo;organisations puissantes puisse engendrer des politiques aussi <strong>uniform\u00e9ment<\/strong> stupides,  pour ne pas parler de leur cruaut\u00e9, de leur nihilisme, de leur abaissement continuel&#8230; ? Comment est-il possible qu&rsquo;une civilisation marqu\u00e9e par la pr\u00e9tention de parvenir \u00e0 une tr\u00e8s haute culture aboutisse de fa\u00e7on aussi aveuglante \u00e0 force d&rsquo;\u00e9vidence \u00e0 l&rsquo;abaissement syst\u00e9matique de la culture, jusqu&rsquo;\u00e0 la m\u00e9diocrit\u00e9, la futilit\u00e9 insupportable, le mensonge d\u00e9gradant, l&rsquo;entropie sans espoir ?<\/p>\n<\/p>\n<p><p>\tUn esprit qui pr\u00e9tend comprendre l&rsquo;histoire d&rsquo;une fa\u00e7on scientifique, fait apr\u00e8s fait, et chaque fois apr\u00e8s v\u00e9rification, n&rsquo;y peut rien comprendre. Il se perd dans les d\u00e9dales de sa d\u00e9monstration et se retrouve, bien rang\u00e9, dans la cohorte des esprits intelligents oblig\u00e9s de cautionner l&rsquo;encha\u00eenement parcellaire qu&rsquo;il d\u00e9crit, qui fait partie d&rsquo;un ensemble accouchant de la b\u00eatise, de la laideur et de la destruction,  avec une conclusion style <em>Prisunic<\/em> : Apr\u00e8s tout, demain ce sera peut-\u00eatre mieux. Il faut s&rsquo;adresser directement \u00e0 l&rsquo;Histoire, et seul un artiste, indiff\u00e9rent aux faits scientifiques \u00e9lev\u00e9s en directives et aux d\u00e9monstrations comme moyen central de son enqu\u00eate, peut y pr\u00e9tendre Car alors, d\u00e9barrass\u00e9 du fardeau de l&rsquo;intelligence en action, il s&rsquo;ouvre n\u00e9cessairement \u00e0 l&rsquo;intuition qui nourrira son inspiration. Au contraire de l&rsquo;historien-scientifique, enferm\u00e9 dans la p\u00e9nombre d\u00e9sormais g\u00e9n\u00e9rale du syst\u00e8me de son intelligence, l&rsquo;historien-artiste est ouvert \u00e0 l&rsquo;en dehors qui l&rsquo;\u00e9claire.<\/p>\n<\/p>\n<p><p>\tAinsi l&rsquo;artiste simplifie-t-il le monde qu&rsquo;il consid\u00e8re. Il conna\u00eet les d\u00e9tails, \u00e9ventuellement, justement pour ne pas s&rsquo;en servir pour la plupart d&rsquo;entre eux, sinon pour leur d\u00e9nier quelque importance que ce soit, ou pour s&rsquo;en servir d&rsquo;une fa\u00e7on d\u00e9cisivement <strong>diff\u00e9rente<\/strong> quand il leur reconna\u00eet une utilit\u00e9. Il reconna\u00eet les grondements souterrains de l&rsquo;Histoire, parce qu&rsquo;il a l&rsquo;oreille fine, parce c&rsquo;est un sismographe intuitif de l&rsquo;Histoire. Cet historien-l\u00e0 est aujourd&rsquo;hui plus que jamais n\u00e9cessaire,  et c&rsquo;est bien pour cela que l&rsquo;historiographie officielle ne cherche qu&rsquo;\u00e0 l&rsquo;\u00e9liminer,  car, dans un monde immens\u00e9ment compliqu\u00e9 par les d\u00e9tails des choses et des mati\u00e8res de plus en plus avanc\u00e9es et complexes (on dit pointues), seul lui peut revenir \u00e0 l&rsquo;essentiel, qu&rsquo;il distingue soudain dans une trou\u00e9e de lumi\u00e8re per\u00e7ant le brouillard immense qui a envahi notre univers. Il y a en lui une ing\u00e9nuit\u00e9 qui ne cesse de redonner sans cesse sa jeunesse \u00e0 son regard, une absence de connaissance apprise dans les normes du syst\u00e8me p\u00e9dagogique qui g\u00e9n\u00e8re une formidable capacit\u00e9 de re-connaissance des choses essentielles dissimul\u00e9es par le brouillard. Et de tout cela, il ne peut se passer, car cette trou\u00e9e de lumi\u00e8re dans le brouillard, qui procure de brefs moments d&rsquo;intense exaltation, est le seul rem\u00e8de qui lui permet d&rsquo;\u00e9carter l&rsquo;angoisse qui l&#8217;emporterait. L&rsquo;historien devenu artiste lutte pour sa vie dans sa qu\u00eate hors des normes, car il sait que l&rsquo;enfermement dans les normes le tuerait avec une nettet\u00e9 aussi tranchante que la guillotine.<\/p>\n<\/p>\n<p><p>\tPeu lui importe d&rsquo;avoir raison en ce sens qu&rsquo;il serait reconnu, il ne progresse que parce qu&rsquo;il est paradoxalement prisonnier de sa libert\u00e9, mais conscient que cet emprisonnement est celui de la grandeur des choses et de l&rsquo;esprit d&rsquo;\u00e9l\u00e9vation. Il est condamn\u00e9 \u00e0 \u00eatre haut ou \u00e0 ne pas \u00eatre. L&rsquo;essence de ce qui le pousse est hors des normes politiques et des apparats sociaux, et c&rsquo;est un bien lourd fardeau. Il n&rsquo;est pas heureux et le bonheur ne lui est pas une notion famili\u00e8re, mais de cela il ne fera jamais une th\u00e8se qui aiderait la psychiatrie \u00e0 soulager les malheurs de ses fr\u00e8res d&rsquo;armes, les autres soumis \u00e0 de semblables tourments. Une fatalit\u00e9 p\u00e8se sur lui et sa d\u00e9marche aventureuse est sa fa\u00e7on \u00e0 lui de tenter d&rsquo;apprivoiser ce monstre-l\u00e0, la fatalit\u00e9, ou, dans tous les cas, de composer avec lui. <\/p>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 ces conditions seulement qu&rsquo;\u00e0 un instant ou l&rsquo;autre, un instant qu&rsquo;il peut qualifier de divin, lui appara\u00eet en un \u00e9clair une partie de la V\u00e9rit\u00e9 du monde. Cela ne l&rsquo;apaise pas pour autant et il retombe bient\u00f4t, mais ce fut un pas de plus dans sa fa\u00e7on de progresser dans l&rsquo;accomplissement de sa part du contrat qui le lie \u00e0 la n\u00e9cessit\u00e9 de son existence.<\/p>\n<\/p>\n<p><p>\tCurieusement, je pourrais \u00e9crire cela comme un transition vers quelques \u00e9claircissements concernant <em>La gr\u00e2ce de l&rsquo;Histoire<\/em><\/p>\n<h3>Gen\u00e8se paradoxale de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em><\/h3>\n<\/p>\n<p><p>\tAu d\u00e9part, ce livre n&rsquo;avait nulle pr\u00e9tention. Il \u00e9tait, au sens propre du mot, <strong>\u00e9triqu\u00e9<\/strong>. Il entendait s&rsquo;attacher au ph\u00e9nom\u00e8ne historique de l&rsquo;observation qu&rsquo;\u00e0 une certaine p\u00e9riode,  que j&rsquo;identifie dans les bornes des ann\u00e9es 1919-1933,  un vaste mouvement intellectuel europ\u00e9en, et surtout fran\u00e7ais, avait parfaitement identifi\u00e9 tous les caract\u00e8res et les fondements de la crise de civilisation dont nous connaissons aujourd&rsquo;hui l&rsquo;explosion temp\u00e9tueuse. En un sens, 1919-1933 avait mieux compris que nous les comprenons nous-m\u00eames les causes fondamentales de la terrible crise qui nous emporte aujourd&rsquo;hui. (*)<\/p>\n<\/p>\n<p><p>\tL\u00e0-dessus est venue se greffer, pour mon compte, la connaissance de la Grande Guerre avec <a href=\"http:\/\/www.dedefensa.org\/article-retour_a_verdun_24_11_2006.html\" class=\"gen\">Verdun<\/a>,  ou dirais-je, comme premi\u00e8re intuition, la re-connaissance, comme si les constats que j&rsquo;y fis \u00e9tait la premi\u00e8re trou\u00e9e de lumi\u00e8re dans le brouillard g\u00e9n\u00e9ral. Verdun m&rsquo;apparut non comme un affrontement absurde de nationalismes, non comme la d\u00e9monstration du lieu commun que la guerre est une chose terrible, mais comme un lieu myst\u00e9rieux et magique o\u00f9 quelque chose de formidable, de consid\u00e9rable, d\u00e9passant \u00e9videmment l&rsquo;homme et sa pr\u00e9tention de contr\u00f4ler le monde, s&rsquo;\u00e9tait manifest\u00e9e avec une puissance inou\u00efe. La beaut\u00e9 de ce qu&rsquo;est devenu le champ de la bataille permet de mieux saisir, par contraste presque pr\u00e9monitoire comme si vous vous retrouviez dans l&rsquo;\u00e2me et dans la peau d&rsquo;un de ces jeunes gens martyris\u00e9s en 1916, l&rsquo;horreur formidable, comme un \u00e9v\u00e9nement venu d&rsquo;ailleurs, de ce que fut cette bataille. La r\u00e9flexion \u00e9vidente, aveuglante, est qu&rsquo;au lieu de conclure que cette bataille n&rsquo;eut aucun sens, comme font les historiens appoint\u00e9s du syst\u00e8me, je conclus qu&rsquo;elle avait au contraire un sens absolument formidable, quasiment m\u00e9tahistorique. Aussit\u00f4t, il devenait \u00e9vident qu&rsquo;un lien devait \u00eatre \u00e9tabli entre cette bataille et la Grande Guerre en g\u00e9n\u00e9ral, et sa manifestation d&rsquo;une force sup\u00e9rieure \u00e9pouvantable,  et la lucidit\u00e9 de ceux qui, dans la p\u00e9riode suivante (1919-1933), identifi\u00e8rent les fondements d&rsquo;une crise de civilisation sans pr\u00e9c\u00e9dent. La phrase de Val\u00e9ry (\u00ab<em>Nous autres, civilisations<\/em>\u00bb) sert de lien, comme une phrase symbolique, entre la Grande Guerre et la lucidit\u00e9 de 1919-1933.<\/p>\n<\/p>\n<p><p>\tJe tenais ma premi\u00e8re intuition et c&rsquo;est autour d&rsquo;elle que l&rsquo;ouvrage commen\u00e7a sa croissance. L&rsquo;id\u00e9e \u00e9triqu\u00e9e \u00e9tait devenue un axe central imposant l&rsquo;id\u00e9e puissante d&rsquo;un Myst\u00e8re \u00e0 r\u00e9soudre. Il fallait aller dans les deux sens : remonter dans le temps pour trouver la source du Myst\u00e8re, aller de l&rsquo;avant pour distinguer ses effets jusqu&rsquo;\u00e0 nous. Dans cette qu\u00eate, on trouve des r\u00e9conforts et des aides inestimables. Celle de Guglielmo Ferrero est essentielle, on le sait, par les nombreuses citations que j&rsquo;en fais, par sa trouvaille superbe d&rsquo;<strong>intuition<\/strong> que la Grande Guerre est un affrontement entre l&rsquo;id\u00e9al de perfection latin et l&rsquo;id\u00e9al de puissance des pays germains (et, ajouterons-nous, anglo-saxons).<\/p>\n<\/p>\n<p><p>\tLa remont\u00e9e dans le temps fait rencontrer ce carrefour fondamental o\u00f9 s&rsquo;entrem\u00ealent les trois R\u00e9volutions,  l&rsquo;am\u00e9ricaine, la fran\u00e7aise et celle du choix de la thermodynamique comme source d&rsquo;\u00e9nergie sugg\u00e9r\u00e9e par le livre d&rsquo;Alain Gras, <em>Le choix du feu<\/em>. Vous vous dites qu&rsquo;il y a l\u00e0 un nud central, qui va d\u00e9velopper une m\u00e9canique gigantesque de puissance, qui se nouera en un premier \u00e9clair de puissance avec la Grande Guerre, qui poursuivra sa route de puissance tout au long du XX\u00e8me si\u00e8cle et de ses \u00e9v\u00e9nements de fer, de sang et de feu, qui se noue \u00e0 nouveau sous nos yeux, aujourd&rsquo;hui, dans l&rsquo;explosion gigantesque d&rsquo;une crise sans pr\u00e9c\u00e9dent. Je r\u00e9sume, \u00f4 combien, une d\u00e9marche gouvern\u00e9e par une intuition encore mal identifi\u00e9e, bard\u00e9e de perceptions, de reconnaissances diverses par des perspectives, des d\u00e9tails de connaissance, de mises en place et d&rsquo;interpr\u00e9tations inattendues d&rsquo;\u00e9v\u00e9nements trop convenus,  jusqu&rsquo;\u00e0 l&rsquo;interrogation finale. Car, \u00e0 un moment ou l&rsquo;autre, l&rsquo;historien intuitif qui cherche se trouve confront\u00e9 \u00e0 la <strong>n\u00e9cessit\u00e9<\/strong> d&rsquo;une explication centrale, qu&rsquo;il hume, qu&rsquo;il devine, qu&rsquo;il croit saisir sans l&#8217;empoigner ferme. Puis, un jour, se concr\u00e9tise cette intuition fondamentale, l\u00e0 non plus comme un \u00e9clair, mais avec un certain apaisement, comme une \u00e9vidence que vous ne distinguiez pas tant elle s&rsquo;offrait si compl\u00e8tement \u00e0 vous, comme si le puzzle se mettait enfin en place. En un sens, on pourrait dire que vous \u00e9tiez poss\u00e9d\u00e9 par l&rsquo;hypoth\u00e8se fondamentale, que vous \u00e9tiez devenu vous-m\u00eame cette hypoth\u00e8se et qu&rsquo;enfin vous la restituez remise en ordre. Vous y \u00eates.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est donc le cas pour cette id\u00e9e d&rsquo;une force historique immense qui s&rsquo;est empar\u00e9e de nos destins \u00e0 l&rsquo;aube du XIX\u00e8me si\u00e8cle et qui s&rsquo;est d\u00e9velopp\u00e9e dans toute sa puissance, influen\u00e7ant tous les comportements historiques. A cette lumi\u00e8re, vous en d\u00e9duisez un r\u00e9arrangement de l&rsquo;Histoire qui \u00e9claire jusqu&rsquo;\u00e0 notre \u00e9poque et donne un sens diff\u00e9rent \u00e0 tous les \u00e9v\u00e9nements jusqu&rsquo;alors appr\u00e9ci\u00e9s du point de vue de la raison humaine. Vous vous sentez alors la force de proposer l&rsquo;interpr\u00e9tation qu&rsquo;il s&rsquo;agit d&rsquo;une chose si compl\u00e8tement diff\u00e9rente qu&rsquo;on peut parler d&rsquo;une deuxi\u00e8me civilisation occidentale, entendant par l\u00e0 qu&rsquo;\u00e0 partir de cette rupture notre civilisation a chang\u00e9 de substance. Vous pouvez alors r\u00e9activer la raison pour mieux \u00e9tayer l&rsquo;explication de votre intuition.<\/p>\n<\/p>\n<p><p>\tParlant de Chateaubriand comme de l&rsquo;arch\u00e9type de cet historien proph\u00e9tique, le philosophe Manuel de Di\u00e9guez parlait du \u00ab<em>cerveau de glace<\/em> [de Chateaubriand] <em>dans une \u00e2me de feu<\/em>\u00bb. C&rsquo;est bien de cette alliance de la glace d&rsquo;une raison forte et stricte, aliment\u00e9e par le feu d&rsquo;une \u00e2me qui re\u00e7oit l&rsquo;intuition, qu&rsquo;il faut parler dans le cas de cette sorte d&rsquo;historien. Il r\u00e9invente l&rsquo;Histoire comme s&rsquo;il la retrouvait, elle qui fut dissimul\u00e9e, d\u00e9form\u00e9e, arrang\u00e9e par les besogneux qui sont essentiellement charg\u00e9s d&rsquo;arranger le pass\u00e9 pour justifier le pr\u00e9sent des ma\u00eetres du jour.<\/p>\n<h3>La double t\u00e2che de l&rsquo;historien<\/h3>\n<\/p>\n<p><p>\tBien entendu, avec cette intuition devenue interpr\u00e9tation et d\u00e9velopp\u00e9e en un r\u00e9cit qui tente d&rsquo;\u00eatre le plus lisible et le plus compr\u00e9hensible aux autres esprits, on se trouve devant une t\u00e2che double. D&rsquo;une part, c&rsquo;est la mission de la communication de votre interpr\u00e9tation historique, d&rsquo;autre part c&rsquo;est la charge constante du doute qui ne cesse de vous habiter parce que vous vous appuyez sur la formidable conviction que vous a donn\u00e9e cette intuition mais qui ne dispose \u00e0 aucun moment de l&rsquo;assurance apaisante de la d\u00e9monstration rationnelle. Ce travail est caract\u00e9ris\u00e9 par une solitude effrayante.<\/p>\n<\/p>\n<p><p>\tAvec votre hypoth\u00e8se, vous avez bris\u00e9 en partie ma solitude effrayante, et soyez-en remerci\u00e9 sans restriction. Votre aide m&rsquo;est infiniment pr\u00e9cieuse, qui m&rsquo;apporte une certaine solidit\u00e9 qui est celle de l&rsquo;hypoth\u00e8se scientifique. Pour autant, elle n&rsquo;implique nullement l&rsquo;indulgence. Maintenant que je m&rsquo;en suis saisie, de l&rsquo;hypoth\u00e8se scientifique, je deviens d&rsquo;une impitoyable exigence. La vision historique saisie par l&rsquo;artiste soudain renforc\u00e9e de l&rsquo;hypoth\u00e8se scientifique exige aussit\u00f4t que l&rsquo;hypoth\u00e8se scientifique accepte d&rsquo;\u00eatre confront\u00e9e \u00e0 la puissante architecture historique de la vision. L&rsquo;historien-artiste n&rsquo;est pas pr\u00e9cis\u00e9ment facile dans ce domaine ; il est exigeant, sans gu\u00e8re de consid\u00e9ration pour la pr\u00e9cision et le travail du scientifique, et il ass\u00e8ne sa vision comme Nietzsche philosophe \u00e0 coups de marteau.  <\/p>\n<\/p>\n<p><p>\tC&rsquo;est pour cette raison et c&rsquo;est dans cet esprit que je ferraille avec vous, depuis quelques semaines, \u00e0 propos de votre hypoth\u00e8se sur les syst\u00e8mes anthropotechniques. Vous avez compris que votre hypoth\u00e8se du syst\u00e8me anthropotechnique, d\u00e8s que je m&rsquo;en suis saisie, est aussit\u00f4t fix\u00e9e dans le temps historique par mon interpr\u00e9tation, et qu&rsquo;elle constitue n\u00e9cessairement une agression terrible et sp\u00e9cifique contre le destin historique de l&rsquo;esp\u00e8ce, une rupture d&rsquo;une continuit\u00e9 dont vous-m\u00eame par contre semblez faire le fondement de notre \u00e9volution. Si je suis largement inclin\u00e9 \u00e0 adopter l&rsquo;explication que l&rsquo;esp\u00e8ce se trouve, en l&rsquo;occurrence, bien plus soumise \u00e0 ces grandes forces de l&rsquo;Histoire que ma\u00eetresse de ces forces, il n&rsquo;en demeure pas moins que subsiste, et m\u00eame s&rsquo;impose le Myst\u00e8re de ces forces,  en l&rsquo;occurrence, ici, ce syst\u00e8me anthropotechnique qui s&rsquo;est saisi de nos destin\u00e9es \u00e0 partir d&rsquo;une certaine p\u00e9riode r\u00e9volutionnaire de notre Histoire, et a incurv\u00e9 nos destin\u00e9e vers un avenir catastrophique. L&rsquo;historien intervient en proposant, voire en imposant des datations historiques, des orientations politiques et m\u00e9tapolitiques, en ass\u00e9nant une lecture m\u00e9tahistorique de nos destin\u00e9es qui suppose n\u00e9cessairement un jugement fondamental de valeur sur notre civilisation et sur ses volte-face. C&rsquo;est sur ces points essentiellement que nous diff\u00e9rons me semble-t-il, car ma conviction est bien qu&rsquo;il y a eu d\u00e9viation fondamentale, transformation de notre destin vers un avenir catastrophique.<\/p>\n<\/p>\n<p><p>\tL\u00e0 o\u00f9 nous nous rejoignons \u00e0 nouveau, c&rsquo;est dans la r\u00e9alisation qu&rsquo;effectivement notre destin\u00e9e se pr\u00e9sente aujourd&rsquo;hui sous des augures catastrophique. Mais cette occurrence n&rsquo;est l\u00e0 que pour faire surgir \u00e0 nouveau nombre d&rsquo;autres questions qui mettront \u00e0 jour \u00e0 nouveau nos diff\u00e9rences d&rsquo;analyses, les couleurs changeantes de nos regards pos\u00e9s sur la situation du monde. Car, pour ma part, c&rsquo;est bien l&rsquo;Histoire qui reste la ma\u00eetresse de notre Grand Tout, et c&rsquo;est bien en elle que repose notre esp\u00e9rance fondamentale, c&rsquo;est bien au nom d&rsquo;elle-m\u00eame que nous devons affirmer notre r\u00e9sistance,  avec l&rsquo;une de ces questions ultimes, bien plus int\u00e9ressante et bien plus riche que la question sur le sens de l&rsquo;Histoire,  cette question, l&rsquo;Histoire a-t-elle une conscience? Apr\u00e8s tout, cela rejoint votre recherche puisque vous posez la m\u00eame question \u00e0 propos du Pentagone et que vous faites des hypoth\u00e8ses sur l&rsquo;avenir qui concerne \u00e9galement, de fa\u00e7on implicite, la question de la conscience avec les syst\u00e8mes post-anthropotechniques dans lesquels vous mettez votre espoir. Cela rejoint votre recherche mais cela ne signifie certainement pas qu&rsquo;il y ait accord; cela laisse de la place pour la poursuite de nos dialogues.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Philippe Grasset<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t(*) D&rsquo;ici la fin de la semaine sera mise en ligne, justement, cette partie (1919-1933) de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-5 : De l&rsquo;historien face \u00e0 l&rsquo;Histoire Puisque nous avons conclu que ces DIALOGUES commenceraient par une s\u00e9rie d&rsquo;\u00e9changes sur nos livres respectifs, trois textes pour chacun d&rsquo;eux, et que nous venons d&rsquo;\u00e9changer des consid\u00e9rations autour de votre livre (trois textes effectivement), alors passons au mien. Pour cette raison, je laisserais de c\u00f4t\u00e9 l&rsquo;essentiel de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[15],"tags":[9389,9071,4427,2631,3969,5959,8397,8386,2622,3014],"class_list":["post-71863","post","type-post","status-publish","format-standard","hentry","category-dialogues","tag-anthropotechnique","tag-artiste","tag-conscience","tag-de","tag-grace","tag-historien","tag-intuition","tag-lhistoire","tag-la","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71863"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71863\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}