{"id":71871,"date":"2010-05-14T11:56:11","date_gmt":"2010-05-14T11:56:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/14\/le-changement-par-limpuissance\/"},"modified":"2010-05-14T11:56:11","modified_gmt":"2010-05-14T11:56:11","slug":"le-changement-par-limpuissance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/05\/14\/le-changement-par-limpuissance\/","title":{"rendered":"Le changement par l&rsquo;impuissance ?"},"content":{"rendered":"<p><p>Notre \u00e9poque en apparence compliqu\u00e9e, o\u00f9 l&rsquo;on vous dit que tout ne va pas si mal au milieu de la crise g\u00e9n\u00e9rale de l&rsquo;effondrement d&rsquo;une civilisation b\u00e2tie sur la puissance,  une telle \u00e9poque ne peut \u00eatre chiche de paradoxes. En trouve-t-on un, assez int\u00e9ressant , du c\u00f4t\u00e9 du Royaume-Uni et de sa coalition Cameron-Clegg (ou Cameron-Clegg-<a href=\"http:\/\/www.dedefensa.org\/article-gouvernement_a_trois_cameron_clegg_et_dieu_14_05_2010.html\" class=\"gen\">Dieu<\/a>)? Dans un texte centr\u00e9 sur l&rsquo;\u00e9limination de la vie publique du <em>spin master<\/em> et \u00e2me damn\u00e9e (de communication) de Tony Blair, Alastair Campbell, Paul Woodward propose cette int\u00e9ressante r\u00e9flexion ce <a href=\"http:\/\/warincontext.org\/2010\/05\/13\/the-end-of-an-era\/\" class=\"gen\">13 mai 2010<\/a>, sur son site <em>War in Context<\/em> (excellent site, <em>indeed<\/em>)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Indeed, Britain&rsquo;s first coalition government since the Second World War opens up a possibility that should be watched with keen attention by observers who might otherwise have no particular interest in British politics. The era where image-makers such as Campbell turned policymaking into an utterly unprincipled message-shaping process, may finally be drawing to a close as the communications apparatus of a single party will no longer hold sway. David Cameron will not have the luxury of merely needing to sell his message to a friendly media but will have to persuade Liberal-Democrat partners much less willing to swallow the Conservative spin.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The political mechanics of consensus and compromise will be hard enough to manage without the additional strain of attempting to balance the competing demands of two communications teams. For that reason, there is a chance that the spin doctors will be sidelined or their influence at least diminished if they further complicate an already complex process.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Beyond Britain&rsquo;s slavish allegiance to Washington during the Blair years, nothing represented the Labour government&rsquo;s abandonment of principle more clearly over the last decade than the relentless erosion of civil liberties in the name of security. There is now the prospect that this trend will be reversed.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>   R\u00e9flexion tr\u00e8s int\u00e9ressante, <em>indeed<\/em>. Il y a l\u00e0 une analyse paradoxale par rapport \u00e0 ce que nous concevons comme repr\u00e9sentation et m\u00e9canisme d&rsquo;un pouvoir efficace. L&rsquo;exemple britannique fut toujours cit\u00e9 comme l&rsquo;arch\u00e9type du pouvoir d\u00e9mocratique et parlementaire efficace, par sa syst\u00e9matisation du d\u00e9gagement d&rsquo;une majorit\u00e9 absolue d&rsquo;un seul parti pour chaque \u00e9lection. Ce n&rsquo;est pas tant le syst\u00e8me bi-parti qui est en cause que l&rsquo;injustice d\u00e9mocratique fondamentale du syst\u00e8me \u00e9lectoral, injustice largement compens\u00e9e, selon la vision tr\u00e8s pragmatique des Britanniques, par ce r\u00e9sultat si net assurant le socle parlementaire intangible du pouvoir. Les \u00e9lections de mai 2010 ont bris\u00e9 cela et, d&rsquo;une certaine fa\u00e7on, qui n&rsquo;est peut-\u00eatre pas la sienne, les exclamations <a href=\"http:\/\/www.dedefensa.org\/article-gouvernement_a_trois_cameron_clegg_et_dieu_14_05_2010.html\" class=\"gen\">exalt\u00e9es<\/a> de Matthew Parris ont leur raison d&rsquo;\u00eatre (\u00ab<em>If God does not exist then  in light of the hidden hand that events have placed on the shoulders of these two new leaders, paving their way and staying their enemies  Nick Clegg and David Cameron may this weekend think it necessary to invent Him<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tParris remercie ce Dieu auquel il ne croit pas et qu&rsquo;il faudrait donc inventer pour l&rsquo;occasion, d&rsquo;avoir forc\u00e9 \u00e0 la r\u00e9union de deux hommes (Cameron et Clegg) qu&rsquo;il estime faits pour s&rsquo;entendre et pour mener une v\u00e9ritable r\u00e9volution du syst\u00e8me, \u00e0 l&rsquo;int\u00e9rieur des r\u00e8gles du syst\u00e8me. Dieu ou pas Dieu, c&rsquo;est l&rsquo;\u00e9lecteur qui a vot\u00e9, et qui, qu&rsquo;il ait \u00e9t\u00e9 inspir\u00e9 ou non, a donn\u00e9 ce r\u00e9sultat inattendu par son <strong>d\u00e9sordre<\/strong> par rapport aux normes de la pratique politique britanniques. Nous nous en sommes d\u00e9j\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-l_imagination_assiege_le_pouvoir_10_05_2010.html\" class=\"gen\">r\u00e9joui<\/a> comme une fa\u00e7on tr\u00e8s postmoderniste de la part de la col\u00e8re populaire de se r\u00e9volter efficacement contre le syst\u00e8me, avec \u00e9ventuellement l&rsquo;aide de Dieu dirigeant le choix de l&rsquo;\u00e9lecteur. C&rsquo;est l\u00e0 que la remarque de Woodward a toute sa place et sa pertinence. Puisque ce d\u00e9sordre a forc\u00e9 \u00e0 une coalition qui s&rsquo;est engag\u00e9e contractuellement pour un gouvernement de cinq ans, cela signifie de nombreux conflits \u00e0 venir et qu&rsquo;il faudra r\u00e9gler, ou au moins de nombreux conflits potentiels qu&rsquo;il faudra d\u00e9samorcer, avec deux \u00e9quipes de communication ayant effectivement des int\u00e9r\u00eats diff\u00e9rentes ; par cons\u00e9quent, certes, l&rsquo;impossibilit\u00e9 de remettre tous les pouvoirs \u00e0 un <em>spin master<\/em>, comme Blair le fit avec Alastair Campbell. D&rsquo;o\u00f9, juge Woodward, un coup d&rsquo;arr\u00eat donn\u00e9 \u00e0 la dictature de la communication.<\/p>\n<\/p>\n<p><p>\tLa remarque vaut effectivement qu&rsquo;on s&rsquo;y arr\u00eate. D&rsquo;abord, pour observer que la rupture du syst\u00e8me britannique si souvent acclam\u00e9 comme mod\u00e8le de stabilit\u00e9 et de coh\u00e9sion (un seul parti, une majorit\u00e9 absolue) n&rsquo;est pas en soi une mauvaise chose. Les directions politiques \u00e9tant r\u00e9duites par leur consentement empress\u00e9e \u00e0 l&rsquo;impuissance la plus compl\u00e8te, \u00e0 une sorte de vu absolu de vassalit\u00e9 au syst\u00e8me anthropotechnique qui nous d\u00e9vore et nous annihile, les moyens puissants d&rsquo;une action politique n&rsquo;ont plus aucun int\u00e9r\u00eat et deviennent m\u00eame compl\u00e8tement n\u00e9gatifs et contre-productifs, puisqu&rsquo;utilis\u00e9s au profit du syst\u00e8me. Ils accentuent l&rsquo;impuissance politique et la vassalit\u00e9 au syst\u00e8me, notamment,  et c&rsquo;est l\u00e0 qu&rsquo;on rejoint la remarque de Woodward,  en donnant les pleins pouvoirs aux repr\u00e9sentants du syst\u00e8me de la communication, l&rsquo;une des deux branches majeures (avec le syst\u00e8me du technologisme) du syst\u00e8me g\u00e9n\u00e9ral, et elle-m\u00eame charg\u00e9e dans ce cas de la construction d&rsquo;une repr\u00e9sentation virtualiste de la direction politique et de son action. La chose est devenue impossible \u00e0 cause du d\u00e9sordre divin (merci \u00e0 Matthew Parris) qui a conduit \u00e0 la n\u00e9cessit\u00e9 d&rsquo;une alliance entre deux fortes personnalit\u00e9s et leurs partis.<\/p>\n<\/p>\n<p><p>\tEffectivement, ces deux personnalit\u00e9s vont gouverner ensemble et ne manqueront pas de marquer leurs territoires, de d\u00e9fendre leurs int\u00e9r\u00eats, de se marquer \u00e0 la culotte comme on dit en termes de rugby. Cela signifie que les \u00e9quipes de communication ne s&rsquo;occuperont plus de construire une image virtualiste de l&rsquo;action de la direction politique pour le public mais plut\u00f4t de se surveiller l&rsquo;une l&rsquo;autre, \u00e9ventuellement de se rectifier l&rsquo;une l&rsquo;autre, voire de s&rsquo;affronter. Au mieux, nous pourrions avoir, notamment avec l&rsquo;aide puissante du syst\u00e8me de la communication, une version gouvernementale de la discorde chez l&rsquo;ennemi avec deux partenaires \u00e9ventuellement et \u00e9pisodiquement adversaires mais oblig\u00e9s de continuer \u00e0 travailler ensemble. (En marge de ce dernier point, nous pr\u00e9ciserons que nous ne suivons pas Parris jusqu&rsquo;\u00e0 croire que Cameron et Clegg, m\u00eame avec Dieu en flanc-garde, vont se r\u00e9v\u00e9ler comme de superbes Gorbatchev \u00e0 la britannique pour foutre le syst\u00e8me cul par dessus t\u00eate. Nous ne leur faisons nul proc\u00e8s d&rsquo;intention mais nous savons tr\u00e8s bien ce qu&rsquo;un  homme politique peut faire et ce qu&rsquo;il ne peut pas faire tant qu&rsquo;il est dans les normes du syst\u00e8me, ce qui reste le cas de Cameron et de Clegg.)<\/p>\n<\/p>\n<p><p>\tCela est bien Le d\u00e9sordre, divin ou \u00e9lectoral, ou les deux ensemble, a bris\u00e9 la dictature du syst\u00e8me de la communication dans le syst\u00e8me britannique. La chose peut nous amener de plaisantes surprises et elle nous permet d&rsquo;\u00eatre <em>fair-play<\/em> et de proclamer : sacr\u00e9s Britanniques ! Il faut leur reconna\u00eetre qu&rsquo;ils s&rsquo;arrangent toujours pour \u00eatre le mod\u00e8le de quelque chose, y compris de l&rsquo;effondrement du syst\u00e8me qu&rsquo;ils ont tant et si longtemps aim\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 mai 2010 \u00e0 11H57<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre \u00e9poque en apparence compliqu\u00e9e, o\u00f9 l&rsquo;on vous dit que tout ne va pas si mal au milieu de la crise g\u00e9n\u00e9rale de l&rsquo;effondrement d&rsquo;une civilisation b\u00e2tie sur la puissance, une telle \u00e9poque ne peut \u00eatre chiche de paradoxes. En trouve-t-on un, assez int\u00e9ressant , du c\u00f4t\u00e9 du Royaume-Uni et de sa coalition Cameron-Clegg (ou&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5315,4060,9015,9479,5253,3015,2631,2825,6200,9016,2622,4907,3014],"class_list":["post-71871","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-cameron","tag-campbell","tag-chez","tag-clegg","tag-coalition","tag-communication","tag-de","tag-democratie","tag-discorde","tag-lennemi","tag-la","tag-parris","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71871"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71871\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}