{"id":71971,"date":"2010-06-17T08:57:41","date_gmt":"2010-06-17T08:57:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/17\/victimes-du-oil-spill-les-ecologistes-institutionnalises-serviteurs-du-systeme\/"},"modified":"2010-06-17T08:57:41","modified_gmt":"2010-06-17T08:57:41","slug":"victimes-du-oil-spill-les-ecologistes-institutionnalises-serviteurs-du-systeme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/17\/victimes-du-oil-spill-les-ecologistes-institutionnalises-serviteurs-du-systeme\/","title":{"rendered":"Victimes du \u201c<em>oil spill<\/em>\u201d : les \u00e9cologistes institutionnalis\u00e9s, serviteurs du syst\u00e8me"},"content":{"rendered":"<p><p>Un aspect remarquable de l&rsquo;actuelle crise du <em>oil spill<\/em> du Golfe du Mexique, c&rsquo;est le silence assourdissant des grandes organisations \u00e9cologistes et de d\u00e9fense de l&rsquo;environnement, US bien s\u00fbr et internationales \u00e0 dominante anglo-saxonne. On commence \u00e0 s&rsquo;int\u00e9resser \u00e0 la chose, dans une occurrence qui repr\u00e9sente une occasion si exceptionnelle pour la cause d\u00e9fendue par ces organisations. Un texte de <em>Politico.com<\/em>, reproduit le m\u00eame jour de sa mise en ligne, le <a href=\"http:\/\/www.commondreams.org\/print\/57201\" class=\"gen\">11 juin 2010<\/a> par <em>CommonDreams.org<\/em>, nous donne quelques explications \u00e9clairantes sur le ph\u00e9nom\u00e8ne.<\/p>\n<\/p>\n<p><p>\tCet \u00e9v\u00e9nement est int\u00e9ressant parce qu&rsquo;il a d&rsquo;abord le m\u00e9rite de compl\u00e9ter la mise au point g\u00e9n\u00e9rale qu&rsquo;il importe de faire sur la r\u00e9elle valeur des mouvements de contestation des ann\u00e9es 1960 culminant dans notre Mai sacro-saint. C&rsquo;est dans ce contexte que prit naissance cet aspect-l\u00e0 du mouvement \u00e9cologiste. On peut donc bien en juger aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>\tLe sympathique paradoxe de la chose, comme nous nous en expliquons dans notre commentaire, est que cette abstention ais\u00e9ment explicable de ces mouvements n&rsquo;est pas un mal. Au contraire, il conduit \u00e0 ass\u00e9ner des coups beaucoup plus rudes au syst\u00e8me qui a r\u00e9ussi \u00e0 phagocyter ce mouvement \u00e9cologiste-l\u00e0.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Last week, it seemed, environmentalists were finally ready to let loose on President Barack Obama over the Gulf oil spill. Actress Q&rsquo;orianka Kilcher chained herself to the White House fence while her mother slathered the Pocahontas star in black paint meant to look like oozing crude. Kilcher&rsquo;s cause? Not the Gulf spill at all but oil-related abuses of indigenous people in Peru, whose president was visiting Obama that day.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As the greatest environmental catastrophe in U.S. history has played out on Obama&rsquo;s watch, the environmental movement has essentially given him a pass  all but refusing to unleash any vocal criticism against the president even as the public has grown more frustrated by Obama&rsquo;s performance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>About a dozen environmental groups took out a full page ad in the Washington Post Tuesday  not to fault Obama over the ecological catastrophe but to thank him for putting on hold an Alaska drilling project. We deeply appreciate your decision. &#8230; the ad says to Obama.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>President Obama is the best environmental president we&rsquo;ve had since Teddy Roosevelt, Sierra Club chairman Carl Pope told the Bangor Daily News last week.  He obviously did not take the crisis in the Minerals Management Service adequately seriously, that&rsquo;s clear. But his agencies have done a phenomenally good job.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Some say there&rsquo;s little doubt that if a spill like the one in the Gulf took place on former President George W. Bush&rsquo;s watch, environmental groups would have unleashed an unsparing fury on the Republican in the White House. For their liberal ally, Obama, they seem willing to hold their tongues.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>These guys have bet the farm on this administration, said Ted Nordhaus, chairman of an environmental think tank, the Breakthrough Institute. There has been a real hesitancy to criticize this administration out of a sense that they&rsquo;re kind of the only game in town. &#8230; These guys are so beholden to this administration to move their agenda that I think they&rsquo;re unwilling to criticize them.<\/em> [ ]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>As the criticism of Obama ramped up in the media last month, some protesters did challenge his handling of the crisis  but they often came from groups not commonly associated with environmental causes. The Make Big Oil Pay signs outside a fundraiser Obama attended in San Francisco on May 25 were carried by a contingent from the socialist group ANSWER (Act Now to Stop War and End Racism), which is mounting a campaign to have the U.S. government seize BP&rsquo;s assets.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The national environmental organizations have become very establishment, very hierarchical and have close ties to decision makers. A lot of their influence is based on their reputations, their expertise and their ability to marshal mainstream members,<\/em>[<em> Matt Nisbet, a professor of environmental communications at American University<\/em>] <em>said. Groups outside the mainstream are benefitting<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn autre aspect de l&rsquo;abstention \u00e9l\u00e9gante des \u00e9colos est mis en \u00e9vidence dans le texte de F. William Engdahl du <a href=\"http:\/\/www.engdahl.oilgeopolitics.net\/print\/Gulf%20Oil%20Spill.pdf\" class=\"gen\">10 juin 2010<\/a>, dans sa partie intitul\u00e9e d&rsquo;une fa\u00e7on tr\u00e8s explicite \u00ab<em>Silence from Eco groups?&#8230; Follow the money<\/em>\u00bb. Les divers groupes \u00e9cologistes et personnalit\u00e9s dirigeantes re\u00e7oivent subsides et gratifications diverses de la part des grands groupes p\u00e9troliers, qui les assurent de leur int\u00e9r\u00eat pour leur combat. Nous sommes donc rassur\u00e9s, l&rsquo;ennemi est dans la place, et absolument \u00e0 son aise parce que si bien \u00e0 sa place<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Ce n&rsquo;est pas d&rsquo;aujourd&rsquo;hui qu&rsquo;on constate l&rsquo;\u00e9volution extr\u00eamement conformiste et le reclassement confortable de nos contestataires \u00e9cologistes des ann\u00e9es 1960. (Ils suivent en cela le parcours des contestataires et <em>leaders<\/em> de Mai [68] en France, dont Marcel Jouhandeau disait \u00e0 l&rsquo;\u00e9poque : \u00ab<em>Ils finiront tous notaires<\/em>\u00bb Disons qu&rsquo;ils ont trouv\u00e9 plus excitant et peut-\u00eatre mieux r\u00e9tribu\u00e9 que notaire, mais l&rsquo;esprit est l\u00e0 et bien l\u00e0, et il est inutile de s&rsquo;y attarder pour comprendre de quoi il s&rsquo;agit,  le passage \u00e0 la bourgeoisie du syst\u00e8me de puissance, le plus vil et le plus honteux dont la classe intellectuelle fran\u00e7aise, pourtant experte en la mati\u00e8re, ait jamais accouch\u00e9.) Les \u00e9colos les plus combatifs des ann\u00e9es 1960, n&rsquo;ont pas manqu\u00e9 \u00e0 la tradition. Les plus remarquables \u00e0 cet \u00e9gard sont les Allemands, avec le st\u00e9r\u00e9otype qu&rsquo;est Joska Fisher, contestataire devenu ministre des affaires \u00e9trang\u00e8res et sans doute l&rsquo;un des hommes politiques europ\u00e9ens qui restera comme le plus vil et le plus servile, jusqu&rsquo;\u00e0 la l\u00e2chet\u00e9 physique, vis-\u00e0-vis des USA. Il le montra sans ambages lors de la guerre du Kosovo, comme Hubert V\u00e9drines en fut le t\u00e9moin. Les Verts allemands sont aujourd&rsquo;hui de tr\u00e8s fid\u00e8les et z\u00e9l\u00e9s auxiliaires du capitalisme am\u00e9ricaniste globalis\u00e9 et de l&rsquo;hyper-lib\u00e9ralisme, avec des tendresses souvent touchantes pour le Pentagone. Le parcours est clair, et r\u00e9compens\u00e9 par une int\u00e9gration sans bavure dans le syst\u00e8me, avec tous les avantages syndicaux.<\/p>\n<\/p>\n<p><p>\tDans le cas qui nous occupe (le <em>oil spill<\/em>), l&rsquo;abstention des \u00e9cologistes institutionnalis\u00e9s et rachet\u00e9s \u00e0 un prix convenable par le syst\u00e8me a au moins deux avantages extr\u00eamement int\u00e9ressants.<\/p>\n<\/p>\n<p><p>\t Le premier est de casser les reins \u00e0 l&rsquo;argument habituel d&rsquo;une certaine (fausse) droite, jouant depuis des d\u00e9cennies les idiots utiles pour le capitalisme hyper-lib\u00e9ral et am\u00e9ricaniste qui charrie fondamentalement des valeurs d\u00e9structurantes de destruction permanente absolument oppos\u00e9es aux conceptions traditionnalistes et structurantes que cette m\u00eame droite pr\u00e9tend parfois d\u00e9fendre, quand elle retrouve, \u00e9pisodiquement, sa m\u00e9moire historique. Pour cette droite \u00e0 la m\u00e9moire courte, l&rsquo;\u00e9cologiste est un gauchiste, donc un diable aux oreilles pointues et \u00e0 la queue fourchue, donc un ennemi des valeurs structurantes qu&rsquo;elle croit d\u00e9fendre. L&rsquo;\u00e9tiquette de gauchiste est d&rsquo;une ambigu\u00eft\u00e9 profonde. Elle est compl\u00e8tement trompeuse dans le cas qui nous occupe mais renvoie \u00e0 une certaine r\u00e9alit\u00e9, compl\u00e8tement ignor\u00e9e par cette critique bien entendu, lorsqu&rsquo;elle aboutit \u00e0 l&rsquo;alliance entre la pouss\u00e9e d\u00e9structurante du d\u00e9sordre cr\u00e9ateur commun aussi bien \u00e0 la veine trotskiste (r\u00e9volution permanente) qu&rsquo;au capitalisme am\u00e9ricaniste hyper-lib\u00e9ral. Quoi qu&rsquo;il en soit, dans le cas qui nous occupe, la vision courte et na\u00efve du gauchisme attribu\u00e9e \u00e0 l&rsquo;\u00e9cologie, et qui discr\u00e9ditait la grande cause de la lutte contre la catastrophe environnementale en m\u00eame temps que lui, dispara\u00eet puisque l&rsquo;\u00e9cologie s&rsquo;est discr\u00e9dit\u00e9e elle-m\u00eame en int\u00e9grant les rangs de sa filiation naturelle qu&rsquo;est le capitalisme am\u00e9ricaniste hyper-lib\u00e9ral. Tous ces gens sont en fait le contraire de ce qu&rsquo;ils disent qu&rsquo;ils sont, et de ce qu&rsquo;on en a fait, puisque les \u00e9cologistes institutionnels type-1960 travaillent aujourd&rsquo;hui objectivement aux c\u00f4t\u00e9s de ceux qui d\u00e9truisent l&rsquo;environnement et les conditions d&rsquo;\u00e9quilibre du monde au nom du syst\u00e8me du technologisme. On est entre amis et en famille.<\/p>\n<\/p>\n<p><p>\t Le second avantage dans le cas du <em>oil spill<\/em> est que l&rsquo;absence de ces \u00e9cologistes pour cause de privil\u00e8ges \u00e0 prot\u00e9ger a permis \u00e0 une opposition multiforme, et non discr\u00e9dit\u00e9e par des slogans tels que gauchistes et compagnie, de se manifester avec une puissance inou\u00efe aux USA. Cette fois, c&rsquo;est tout le syst\u00e8me de la communication, dans sa position nouvelle et \u00e0 front renvers\u00e9 de critique automatique des effets du syst\u00e8me du technologisme, qui s&rsquo;est d\u00e9cha\u00een\u00e9e \u00e0 propos du <em>oil spill<\/em>. En ce sens, le silence des \u00e9cologistes pare le pr\u00e9sident Obama d&rsquo;un soutien et d&rsquo;une alliance qui ne lui font pas honneur, et qui pourraient lui co\u00fbter cher. Il est plus int\u00e9ressant aujourd&rsquo;hui d&rsquo;entendre un James Carville, ancien conseiller de Clinton, un Keith Olbermann, de MSNBC, et tant d&rsquo;autres animateurs de <em>talk shows<\/em>, journalistes, etc., qui font leur travail au nom du syst\u00e8me de la communication, en tirant \u00e0 boulets rouges contre les effets du <em>oil spill<\/em> et la d\u00e9vastation qui s&rsquo;ensuit. Ils d\u00e9douanent compl\u00e8tement la lutte contre la destruction de l&rsquo;environnement des lourdes consid\u00e9rations des id\u00e9ologues born\u00e9s et hyst\u00e9riques qui s&#8217;emploient depuis des d\u00e9cennies \u00e0 classer leurs adversaires selon les r\u00e9f\u00e9rences-bidon du si\u00e8cle des id\u00e9ologies, ce XX\u00e8me qui pourrait aussi bien \u00eatre nomm\u00e9 le si\u00e8cle des dupes que le si\u00e8cles des grands massacres de masse,  les deux allant d&rsquo;ailleurs de concert, dans une harmonie remarquable.<\/p>\n<\/p>\n<p><p>\tLorsque Nisbett, cit\u00e9 plus haut, dit : \u00ab<em>In some ways, the media coverage is doing a lot of the work for the environmental groups. They have a perfect narrative going right now. &#8230;The lower profile is working for them.<\/em>\u00bb, il pose un jugement juste en partie et sophistique pour l&rsquo;essentiel. Ce que le <em>media coverage<\/em> a fait comme travail, c&rsquo;est celui de groupes environnementaux qui n&rsquo;ont jamais exist\u00e9, en faveur de la v\u00e9ritable lutte contre la destruction de l&rsquo;environnement, et cela \u00e0 cause des automatismes du syst\u00e8me de la communication, simplement parce que la destruction du monde (ici, le cas du <em>oil spill<\/em>) est un spectacle sensationnel et r\u00e9pugnant \u00e0 la fois, qui ne peut pas ne pas \u00eatre exploit\u00e9 par ce syst\u00e8me de la communication. Mais le <em>media coverage<\/em> n&rsquo;a en aucune fa\u00e7on travaill\u00e9 pour eux (pour les \u00e9cologistes), puisque leur travail, aux \u00e9cologistes institutionnels, n&rsquo;a \u00e9t\u00e9 finalement que de s&rsquo;int\u00e9grer au syst\u00e8me en lui apportant la caution d&rsquo;une apparence d&rsquo;\u00e9cologie. Pour le reste, le <em>oil spill<\/em> et leur comportement les discr\u00e9ditent compl\u00e8tement et c&rsquo;est la meilleure nouvelle pour l&rsquo;\u00e9cologie qu&rsquo;on pouvait esp\u00e9rer.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 juin 2010 \u00e0 08H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un aspect remarquable de l&rsquo;actuelle crise du oil spill du Golfe du Mexique, c&rsquo;est le silence assourdissant des grandes organisations \u00e9cologistes et de d\u00e9fense de l&rsquo;environnement, US bien s\u00fbr et internationales \u00e0 dominante anglo-saxonne. On commence \u00e0 s&rsquo;int\u00e9resser \u00e0 la chose, dans une occurrence qui repr\u00e9sente une occasion si exceptionnelle pour la cause d\u00e9fendue par&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8697,3066,4363,3015,2631,3907,5725,2651,3577,4249,9687,4398,7428,9688,2622,3096,6888,9640,6258,3014,4268],"class_list":["post-71971","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-8697","tag-americaniste","tag-capitalisme","tag-communication","tag-de","tag-destructuration","tag-discredit","tag-du","tag-ecologie","tag-ecologistes","tag-environnementaux","tag-fisher","tag-gauchiste","tag-institutionnalises","tag-la","tag-mai","tag-oil","tag-spill","tag-structuration","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71971"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71971\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}