{"id":71979,"date":"2010-06-19T10:29:37","date_gmt":"2010-06-19T10:29:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/19\/mister-obamyde\/"},"modified":"2010-06-19T10:29:37","modified_gmt":"2010-06-19T10:29:37","slug":"mister-obamyde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/19\/mister-obamyde\/","title":{"rendered":"Mister Obamyde"},"content":{"rendered":"<p><h2 class=\"common-article2\">Mister Obamyde<\/h2>\n<\/p>\n<p><p>\tD\u00e9cid\u00e9ment Obama n&rsquo;a pas fini de d\u00e9cevoir.<\/p>\n<\/p>\n<p><p>\tLoin de diminuer l&rsquo;effort de guerre US, voil\u00e0 qu&rsquo;il l&rsquo;\u00e9tend dans un grand nombre de pays. L\u00e0 o\u00f9 l&rsquo;\u00e9quipe Bush s&rsquo;\u00e9tait content\u00e9e de 60 pays, l&rsquo;actuel pr\u00e9sident a accru le terrain de jeu de ses forces sp\u00e9ciales de 15 pays. <em>Voltairenet.org<\/em> (<a href=\"http:\/\/www.voltairenet.org\/article165698.html\" class=\"gen\">http:\/\/www.voltairenet.org\/article165698.html<\/a>) a relay\u00e9 un article du Washington Post datant du 4 juin.<\/p>\n<\/p>\n<p><p>\tSi la GWOR, m\u00e9diatis\u00e9e au possible, est finie, le combat continue :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Selon le Washington Post, la Maison-Blanche a r\u00e9serv\u00e9 9,8 milliards de dollars pour les Op\u00e9rations sp\u00e9ciales en 2011 (6,3 milliards imput\u00e9s sur le budget g\u00e9n\u00e9ral et 3,5 milliards de d\u00e9penses exceptionnelles).<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Pr\u00e9sentant son rapport annuel au Conseil des Droits de l&rsquo;homme des Nations Unies, le rapporteur sp\u00e9cial sur les ex\u00e9cutions extra-judiciaires a not\u00e9 la banalisation des assassinats par drones. Les Etats-Unis sont le principal Etat dans le monde \u00e0 pratiquer les ex\u00e9cutions extra-judiciaires. Elles sont peu m\u00e9diatis\u00e9es, hormis lorsque Washington se vante d&rsquo;avoir assassin\u00e9 sans jugement de pr\u00e9tendus chefs d&rsquo;Al-Qaida, car elles ont lieu dans des Etats du tiers-monde.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;article du Washington Post<\/p>\n<\/p>\n<p><p>\t(<a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/content\/article\/2010\/06\/03\/AR2010060304965.html?wprss=rss_world\/africa\" class=\"gen\">lien<\/a>) signale une \u00e9volution significative de l&rsquo;usage de ces forces sp\u00e9ciales.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bush-era clashes between the Defense and State departments over Special Operations deployments have all but ceased. Former d\u00e9fense secretary Donald H. Rumsfeld saw them as an independent force, approving in some countries Special Operations intelligence-gathering missions that were so secret that the U.S. ambassador was not told they were underway. But the close relationship between Defense Secretary Robert M. Gates and Secretary of State Hillary Rodham Clinton is said to have smoothed out the process.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In some places, we are quite obvious in our presence, Adm. Eric T. Olson, head of the Special Operations Command, said in a speech. In some places, in deference to host-country sensitivities, we are lower in profile. In every place, Special Operations forces activities are coordinated with the U.S. ambassador and are under the operational control of the four-star regional commander. [] Eighty percent of our investment is now in resolving current conflicts, not in building capabilities with partners to avoid future ones, one official said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;implication des ambassadeurs dans les op\u00e9rations des forces sp\u00e9ciales montre combien ceux-ci ont perdu une large part de leur influence sur le terrain. De plus le fait que 80% des fonds soient utilis\u00e9s pour les conflits en cours confirme qu&rsquo;il s&rsquo;agit d&rsquo;actions \u00e0 court terme et que les USA n&rsquo;ont d\u00e9sormais plus aucune vision \u00e0 moyen ou long terme.<\/p>\n<\/p>\n<p><p>\tM. Obama se garde bien de nous montrer cette face sombre de sa personnalit\u00e9. Mais il est fort \u00e0 parier que cet aspect sera prochainement r\u00e9v\u00e9l\u00e9, pr\u00e9cipitant un peu plus le syst\u00e8me vers sa fin.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>Bilbo<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mister Obamyde D\u00e9cid\u00e9ment Obama n&rsquo;a pas fini de d\u00e9cevoir. Loin de diminuer l&rsquo;effort de guerre US, voil\u00e0 qu&rsquo;il l&rsquo;\u00e9tend dans un grand nombre de pays. L\u00e0 o\u00f9 l&rsquo;\u00e9quipe Bush s&rsquo;\u00e9tait content\u00e9e de 60 pays, l&rsquo;actuel pr\u00e9sident a accru le terrain de jeu de ses forces sp\u00e9ciales de 15 pays. Voltairenet.org (http:\/\/www.voltairenet.org\/article165698.html) a relay\u00e9 un article&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[8842,3460,6208,4983],"class_list":["post-71979","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bilbo","tag-forces","tag-obama","tag-speciales"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71979"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71979\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}