{"id":71985,"date":"2010-06-21T05:59:56","date_gmt":"2010-06-21T05:59:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/21\/crise-multidimensionnelle-et-aux-perceptions-multiples\/"},"modified":"2010-06-21T05:59:56","modified_gmt":"2010-06-21T05:59:56","slug":"crise-multidimensionnelle-et-aux-perceptions-multiples","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/21\/crise-multidimensionnelle-et-aux-perceptions-multiples\/","title":{"rendered":"Crise multidimensionnelle et aux perceptions multiples"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Crise multidimensionnelle et aux perceptions multiples<\/h2>\n<\/p>\n<p><p>L&rsquo;\u00e9volution d&rsquo;une crise commenc\u00e9e assez discr\u00e8tement et transform\u00e9e en deux mois en un \u00e9v\u00e9nement fondamental par sa diversification et l&rsquo;action puissante du syst\u00e8me de la communication, voil\u00e0 le caract\u00e8re principal de la crise de l'\u00a0\u00bb<em>oil spill<\/em>\u00a0\u00bb dans le Golfe du Mexique. Les accusations d&rsquo;un candidat r\u00e9publicain de Caroline du Nord, Bill Randall, sur un \u00ab\u00a0complot\u00a0\u00bb BHO-BP (voir dans <em>Ouverture libre<\/em>, ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_crise_fleurit_voici_le_complot_bho-bp_21_06_2010.html?admin=1\">21 juin 2010<\/a>) font effectivement plus partie du domaine de la perception, de la communication, etc., que de la r\u00e9alit\u00e9 politique (quoi qu&rsquo;il en soit de cet int\u00e9ressant \u00ab\u00a0complot\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>L&rsquo;absence tr\u00e8s caract\u00e9ristique des grandes organisations \u00e9cologiques dans le d\u00e9bat sur cette crise, \u00e0 cause de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-victimes_du_oil_spill_les_ecologistes_institutionnalises_serviteurs_du_systeme_17_06_2010.html\">la corruption<\/a> syst\u00e9mique de notre \u00e9poque, a ouvert les vannes \u00e0 toute la puissance du syst\u00e8me de la communication. C&rsquo;est-\u00e0-dire que la crise, au lieu de rester dans les bornes de sa sp\u00e9cificit\u00e9 initiale (\u00e9cologie, environnement, exploitation des ressources \u00e9nerg\u00e9tiques) a pris des dimensions \u00e9piques, partant dans tous les sens et de tous les c\u00f4t\u00e9s, sans souci de la r\u00e9alit\u00e9 et de la justesse de l&rsquo;analyse, seulement avec la pr\u00e9occupation de l&rsquo;effet. L&rsquo;intervention de Randall est bien significative de cette situation, et elle est donn\u00e9e comme exemple \u00e9ventuellement folklorique plut\u00f4t que comme un \u00e9v\u00e9nement d&rsquo;importance. (En attendant, qui sait, que la chose soit exploit\u00e9e et document\u00e9e s\u00e9rieusement ?)<\/p>\n<\/p>\n<p><p>La crise est aujourd&rsquo;hui quasiment pr\u00e9sent\u00e9e comme \u00ab\u00a0la plus grande catastrophe\u00a0\u00bb environnementale qu&rsquo;aient connues les USA (et sans doute le reste du monde, par respect des pr\u00e9s\u00e9ances). C&rsquo;est l\u00e0 un ph\u00e9nom\u00e8ne de perception et le produit de l&rsquo;action du syst\u00e8me de la communication. Un article du New York <em>Times<\/em> du <a class=\"gen\" href=\"http:\/\/www.nytimes.com\/2010\/06\/19\/science\/earth\/19enviro.html?hp=&#038;pagewanted=print\">19 juin 2010<\/a> montre qu&rsquo;il y a eu, aux USA, des catastrophes pour l&rsquo;instant beaucoup plus importantes et plus graves que ce qui s&rsquo;est pass\u00e9 jusqu&rsquo;ici dans le Golfe du Mexique. Mais qu&rsquo;importe la r\u00e9alit\u00e9, &ndash; et nous faisons cette observation sans ironie aucune. La perception, aujourd&rsquo;hui, \u00e9crase tout le reste, notamment la soi-disant \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb, et cela \u00e0 cause du d\u00e9cha&icirc;nement du syst\u00e8me de la communication qui r\u00e9unit divers domaines, divers int\u00e9r\u00eats, divers projets, qui mobilise les psychologies, etc. (La situation politique aux USA, dans la perspective des \u00e9lections <em>mid-term<\/em>, n&rsquo;est pas le moindre de ces facteurs de diversification et d&rsquo;intensification dramatique de la crise. Elle implique les manoeuvres politique autant qu&rsquo;une angoisse psychologique fort honorable pour l&rsquo;\u00e9tat du syst\u00e8me.)<\/p>\n<\/p>\n<p><p>Nous faisons ces observations effectivement sans la moindre ironie. La \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb de situation, aujourd&rsquo;hui, n&rsquo;a qu&rsquo;une place limit\u00e9e dans une crise de cette ampleur, &ndash; telle ampleur, d&rsquo;ailleurs, parce que cette \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb ne fait pas le poids face aux perceptions et \u00e0 l&rsquo;action du syst\u00e8me de la communication, &ndash; chacun des caract\u00e8res de la situation pouvant \u00eatre indiff\u00e9remment et successivement cause et cons\u00e9quence dans l&rsquo;\u00e9volution de la situation. Ainsi appara&icirc;t la v\u00e9ritable r\u00e9alit\u00e9 de la crise, quelle que soit la \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb \u00e0 laquelle tiennent les esprits rigoureux et rationnels. C&rsquo;en est au point, sans aucun doute, o&ugrave; cette r\u00e9alit\u00e9 de la perception et de la communication devient la v\u00e9ritable r\u00e9alit\u00e9 sans qu&rsquo;il soit n\u00e9cessaire de d\u00e9plorer ce d\u00e9veloppement. Ce que montre la crise du \u00ab\u00a0<em>oil spill<\/em>\u00a0\u00bb ainsi transform\u00e9e par traitement du syst\u00e8me de la communication, c&rsquo;est finalement la situation bien <strong>r\u00e9elle<\/strong> de la crise g\u00e9n\u00e9rale du syst\u00e8me de l&rsquo;am\u00e9ricanisme et, notamment, le d\u00e9sordre extraordinaire qui caract\u00e9rise son fonctionnement \u00e0 la fois erratique et hyst\u00e9rique. Cette r\u00e9alit\u00e9 de la crise g\u00e9n\u00e9rale du syst\u00e8me de l&rsquo;am\u00e9ricanisme n&#8217;emp\u00eache nullement de mettre en \u00e9vidence les probl\u00e8mes inh\u00e9rents \u00e0 la \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb initiale, &ndash; \u00ab\u00a0\u00e9cologie, environnement, exploitation des ressources \u00e9nerg\u00e9tiques\u00a0\u00bb ; au contraire, elle le fait d&rsquo;une fa\u00e7on bien plus fondamentale, bien plus dramatique, \u00e0 la mesure de la gravit\u00e9 r\u00e9elle de ces diff\u00e9rents facteurs ; elle le fait d&rsquo;un point de vue politique encore plus qu&rsquo;\u00e9cologique et environnemental, et, par cons\u00e9quent, avec la potentialit\u00e9 d&rsquo;une mise en cause g\u00e9n\u00e9rale du syst\u00e8me.<\/p>\n<\/p>\n<p><p>La r\u00e9alit\u00e9 impos\u00e9e par le syst\u00e8me de la communication, qu&rsquo;on serait inclin\u00e9e \u00e0 discr\u00e9diter par esprit de s\u00e9rieux pour son caract\u00e8re artificiel et construit, ou par esprit d&rsquo;opposition au syst\u00e8me g\u00e9n\u00e9ral dont il est un des composants, s&rsquo;approche finalement beaucoup plus de la \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb de la crise g\u00e9n\u00e9rale de l&rsquo;am\u00e9ricanisme qu&rsquo;une \u00ab\u00a0r\u00e9alit\u00e9 objective\u00a0\u00bb initiale du \u00ab\u00a0<em>oil spill<\/em>\u00a0\u00bb maintenue comme facteur principal de la situation. (Cette remarque vaut d&rsquo;autant plus qu&rsquo;on devrait avoir appris, m\u00eame chez les esprits rigoureux et rationnels, \u00e0 se m\u00e9fier tout de m\u00eame, et fort s\u00e9rieusement, des \u00ab\u00a0r\u00e9alit\u00e9s objectives\u00a0\u00bb strictes, lorsqu&rsquo;on m\u00e9dite les exemples divers du pass\u00e9 concernant leurs manipulations diverses, leurs transformations, leurs \u00e9volutions.) Il y a donc un argument formidable qui est en train de se d\u00e9velopper concernant le r\u00f4le de plus en plus <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_dissolution_du_pouvoir_politique_ddecrisis_14_06_2010.html\">fratricide<\/a> du syst\u00e8me de la communication, qui est cens\u00e9 renforcer et soutenir l&rsquo;autre \u00e9l\u00e9ment clef du syst\u00e8me, qui est le syst\u00e8me du technologisme, et qui tient de plus en plus souvent le r\u00f4le inverse. Ce r\u00f4le \u00ab\u00a0fratricide\u00a0\u00bb du syst\u00e8me de la communication est la meilleure nouvelle qui pouvait se signaler \u00e0 ceux qui recherchent la mise en cause et la destruction du syst\u00e8me. Bien entendu, le fait que tout cela se d\u00e9roule aux USA, ce pays qui tient une partie importante de sa \u00ab\u00a0substance\u00a0\u00bb, d\u00e8s son origine, du syst\u00e8me de la communication, favorise encore plus le ph\u00e9nom\u00e8ne, le rend irr\u00e9sistible, d\u00e9vastateur, encore plus \u00ab\u00a0fratricide\u00a0\u00bb qu&rsquo;on ne pouvait l&rsquo;imaginer.<\/p>\n<\/p>\n<p><p>Mis en ligne le 21 juin 2010 \u00e0 06H02<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crise multidimensionnelle et aux perceptions multiples L&rsquo;\u00e9volution d&rsquo;une crise commenc\u00e9e assez discr\u00e8tement et transform\u00e9e en deux mois en un \u00e9v\u00e9nement fondamental par sa diversification et l&rsquo;action puissante du syst\u00e8me de la communication, voil\u00e0 le caract\u00e8re principal de la crise de l&rsquo;\u00a0\u00bboil spill\u00a0\u00bb dans le Golfe du Mexique. Les accusations d&rsquo;un candidat r\u00e9publicain de Caroline du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3015,9706,3858,3228,2631,2651,9704,7394,3723,2622,2943,9705,6888,5899,9640,3014,4268],"class_list":["post-71985","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-communication","tag-construite","tag-corruption","tag-crise","tag-de","tag-du","tag-fratricide","tag-generale","tag-golfe","tag-la","tag-mexique","tag-objective","tag-oil","tag-realite","tag-spill","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=71985"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/71985\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=71985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=71985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=71985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}