{"id":72025,"date":"2010-06-30T07:46:58","date_gmt":"2010-06-30T07:46:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/30\/obama-liran-et-la-fureur-bresilienne\/"},"modified":"2010-06-30T07:46:58","modified_gmt":"2010-06-30T07:46:58","slug":"obama-liran-et-la-fureur-bresilienne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/06\/30\/obama-liran-et-la-fureur-bresilienne\/","title":{"rendered":"Obama, l&rsquo;Iran et la fureur br\u00e9silienne"},"content":{"rendered":"<p><p>Nous avons obtenu quelques indications int\u00e9ressantes concernant l&rsquo;\u00e9tat d&rsquo;esprit au Br\u00e9sil par rapport \u00e0 certaines affaires en cours. La source consult\u00e9e est proche des milieux dirigeants br\u00e9siliens (Lula) et donne un \u00e9cho des appr\u00e9ciations g\u00e9n\u00e9rales qui y circulent, ainsi que du climat g\u00e9n\u00e9ral dans le pays,  dans ce cas, concernant le r\u00f4le des USA dans l&rsquo;affaire de l&rsquo;accord de T\u00e9h\u00e9ran du 17 mai, entre l&rsquo;Iran, le Br\u00e9sil et la Turquie.<\/p>\n<\/p>\n<p><p>\t La source confirme que c&rsquo;est avec le complet accord personnel, act\u00e9 et \u00e9crit du pr\u00e9sident US, par une lettre envoy\u00e9e par Obama \u00e0 Lula et dont le contenu a \u00e9t\u00e9 publi\u00e9 dans la presse br\u00e9silienne, que le pr\u00e9sident Lula a agi dans cette affaire. La documentation de la chose ayant \u00e9t\u00e9 ainsi expos\u00e9e en public, \u00ab<em>les dirigeants br\u00e9siliens, la classe politique, l&rsquo;opposition, les militaires, l&rsquo;opinion publique, tout le monde a \u00e9t\u00e9 stup\u00e9fait du comportement US imm\u00e9diatement apr\u00e8s l&rsquo;accord alors qu&rsquo;existait ce soutien, d&rsquo;une fa\u00e7on aussi formelle et aussi claire<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNotre source insiste sur le fait que \u00ab<em>m\u00eame la droite br\u00e9silienne d&rsquo;opposition, habituellement pro-am\u00e9ricaine, et les militaires<\/em>\u00bb, ont \u00e9prouv\u00e9 ce m\u00eame sentiment de stup\u00e9faction et cette sensation d&rsquo;avoir \u00e9t\u00e9 compl\u00e8tement trahi dans cette affaire. Elle insiste sur les effets absolument profonds de l&rsquo;attitude US, qui vont marquer d&rsquo;une fa\u00e7on effectivement durable l&rsquo;attitude br\u00e9silienne vis-\u00e0-vis des USA. \u00ab<em>Nous ne l&rsquo;oublierons pas, c&rsquo;est une certitude, et cela dans toutes les classes de l&rsquo;opinion et dans tous les domaines de la soci\u00e9t\u00e9 et de la classe politique.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur le fond, notre source exprime une incompr\u00e9hension g\u00e9n\u00e9rale de l&rsquo;attitude US, c&rsquo;est-\u00e0-dire le soutien explicite, actif, sinon l&rsquo;incitation d&rsquo;Obama \u00e0 agir avant l&rsquo;intervention de Lula et l&rsquo;accord de T\u00e9h\u00e9ran, suivis du l\u00e2chage presque instantan\u00e9 et de la condamnation de l&rsquo;accord apr\u00e8s que celui-ci ait \u00e9t\u00e9 sign\u00e9. L&rsquo;explication avanc\u00e9e, qui est du domaine de la sp\u00e9culation, rejoint notre propre conviction : \u00ab<em>On a finalement l&rsquo;impression d&rsquo;un immense d\u00e9sordre, d&rsquo;un d\u00e9sint\u00e9r\u00eat complet pour le suivi des choses, que la politique US se fait au jour le jour, selon les circonstances, selon les int\u00e9r\u00eats changeants<\/em>\u00bb Par cons\u00e9quent, le l\u00e2chage \u00e9tait simplement une obligation du jour, sans doute d&rsquo;Hillary Clinton devant le Congr\u00e8s, avec les habituelles pressions d&rsquo;Isra\u00ebl et de son lobby, voire pour pr\u00e9venir ces pressions, et avec en plus la m\u00e9canique de l&rsquo;\u00e9laboration des sanctions \u00e0 l&rsquo;ONU en cours. Il y a aussi, bien entendu, la r\u00e9action apr\u00e8s l&rsquo;accord, per\u00e7ue dans de nombreux commentaires US, que les USA ne pouvaient laisser d&rsquo;autres puissances diriger un \u00e9pisode d&rsquo;une affaire si importante,  r\u00e9action d&rsquo;autant plus remarquable dans son incons\u00e9quence qu&rsquo;Obama lui-m\u00eame avait primitivement incit\u00e9 le Br\u00e9sil \u00e0 agir. Qu&rsquo;importe le d\u00e9tail de l&rsquo;explication, l&rsquo;essentiel \u00e9tant bien l&rsquo;absence de suivi, l&rsquo;absence de contr\u00f4le, l&rsquo;\u00e9clatement et le d\u00e9sordre du pouvoir \u00e0 Washington, la conformation de la politique aux \u00e9v\u00e9nements et aux r\u00e9actions du jour.<\/p>\n<\/p>\n<p><p>\tNotre source estime que, dans l&rsquo;\u00e9tat actuel des choses, l&rsquo;accord de T\u00e9h\u00e9ran est mort apr\u00e8s tous les \u00e9v\u00e9nements qui ont suivi, aussi bien \u00e0 cause de consid\u00e9rations techniques (n\u00e9cessit\u00e9 de la coop\u00e9ration technique d&rsquo;autres pays engag\u00e9s dans la d\u00e9cision des sanctions) qu&rsquo;\u00e0 cause de l&rsquo;attitude des Iraniens apr\u00e8s le vote des sanctions \u00e0 l&rsquo;ONU.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 juin 2010 \u00e0 07H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons obtenu quelques indications int\u00e9ressantes concernant l&rsquo;\u00e9tat d&rsquo;esprit au Br\u00e9sil par rapport \u00e0 certaines affaires en cours. La source consult\u00e9e est proche des milieux dirigeants br\u00e9siliens (Lula) et donne un \u00e9cho des appr\u00e9ciations g\u00e9n\u00e9rales qui y circulent, ainsi que du climat g\u00e9n\u00e9ral dans le pays, dans ce cas, concernant le r\u00f4le des USA dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[9764,3677,2631,3356,6700,2773,3822,3676,6208,3769,5201,3248],"class_list":["post-72025","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-acccord","tag-bresil","tag-de","tag-desordre","tag-fureur","tag-iran","tag-lettre","tag-lula","tag-obama","tag-pouvoir","tag-teheran","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72025"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72025\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}