{"id":72067,"date":"2010-07-09T13:12:15","date_gmt":"2010-07-09T13:12:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/09\/dialogues-9-a-propos-de-lintelligence-geopoetique-ii\/"},"modified":"2010-07-09T13:12:15","modified_gmt":"2010-07-09T13:12:15","slug":"dialogues-9-a-propos-de-lintelligence-geopoetique-ii","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/09\/dialogues-9-a-propos-de-lintelligence-geopoetique-ii\/","title":{"rendered":"<em>DIALOGUES<\/em>-9 : \u00e0 propos de l&rsquo;intelligence g\u00e9opo\u00e9tique II"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-9 : \u00e0 propos de l&rsquo;intelligence g\u00e9opo\u00e9tique II<\/h2>\n<\/p>\n<p><p>\tJe lis et relis votre texte \u00ab<em>Il y a myst\u00e8re et Myst\u00e8re<\/em>\u00bb (<em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-il_y_a_mystere_et_mystere_01_07_2010.html\" class=\"gen\">1er juillet 2010<\/a>), lui-m\u00eame provoqu\u00e9 par quelques \u00e9changes avec vos lecteurs au sujet d&rsquo;un pr\u00e9c\u00e9dent <em>F&#038;C<\/em> (\u00ab<em>L&rsquo;ent\u00eatement afghan et notre structure crisique<\/em>\u00bb, <a href=\"http:\/\/www.dedefensa.org\/article-l_entetement_afghan_et_notre_structure_crisique_29_06_2010.html\" class=\"gen\">29 juin 2010<\/a>). Rarement, ce me semble, vous avez \u00e9t\u00e9 aussi clair ou p\u00e9remptoire dans votre exigence m\u00e9thodologique.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Nous plaidons d\u00e9sormais pour que cette sorte d&rsquo;observation entre dans la r\u00e9flexion rationnelle,  non pas r\u00e9flexion emprisonn\u00e9e \u00e0 la raison mais r\u00e9flexion utilisant<\/em> <strong><em>notamment<\/em><\/strong> <em>la raison comme outil pour se d\u00e9velopper, \u00e0 c\u00f4t\u00e9 d&rsquo;autres outils, comme l&rsquo;intuition, la conviction, etc. C&rsquo;est-\u00e0-dire que nous plaidons pour que la r\u00e9flexion rationnelle entre, comme un \u00e9l\u00e9ment parmi d&rsquo;autres, dans le domaine du supra-rationnel sans verser dans la m\u00e9thodologie imp\u00e9rative et int\u00e9griste de l&rsquo;id\u00e9ologie, de la croyance, de la foi, etc., m\u00eame si l&rsquo;acteur de cette r\u00e9flexion peut sacrifier \u00e0 ceci ou \u00e0 cela, \u00e0 c\u00f4t\u00e9 de cette r\u00e9flexion contr\u00f4l\u00e9e. La r\u00e9flexion rationnelle doit devenir une r\u00e9flexion supra-rationnelle<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCela fait longtemps que je cherche quelque chose de ce genre, tant\u00f4t confus\u00e9ment, tant\u00f4t plus clairement, sans n&rsquo;avoir jamais aussi bien pu le formuler que vous ne le f\u00eetes ici.<\/p>\n<\/p>\n<p><p>\t(N.B. Plut\u00f4t que supra-rationnelle, oserais-je sugg\u00e9rer trans-rationnel, dans le sens de comprenant le rationnel, mais l&rsquo;en de\u00e7\u00e0 aussi, l&rsquo;\u00e0-c\u00f4t\u00e9, et les autres choses englobantes \u00e9galement). <\/p>\n<\/p>\n<p><p>\tAu cours de mes p\u00e9r\u00e9grinations, j&rsquo;ai cependant trouv\u00e9 deux r\u00e9flexions, deux types, deux penseurs actuels \u00ab<em>qui utilisent la raison comme outil pour se d\u00e9velopper, \u00e0 c\u00f4t\u00e9 d&rsquo;autres outils comme l&rsquo;intuition, la conviction, etc.<\/em>\u00bb. Et qui partent r\u00e9solument de l&rsquo;h\u00e9ritage culturel europ\u00e9en qu&rsquo;ils connaissent pour s&rsquo;ouvrir au plus vaste qu&rsquo;ils d\u00e9couvrent. Les deux sont des po\u00e8tes \u00e0 la limite du terme, c&rsquo;est-\u00e0-dire dans le sens original, haut et fort et non restrictif du terme : Kenneth White et Henri Meschonnic. <\/p>\n<\/p>\n<p><p>\tJe transcris ci-apr\u00e8s une partie d&rsquo;une vid\u00e9o o\u00f9 Kenneth White (de langue maternelle anglaise), interrog\u00e9 par Bernard Pivot (\u00e9mission <em>Double Je<\/em> datant de 2006), r\u00e9sume une de ses pens\u00e9es qui rejoint, me semble-t-il, ce supra-rationnel \/transrationnel pour lequel vous plaidez (et moi avec vous) (<a href=\"http:\/\/www.dailymotion.com\/video\/x11l9c_kenneth-white-double-je-2-2-b-pivot_music\" class=\"gen\">lien<\/a>) : <\/p>\n<\/p>\n<p><p>\tBernard Pivot : \u00ab<em>On vous doit la cr\u00e9ation d&rsquo;un mot, qui rassemble toute une philosophie, une mani\u00e8re de penser, c&rsquo;est le mot g\u00e9opo\u00e9tique. Je voudrais que vous expliquiez rapidement.<\/em><\/p>\n<\/p>\n<p><p>\tKW : \u00ab<em>On parlait tout \u00e0 l&rsquo;heure de culture. Je crois que la culture a \u00e9t\u00e9 port\u00e9e par plusieurs choses, beaucoup de choses, \u00e0 travers les si\u00e8cles et les mill\u00e9naires. Elle a \u00e9t\u00e9 port\u00e9e par exemple par le mythe, par la religion, par la m\u00e9taphysique, et \u00e0 la fin par l&rsquo;Histoire. Tout \u00e7a ne marche plus aujourd&rsquo;hui. \u00c0 la limite aujourd&rsquo;hui on pourrait dire que la culture n&rsquo;est plus port\u00e9e par rien. On a une production culturelle, et il n&rsquo;y a jamais eu autant, mais en poussant les choses un petit peu on pourrait dire que c&rsquo;est une production culturelle sans culture. Sauf exception. Alors je me suis dit : est-ce qu&rsquo;il y a quelque chose sur lequel on peut \u00eatre d&rsquo;accord, dans le monde entier  parce que je crois qu&rsquo;il faut quand m\u00eame penser en terme de monde entier , au-del\u00e0 des religions, au-del\u00e0 des id\u00e9ologies identitaires qui commencent \u00e0 s\u00e9vir justement dans l&rsquo;absence d&rsquo;une fondation de culture<\/em> []<em>, est-ce qu&rsquo;il y a quelque chose sur lequel on puisse \u00eatre d&rsquo;accord. Je me suis dit : pourquoi pas la Terre m\u00eame, sur laquelle on essaye de vivre. D&rsquo;o\u00f9 le \u00ab g\u00e9o \u00bb de g\u00e9opo\u00e9tique.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Et puis si on fait l&rsquo;histoire des cultures du monde, on se rend compte qu&rsquo;il y a toujours une po\u00e9tique au centre. La culture grecque n&rsquo;existerait pas, bien s\u00fbr sans la politique : ce sont les Grecs qui inventent la politique ; mais elle n&rsquo;existerait pas sans Hom\u00e8re, sans la po\u00e9tique oc\u00e9anique d&rsquo;Hom\u00e8re. La politique se dess\u00e9cherait s&rsquo;il n&rsquo;y avait pas la po\u00e9tique d&rsquo;Hom\u00e8re.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAilleurs (<a href=\"\/(http:\/\/www.dailymotion.com\/video\/x1gyon_kenneth-white_travel\" class=\"gen\">lien<\/a>), K.W. pr\u00e9cise : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>En Gr\u00e8ce, les Grecs inventent la politique, mais la politique se dess\u00e9cherait, deviendrait de la politicaillerie, s&rsquo;il n&rsquo;y avait pas la po\u00e9tique d&rsquo;Hom\u00e8re, qui est oc\u00e9anique,<\/em> <strong><em>qui irrigue le terrain de la politique<\/em><\/strong>. <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Je remonte jusqu&rsquo;\u00e0 Aristote, qui utilise l&rsquo;expression no\u00fbs poi\u00eatikos, l&rsquo;intelligence po\u00e9tique : c&rsquo;est l&rsquo;intelligence fondamentale, c&rsquo;est l&rsquo;intelligence vraiment premi\u00e8re. C&rsquo;est dans ce sens-l\u00e0 que j&rsquo;utilise ce mot de po\u00e9tique, et cette intelligence po\u00e9tique peut s&rsquo;appliquer \u00e0 tous les domaines, \u00e0 la pens\u00e9e, \u00e0 la prose \u00e9videmment,<\/em> [aux] <em>essais aussi,<\/em> [] <em>\u00e0 tous les domaines : \u00e0 la litt\u00e9rature, \u00e0 la philosophie et, qui sait, peut-\u00eatre demain ou apr\u00e8s-demain, \u00e0 la politique. <\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAutrement dit : pas de culture, pas de politique, pas de domaine de la pens\u00e9e, sans une po\u00e9tique pr\u00e9alable, qui est pens\u00e9e qui saisit les choses \u00e0 la base, par leurs d\u00e9buts, qui a une dynamique, une force de parole, d&rsquo;\u00e9coute, de marche, de pr\u00e9sence, d&rsquo;attention. <\/p>\n<h3>Proposition<\/h3>\n<\/p>\n<p><p>\tCette intelligence po\u00e9tique, en tant qu&rsquo;il me semble parfois l&rsquo;effleurer (pas par go\u00fbt ou don quelconque, loin de l\u00e0 ! mais par accident, par n\u00e9cessit\u00e9 post-traumatique, pour faire vite), c&rsquo;est un m\u00e9lange de m\u00e9ditation, de pierre d&rsquo;achoppement, de corporalit\u00e9 active et \u00e9veill\u00e9e, de pens\u00e9e libre et vivante, de culture, de contact avec la vie, d&rsquo;\u00e9coute des choses du monde  \u00e0 commencer par celle qui sont sous notre nez, l\u00e0, maintenant , de travail et de densification. <\/p>\n<\/p>\n<p><p>\tHenri Meschonnic, dans sa proposition d&rsquo;une nouvelle th\u00e9orie critique du langage prenant en compte ce que fait la po\u00e9sie (<em>La rime et la vie<\/em>, 2006, Gallimard), permet de pr\u00e9ciser le sujet po\u00e9tique et donc cette dimension, oubli\u00e9e elle aussi, de la vie humaine. J&rsquo;interpr\u00e8te tr\u00e8s librement ce qu&rsquo;il dit (pp. 430-431) : le sujet po\u00e9tique, l&rsquo;homme, la femme, la personne en ce qu&rsquo;elle est parlante, \u00ab<em>n&rsquo;est pas le sujet psychologique ou le sujet philosophique qui sait ce qu&rsquo;il fait et donc fait ce qu&rsquo;il sait<\/em>\u00bb ; vivre, en tant que sujet po\u00e9tique, <strong>ce n&rsquo;est pas<\/strong> faire ce qu&rsquo;on sait faire ; vivre, c&rsquo;est faire ce qu&rsquo;on ne sait pas faire, et donc ainsi sentir et vivre la rugosit\u00e9 du vivant, engendrer des rencontres, des actes inattendus, du mouvement, cr\u00e9er et faire vivre des relations qui nous augmentent, nous rendent auteurs, vivre et cr\u00e9er des histoires, etc.<\/p>\n<\/p>\n<p><p>\tL&rsquo;intelligence po\u00e9tique de K.W. devient ainsi l&rsquo;intelligence fondamentale qu&rsquo;on utilise quand on vit, quand on se fait sujet po\u00e9tique, parlant, pr\u00e9sent, vivant ; c&rsquo;est l&rsquo;intelligence attentive, ouverte \u00e0 l&rsquo;inconnu, \u00e0 l&rsquo;inattendu, au non donn\u00e9 d&rsquo;avance, \u00e0 l&rsquo;intempestif ; c&rsquo;est l&rsquo;intelligence premi\u00e8re de la vie en tant qu&rsquo;elle (la vie) est inattendue, ouverte, non donn\u00e9e, oc\u00e9anique, qui (l&rsquo;intelligence) se densifie et se fait auteur (agrandit), et qui irrigue <strong>ensuite<\/strong> le reste des terrains la pens\u00e9e (politique, philosophique, scientifique, \u00e9conomique, etc., etc.) et de la culture. <\/p>\n<\/p>\n<p><p>\tLe caract\u00e8re ouvert de cette pens\u00e9e, caract\u00e9ristique fondamentale d&rsquo;une pens\u00e9e vivante, lui permet, outre de naviguer sur le caract\u00e8re eschatologique de notre temps de crises (eschatologique comme ouvert sur un avenir impr\u00e9dictible, comme l&rsquo;entend l&rsquo;auteur de ce site), d&rsquo;\u00e9viter de \u00ab<em>verser dans la m\u00e9thodologie imp\u00e9rative et int\u00e9griste de l&rsquo;id\u00e9ologie, de la croyance, de la foi, etc.<\/em>\u00bb, et d&rsquo;\u00eatre \u00e0 l&rsquo;\u00e9coute des \u00e9l\u00e9ments de cette po\u00e9tique forte pour la culture d&rsquo;apr\u00e8s le Moderne.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est une mani\u00e8re, pour la raison, de se reconna\u00eetre limit\u00e9e, ne serait-ce que pour exprimer, par exemple, le savoir-faire, les pratiques, la culture et la fa\u00e7on d&rsquo;habiter des saigneurs de la for\u00eat de la Lande (Michel Serres a une jolie chronique l\u00e0-dessus [<a href=\"http:\/\/www.france-info.com\/chroniques-le-sens-de-l-info-2009-03-01-la-foret-des-landes-255228-81-173.html\" class=\"gen\">lien<\/a>]), des mariniers de la Garonne, des p\u00eacheurs de Louisiane ou des paysans du Pays d&rsquo;En haut  toutes choses qui pr\u00e9cis\u00e9ment se vivent, s&rsquo;exp\u00e9rimentent, s&rsquo;apprennent, se transmettent, mais ne se rationalisent pas et ne se rationaliseront jamais, parce qu&rsquo;il s&rsquo;agit de vie, de vivants, de mani\u00e8re qu&rsquo;ont ces vivants d&rsquo;habiter et de vivre leur lieux et de faire sens. C&rsquo;est une raison qui se reconna\u00eet elle-m\u00eame en tant que ph\u00e9nom\u00e8ne vivant (une raison postnietzsch\u00e9enne qui sait que c&rsquo;est le corps qui parle), une raison qui sait qu&rsquo;elle peut produire un syst\u00e8me d&rsquo;une puissance mat\u00e9rielle \u00e9tonnante, convoquer, gr\u00e2ce \u00e0 ses ing\u00e9nieuses d\u00e9marches r\u00e9ductionnistes ou statistiques, des forces d&rsquo;une puissance redoutable (de quoi aller sur la Lune ou cr\u00e9er de petits soleils sur la Terre), mais qui sait que le r\u00e9el est fondamentalement et intrins\u00e8quement irr\u00e9ductible (\u00e0 sa d\u00e9marche). Une raison qui comprend qu&rsquo;elle se dess\u00e8che et meurt si elle ne s&rsquo;appuie pas sur une culture, une po\u00e9tique. Une raison qui n&rsquo;a pas peur de se reconna\u00eetre irrigu\u00e9e par une po\u00e9tique de la Terre, l&rsquo;\u00e9coute du monde et des choses  vivantes et dites inertes  , o\u00f9 chacun a sa parole, du Gulf Stream aux subtiles couches d&rsquo;argiles et de silts du Golfe du Mexique ; des bayous aux m\u00e9langes de gaz, d&rsquo;huile et d&rsquo;eau sous pression qui se faufilent dans le d\u00e9licat labyrinthe des structures g\u00e9ologiques. Ce que le p\u00eacheur local comme le g\u00e9ologue de base entend, respectivement, malgr\u00e9 son inscription dans une globalisation furieuse ou sa formation scientifique, simplement parce qu&rsquo;ils ne se r\u00e9duisent pas \u00e0 cela (ce qui permet par exemple au g\u00e9ologue cit\u00e9 par Naomi Klein, Jill Schneiderman, de parler de Puits de Pandore, <em>Pandora&rsquo;s well<\/em>). Ce que Tony Hayward n&rsquo;entends plus  ce que ne peuvent plus entendre les gens haut plac\u00e9s, isol\u00e9s : le syst\u00e8me l&rsquo;interdit (voyez cette photo \u00e9tonnement parlante du pauvre chef ex\u00e9cutif de BP [<a href=\"http:\/\/www.nytimes.com\/interactive\/2010\/05\/27\/us\/201005_oil-spill-photo-gallery.html\" class=\"gen\">lien<\/a>], photo num\u00e9ro 103, semaine du 2 au 8 mai accessible depuis l&rsquo;index).<\/p>\n<\/p>\n<p><p>\tUne \u00e9coute (g\u00e9o)po\u00e9tique qui peut par contre permettre, soutenir, rendre compte, \u00e9tayer ce que vous appelez cette \u00ab<em>id\u00e9e finalement supra-rationnelle de la participation de la nature du monde dans l&rsquo;affrontement G4G<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tCette relation dynamique entre intelligence po\u00e9tique et analyse rationnelle dont parle White, c&rsquo;est, me semble-t-il et comme vous nous en avez si bien fait part, ce qu&rsquo;a mis en place Naomi Klein (bien qu&rsquo;elle parle modestement de <em>feeling<\/em>) : entendre une po\u00e9tique (en l&rsquo;occurrence celle des U&rsquo;wa des for\u00eats de Colombie), qui vient soudain irriguer, porter, placer son analyse rationnelle, \u00e9conomique, dans un cadre plus vaste, plus \u00e9lev\u00e9, plus vivant.<\/p>\n<\/p>\n<p><p>\tCette relation dynamique entre intelligence po\u00e9tique et analyse rationnelle c&rsquo;est, mais ce n&rsquo;est qu&rsquo;une proposition de ma part, dans laquelle il ne se reconna\u00eetra peut \u00eatre pas mais qui ressemble tellement \u00e0 ce qui est d\u00e9crit chez Naomi Klein, c&rsquo;est ce que Philippe Grasset fait : une analyse, un travail journalistique et une chronique conduite par une raison fine, mais irrigu\u00e9e, nourrie par une intelligence po\u00e9tique certaine (dont le fonctionnement est quasi totalement et si talentueusement d\u00e9crit, dans tous ses multiples dimensions et cheminements, dans <em>Les \u00c2mes de Verdun<\/em>  bien qu&rsquo;il y emploie (trop ?) modestement le mot d&rsquo;intuition). Cette intelligence po\u00e9tique du monstre anthropocentrique dans son entier, dans ses origines, dans les mille tourbillons chaotiques qui lui tiennent lieu de dynamique, et pour lequel il a d\u00e9velopp\u00e9 une oreille aff\u00fbt\u00e9e \u00e0 nulle autre pareille. Cette intelligence po\u00e9tique qui lui permet de traverser quotidiennement les terres d\u00e9vast\u00e9es et carbonis\u00e9es de notre civilisation en train de s&rsquo;effondrer et de revenir nous le chanter (entend-il quelque chose d&rsquo;autre, par del\u00e0, qui lui donne chaque jour la force ?)  du moins me plais-je \u00e0 l&rsquo;imaginer ainsi.<\/p>\n<\/p>\n<p><p>\tBien s\u00fbr, l\u00e0 o\u00f9 Naomi Klein cite d\u00e9j\u00e0 quelques possibles \u00e9l\u00e9ments de cette po\u00e9tique forte que White accumule pour nourrir une culture nouvelle, M. Grasset est lui dans la critique active du temps imm\u00e9diat. Ce qui lui permet par contre de donner toute leur ampleur et leur vie \u00e0 ces concepts (deuxi\u00e8me civilisation occidentale, parenth\u00e8se monstrueuse, monstre bas\u00e9 sur ses deux mamelles : syst\u00e8mes de la communication et du technologisme, etc. etc.) qui, outre de clarifier, fortifier et mettre des paroles sur notre r\u00e9sistance, feront assur\u00e9ment partie des \u00e9l\u00e9ments retenus pour raconter cela \u00e0 nos enfants et petits-enfants.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Christian Steiner<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tP.S. J&rsquo;ai \u00e9crit ce texte parce que je suis tomb\u00e9 par hasard sur des vid\u00e9os d&rsquo;interview de Kenneth White, et que je les ai mises en relations avec des exp\u00e9riences r\u00e9centes (trop r\u00e9cente ? d&rsquo;o\u00f9 peut \u00eatre un texte encore quelque peu fi\u00e9vreux et pris dans sa gangue).<\/p>\n<\/p>\n<p><p>\tJe ne peux que renvoyer le lecteur \u00e9ventuellement int\u00e9ress\u00e9 aux textes de K.W. lui-m\u00eame, par exemple \u00e0 cette br\u00e8ve introduction \u00e9crite en 1994, intitul\u00e9e \u00ab<em>Consid\u00e9rations premi\u00e8res<\/em>\u00bb, et notamment aux deux premiers paragraphes, \u00ab<em>A propos de la culture<\/em>\u00bb et \u00ab<em>Que faut-il entendre par po\u00e9tique<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tLe tout est accessible en ligne \u00e0 ce <a href=\"http:\/\/www.geopoetique.net\/archipel_fr\/institut\/introgeopoetique\/index.html\" class=\"gen\">lien<\/a>.<\/p>\n<\/p>\n<p><p>\tPropos plus d&rsquo;actualit\u00e9 que jamais. J&rsquo;en citerai cet extrait, qui est loin d&rsquo;\u00eatre le fond du propos de l&rsquo;auteur, juste pour l&rsquo;anecdote et le sourire (\u00e0 moins que ce ne soit pour le trouble de la fulgurance du r\u00e9sum\u00e9 de ces 16 derni\u00e8res ann\u00e9es) :<\/p>\n<\/p>\n<p><p>\t\u00ab<D>Assur\u00e9ment, l&rsquo;autoroute<D> [de l&rsquo;Occident]<em>, telle que je la vois, ne m\u00e8ne nulle part, sinon \u00e0 des platitudes de plus en plus plates entrecoup\u00e9es d&rsquo;un d\u00e9sastre ici et l\u00e0 (un Tchernobyl \u00e0 gauche, une mar\u00e9e noire \u00e0 droite) le tout enrob\u00e9 dans une esp\u00e8ce de brouhaha quotidien pour faire croire que quelque chose se passe quelque part.<\/em><\/p>\n<\/p>\n<p><\/p>\n<h4>Note importante<\/h4>\n<p>Pour nos lecteurs, ceci. Ce texte est publi\u00e9 \u00e0 la fois dans Ouverture libre et dans la rubrique d&rsquo;archivage <em>DIALOGUES<\/em>. Si vous voulez mettre un commentaire, choisissez plut\u00f4t le <em>Forum<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-9_de_l_intelligence_geopoetique_ii_09_07_2010.html\" class=\"gen\">texte<\/a> de la rubrique <em>DIALOGUES<\/em>. Merci.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-9 : \u00e0 propos de l&rsquo;intelligence g\u00e9opo\u00e9tique II Je lis et relis votre texte \u00abIl y a myst\u00e8re et Myst\u00e8re\u00bb (F&#038;C du 1er juillet 2010), lui-m\u00eame provoqu\u00e9 par quelques \u00e9changes avec vos lecteurs au sujet d&rsquo;un pr\u00e9c\u00e9dent F&#038;C (\u00abL&rsquo;ent\u00eatement afghan et notre structure crisique\u00bb, 29 juin 2010). Rarement, ce me semble, vous avez \u00e9t\u00e9 aussi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9821,9822,5535,3177,7872,9707],"class_list":["post-72067","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-geopetique-ii","tag-mesconic","tag-raison","tag-sacre","tag-steiner","tag-white"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72067"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72067\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}