{"id":72077,"date":"2010-07-13T04:58:31","date_gmt":"2010-07-13T04:58:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/13\/bon-anniversaire-ddecrisis\/"},"modified":"2010-07-13T04:58:31","modified_gmt":"2010-07-13T04:58:31","slug":"bon-anniversaire-ddecrisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/13\/bon-anniversaire-ddecrisis\/","title":{"rendered":"\u201cBon anniversaire, <em>dde.crisis<\/em>\u201d"},"content":{"rendered":"<p><p>Ci-dessous, nous publions l&rsquo;\u00e9ditorial du dernier num\u00e9ro du premier volume (premi\u00e8re ann\u00e9e) de parution de <em>dde.crisis<\/em>. C&rsquo;est le 10 septembre 2009 qu&rsquo;a paru le premier num\u00e9ro de la version en ligne de <em>dde.crisis<\/em>, qui prenait la succession de la Lettre d&rsquo;Analyse <em>de defensa &#038; eurostrat\u00e9gie<\/em> (publi\u00e9 en version classique, en papier v\u00e9n\u00e9rable). Ce num\u00e9ro du <a href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_juillet_2010.html\" class=\"gen\">10 juillet 2010<\/a> \u00e9tant le dernier (num\u00e9ro 20) de la premi\u00e8re ann\u00e9e de parution de <em>dde.crisis<\/em> , la publication repara\u00eetra \u00e0 partir du 10 septembre 2010.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9ditorial marque cet \u00e9v\u00e9nement et tente d&rsquo;en tirer quelques enseignements. <\/p>\n<h3>\u00ab<strong><em>Bon anniversaire, dde.crisis<\/em><\/strong><\/h3>\n<\/p>\n<p><p>\t\u00bb<em>Il y a un an, paraissait le dernier num\u00e9ro (\u00e9dition papier) de la Lettre d&rsquo;Analyse de defensa &#038; eurostrat\u00e9gie (dd&#038;e). L&rsquo;\u00e9motion n&rsquo;\u00e9tait pas absente, pour nous, apr\u00e8s largement plus d&rsquo;un quart de si\u00e8cle de publication. Mais l&rsquo;\u00e9motion ne doit rien c\u00e9der \u00e0 la volont\u00e9 de poursuivre, jusqu&rsquo;o\u00f9 nos pas nous portent&#8230; Pour cette raison notamment,  il y en a d&rsquo;autres, \u00e9videmment,  dde.crisis, en parution en ligne, prit le relais.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Aujourd&rsquo;hui se termine la premi\u00e8re ann\u00e9e de parution de dde.crisis (interruption jusqu&rsquo;au 10 septembre 2010, selon notre formule classique.) Bon anniversaire par anticipation logique, dde.crisis !<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>L&rsquo;occasion invite n\u00e9cessairement \u00e0 la r\u00e9flexion. Il s&rsquo;agit de consid\u00e9rer dans quelle mesure la reconversion est r\u00e9ussie, cela sur le cas bien particulier du changement th\u00e9matique que cette publication a subi. S&rsquo;il y avait des n\u00e9cessit\u00e9s pratiques, concr\u00e8tes, voire \u00e9conomiques au d\u00e9part pour ce changement, nous avons profit\u00e9 de ces circonstances plut\u00f4t peu encourageantes (il n&rsquo;est jamais tr\u00e8s bon signe de devoir faire des \u00e9conomies) pour tenter de faire d&rsquo;un mal un bien&#8230; En changeant le titre de la publication, de dd&#038;e en dde.crisis, nous n&rsquo;avons pas seulement marqu\u00e9 le changement de formule. Nous avons r\u00e9ellement effectu\u00e9 un changement th\u00e9matique important.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Les mots importants, lorsqu&rsquo;on les d\u00e9termine \u00e0 partir d&rsquo;une pens\u00e9e embryonnaire, donnent en retour, une fois formul\u00e9s, une impulsion nouvelle pour que cette pens\u00e9e embryonnaire se d\u00e9veloppe et tienne des promesses auxquelles on n&rsquo;avait pas pr\u00eat\u00e9 garde initialement. Ce fut le cas pour crisis, qui signifie crise en anglais mais aussi en latin (et c&rsquo;est cette derni\u00e8re traduction que nous retenons). Une fois choisi, le titre nous a restitu\u00e9 une impulsion nouvelle pour la recherche de th\u00e8mes, pour leur d\u00e9veloppement, etc. Au lieu de penser (!) le monde en termes de relations internationales classiques, d&rsquo;attitudes et d&rsquo;\u00e9v\u00e9nements divers, nous l&rsquo;avons pens\u00e9 en termes de crises diverses et accumul\u00e9es. De ce point de vue, nous f\u00fbmes bien entendu servi, rejoignant en cela notre conception que les crises forment d\u00e9sormais la structure (structure crisique) de l&rsquo;\u00e9volution de notre monde. Ainsi dde.crisis devint-il un exercice passionnant alors qu&rsquo;il n&rsquo;avait \u00e9t\u00e9 au d\u00e9part qu&rsquo;une formule de sauvegarde.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Exercice r\u00e9ussi? Bien malin qui pourrait le dire, et encore plus malin qui croirait pouvoir affirmer qu&rsquo;il importe de la dire. Pour nous, dans tous les cas, le fait est que nous nous sentons bien \u00e0 l&rsquo;aise dans ce cadre d\u00e9fini par un mot, parce que ce mot est un reflet fid\u00e8le et puissant de notre \u00e9poque. De ce point de vue-l\u00e0, du point de vue de la plume, du point de vue de l&rsquo;artisan de l&rsquo;analyse, du point de vue du chercheur et du r\u00e9cepteur des intuitions fondamentales, le r\u00e9sultat est bon, significatif, encourageant et heureux. Il reste \u00e0 dde.crisis \u00e0 trouver son lectorat, ce qui, on ne sera pas \u00e9tonn\u00e9 de l&rsquo;apprendre, n&rsquo;est pas chose simple.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans ce dernier <a href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_juillet_2010.html\" class=\"gen\">num\u00e9ro<\/a> de la premi\u00e8re ann\u00e9e de <em>dde.crisis<\/em>, nous tentons d&rsquo;\u00e9tablir une appr\u00e9ciation g\u00e9n\u00e9rale de la crise qui frappe notre civilisation, au travers de ce qui nous en para\u00eet l&rsquo;essentiel,  savoir, la crise de la raison humaine. Voici le sommaire de cette rubrique <em>de defensa<\/em>.<\/p>\n<h4>\u00ab<strong><em>La raison  face \u00e0 elle-m\u00eame<\/em><\/strong><\/h4>\n<p>\u00bb<em> Le constat g\u00e9n\u00e9ral de la situation crique que nous connaissons, situation issue de plusieurs si\u00e8cles d&rsquo;activit\u00e9s inspir\u00e9es et guid\u00e9es par la raison humaine, conduit \u00e0 la mise en cause radicale de la raison humaine.  Face \u00e0 ce constat, les derniers garde-chiourmes du syst\u00e8me proclament le triomphe et l&rsquo;intangibilit\u00e9 de la raison humaine, organisatrice du syst\u00e8me g\u00e9n\u00e9ral.  Entre ces deux extr\u00eames, l&rsquo;affrontement est in\u00e9vitable: pour venir au terme de la crise, il faudra \u00e9craser la raison humaine dans le r\u00f4le inspirateur et directeur de la civilisation qu&rsquo;elle s&rsquo;est arrog\u00e9.  Pour comprendre la d\u00e9rive catastrophique de la raison humaine, on doit notamment et imp\u00e9rativement remonter au XVIII\u00e8me si\u00e8cle et \u00e0 la catastrophe qu&rsquo;il a organis\u00e9e,  cela au travers d&rsquo;un mot singulier qui r\u00e9sume la mentalit\u00e9 du si\u00e8cle: persiflage.  La capitulation de la raison humaine et son ralliement catastrophique \u00e0 un puissant courant de la mati\u00e8re d\u00e9cha\u00een\u00e9e s&rsquo;explique par la fatigue de la psychologie humaine depuis la Renaissance.  Comment la raison humaine, min\u00e9e par la fatigue de la psychologie, s&rsquo;est volontairement asservie au courant d\u00e9structurant de la mati\u00e8re d\u00e9cha\u00een\u00e9e qui r\u00e9git la deuxi\u00e8me civilisation occidentale, ou contre-civilisation, depuis la fin du XVIII\u00e8me.<\/em><\/p>\n<h4>\u00bb<em> Le temps passe et presse<\/em><\/h4>\n<p>\u00bb<em> Sommes-nous en 1789 une nouvelle fois? Pour les \u00e9v\u00e9nements, bien entendu pas; mais pour la fatigue de la psychologie, il y a sans aucun doute une correspondance \u00e9vidente, et nul ne peut pr\u00e9voir les \u00e9v\u00e9nements qui en r\u00e9sulteront.  La crise de la raison humaine nous fait orphelins d&rsquo;une parent\u00e9 que nous croyions sanctifi\u00e9e par le Progr\u00e8s. Il y a des circonstances o\u00f9 il vaut mieux \u00eatre orphelins que d\u00e9pendre de parents ill\u00e9gitimes et diaboliques. <\/em> <em>L&rsquo;alternative n\u00e9cessaire implique une r\u00e9volution de la pens\u00e9e: r\u00e9trograder la raison dans sa fonction originelle d&rsquo;outil parmi d&rsquo;autres de la pens\u00e9e et r\u00e9habiliter des conceptions sur-rationnelles comme l&rsquo;intuition et le domaine du sacr\u00e9.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 juillet 2010 \u00e0 05H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci-dessous, nous publions l&rsquo;\u00e9ditorial du dernier num\u00e9ro du premier volume (premi\u00e8re ann\u00e9e) de parution de dde.crisis. C&rsquo;est le 10 septembre 2009 qu&rsquo;a paru le premier num\u00e9ro de la version en ligne de dde.crisis, qui prenait la succession de la Lettre d&rsquo;Analyse de defensa &#038; eurostrat\u00e9gie (publi\u00e9 en version classique, en papier v\u00e9n\u00e9rable). Ce num\u00e9ro du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3228,9826,2631,9827,2622,5535],"class_list":["post-72077","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-crise","tag-ddde-crisis","tag-de","tag-humaine","tag-la","tag-raison"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72077"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72077\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}