{"id":72087,"date":"2010-07-14T17:37:25","date_gmt":"2010-07-14T17:37:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/14\/sommes-nous-en-1789\/"},"modified":"2010-07-14T17:37:25","modified_gmt":"2010-07-14T17:37:25","slug":"sommes-nous-en-1789","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/14\/sommes-nous-en-1789\/","title":{"rendered":"Sommes-nous en 1789 ?"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Sommes-nous en 1789 ?<\/h2>\n<\/p>\n<p><p>14 juillet 2010 &mdash; Effectivement, l&rsquo;id\u00e9e est r\u00e9pandue, chez les adversaires du syst\u00e8me, notamment \u00e0 gauche mais pourquoi pas ailleurs, c&rsquo;est-\u00e0-dire dans le spectre extr\u00eamement large de la r\u00e9sistance au syst\u00e8me, de comparer la p\u00e9riode actuelle aux ann\u00e9es, aux mois qui pr\u00e9c\u00e9d\u00e8rent les d\u00e9buts de la R\u00e9volution Fran\u00e7aise. Nous avons abord\u00e9 notamment cette id\u00e9e dans notre dernier <em>dde.crisis<\/em> du <a class=\"gen\" href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_juillet_2010.html\">10 juillet 2010<\/a>.<\/p>\n<\/p>\n<p><p>Le premier paragraphe de la partie de la rubrique explorant cette hypoth\u00e8se \u00e9tait le suivant :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Il est de coutume, surtout dans la culture d&rsquo;opposition au syst\u00e8me, d&rsquo;annoncer que nous sommes en 1789 et qu&rsquo;une nouvelle Grande R\u00e9volution menace. Acceptons l&rsquo;analogie. Ce n&rsquo;est certainement pas pour annoncer pour demain matin (14 juillet 2010) la prise du b\u00e2timent du FMI comme si c&rsquo;\u00e9tait la Bastille, ni des \u00e9meutes de la faim qui renverseraient un r\u00e9gime tricentenaire. Nous consid\u00e9rons que ces sch\u00e9mas sont d\u00e9pass\u00e9s et montrent les limites de la raison humaine \u00e0 concevoir sa propre crise terminale. (La plupart des opposants au syst\u00e8me, ceux-l\u00e0 m\u00eame qui annoncent que \u00ab\u00a0nous sommes en 1789\u00a0\u00bb, qui d\u00e9noncent un syst\u00e8me asservisseur de la raison humaine consentante, sont eux-m\u00eames d\u00e9pendants de cette raison humaine pour la prospective.) Par contre, ce qui, \u00e0 notre sens, ressemble \u00e0 1789, c&rsquo;est l&rsquo;\u00e9tat de notre psychologie &ndash; la m\u00eame fatigue, voulons-nous dire, d&rsquo;une psychologie qui a trop subi de pressions \u00e0 la fois du syst\u00e8me et de la raison dont elle devrait \u00eatre l&rsquo;outil, qui lui imposent des perceptions diff\u00e9rentes de la r\u00e9alit\u00e9.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous allons envisager, sur un plan plus pratique et li\u00e9 \u00e0 l&rsquo;actualit\u00e9, le champ d&rsquo;application possible de cette hypoth\u00e8se. (Dans <em>dde.crisis<\/em>, nous nous attachons surtout \u00e0 ins\u00e9rer l&rsquo;analogie et l&rsquo;hypoth\u00e8se qu&rsquo;elle sugg\u00e8re dans le cadre beaucoup plus vaste de \u00ab\u00a0la crise de la raison humaine\u00a0\u00bb, notamment \u00e0 la lumi\u00e8re de la r\u00e9f\u00e9rence \u00e9v\u00e9nementielle que nous fournit cette m\u00eame analogie, &ndash; <em>dito<\/em>, le Si\u00e8cle des Lumi\u00e8res jusqu&rsquo;\u00e0 1789.)<\/p>\n<\/p>\n<p><p>En d\u00e9veloppant notre analyse des \u00e9v\u00e9nements historiques comme nous le faisons dans <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> (voir notre <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/section-la_grace_de_l_histoire.html\">rubrique<\/a>), notamment en pla\u00e7ant la R\u00e9volution Fran\u00e7aise comme l&rsquo;un des trois \u00e9v\u00e9nements constitutifs de ce que nous nommons la \u00ab\u00a0deuxi\u00e8me civilisation occidentale\u00a0\u00bb, ou la \u00ab\u00a0contre-civilisation\u00a0\u00bb, nous avons privil\u00e9gi\u00e9 une \u00e9valuation de la R\u00e9volution Fran\u00e7aise qui modifie compl\u00e8tement la place faite aux diff\u00e9rents facteurs qui la d\u00e9terminent. Nous consid\u00e9rons les facteurs politiques, sociaux, \u00e9conomiques, etc., &ndash; tout ce qui est consid\u00e9r\u00e9, classiquement et \u00ab\u00a0rationnellement\u00a0\u00bb, c&rsquo;est-\u00e0-dire id\u00e9ologiquement, selon le prisme id\u00e9ologique hostile \u00e0 l&rsquo;Ancien R\u00e9gime, &ndash; comme accessoires, c&rsquo;est-\u00e0-dire secondaires. Nous ne nions pas leur importance \u00e9v\u00e9nementielle, quantitative, etc., mais leur nions la place de \u00ab\u00a0cause premi\u00e8re\u00a0\u00bb qui leur est en g\u00e9n\u00e9ral attribu\u00e9e. Nous faisons une place essentielle \u00e0 la psychologie, comme au facteur primaire et primordial, comme \u00e0 la \u00ab\u00a0cause premi\u00e8re\u00a0\u00bb effectivement, de la R\u00e9volution.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9volution de la psychologie fait dire \u00e0 certains, toujours selon une interpr\u00e9tation id\u00e9ologique, qu&rsquo;on voit au XVIII\u00e8me si\u00e8cle la naissance d&rsquo;une \u00ab\u00a0opinion publique\u00a0\u00bb. Nous interpr\u00e9tons cette \u00e9volution d&rsquo;une fa\u00e7on tr\u00e8s diff\u00e9rente, comme la d\u00e9cadence des \u00e9lites de cette nation, &ndash; \u00e9lites comprenant aussi bien le \u00ab\u00a0parti des philosophes\u00a0\u00bb que l&rsquo;aristocratie et le clerg\u00e9, regroup\u00e9s en un vaste \u00ab\u00a0parti des salons\u00a0\u00bb o&ugrave; s&rsquo;exprimait une contestation syst\u00e9matiques de toutes les structures existantes. C&rsquo;est-\u00e0-dire que l'\u00a0\u00bb\u00e9lite\u00a0\u00bb est celle de la civilisation en place, qu&rsquo;elle soit du parti du r\u00e9gime en place ou du parti \u00e9ventuellement contestataire de ce r\u00e9gime, &ndash; et c&rsquo;est cette \u00ab\u00a0\u00e9lite\u00a0\u00bb, <em>as a whole<\/em>, qui porte la responsabilit\u00e9 des \u00e9v\u00e9nements.<\/p>\n<\/p>\n<p><p>Nous attribuons cette contestation syst\u00e9matique moins aux id\u00e9es elles-m\u00eames, avec leur contenu, qu&rsquo;au fait que ces id\u00e9es nouvelles n&rsquo;\u00e9taient pas soutenues et \u00ab\u00a0contr\u00f4l\u00e9es\u00a0\u00bb par une psychologie solide. Au contraire, nous identifions une psychologie \u00e9puis\u00e9e depuis son \u00e9volution depuis la Renaissance, qui fait que les id\u00e9es n&rsquo;avaient plus d&rsquo;assise psychologique solide, que leur contenu imm\u00e9diat et apparent \u00e9tait privil\u00e9gi\u00e9 dans la ma&icirc;trise qu&rsquo;on tentait d&rsquo;avoir d&rsquo;elles, alors que la logique circonstancielle et historique que ces id\u00e9es d\u00e9clenchaient \u00e9tait laiss\u00e9e \u00e0 elle-m\u00eame. Le r\u00e9sultat de cette circonstance est l&rsquo;irresponsabilit\u00e9, \u00e9vidente dans le chef des \u00e9lites fran\u00e7aises. Ce ph\u00e9nom\u00e8ne est concr\u00e9tis\u00e9 par le destin extraordinaire d&rsquo;un mot tr\u00e8s caract\u00e9ristique, apparu brutalement en 1734, qui fut alors d&rsquo;un emploi extraordinairement fourni, bien au-del\u00e0 de la mode, bien au-del\u00e0 de la France mais pour d\u00e9finir la France d&rsquo;alors, pour brusquement tomber en d\u00e9su\u00e9tude en 1789. Il s&rsquo;agit du mot \u00ab\u00a0persiflage\u00a0\u00bb, dont l&rsquo;\u00e9tymologie et le sens restent obscurs, et qui appara&icirc;t ainsi comme un ph\u00e9nom\u00e8ne linguistique exprimant effectivement d&rsquo;une fa\u00e7on symbolique bien plus que rationnelle, cette irresponsabilit\u00e9 des \u00e9lites et leur psychologie \u00e9puis\u00e9e affaiblissant le jugement jusqu&rsquo;\u00e0 le rendre impuissant dans son \u00e9valuation des cons\u00e9quences de la logique des id\u00e9es nouvelles que ces m\u00eames \u00e9lites favorisaient.<\/p>\n<\/p>\n<p><p>Deux \u00e9tudes r\u00e9centes, \u00e9crites par deux universitaires, ont \u00e9t\u00e9 consacr\u00e9es aux myst\u00e8res de l&rsquo;\u00e9tymologie, de la s\u00e9mantique et de la puissance symbolique \u00e0 la fois de ce mot : <em>Le si\u00e8cle du persiflage, 1734-1789<\/em>, d&rsquo;Elisabeth Bourguignat (PUF, 1998), et <em>Th\u00e9orie du persiflage<\/em>, de Pierre Chartier (PUF, 2005). Bourguignat \u00e9crit que les deux formes de persiflage mondain qu&rsquo;elle identifie<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>ont, bien involontairement,<\/em> <strong><em>fait le lit<\/em><\/strong> <em>de la R\u00e9volution, &ndash; alors que la philosophie, pour sa part, la<\/em> <strong><em>pr\u00e9parait<\/em><\/strong> <em>activement. Le persiflage sera rejet\u00e9 dans l&rsquo;enfer de l&rsquo;Ancien R\u00e9gime ; Voltaire et Rousseau entreront dans le Panth\u00e9on de la R\u00e9volution<\/em>&raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En \u00e9cartant r\u00e9solument dans cette citation, selon notre jugement, la nuance capitale du \u00ab\u00a0bien involontairement\u00a0\u00bb, nous aurions tendance \u00e0 ne pas s\u00e9parer le persiflage des philosophes, mais au contraire \u00e0 regrouper tout cela dans un parti des salons (ou, plus justement dit apr\u00e8s tout, \u00ab\u00a0parti des salonards\u00a0\u00bb) m\u00e9langeant tous ces repr\u00e9sentants de l&rsquo;Ancien R\u00e9gime en une r\u00e9volte irresponsable, volontaire ou involontaire, contre l&rsquo;Ancien R\u00e9gime, &ndash; les philosophes, l&rsquo;aristocratie, le clerg\u00e9, la Cour, voire le Roi (Louis XVI le r\u00e9formiste) \u00e0 certains moments ; \u00ab\u00a0les salons\u00a0\u00bb, en un mot, comme ph\u00e9nom\u00e8ne principal et explosif du si\u00e8cle et nullement \u00ab\u00a0l&rsquo;opinion publique\u00a0\u00bb comme on l&rsquo;a dit, en instaurant r\u00e9troactivement la vertu d\u00e9mocratique, \u00e0 la fa\u00e7on dont fait souvent la loi id\u00e9ologique aujourd&rsquo;hui. Tout cela r\u00e9v\u00e8le effectivement la psychologie \u00e9puis\u00e9e d&rsquo;une hi\u00e9rarchie qui abandonne ses responsabilit\u00e9s historiques au profit de l&rsquo;irresponsabilit\u00e9 mondaine. La R\u00e9volution va liquider le persiflage et tout ce qui va avec au profit de la &laquo;<em>guillotine permanente<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>(La &laquo;<em>guillotine permanente<\/em>&raquo;, &ndash; d\u00e9cision d&rsquo;ao&ucirc;t 1792 d&rsquo;un obscur bureaucrate r\u00e9volutionnaire de la commune de Paris, communiqu\u00e9e au bourreau Samson, de ne plus d\u00e9monter sa machine apr\u00e8s chaque ex\u00e9cution, mais de la laisser d\u00e9sormais en place, pr\u00eate \u00e0 l&rsquo;usage quotidien, au centre de la sublime capitale, Paris, qui fut effectivement le centre de la civilisation occidentale au XVIII\u00e8me si\u00e8cle. Puisqu&rsquo;il est \u00e9vident, dit le personnage, qu&rsquo;elle va beaucoup servir, la machine de monsieur Guillotin, \u00ab\u00a0laisse-l\u00e0 donc en place, citoyen Samson\u00a0\u00bb&hellip; C&rsquo;est le signe pr\u00e9monitoire que \u00ab\u00a0la mati\u00e8re d\u00e9cha&icirc;n\u00e9e\u00a0\u00bb, la violence et la brutalit\u00e9 qui vont accoucher du technologisme, sont d\u00e9sormais aux commandes. La &laquo;<em>guillotine permanente<\/em>&raquo; a chass\u00e9 le persiflage, mais elle en est l&rsquo;enfant&hellip;)<\/p>\n<\/p>\n<p><p>Enfin, nous gardons de cette rapide synth\u00e8se d&rsquo;une analyse qui constituera la derni\u00e8re partie de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> en situant l&rsquo;importance essentielle du facteur psychologique dans l&rsquo;\u00e9volution des comportements et des actes, cette id\u00e9e de \u00ab\u00a0la psychologie \u00e9puis\u00e9e\u00a0\u00bb des \u00e9lites comme \u00e9l\u00e9ment d\u00e9terminant et incontestablement premier de la pr\u00e9paration historique de la R\u00e9volution Fran\u00e7aise. Nulle id\u00e9e de distinction id\u00e9ologique dans tout cela (progressisme, conservatisme, lib\u00e9ralisme, etc.), parce que l&rsquo;id\u00e9ologie nous para&icirc;t \u00eatre le faux nez dont la raison humaine affuble son explication de l&rsquo;Histoire, pour se faire croire \u00e0 elle-m\u00eame qu&rsquo;elle contr\u00f4le l&rsquo;Histoire. Moyennant quoi, l&rsquo;Histoire finit par faire quelque pied de nez \u00e0 la raison humaine.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Certes, nous sommes en 1789, type \u00ab\u00a0contre-1789\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Notre appr\u00e9ciation est qu&rsquo;effectivement notre \u00e9poque, avec une acc\u00e9l\u00e9ration depuis la fin de la Guerre froide et 9\/11, conna&icirc;t un paroxysme de l&rsquo;\u00e9puisement de la psychologie, tr\u00e8s semblable en substance \u00e0 celui du XVIII\u00e8me si\u00e8cle. Il s&rsquo;agit effectivement de cette incapacit\u00e9 de la psychologie de donner une fermet\u00e9 logique \u00e0 la pens\u00e9e, et un \u00e9puisement largement similaire et certainement tr\u00e8s sup\u00e9rieur \u00e0 celui qui domina au XVIII\u00e8me si\u00e8cle et dans les derni\u00e8res d\u00e9cennies avant la R\u00e9volution. Il y a des similitudes sociales et \u00ab\u00a0id\u00e9ologiques\u00a0\u00bb qui traduisent cet \u00e9puisement de la psychologie.<\/p>\n<\/p>\n<p><p>&bull; On retrouve un m\u00eame \u00ab\u00a0parti des salonnards\u00a0\u00bb qui regroupe \u00e0 peu pr\u00e8s toutes les \u00e9lites, les intellectuels (nouveaux noms pour \u00ab\u00a0les philosophes\u00a0\u00bb, puisque philosophes sans philosophie), le pouvoir politique, l&rsquo;aristocratie \u00ab\u00a0du jour\u00a0\u00bb (financi\u00e8re, m\u00e9diatique, etc.). Ce \u00ab\u00a0parti des salonards\u00a0\u00bb tient le haut du pav\u00e9 et exerce une dictature compl\u00e8te sur la forme et le fond de la \u00ab\u00a0pens\u00e9e autoris\u00e9e\u00a0\u00bb, devenue \u00ab\u00a0pens\u00e9e officielle\u00a0\u00bb. Tout le monde est complice dans l&rsquo;exercice et tout le monde s&rsquo;en arrange, dans la mesure o&ugrave; l&rsquo;avantage de cette pens\u00e9e est d&rsquo;user de mat\u00e9riaux au bel aspect mais \u00e0 la forme compl\u00e8tement ind\u00e9finie, dispensant ainsi la psychologie de l&rsquo;effort que demanderait l&rsquo;expansion logique d&rsquo;une pens\u00e9e bien d\u00e9finie et bien identifi\u00e9e. On parle des \u00ab\u00a0valeurs\u00a0\u00bb, des \u00ab\u00a0id\u00e9es nouvelles\u00a0\u00bb, de la \u00ab\u00a0r\u00e9forme\u00a0\u00bb, comme on parlait de tout cela deux si\u00e8cles avant.<\/p>\n<\/p>\n<p><p>&bull; La pens\u00e9e se r\u00e9sume effectivement \u00e0 un conformisme dictatorial, \u00e0 ces quelques grandes id\u00e9es, &ndash; les plus vagues possibles, les plus vertueuses possibles, &ndash; et \u00e0 une irresponsabilit\u00e9 compl\u00e8te par rapport \u00e0 leurs effets par refus, sinon incapacit\u00e9 psychologique de les mesurer. Le reste de la vie \u00ab\u00a0intellectuelle\u00a0\u00bb se dissout dans les pratiques mondaines et m\u00e9diatiques des apparences, il se d\u00e9finit par un individualisme forcen\u00e9, une absence compl\u00e8te de solidarit\u00e9 et une vision sarcastique de toute tentative de renverser ce courant g\u00e9n\u00e9ral et de tenter d&rsquo;appr\u00e9cier la r\u00e9alit\u00e9. Ces conditions sont aujourd&rsquo;hui notablement aggrav\u00e9es par rapport au XVIII\u00e8me si\u00e8cle, le \u00ab\u00a0persiflage\u00a0\u00bb postmoderniste n&rsquo;ayant ni le brio ni l&rsquo;\u00e9l\u00e9gance qu&rsquo;on pouvait encore distinguer dans le Si\u00e8cle des Lumi\u00e8res, mais se complaisant au contraire dans la vulgarit\u00e9, la laideur et l&rsquo;inculture, et pratiquant le terrorisme intellectuel comme l&rsquo;on va \u00e0 confesse chaque dimanche.<\/p>\n<\/p>\n<p><p>Tout se passe comme si nous revenions \u00e0 la \u00ab\u00a0case d\u00e9part\u00a0\u00bb du premier 1789, mais quelques \u00e9tages en-dessous, si pas au deuxi\u00e8me ou troisi\u00e8me sous-sol dans cette \u00e9volution en spirale vers le plus bas possible, &ndash; et, bien entendu, dans un sens g\u00e9n\u00e9ral inverse, c&rsquo;est l\u00e0 l&rsquo;int\u00e9r\u00eat essentiel de cette circonstance potentielle. 1789 a inaugur\u00e9, avec les r\u00e9volutions parall\u00e8les (la R\u00e9volution am\u00e9ricaine et la r\u00e9volution du choix de la thermodynamique pour la production d&rsquo;\u00e9nergie), une \u00ab\u00a0deuxi\u00e8me civilisation occidentale\u00a0\u00bb sous la forme d&rsquo;une dynamique de la mati\u00e8re d\u00e9cha&icirc;n\u00e9e, s&rsquo;exprimant dans le syst\u00e8me du technologisme. Le syst\u00e8me de la communication, qui lui a \u00e9t\u00e9 adjoint, a acc\u00e9l\u00e9r\u00e9 l&rsquo;\u00e9volution g\u00e9n\u00e9rale de cette dynamique vers ses conditions de crise terminale, alimentant cette situation sociale et mondaine du postmodernisme, qui serait effectivement du m\u00eame ordre que le climat du XVIII\u00e8me si\u00e8cle, mais caricatur\u00e9, infiniment aggrav\u00e9 par un nihilisme maximaliste enfant\u00e9 par l&rsquo;accouplement monstrueux du mercantilisme et d&rsquo;un <em>carpe diem<\/em> r\u00e9duit aux acqu\u00eats de l&rsquo;instant.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9puisement de la psychologie humaine, apr\u00e8s cette exp\u00e9rience catastrophique des deux derniers si\u00e8cles qui ont vu la r\u00e9alisation de la modernit\u00e9, est infiniment plus grand qu&rsquo;il n&rsquo;\u00e9tait en 1789. On doit d&rsquo;ailleurs \u00e9galement parler de pathologie \u00e0 cet \u00e9gard, cela va de soi, et une pathologie affectant toute une civilisation, jusqu&rsquo;aux hypoth\u00e8ses tout \u00e0 fait acceptables de la tendance suicidaire comme seule r\u00e9action collective encore identifiable. La diff\u00e9rence fondamentale est que l&rsquo;\u00e9puisement de la psychologie d&rsquo;avant 1789 appelait l&rsquo;accomplissement de la catastrophe dont il \u00e9tait la pr\u00e9misse tandis que l&rsquo;\u00e9puisement de la psychologie d&rsquo;aujourd&rsquo;hui est la cons\u00e9quence de cette catastrophe.<\/p>\n<\/p>\n<p><p>Bien entendu, le th\u00e9\u00e2tre et sa sc\u00e8ne ont chang\u00e9 \u00e9galement. De la seule France qui porta seule jusqu&rsquo;\u00e0 cette r\u00e9volution de 1789 l&rsquo;\u00e9puisement de sa psychologie, on est pass\u00e9 \u00e0 la sc\u00e8ne mondiale am\u00e9nag\u00e9e par le \u00ab\u00a0bloc occidentaliste-am\u00e9ricaniste\u00a0\u00bb. Rien que de tr\u00e8s normal, la globalisation se manifestant principalement dans le champ catastrophique. Quelle va \u00eatre l&rsquo;aventure, cette fois ? On ne distingue pas ce qui pourrait tenir lieu de Bastille \u00e0 prendre aujourd&rsquo;hui, pour transformer la crise de la psychologie et les multiples autres crises (\u00ab\u00a0structure crisique\u00a0\u00bb) en cours, en crise g\u00e9n\u00e9rale enfin exprim\u00e9e ; on peut m\u00eame envisager l&rsquo;hypoth\u00e8se que l&rsquo;\u00e9v\u00e9nement a d\u00e9j\u00e0 eu lieu sans que nous le notions pr\u00e9cis\u00e9ment selon cette appr\u00e9ciation, que la nouvelle R\u00e9volution a d\u00e9j\u00e0 commenc\u00e9, sous une forme diff\u00e9rente. Que ce soit 9\/11 ou 9\/15, pour prendre les codes am\u00e9ricanistes marquant les \u00e9tapes de la crise, ou tout autre \u00e9v\u00e9nement dans ces derni\u00e8res ann\u00e9es, la Bastille serait d\u00e9j\u00e0 prise.<\/p>\n<\/p>\n<p><p>Dans tous les cas, cela importe peu, ce jugement \u00e0 la mesure des \u00e9v\u00e9nements qui, dans une \u00e9poque gouvern\u00e9e par le syst\u00e8me de la communication, existent surtout par la perception qu&rsquo;on en a, et cette perception d\u00e9pendant \u00e9videmment de la psychologie. L&rsquo;analogie de 1789 vaut donc essentiellement pour la psychologie, et rejoint notre jugement g\u00e9n\u00e9ral concernant l&rsquo;importance essentielle du domaine ; elle vaut pour la fin d&rsquo;un monde cr\u00e9\u00e9 (notamment) par le premier 1789, \u00e0 partir des m\u00eames travers humains que l&rsquo;on rel\u00e8ve aujourd&rsquo;hui, en infiniment grossis et accentu\u00e9s, ce qui implique effectivement une continuit\u00e9&hellip; Mais cette continuit\u00e9 s&rsquo;arr\u00eate l\u00e0 car, bien entendu, les \u00e9v\u00e9nements vont dans le sens contraire s&rsquo;il s&rsquo;agit d&rsquo;un nouveau 1789.<\/p>\n<\/p>\n<p><p>S&rsquo;il s&rsquo;agit d&rsquo;un autre 1789, comme nous en acceptons l&rsquo;id\u00e9e, on comprend qu&rsquo;il ne s&rsquo;agit pas du m\u00eame 1789, mais bien d&rsquo;une sorte de \u00ab\u00a0contre-1789\u00a0\u00bb, tout comme cette \u00ab\u00a0deuxi\u00e8me civilisation occidentale\u00a0\u00bb est en r\u00e9alit\u00e9 une \u00ab\u00a0contre-civilisation\u00a0\u00bb qui arrive \u00e0 sa crise terminale, dont la crise n&rsquo;implique pas une simple chute mais la rupture au bout de la chute. La rupture n&rsquo;implique nullement un retour \u00e0 1788, ce qui est le diagnostic des sots ou des persifleurs qui voudraient ridiculiser l&rsquo;argument pour se faire bien voir dans les salons, &ndash; bref, ils ont du temps \u00e0 perdre. Ce \u00ab\u00a0contre-1789\u00a0\u00bb implique la rupture d&rsquo;un mal\u00e9fice qui nous encha&icirc;ne, \u00e0 cause du premier 1789 et du reste, \u00e0 un processus nihiliste et suicidaire, o&ugrave; la \u00ab\u00a0raison humaine\u00a0\u00bb a accept\u00e9, elle, de s&rsquo;encha&icirc;ner paradoxalement au d\u00e9cha&icirc;nement de la mati\u00e8re en \u00e9change de l&rsquo;illusion de ma&icirc;triser le destin du monde. \u00ab\u00a0Contre-1789\u00a0\u00bb, contre 1789, pour voir jusqu&rsquo;o&ugrave; r\u00e9siste notre pacte faustien. C&rsquo;est une exp\u00e9rience int\u00e9ressante.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sommes-nous en 1789 ? 14 juillet 2010 &mdash; Effectivement, l&rsquo;id\u00e9e est r\u00e9pandue, chez les adversaires du syst\u00e8me, notamment \u00e0 gauche mais pourquoi pas ailleurs, c&rsquo;est-\u00e0-dire dans le spectre extr\u00eamement large de la r\u00e9sistance au syst\u00e8me, de comparer la p\u00e9riode actuelle aux ann\u00e9es, aux mois qui pr\u00e9c\u00e9d\u00e8rent les d\u00e9buts de la R\u00e9volution Fran\u00e7aise. Nous avons abord\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[9495,9837,2631,2604,9838,2747,3969,9840,8386,2622,3209,5623,9839,3099,2879,8973],"class_list":["post-72087","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-9495","tag-contre-1789","tag-de","tag-des","tag-faustien","tag-francaise","tag-grace","tag-guilottine","tag-lhistoire","tag-la","tag-pacte","tag-parti","tag-persiflage","tag-psychologie","tag-revolution","tag-salonards"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72087"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72087\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}