{"id":72108,"date":"2010-07-19T17:02:25","date_gmt":"2010-07-19T17:02:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/19\/dialogues-10-la-crise-de-la-raison\/"},"modified":"2010-07-19T17:02:25","modified_gmt":"2010-07-19T17:02:25","slug":"dialogues-10-la-crise-de-la-raison","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/19\/dialogues-10-la-crise-de-la-raison\/","title":{"rendered":"<em>DIALOGUES<\/em>-10 : La crise de la raison"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-10 : La crise de la raison<\/h2>\n<\/p>\n<p><p>\tJe voudrais confirmer une sorte de rupture par rapport \u00e0 la premi\u00e8re phase de ces <em>DIALOGUES<\/em>, pour lancer cette s\u00e9rie d&rsquo;entretiens sur une voie un peu diff\u00e9rente,  disons incurv\u00e9e, car les sujets initialement trait\u00e9s restent concern\u00e9s. Jean-Paul Baquiast l&rsquo;a lui-m\u00eame sugg\u00e9r\u00e9, dans un <a href=\"http:\/\/www.dedefensa.org\/forum-il_y_a_mystere_et_mystere_01_07_2010.html\" class=\"gen\">commentaire<\/a> sur le <em>Forum<\/em> du texte <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-il_y_a_mystere_et_mystere_01_07_2010.html\" class=\"gen\">1er juillet 2010<\/a>, \u00ab<em>Il y a myst\u00e8re et Myst\u00e8re<\/em>\u00bb :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Je pense que les questions que vous \u00e9voquez les uns et les autres devraient \u00eatre approfondies encore, notamment dans les Dialogues<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tLe texte de monsieur Christian Steiner, du <a href=\"http:\/\/www.dedefensa.org\/article-de_l_intelligence_geopoetique_ii_04_07_2010.html\" class=\"gen\">4 juillet 2010<\/a>, sur <em>Ouverture libre<\/em>, confirme l&rsquo;int\u00e9r\u00eat du sujet et du d\u00e9bat. C&rsquo;est pour cette raison que nous l&rsquo;avons invit\u00e9 \u00e0 entrer dans nos <em>DIALOGUES<\/em>, \u00e0 inscrire ce m\u00eame texte effectivement dans nos \u00e9changes. A cet \u00e9gard, le s de <em>DIALOGUES<\/em> \u00e9tait pr\u00e9monitoire,  une intuition de plus, apr\u00e8s tout<\/p>\n<h3>Caract\u00e8re utilitaire et autonome de la psychologie<\/h3>\n<\/p>\n<p><p>\tJ&rsquo;encha\u00eene donc sur le texte de monsieur Steiner, qui, lui-m\u00eame, encha\u00eenait sur cet autre texte (ce m\u00eame \u00ab<em>Il y a myst\u00e8re et Myst\u00e8re<\/em>\u00bb), publi\u00e9 hors-<em>DIALOGUES<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/article-il_y_a_mystere_et_mystere_01_07_2010.html\" class=\"gen\">1er juillet 2010<\/a>. Je vais donc d\u00e9velopper l&rsquo;id\u00e9e centrale initiale qui pourrait se r\u00e9sumer d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale \u00e0 ceci : il faut <strong>absolument<\/strong>, d&rsquo;une part agrandir et hausser la pens\u00e9e \u00e0 des domaines autres que la raison, d&rsquo;autre part r\u00e9aliser ce bouleversement dans une combinaison o\u00f9 la raison n&rsquo;a pas la place dominante qu&rsquo;on lui donne d&rsquo;habitude,  souvent proche d&rsquo;une position exclusive. C&rsquo;est donc le point central de mon propos : la raison n&rsquo;est pas l&rsquo;\u00e9l\u00e9ment exclusif de la pens\u00e9e, elle n&rsquo;en est m\u00eame pas n\u00e9cessairement l&rsquo;\u00e9l\u00e9ment central ni le plus haut. (Notez que lorsque je parle de raison, il ne peut s&rsquo;agir dans ce cas que de la raison humaine.)<\/p>\n<\/p>\n<p><p>\tAvant d&rsquo;aller plus loin sur ce point, voici un <em>distinguo<\/em> absolument essentiel. Lorsque je parle de la raison, je parle d&rsquo;un \u00e9l\u00e9ment parmi d&rsquo;autres de la pens\u00e9e,  on verra lequel plus loin, selon mes conceptions,  et, par cons\u00e9quence assez logique, lorsque je parle de la psychologie, ce que je fais souvent et d&rsquo;une fa\u00e7on que je voudrais importante, je parle d&rsquo;un \u00e9l\u00e9ment annexe de la pens\u00e9e. Pour moi, la psychologie est un syst\u00e8me de la cat\u00e9gorie qu&rsquo;on pourrait qualifier d&rsquo;utilitaire, qui est une sorte d&rsquo;aliment, ou de carburant de la pens\u00e9e. Sa qualit\u00e9 biologique, sensorielle, fonctionnelle, intuitive, donne \u00e0 la pens\u00e9e un mat\u00e9riel de fonctionnement d&rsquo;autant plus raffin\u00e9. Vous savez que l&rsquo;une de mes th\u00e8ses pour expliquer la d\u00e9cadence du comportement des \u00e9lites fran\u00e7aises au XVIII\u00e8me si\u00e8cle, conduisant \u00e0 la R\u00e9volution, ne tient nullement aux id\u00e9es et \u00e0 leur contenu,  fussent-elles, ces id\u00e9es, r\u00e9volutionnaires et\/ou extraordinairement \u00e9labor\u00e9es, puissantes, etc.,  mais \u00e0 l&rsquo;\u00e9puisement de la psychologie, \u00e0 la mauvaise qualit\u00e9 du carburant, qui conduit \u00e0 accepter les id\u00e9es sans avoir la <strong>force<\/strong> intellectuelle (et non l&rsquo;intelligence, qualit\u00e9 syst\u00e9matiquement sur\u00e9valu\u00e9e) d&rsquo;observer, de comprendre, voire plus encore de distinguer par intuition les effets engendr\u00e9s par le d\u00e9veloppement logique \u00e0 long terme de ces id\u00e9es, et donc de les contr\u00f4ler.<\/p>\n<\/p>\n<p><p>\tCela signifie <strong>aussi<\/strong> que la psychologie, qui est au service de la pens\u00e9e, n&rsquo;est nullement au service de la raison, puisque la raison, selon mes conceptions, n&rsquo;est qu&rsquo;un \u00e9l\u00e9ment de la pens\u00e9e, un parmi d&rsquo;autres. La psychologie n&rsquo;est pas li\u00e9e \u00e0 la raison, elle a son autonomie de syst\u00e8me ; elle d\u00e9pend de la pens\u00e9e, pour l&rsquo;agr\u00e9ment \u00e0 son apport, exactement au m\u00eame titre que la raison d\u00e9pend de la pens\u00e9e. Il s&rsquo;en d\u00e9duit que la pens\u00e9e doit juger de la valeur de l&rsquo;apport de la psychologie, non selon le <em>diktat<\/em> de la raison, mais selon ce qu&rsquo;elle juge de la force et de la sant\u00e9 de la psychologie \u00e0 assurer son r\u00f4le utilitaire.<\/p>\n<h3>Usurpation et subversion de la raison<\/h3>\n<\/p>\n<p><p>\tTout cela me conduit \u00e9videmment au proc\u00e8s de la raison,  ou, dirais-je, au proc\u00e8s inutile de la raison. Il n&rsquo;entre pas dans mes intentions de la condamner sans appel ni sursis, et, par cons\u00e9quent, de faire ce proc\u00e8s qui est d\u00e9j\u00e0 instruit et conduit \u00e0 bien par les \u00e9v\u00e9nements que nous subissons aujourd&rsquo;hui. Il entre dans mes intentions de d\u00e9noncer ce que cinq si\u00e8cles de pr\u00e9-modernit\u00e9 et de modernit\u00e9, dont essentiellement nos deux derniers si\u00e8cles de modernit\u00e9, ont fait de la raison. En l&rsquo;occurrence, le vrai coupable est la modernit\u00e9 et non la raison, mais il reste que la raison est devenue dans ce traitement une monstrueuse caricature d&rsquo;elle-m\u00eame, une affirmation vaniteuse et trompeuse d&rsquo;une conception de la ma\u00eetrise du monde et, en r\u00e9alit\u00e9, derri\u00e8re cette apparence, l&rsquo;esclave docile et l&rsquo;alibi d&rsquo;un courant furieux de la mati\u00e8re d\u00e9cha\u00een\u00e9e cr\u00e9atrice d&rsquo;un syst\u00e8me d\u00e9structurant qui pulv\u00e9rise la civilisation en une ivresse de puissance et en une r\u00e9duction entropique syst\u00e9matique de tout ce qui est qualitatif au profit d&rsquo;un nivellement terrifiant par la puissance quantitative. Le p\u00e9ch\u00e9 terrible de la raison subvertie est d&rsquo;avoir couvert tout cela d&rsquo;un masque de mesure et de morale.<\/p>\n<\/p>\n<p><p>\tLa raison ainsi pervertie est devenue subversion pure. Elle a usurp\u00e9 la pens\u00e9e, se substituant \u00e0 elle et pr\u00e9tendant \u00eatre la pens\u00e9e \u00e0 elle seule. M\u00eame la spiritualit\u00e9 est devenue une annexe de la raison, perdant ainsi ses caract\u00e8res de transcendance qui en faisaient toute la sublime valeur. Le pire de cette pi\u00e8tre aventure est que ce triomphe de la raison pervertie marque en fait son asservissement \u00e0 une dynamique d\u00e9cha\u00een\u00e9e de la mati\u00e8re qui est son v\u00e9ritable ma\u00eetre.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est plus temps, comme je disais plus haut, de faire un proc\u00e8s de la raison pervertie, mais de constater les effets de cette triste aventure. Aucune enqu\u00eate ni instruction du dossier ne s&rsquo;imposent, l&rsquo;\u00e9vidence de la catastrophe o\u00f9 s&rsquo;ab\u00eeme le monde et notre caricature catastrophique de civilisation en phase ultime y suffisent. Partout, la mati\u00e8re d\u00e9cha\u00een\u00e9e nous entra\u00eene dans un destin dont il est difficile de ne pas deviner d&rsquo;intuition le caract\u00e8re catastrophique, et destin sur lequel nous n&rsquo;avons plus aucune prise. La seule faiblesse de cette situation est paradoxalement sa force ; cette \u00e9vidence est tellement forte qu&rsquo;elle conduit nombre d&rsquo;esprits soumis \u00e0 cette raison pervertie \u00e0 ne pas y croire,  parce c&rsquo;est trop \u00e9vident, c&rsquo;est trop \u00e9crasant, c&rsquo;est trop d\u00e9sesp\u00e9rant,  parce que c&rsquo;est trop <strong>impr\u00e9vu<\/strong> par rapport aux normes auxquelles nous sommes soumis. On notera que ce n&rsquo;est pas une attitude rationnelle mais une attitude de croyant, qui oppose sa foi \u00e0 l&rsquo;\u00e9vidence de la dynamique de la situation du monde,  bien que sa foi pr\u00e9tende \u00eatre le simple constat du triomphe de la raison dans sa ma\u00eetrise de la situation du monde. Mais nous savons bien que la raison est devenue une religion, qu&rsquo;elle a m\u00eame sa m\u00e9taphysique. (Il suffit de lire <a href=\"http:\/\/www.dedefensa.org\/article-lettre_ouverte_a_noam_chomsky_suite_a_sa_visite_a_paris_18_06_2010.html\" class=\"gen\">Diana Johnstone<\/a> ou de citer cette remarque d&rsquo;Elie Barnavi, dans le <em>A un ami isra\u00e9lien<\/em> de R\u00e9gis Debray [Flammarion, 2010]: \u00ab<em>La Shoah s&rsquo;est hiss\u00e9e au rang de religion civile de l&rsquo;Occident.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tDans toute cette organisation faussaire, avec tous ses attributs, du r\u00f4le que s&rsquo;est attribu\u00e9e la raison subvertie, ou du r\u00f4le que la raison subvertie a \u00e9t\u00e9 contrainte inconsciemment d&rsquo;assumer, l&rsquo;usurpation est totale. Jamais la crise la plus immense qu&rsquo;on puisse concevoir n&rsquo;est apparue paradoxalement en termes aussi simples.<\/p>\n<h3>N\u00e9cessit\u00e9 et force de l&rsquo;intuition<\/h3>\n<\/p>\n<p><p>\tJ&rsquo;ai d\u00e9j\u00e0 dit ma conviction qu&rsquo;il \u00e9tait n\u00e9cessaire de faire entrer dans la pens\u00e9e des facteurs qui \u00e9chappent au contr\u00f4le de la raison (je parle comme un expert du Pentagone alors que la mati\u00e8re est si haute,  voil\u00e0 o\u00f9 nous m\u00e8nent les automatismes de la raison subvertie). J&rsquo;ai notamment parl\u00e9 du r\u00f4le central,  j&rsquo;insiste sur ce qualificatif de <strong>central<\/strong>,  de l&rsquo;intuition dans certaines d\u00e9marches de ma propre pens\u00e9e, pour prendre une r\u00e9f\u00e9rence que je connais.<\/p>\n<\/p>\n<p><p>\tUn lecteur particuli\u00e8rement \u00e9rudit, particuli\u00e8rement \u00e9clair\u00e9, m&rsquo;a offert un long commentaire d&rsquo;une extr\u00eame richesse sur mes propos. Je tiens \u00e0 lui dire ma reconnaissance car il m&rsquo;a beaucoup aid\u00e9. Voici un extrait de ce qu&rsquo;il dit de sa lecture de ce texte (<em>DIALOGUES<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-7_propos_d_un_historien_visionnaire__03_06_2010.html\" class=\"gen\">3 juin 2010<\/a>) o\u00f9 je parlai d&rsquo;une de mes exp\u00e9riences de l&rsquo;intuition ayant orient\u00e9 et conduit le texte du livre <em>Les \u00c2mes de Verdun<\/em>. (Ce lecteur demande \u00e0 conserver l&rsquo;anonymat, et je respecte \u00e9videmment son d\u00e9sir, qui s&rsquo;appuie d&rsquo;ailleurs sur des raisons absolument respectables.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Il me semble \u00e9vident que la substance de vos textes laisse entrevoir, d&rsquo;ailleurs bien souvent entre les mots, la pr\u00e9sence d&rsquo;un contenu purement intuitif, produit d&rsquo;une sorte d&rsquo;inspiration qui n&rsquo;est artistique qu&rsquo;au sens religieux antique de l&rsquo;id\u00e9e du po\u00e8te, et, plus pr\u00e9cis\u00e9ment, de ce que les anciens philosophes grecs appelaient une intellection,<\/em> <strong><em>no\u00e8sis<\/em><\/strong><em>, laquelle n&rsquo;a strictement rien \u00e0 voir avec ce que l&rsquo;on entend g\u00e9n\u00e9ralement aujourd&rsquo;hui<\/em> [] <em>par ce terme (imagination, intuition n\u00e9buleuse pr\u00e9-rationelle, fantasme, etc.), puisqu&rsquo;elle d\u00e9signe \u00e0 l&rsquo;origine le fruit d&rsquo;une facult\u00e9 cognitive supra-rationnelle, qui s&rsquo;actualise en une fulgurance ne se laissant pas r\u00e9duire \u00e0 la seule somme des \u00e9l\u00e9ments d&rsquo;un encha\u00eenement rationnel, et dont l&rsquo;Occident moderne, depuis au moins Kant, nie tout simplement l&rsquo;existence, la chose \u00e9tant manifestement devenue plut\u00f4t rare. Ainsi, lorsque, pour d\u00e9crire la nature artistique et non scientifique de votre d\u00e9marche d&rsquo;historien, vous \u00e9voquez cet instant pouvant \u00eatre qualifi\u00e9 de divin et de trou\u00e9e de lumi\u00e8re dans le brouillard, qui procure de brefs moments d&rsquo;intense exaltation, o\u00f9 appara\u00eet en un \u00e9clair une partie de la V\u00e9rit\u00e9 du monde, vous paraphrasez sans le savoir (?!) Platon lui-m\u00eame expliquant pourquoi le centre g\u00e9n\u00e9rateur de sa philosophie ne fera jamais l&rsquo;objet d&rsquo;un texte articul\u00e9 selon les normes scientifiques: De moi, du moins, \u00e9crit Platon dans un texte c\u00e9l\u00e8bre, il n&rsquo;existe et il n&rsquo;y aura certainement jamais aucun ouvrage sur pareils sujets. Il n&rsquo;y a pas moyen, en effet, de les mettre en formules, comme on fait pour les autres sciences, mais c&rsquo;est quand on a longtemps fr\u00e9quent\u00e9 ces probl\u00e8mes, quand on a v\u00e9cu avec eux que la v\u00e9rit\u00e9 jaillit soudain (<\/em><strong><em>exaiphn\u00e8s<\/em><\/strong><em>) dans l&rsquo;\u00e2me, comme la lumi\u00e8re jaillit de l&rsquo;\u00e9tincelle, et ensuite cro\u00eet d&rsquo;elle-m\u00eame (Lettre VII, 341c-d).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette appr\u00e9ciation m&rsquo;encourage \u00e9videmment \u00e0 suivre la voie qui est d&rsquo;observer que la structure de notre pens\u00e9e doit \u00eatre compl\u00e8tement modifi\u00e9e, \u00e0 la fois augment\u00e9e et r\u00e9organis\u00e9e, \u00e9videmment dans le sens qualitatif. Une r\u00e9volte s&rsquo;impose. Notre pens\u00e9e,  dans laquelle je donne \u00e9videmment sa place \u00e0 l&rsquo;\u00e2me, sans h\u00e9sitation,  a absolument besoin de hauteur et elle a besoin de faire montre d&rsquo;humilit\u00e9 devant cette hauteur qu&rsquo;elle doit acqu\u00e9rir. On ne peut obtenir ce r\u00e9sultat qu&rsquo;en nous d\u00e9barrassant du <em>diktat<\/em> de notre propre pens\u00e9e aujourd&rsquo;hui elle-m\u00eame subvertie, apr\u00e8s avoir laiss\u00e9 pervertir notre raison, l&rsquo;avoir institu\u00e9e inspiratrice alors qu&rsquo;elle n&rsquo;est qu&rsquo;ex\u00e9cutante et organisatrice, l&rsquo;avoir laiss\u00e9e ex\u00e9cuter son uvre de subversion. La raison (la raison humaine) qui est n\u00e9e de nous-m\u00eames ne peut \u00eatre l&rsquo;inspiratrice d&rsquo;un sens qui nous manque d\u00e9sesp\u00e9r\u00e9ment, dont il est <strong>raisonnable<\/strong>, au regard de la catastrophe o\u00f9 nous nous sommes pr\u00e9cipit\u00e9s nous-m\u00eames, raison humaine en t\u00eate, d&rsquo;envisager qu&rsquo;il ne peut venir que de l&rsquo;ext\u00e9rieur de nous.<\/p>\n<\/p>\n<p><p>\tLes indications ci-dessus, notamment celles de mon lecteur si obligeant et \u00e9rudit, nous montrent qu&rsquo;il existe des qualit\u00e9s fondamentales qui ont leur place dans la pens\u00e9e, au-dessus de la raison. (C&rsquo;est pourquoi je pr\u00e9f\u00e9rerais, par rapport \u00e0 l&rsquo;avis de monsieur Christian Steiner, conserver l&rsquo;expression supra-rationnel plut\u00f4t que l&rsquo;expression trans-rationnel qu&rsquo;il propose.)<\/p>\n<h3>Reconstruire la pens\u00e9e comme ils b\u00e2tissaient des cath\u00e9drales<\/h3>\n<\/p>\n<p><p>\tBien entendu, l&rsquo;orientation est claire et l&rsquo;id\u00e9e g\u00e9n\u00e9rale exsude du discours lui-m\u00eame. Notre pens\u00e9e manque d\u00e9sesp\u00e9r\u00e9ment des \u00e9l\u00e9ments qui pourraient l&rsquo;\u00e9lever et la transcender. Cinq si\u00e8cles de l&rsquo;\u00e9volution de la perversion de la raison ont cr\u00e9\u00e9 une solitude terrifiante de l&rsquo;\u00eatre, avec comme seule r\u00e9f\u00e9rence la subversion qu&rsquo;engendre cette raison pervertie. Que l&rsquo;on nomme cette solitude individualisme ou modernit\u00e9 importe peu, si l&rsquo;on sait reconna\u00eetre la catastrophe du monde o\u00f9 elle nous a men\u00e9s.<\/p>\n<\/p>\n<p><p>\tIl ne s&rsquo;agit pas ici de proposer des conceptions diff\u00e9rentes (id\u00e9ologie, religion, morale, politique, th\u00e9orie philosophique, etc.), des croyances ou des non-croyances, des opinions, etc., mais de rechercher une nouvelle organisation de la pens\u00e9e. Lorsqu&rsquo;on sugg\u00e8re qu&rsquo;il faut introduire une dimension spirituelle, il ne s&rsquo;agit pas de penser Dieu (!) avec la raison, ni de penser Dieu (!) selon telle ou telle religion, mais d&rsquo;introduire dans la pens\u00e9e un \u00e9l\u00e9ment de spiritualit\u00e9, ou de sacr\u00e9, qui constituerait n\u00e9cessairement une part essentielle de cette pens\u00e9e et n\u00e9cessairement la part la plus haute. La raison ne serait pr\u00e9sente que pour mieux utiliser la pr\u00e9sence de cet \u00e9l\u00e9ment de spiritualit\u00e9 ou de sacr\u00e9, pour modifier la pens\u00e9e \u00e0 mesure en lui donnant un \u00e9lan diff\u00e9rent. Cela n&rsquo;implique rien d&rsquo;autre qu&rsquo;une m\u00e9thodologie ; cela n&rsquo;implique nullement qu&rsquo;on prouvera l&rsquo;existence de Dieu, ni le contraire, qui sont des pr\u00e9occupations bien inutiles pour nos pauvres pens\u00e9es ; cela implique qu&rsquo;on change la fa\u00e7on de penser ce qui peut et doit \u00eatre pens\u00e9.<\/p>\n<\/p>\n<p><p>\tBien entendu, cette sorte de d\u00e9marche n&rsquo;est pas nouvelle puisque, comme on l&rsquo;a vu, Platon lui-m\u00eame y sacrifiait. (Elle l&rsquo;est d&rsquo;autant moins qu&rsquo;il s&rsquo;agit, \u00e0 mon sens, de la <strong>seule<\/strong> fa\u00e7on de penser pleinement,  mais cela n&rsquo;est qu&rsquo;une opinion, et, \u00e0 mon sens, fort <strong>raisonnable<\/strong>.) Il s&rsquo;agit plut\u00f4t de consid\u00e9rer cette d\u00e9marche, dans ce moment historique et m\u00eame m\u00e9tahistorique, comme une <strong>clef<\/strong> pour pouvoir s&rsquo;\u00e9vader. Nous sommes \u00e0 un moment o\u00f9, d&rsquo;une part, la catastrophe du monde d\u00e9voile la perversion qui a fait de la raison, en la d\u00e9formant, un outil de subversion d&rsquo;une horrible efficacit\u00e9 ; o\u00f9, d&rsquo;autre part, la puissance du syst\u00e8me de la communication, jusqu&rsquo;\u00e0 son aspect fratricide, le virtualisme avec lui, l&rsquo;un et l&rsquo;autre qui fracassent toute notion d&rsquo;objectivit\u00e9, permettent d&rsquo;autant mieux de secouer les cha\u00eenes du  <em>diktat<\/em> de la raison subversive que cette raison n&rsquo;est plus prot\u00e9g\u00e9e par son \u00e9tiquette d&rsquo;objectivit\u00e9. Il s&rsquo;agit de profiter de cette double occasion catastrophique pour se lib\u00e9rer des cha\u00eenes qui nous tiennent, pour glisser la clef dans la serrure qui convient, et agir,  et faire agir sa pens\u00e9e.<\/p>\n<\/p>\n<p><p>\tCe n&rsquo;est pas de foi ou de croyance \u00e0 mettre dans la pens\u00e9e dont nous avons besoin,  au contraire, nous en sommes submerg\u00e9s jusqu&rsquo;\u00e0 la naus\u00e9e, de toutes les sortes, de toutes leurs \u00e9glises et de toutes leurs valeurs pr\u00e9sent\u00e9es par leur <em>marketing<\/em>,  mais d&rsquo;audace \u00e0 y mettre, comme d&rsquo;une fa\u00e7on d&rsquo;\u00eatre lib\u00e9ratrice, sans pr\u00e9jug\u00e9s, y compris ceux de la vertu (disons de leur vertu) parce que l&rsquo;audace n&rsquo;en a cure. La principale de ces audaces est d&rsquo;accepter d&rsquo;organiser sa pens\u00e9e hors de la dictature que nous nous sommes impos\u00e9s. Le principal pr\u00e9jug\u00e9 \u00e0 \u00e9carter, c&rsquo;est celui qui nous pousse \u00e0 ne pas prendre au s\u00e9rieux le sacr\u00e9 et la spiritualit\u00e9 (car penser le sacr\u00e9 et la spiritualit\u00e9 selon la raison subvertie ou selon une \u00e9glise agr\u00e9\u00e9e par la raison subvertie, c&rsquo;est bien ne pas les prendre au s\u00e9rieux). La meilleure fa\u00e7on de l&rsquo;\u00e9carter, ce pr\u00e9jug\u00e9, est d&rsquo;introduire dans l&rsquo;architecture de la pens\u00e9e le sacr\u00e9 et la spiritualit\u00e9 \u00e0 la hauteur qui convient. Il s&rsquo;agit de reconstruire la pens\u00e9e exactement comme, <em>in illo tempore<\/em>, d&rsquo;autres que nous b\u00e2tissaient des cath\u00e9drales.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Philippe Grasset<\/p>\n<\/p>\n<p><\/p>\n<h4>Note importante<\/h4>\n<p>Pour nos lecteurs, ceci. Ce texte est publi\u00e9 \u00e0 la fois dans Ouverture libre et dans la rubrique d&rsquo;archivage <em>DIALOGUES<\/em>. Si vous voulez mettre un commentaire, choisissez plut\u00f4t le Forum du <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-10_la_crise_de_la_raison_humaine_19_07_2010.html\" class=\"gen\">texte<\/a> de la rubrique <em>DIALOGUES<\/em>. Merci.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-10 : La crise de la raison Je voudrais confirmer une sorte de rupture par rapport \u00e0 la premi\u00e8re phase de ces DIALOGUES, pour lancer cette s\u00e9rie d&rsquo;entretiens sur une voie un peu diff\u00e9rente, disons incurv\u00e9e, car les sujets initialement trait\u00e9s restent concern\u00e9s. Jean-Paul Baquiast l&rsquo;a lui-m\u00eame sugg\u00e9r\u00e9, dans un commentaire sur le Forum du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3089,9859,7784,9827,8397,2964,8319,9858,4119,5535,3177,9860,8049],"class_list":["post-72108","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-cohen","tag-daniel","tag-diktat","tag-humaine","tag-intuition","tag-pensee","tag-perversion","tag-pervertie","tag-platon","tag-raison","tag-sacre","tag-spirutualite","tag-subversion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72108"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72108\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}