{"id":72115,"date":"2010-07-22T09:57:40","date_gmt":"2010-07-22T09:57:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/22\/lambiguite-bienvenue-du-parti-tea-party\/"},"modified":"2010-07-22T09:57:40","modified_gmt":"2010-07-22T09:57:40","slug":"lambiguite-bienvenue-du-parti-tea-party","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/22\/lambiguite-bienvenue-du-parti-tea-party\/","title":{"rendered":"L&rsquo;ambigu\u00eft\u00e9 bienvenue du \u201cparti\u201d <em>Tea Party<\/em>"},"content":{"rendered":"<p><p>La formation du <em>caucus<\/em> du mouvement <em>Tea Party<\/em> \u00e0 la Chambre des Repr\u00e9sentants se d\u00e9roule dans une <a href=\"http:\/\/www.dedefensa.org\/article-tea_party_ou_comment_s_organiser_sans_se_compromettre_20_07_2010.html\" class=\"gen\">ambigu\u00eft\u00e9<\/a> qui rend bien compte du caract\u00e8re du mouvement. Un article de l&rsquo;<em>Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/americas\/tea-party-unites-to-fight-obama-in-congress-2032172.html\" class=\"gen\">22 juillet 2010<\/a> d\u00e9taille la pr\u00e9sentation du <em>caucus<\/em>, hier \u00e0 Washington, par son initiatrice, la r\u00e9publicaine Michele Bachmann. Vingt-quatre parlementaires r\u00e9publicains s&rsquo;y sont affili\u00e9s, ce qui n&rsquo;est pas rien.<\/p>\n<\/p>\n<p><p>\tLa situation est tr\u00e8s particuli\u00e8re et sp\u00e9cifique puisque le parti r\u00e9publicain, qui n&rsquo;a pas encore r\u00e9agi, n&rsquo;a m\u00eame pas \u00e9t\u00e9 inform\u00e9 par Bachmann de son initiative. (\u00ab<em>The party&rsquo;s top leadership has so far not joined or even voiced support for it, perhaps because Ms Bachmann revealed only last weekend that she was creating the caucus after not bothering, apparently, to tell anyone in the Republican hierarchy what she was up to<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t L&rsquo;article rend justement compte de la r\u00e9serve et du d\u00e9sarroi de la direction du parti r\u00e9publicain, et aussi du parti d\u00e9mocrate \u00e0 sa fa\u00e7on, devant cette initiative qui ne fait que concr\u00e9tiser formellement la r\u00e9serve et le d\u00e9sarroi o\u00f9 le mouvement <em>Tea Party<\/em> met les deux partis, c&rsquo;est-\u00e0-dire l&rsquo;<em>establishment<\/em> washingtonien, m\u00eame si on d\u00e9peint ce mouvement comme la droite populiste du parti r\u00e9publicain. La tendance g\u00e9n\u00e9rale des commentaires est aussi d&rsquo;identifier la cr\u00e9ation d&rsquo;un parti alors qu&rsquo;il ne s&rsquo;agit que d&rsquo;un <em>caucus<\/em>, qui ne peut \u00eatre confondu avec un parti. Pourtant, une enqu\u00eate de <em>politico-Com<\/em> montre que 25% des Am\u00e9ricains pensent que <em>Tea Party<\/em> peut devenir un troisi\u00e8me parti viable Bref, tout et son contraire, \u00e0 propos de <em>Tea Party<\/em>.<\/p>\n<\/p>\n<p><p>\tM\u00eame les accusations de racisme soul\u00e8vent des pol\u00e9miques, y compris \u00e0 gauche et chez les progressistes. L&rsquo;affaire qui a oppos\u00e9 le NAACP de d\u00e9fense des droits civiques des Africains-Am\u00e9ricains \u00e0 <em>Tea Party<\/em>, que nous avions \u00e9voqu\u00e9e le <a href=\"http:\/\/www.dedefensa.org\/article-tea_party_ou_comment_s_organiser_sans_se_compromettre_20_07_2010.html\" class=\"gen\">20 juillet 2010<\/a> en annon\u00e7ant la formation du <em>caucus<\/em>, am\u00e8ne quelques appr\u00e9ciations dubitatives \u00e0 propos du m\u00eame NAACP (voir sur <em>Truthdig.org<\/em>, le <a href=\"http:\/\/www.truthdig.com\/report\/item\/racism_reconsidered_20100722\/\" class=\"gen\">22 juillet 2010<\/a>) autant que de l&#8217;emploi immod\u00e9r\u00e9 du mot racisme. Il est \u00e9vident que l&rsquo;accusation de racisme fait partie de l&rsquo;arsenal bureaucratique du syst\u00e8me, comme dans tous les pays du syst\u00e8me occidentaliste, et son emploi syst\u00e9matique risque parfois de provoquer des effets de boomerang. Dans tous les cas, on est loin, dans ce domaine, d&rsquo;approcher une situation de discr\u00e9dit de <em>Tea Party<\/em>, et il est tr\u00e8s probable qu&rsquo;il existe une frange non n\u00e9gligeable de l&rsquo;ensemble progressiste US qui croit \u00e0 un possible rapprochement avec <em>Tea Party<\/em>, consid\u00e9r\u00e9 dans ce cas plus comme une dissidence du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tDans ces divers exemples de situation, on retrouve le m\u00eame caract\u00e8re d&rsquo;insaisissabilit\u00e9 de <em>Tea Party<\/em>, selon les normes, positives ou n\u00e9gatives, du syst\u00e8me. Le mouvement a d\u00e9j\u00e0 subi bien des vicissitudes, il a \u00e9t\u00e9 fortement attaqu\u00e9, d\u00e9nonc\u00e9, etc., mais son caract\u00e8re d\u00e9structur\u00e9, tr\u00e8s divers et sans organisation bien pr\u00e9cise semble toujours le prot\u00e9ger. L&rsquo;initiative de <a href=\"http:\/\/www.dedefensa.org\/article-la_femme_est_l_extremisme_de_l_homme_17_11_2009.html\" class=\"gen\">Bachmann<\/a> est aussi bien une tentative de l&rsquo;ambitieuse et tr\u00e8s extr\u00e9miste parlementaire r\u00e9publicaine et populiste pour s&rsquo;approprier, dans tous les cas \u00e0 la Chambre, la dynamique <em>Tea Party<\/em>. On verra ce qu&rsquo;il en restera. En attendant l&rsquo;initiative est faite d&rsquo;une fa\u00e7on qui conforte objectivement les caract\u00e8res de <em>Tea Party<\/em> qu&rsquo;on a rappel\u00e9s, et la fa\u00e7on dont la direction r\u00e9publicaine a \u00e9t\u00e9 \u00e9cart\u00e9e de l&rsquo;op\u00e9ration, la g\u00eane et la m\u00e9fiance \u00e9videntes qui caract\u00e9risent l&rsquo;attitude de cette direction renforcent le statut \u00e0 part de <em>Tea Party<\/em>, m\u00eame \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un des temples sacr\u00e9s du syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tEncore une fois, peu importe les id\u00e9es de <em>Tea Party<\/em>, d&rsquo;autant qu&rsquo;elles sont nombreuses, diverses, parfois proches d&rsquo;\u00eatre contradictoires ; et l&rsquo;on pourrait dire la m\u00eame chose des appr\u00e9ciations pour et contre <em>Tea Party<\/em>. L&rsquo;essentiel est bien que <em>Tea Party<\/em> continue \u00e0 \u00eatre, par sa nature m\u00eame et presqu&rsquo;involontairement, un ferment de d\u00e9structuration du syst\u00e8me et, comme tel, quelque chose qu&rsquo;il faut suivre avec attention et int\u00e9r\u00eat. L&rsquo;espoir n&rsquo;est pas ici que <em>Tea Party<\/em> parvienne \u00e0 \u00eatre un troisi\u00e8me parti, ce qui serait proche d&rsquo;une institutionnalisation, et donc en grand danger de r\u00e9cup\u00e9ration. L&rsquo;important est que <em>Tea Party<\/em> continue \u00e0 semer trouble, m\u00e9fiance et d\u00e9sarroi, qu&rsquo;il continue \u00e0 \u00e9voluer toujours un peu en marge,  puisqu&rsquo;un <em>caucus<\/em> n&rsquo;est d\u00e9cid\u00e9ment pas un parti. L&rsquo;important est que personne, dans l&rsquo;<em>establishment<\/em>, surtout chez les r\u00e9publicains, ne peut lancer une attaque radicale et destructrice contre <em>Tea Party<\/em> parce qu&rsquo;il y a les \u00e9lections en novembre prochain, puis les \u00e9lections en novembre 2012, et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tEncore une fois est fait le constat que le syst\u00e8me ne parvient plus \u00e0 r\u00e9soudre aucune des crises qui l&rsquo;assaillent, au cur de la structure crisique qui le caract\u00e9rise aujourd&rsquo;hui. Car, bien entendu, <em>Tea Party<\/em> est une crise du syst\u00e8me, rien d&rsquo;autre et rien de moins. C&rsquo;est cet aspect qui le rend int\u00e9ressant, et rien d&rsquo;autre, ni ses intentions, ni ses id\u00e9es, ni toutes ces choses qui constituent l&rsquo;habituel arsenal d&rsquo;une force politique pr\u00e9tendant \u00e0 l&rsquo;originalit\u00e9 et qui se pr\u00e9pare \u00e0 \u00eatre r\u00e9cup\u00e9r\u00e9e en bonne et due forme. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 juillet 2010 \u00e0 10H02<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La formation du caucus du mouvement Tea Party \u00e0 la Chambre des Repr\u00e9sentants se d\u00e9roule dans une ambigu\u00eft\u00e9 qui rend bien compte du caract\u00e8re du mouvement. Un article de l&rsquo;Independent du 22 juillet 2010 d\u00e9taille la pr\u00e9sentation du caucus, hier \u00e0 Washington, par son initiatrice, la r\u00e9publicaine Michele Bachmann. Vingt-quatre parlementaires r\u00e9publicains s&rsquo;y sont affili\u00e9s,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8885,9861,3359,3907,7069,3424,5310,8256],"class_list":["post-72115","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bachmann","tag-caucus","tag-chambre","tag-destructuration","tag-party","tag-racisme","tag-republicains","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72115"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72115\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}