{"id":72117,"date":"2010-07-23T08:54:56","date_gmt":"2010-07-23T08:54:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/23\/tuer-bien-a-labri-derriere-une-console\/"},"modified":"2010-07-23T08:54:56","modified_gmt":"2010-07-23T08:54:56","slug":"tuer-bien-a-labri-derriere-une-console","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/23\/tuer-bien-a-labri-derriere-une-console\/","title":{"rendered":"Tuer bien \u00e0 l&rsquo;abri derri\u00e8re une console"},"content":{"rendered":"<p><h2 class=\"common-article2\">Tuer bien \u00e0 l&rsquo;abri derri\u00e8re une console<\/h2>\n<\/p>\n<p><p>\tOn n&rsquo;arr\u00eate pas le progr\u00e8s, c&rsquo;est connu. Au travers d&rsquo;un reportage diffus\u00e9 r\u00e9cemment au JT d&rsquo;une cha\u00eene fran\u00e7aise admirative, l&rsquo;arm\u00e9e am\u00e9ricaine faisait l&rsquo;\u00e9loge d&rsquo;un  nouveau centre de formation o\u00f9, avant de partir au front, les GI&rsquo;s allaient apprendre \u00e0 se battre sur un simulateur. C&rsquo;\u00e9tait la confirmation \u00e9clatante, rendue presque comique par la fiert\u00e9 des instructeurs am\u00e9ricains d\u00e9crivant leur nouveau jouet, du fantastique d\u00e9crochage qui \u00e9loigne, jour apr\u00e8s jour, progr\u00e8s technologique apr\u00e8s progr\u00e8s technologique, l&rsquo;<em>homo americanus<\/em> du monde r\u00e9el.<\/p>\n<\/p>\n<p><p>\tMais il y a d\u00e9sormais plus fort en la mati\u00e8re puisqu&rsquo;aujourd&rsquo;hui on peut massacrer de vrais civils Irakiens ou Afghans, en chair et en os, qui respirent, bougent, pensent, \u00e9prouvent, aiment, souffrent, saignent et tout et tout, avec une simple petite console install\u00e9e dans le Nevada et connect\u00e9e \u00e0 un drone. Bien \u00e0 l&rsquo;abri \u00e0 12.000 km du th\u00e9\u00e2tre d&rsquo;op\u00e9rations, de bons petits fonctionnaires US, douillettement install\u00e9s dans leur petit bureau, alternent ainsi, candides mais appliqu\u00e9s, un petit massacre et un <em>donuts<\/em>, une petite tuerie et une poign\u00e9e de <em>marshmallow<\/em> avant d&rsquo;aller faire la bise \u00e0 leur prog\u00e9niture sans avoir besoin de penser aux membres arrach\u00e9s, aux familles d\u00e9cim\u00e9es, aux enfants \u00e9ventr\u00e9s par leurs ludiques petites activit\u00e9s diurnes au service de la Libert\u00e9.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est l\u00e0 l&rsquo;une des grandes vertus du technologisme militaire US, capable d\u00e9sormais de produire des instruments qui met \u00e0 l&rsquo;abri l&rsquo;assassin de ses crimes, met \u00e0 l&rsquo;abri le bon petit soldat de l&#8217;empire du risque et de la culpabilit\u00e9, qui permet <em>in fine<\/em> de nier le crime et surtout l&rsquo;existence m\u00eame de la victime du crime puisque, par \u00e9cran interpos\u00e9, tout ce que le soldat-joueur tue en d\u00e9finitive, ce sont des pixels. Bien s\u00fbr, le syst\u00e8me anthropotechnique constitu\u00e9 dans ce cas par le soldat-joueur et sa machine nous appara\u00eet clairement comme une d\u00e9viance dont on flaire imm\u00e9diatement le caract\u00e8re profond\u00e9ment naus\u00e9abond et malsain. Et l&rsquo;on \u00e9prouve soudain une certaine admiration pour les insurg\u00e9s de toutes les guerres US qui montent au front avec des kalachs recycl\u00e9es et des bombes artisanales, assumant leur responsabilit\u00e9 de tueurs et reconnaissant au moins leur victime d&rsquo;en accepter les \u00e9claboussures sur la lame de leur couteau ou leurs mains.<\/p>\n<\/p>\n<p><p>\tBien s\u00fbr, ces d\u00e9rives technologiques et l&rsquo;\u00e9loignement du r\u00e9el qu&rsquo;elles imposent nous apprennent aussi une chose, ou plut\u00f4t nous la confirme. Le syst\u00e8me am\u00e9ricaniste\/occidentaliste produit une technologie qui l&rsquo;\u00e9loigne sans cesse un peu plus du r\u00e9el, lui fait perdre le contact avec la guerre et ses lois ce qui signifie, \u00e0 plus forte raison dans les guerres de 4\u00e8me g\u00e9n\u00e9ration, une d\u00e9faite assur\u00e9e. Car le plus fabuleux des syst\u00e8mes anthropotechnique permet sans doute de vitrifier un pays tout entier \u00e0 distance, ou peut-\u00eatre de le renvoyer \u00e0 l&rsquo;\u00e2ge de pierre sans y avoir pos\u00e9 le pied. Mais au final, il ne viendra jamais \u00e0 bout de celui qui, en face, au milieu des d\u00e9combres, se rel\u00e8vera l&rsquo;arme \u00e0 la main et la rage au cur pour d\u00e9fendre sa terre et sa famille.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Pierre Vaudan<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t<a href=\"http:\/\/www.timesonline.co.uk\/tol\/life_and_style\/men\/article5944961.ece\" class=\"gen\">http:\/\/www.timesonline.co.uk\/tol\/life_and_style\/men\/article5944961.ece<\/a><\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.youtube.com\/watch?v=qbpyHYerFp0\" class=\"gen\">http:\/\/www.youtube.com\/watch?v=qbpyHYerFp0<\/a><\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.mondialisation.ca\/index.php?context=va&#038;aid=10513\" class=\"gen\">http:\/\/www.mondialisation.ca\/index.php?context=va&#038;aid=10513<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tuer bien \u00e0 l&rsquo;abri derri\u00e8re une console On n&rsquo;arr\u00eate pas le progr\u00e8s, c&rsquo;est connu. Au travers d&rsquo;un reportage diffus\u00e9 r\u00e9cemment au JT d&rsquo;une cha\u00eene fran\u00e7aise admirative, l&rsquo;arm\u00e9e am\u00e9ricaine faisait l&rsquo;\u00e9loge d&rsquo;un nouveau centre de formation o\u00f9, avant de partir au front, les GI&rsquo;s allaient apprendre \u00e0 se battre sur un simulateur. C&rsquo;\u00e9tait la confirmation \u00e9clatante,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9876,2932,9812],"class_list":["post-72117","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-console","tag-drone","tag-vaudan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72117"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72117\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}