{"id":72132,"date":"2010-07-27T11:36:27","date_gmt":"2010-07-27T11:36:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/27\/le-laboratoire-de-notre-folie\/"},"modified":"2010-07-27T11:36:27","modified_gmt":"2010-07-27T11:36:27","slug":"le-laboratoire-de-notre-folie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/07\/27\/le-laboratoire-de-notre-folie\/","title":{"rendered":"Le laboratoire de notre folie"},"content":{"rendered":"<p><h2 class=\"common-article\">Le laboratoire de notre folie<\/h2>\n<\/p>\n<p><p>\t27 juillet 2010  Comment d\u00e9finir l&rsquo;Afghanistan ? Ecartons les futilit\u00e9s habituelles, s&rsquo;il vous pla\u00eet,  enjeux g\u00e9ostrat\u00e9giques, barrage contre l&rsquo;islamisme, les <em>tchador<\/em> ou pas pour les dames,  et posons s\u00e9rieusement cette question. L&rsquo;Afghanistan est-il le laboratoire <em>in vivo<\/em> du d\u00e9roulement extr\u00eamement rapide de la folie occidentaliste et am\u00e9ricaniste ? Nous approchons d&rsquo;un d\u00e9bat int\u00e9ressant. Cette guerre,  l&rsquo;\u00e9trange mot, dans ce cas,  est-elle l&rsquo;exposition exemplaire, <em>in vitro<\/em>, des spasmes d&rsquo;un syst\u00e8me qui ne sait plus qui il est, ce qu&rsquo;il veut, o\u00f9 il va et ainsi de suite ?<\/p>\n<\/p>\n<p><p>\tLa question, apr\u00e8s la pr\u00e9c\u00e9dente, est int\u00e9ressante. Les fuites de <em>Wikileaks<\/em> orchestr\u00e9es par son \u00e9nigmatique \u00e9diteur, Julian Assange, constituent un acte important pour d\u00e9couvrir un peu plus la tr\u00e8s int\u00e9ressante r\u00e9alit\u00e9 de ces questions et, par contraste, l&rsquo;extr\u00eame et presque \u00e9mouvante futilit\u00e9 des questions s\u00e9rieuses des moralistes, strat\u00e8ges et penseurs appoint\u00e9s du syst\u00e8me, de BHL \u00e0 Sarkozy. Question subsidiaire mais n\u00e9anmoins ultime : au nom de quoi agit Julian Assange ? C&rsquo;est-\u00e0-dire, au nom de qui ? Au nom du Ciel ? La question (la derni\u00e8re) est amusante Poursuivons.<\/p>\n<\/p>\n<p><p>\t Comme cela \u00e9tait pr\u00e9vu et pr\u00e9visible \u00e0 la fois, les fuites de <em>Wikileaks<\/em>-Assange n&rsquo;apportent rien de <strong>nouveau<\/strong>. (Cela a \u00e9t\u00e9 la r\u00e9action roborative et d&rsquo;un solide bon sens du pr\u00e9sident afghan et corrupteur-corrompu en chef, Hamid Karza\u00ef, \u00e0 l&rsquo;annonce de la chose : \u00ab<em>There is nothing new<\/em>\u00bb Un orf\u00e8vre en la mati\u00e8re.) Pourtant, le fait est qu&rsquo;il s&rsquo;agit d&rsquo;une v\u00e9ritable <strong>temp\u00eate<\/strong> qui secoue le monde pensant et sp\u00e9culant du bloc occidentaliste-am\u00e9ricaniste. D&rsquo;abord, cette civilisation qui ne conna\u00eet que la force, la puissance et le poids comme r\u00e9f\u00e9rence, donc tout ce qui est quantitatif avec une absolue ignorance du qualitatif, cette civilisation ne peut que s&rsquo;incliner devant la quantit\u00e9 : 92.000 documents, mazette (91.731, exactement.)<\/p>\n<\/p>\n<p><p>\tEnsuite, cette civilisation est touch\u00e9e au cur. La presse officielle, ou presse-<em>Pravda<\/em>, s&rsquo;est pr\u00e9cipit\u00e9e sur l&rsquo;affaire, elle y a m\u00eame collabor\u00e9. C&rsquo;est un peu comme s&rsquo;il y avait moyen, par ce biais, de se refaire une vertu, sinon une sant\u00e9. Le New York <em>Times<\/em> se croirait revenu au temps des <em>Pentagon Papers<\/em>, temps o\u00f9 il pouvait jouer au parangon de la vertu constitutionnaliste du quatri\u00e8me pouvoir qui fait se p\u00e2mer d&rsquo;aise l&rsquo;\u00e9lite des salons occidentalistes-am\u00e9ricanistes depuis deux si\u00e8cles. (La presse ind\u00e9pendante comme chien de garde des libert\u00e9s constitutionnelles dont les <em>Founding Fathers<\/em> \u00e9taient si fiers, avec Montesquieu en bandouill\u00e8re et quelques \u00e9chos du \u00ab<em>Sans la libert\u00e9 de bl\u00e2mer il n&rsquo;est pas d&rsquo;\u00e9loge flatteur<\/em>\u00bb. Vertige d&rsquo;un instant d&rsquo;une vertu retrouv\u00e9e, pour un instant, du temps o\u00f9 la raison am\u00e9ricaniste-occidentaliste croyait tenir la recette du monde meilleur.)<\/p>\n<\/p>\n<p><p>\tLes fuites de <em>Wikileaks<\/em>, par leur aspect <strong>quantitatif<\/strong>, seule chose qui importe pour le syst\u00e8me, ont soulev\u00e9 un li\u00e8vre de taille, elles ont lev\u00e9 une mar\u00e9e d\u00e9ferlante comme les aime le syst\u00e8me de la communication (effet fratricide, suite et sans fin,  voir plus loin). 92.000 documents, cela fait un tel poids qu&rsquo;on ne peut escamoter la chose, qu&rsquo;on n&rsquo;a m\u00eame plus le d\u00e9sir d&rsquo;escamoter la chose, qu&rsquo;on \u00e9prouve m\u00eame un certain plaisir \u00e0 ne pas escamoter la chose&#8230; Peu importe qu&rsquo;ils nous disent, ces documents, tout ce que nous savons d\u00e9j\u00e0, c&rsquo;est bien le <strong>poids<\/strong> qui compte. Notre intelligence, notre raison humaine, aujourd&rsquo;hui, ne peuvent pas ne pas r\u00e9agir devant l&rsquo;argument du <strong>poids<\/strong>,  l&rsquo;on peut m\u00eame dire que cette raison humaine, dans l&rsquo;\u00e9tat o\u00f9 elle se trouve du fait des catastrophes qu&rsquo;elle a elle-m\u00eame engendr\u00e9es et de sa vanit\u00e9 incompressible, n&rsquo;est plus capable de r\u00e9agir que devant l&rsquo;argument du poids. D&rsquo;o\u00f9 l&rsquo;\u00e9cho formidable des fuites.<\/p>\n<\/p>\n<p><p>\tLe s\u00e9nateur Kerry, un archi-mandarin du syst\u00e8me et pr\u00e9sident de la pompeuse commission des relations ext\u00e9rieures du non moins pompeux S\u00e9nat des Etats-Unis, a trouv\u00e9 bien du charme \u00e0 cette fuite d&rsquo;un poids massif. Il nous communique donc ceci : \u00ab<em>However illegally these documents came to light, they raise serious questions about the reality of America&rsquo;s policy toward Pakistan and Afghanistan. Those policies are at a critical stage and these documents may very well underscore the stakes and make the calibrations needed to get the policy right more urgent.<\/em>\u00bb Et Steve Clemons, qui cite ce communiqu\u00e9, <a href=\"http:\/\/www.thewashingtonnote.com\/archives\/2010\/07\/john_kerry_smel\/\" class=\"gen\">se demande<\/a> si Kerry ne conna\u00eet pas Daniel Ellsberg et s&rsquo;il n&rsquo;est pas un admirateur secret du moment <em>Pentagon Papers<\/em> (en 1971). Il faut dire que le mandarin Kerry \u00e9tait, en 1971, de retour du Vietnam o\u00f9 il avait fait une belle guerre et mesur\u00e9 la cruaut\u00e9 et la b\u00eatise de cette guerre, et il militait avec vigueur dans les troupes <em>antiwar<\/em> de la Grande R\u00e9publique. <em>Wikileaks<\/em> l&rsquo;a rajeuni, en un sens.<\/p>\n<\/p>\n<p><p>\tBref, le roi est nu constate-t-on de toutes parts, alors qu&rsquo;on le croyait bard\u00e9 de syst\u00e8mes performants, de lunettes de vis\u00e9e \u00e0 infra-rouges, de lunettes noires qui permettent de prot\u00e9ger vos pens\u00e9es secr\u00e8tes, de fusils d&rsquo;assaut agr\u00e9\u00e9s par Hollywood, de missiles qui savent reconna\u00eetre les talibans rien qu&rsquo;au turban. Les fuites ne nous apprennent rien et, pourtant, leur <strong>poids<\/strong> nous force et nous d\u00e9cille le regard. C&rsquo;est un \u00e9trange ph\u00e9nom\u00e8ne,  ou bien, non, c&rsquo;est un ph\u00e9nom\u00e8ne logique dans la logique du fou qui r\u00e8gne sur nous ; car lorsque nous disons d\u00e9ciller le regard, cela concerne beaucoup moins ce qu&rsquo;il convient de faire en Afghanistan et ce qui va se passer en Afghanistan que d&rsquo;observer l&rsquo;importance consid\u00e9rable que l&rsquo;Afghanistan a prise dans la crise du syst\u00e8me dans sa phase de folie et d&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>\tComme nous en jurions <a href=\"http:\/\/www.dedefensa.org\/article-afghan_wikileaks_et_pentagon_papers_comparaison__26_07_2010.html\" class=\"gen\">hier<\/a>, nous jurerions bien que les fuites ne changeront rien \u00e0 la strat\u00e9gie, sinon pour la durcir encore. Comme l&rsquo;on ne le dit pas assez souvent, non seulement on ne change pas une \u00e9quipe qui perd, mais, plus encore, on ne change surtout pas une \u00e9quipe qui n&rsquo;existe pas. Plac\u00e9s devant cet afflux de r\u00e9actions, les services concern\u00e9s de l&rsquo;OTAN ont eu comme r\u00e9action d&rsquo;attendre et de voir comme r\u00e9agirait Washington. La r\u00e9action de Washington-Pentagone a \u00e9t\u00e9 de dire qu&rsquo;il faudrait des jours, peut-\u00eatre des semaines, pour \u00e9valuer les d\u00e9g\u00e2ts caus\u00e9s par les fuites. A tout hasard, on met en \u00e9vidence que ces fuites, au moins, montrent que le Pakistan n&rsquo;est pas le partenaire loyal qu&rsquo;on n&rsquo;a jamais dit qu&rsquo;il \u00e9tait. En un mot, les fuites ont obtenu le r\u00e9sultat recherch\u00e9es (si ce n&rsquo;est l&rsquo;\u00e9tat recherch\u00e9 par Assange, c&rsquo;est celui qui est recherch\u00e9 par le Ciel) : elles ont install\u00e9 la discorde chez l&rsquo;ennemi, sous la forme pernicieuse de la confusion et de l&rsquo;attentisme h\u00e9b\u00e9t\u00e9 (Pour rappel, en disant ennemi, nous ne parlons que du syst\u00e8me. Les seuls \u00e0 ne pas vraiment s&rsquo;int\u00e9resser \u00e0 l&rsquo;affaire, on le remarquera, ce sont les mythiques talibans.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;orf\u00e8vre en la mati\u00e8re <a href=\"http:\/\/www.dedefensa.org\/article-ellsberg_cockburn_et_afghan_wikileaks_27_07_2010.html\" class=\"gen\">Ellsberg<\/a> a donc raison. Cette s\u00e9quence des fuites de <em>Wikileaks<\/em> vaut bien celle des <em>Pentagon Papers<\/em>, et c&rsquo;est bien par ce biais des fuites massives et de grand <strong>poids<\/strong>, selon la tactique \u00e9vidente dite du roi est nu, qu&rsquo;il faut frapper la b\u00eate. Ellsberg dit du soldat de premi\u00e8re classe Manning (et non sous-officier, comme nous l&rsquo;avions promu par inadvertance), qui est la source originelle des fuites et qui est en prison pour cela, qu&rsquo;il est \u00ab<em>the first person I&rsquo;ve heard in forty years who is in the same state of mind that I was forty years ago<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAutrement dit,  la r\u00e9volution couve puisque la conscience des ann\u00e9es du Vietnam rena\u00eet ? Pas si vite, ce n&rsquo;est pas si simple. Le terme r\u00e9volution est acceptable d&rsquo;une fa\u00e7on symbolique, quoique le terme effondrement lui conviendrait beaucoup mieux. Il s&rsquo;agit d&rsquo;un processus m\u00e9canique, sinon organique,  si l&rsquo;on pr\u00eate au syst\u00e8me, comme nous sommes toujours de plus en plus tent\u00e9s de le faire, des caract\u00e9ristiques d&rsquo;autonomie telles qu&rsquo;on puisse en faire une entit\u00e9 autonome, qui trouve elle-m\u00eame ses voies vers son \u00e9volution finale, qui est \u00e9videmment l&rsquo;effondrement. Il ne s&rsquo;agit pas d&rsquo;un processus politique ; l&rsquo;homme comparse mineur dans cette affaire, et rien d&rsquo;autre.<\/p>\n<h3>Le <em>surge<\/em> du syst\u00e8me de la communication<\/h3>\n<\/p>\n<p><p>\tOn observera avec justesse que nous usons fort abondamment du mot folie dans nos titres, ces derniers temps. (Le titre de ce texte, certes, celui du <a href=\"http:\/\/www.dedefensa.org\/article-la_folie_caracterielle_de_l_empire_19_07_2010.html\" class=\"gen\">19 juillet 2010<\/a>, celui du <a href=\"http:\/\/www.dedefensa.org\/article-publicite_autour_de_la_folie_du_systeme_23_07_2010.html\" class=\"gen\">23 juillet 2010<\/a>.) Ce n&rsquo;est pas un hasard ni, n\u00e9cessairement, un signe de bon \u00e9quilibre mental pour notre compte. Sur ce dernier  cas, on verra<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;on voit, par contre, dans le moment historique pr\u00e9sent, nous semble-t-il, c&rsquo;est un avancement remarquable de la folie du syst\u00e8me. La surprise, tout bien consid\u00e9r\u00e9, est que l&rsquo;Afghanistan soit devenu l&rsquo;un des laboratoires d&rsquo;observation favoris de cet avancement. On pouvait penser que l&rsquo;exp\u00e9rience irakienne, salu\u00e9e \u00e0 l&rsquo;\u00e9poque comme un cas encore presque unique de la manifestation de cette folie autodestructrice du syst\u00e8me, constituerait une exp\u00e9rience salutaire pour inviter \u00e0 plus de prudence dans l&rsquo;avenir. (On estimait m\u00eame qu&rsquo;il s&rsquo;agissait d&rsquo;un cas d&rsquo;usurpation, un fou, en l&rsquo;occurrence GW Bush, s&rsquo;\u00e9tant empar\u00e9 des commandes dans un moment d&rsquo;inattention du syst\u00e8me et des urnes \u00e9lectorales de Floride.) C&rsquo;est tout le contraire qui se produit, comme si les erreurs, les sottises, les non-sens accumul\u00e9s invitaient \u00e0 toujours en faire plus. Devant cette \u00e9vidence, on est conduit \u00e0 conclure que le sch\u00e9ma d&rsquo;une civilisation absolument prisonni\u00e8re d&rsquo;un syst\u00e8me qui ne peut que renouveler ses erreurs, chaque fois en plus grave, devient l&rsquo;observation centrale et \u00e9vidente de la situation. Ce qui se passe en Afghanistan est le produit de l&rsquo;activit\u00e9 du syst\u00e8me lui-m\u00eame, que ceux qui le servent ne peuvent que suivre sans s&rsquo;interroger \u00e0 ce propos, n&rsquo;en ayant ni le go\u00fbt, ni m\u00eame l&rsquo;id\u00e9e. <\/p>\n<\/p>\n<p><p>\tLa r\u00e9action du syst\u00e8me, \u00e0 c\u00f4t\u00e9 de tout ce qu&rsquo;on a d\u00e9crit plus haut, est d&rsquo;encore accentuer les conditions de sa folie, de monter aux extr\u00eames selon son habitudes d&rsquo;ores et d\u00e9j\u00e0 bien \u00e9tablie. Les experts s&rsquo;activent d\u00e9j\u00e0 avec gourmandise devant ce qu&rsquo;ils nomment (AFP relay\u00e9 par <em>SpaceWar.com<\/em> le <a href=\"http:\/\/www.spacewar.com\/reports\/Wikileaks_case_puts_focus_on_digital_security_challenges_999.html\" class=\"gen\">26 juillet 2010<\/a>) \u00ab[<em>the<\/em>] <em>security challenges of the digital age, when gigabytes of stolen data can be shared in one click<\/em>\u00bb. Cela nous promet une nouvelle mar\u00e9e de proc\u00e9dures, de r\u00e8gles, de contraintes, d&rsquo;enfermements, de contr\u00f4le de la communication par une sur-communication,  encore plus de lenteur, de paralysie, de d\u00e9sordre fig\u00e9, qui toucheront toutes les structures du syst\u00e8me. La r\u00e9action politique est d&rsquo;accro\u00eetre les pressions pour renforcer l&rsquo;engagement dans la guerre jusqu&rsquo;\u00e0 la victoire, tandis qu&rsquo;en sens inverse l&rsquo;opposition \u00e0 la guerre, y compris dans l&rsquo;<em>establishment<\/em> o\u00f9 le d\u00e9sordre r\u00e8gne, a trouv\u00e9 une base solide sur laquelle appuyer sa revendication, entra\u00eenant \u00e9videmment une surench\u00e8re des exigences dans ce sens. On dit d\u00e9j\u00e0 que l&rsquo;administration Obama serait pr\u00eate, \u00e0 la suite de cette fuite massive, \u00e0 compl\u00e8tement abandonner la limite de juillet 2011 pour le d\u00e9but du retrait des forces US, tandis que l&rsquo;opposition \u00e0 l&rsquo;engagement, s&rsquo;appuyant sur ses propres conclusions tir\u00e9es de la m\u00eame fuite massive, en ferait d\u00e9sormais une exigence fondamentale. Ce d\u00e9bat-l\u00e0 pourrait bien d&rsquo;ores et d\u00e9j\u00e0 figurer dans la campagne \u00e9lectorale US pour novembre prochain et, d\u00e9j\u00e0, dans la campagne pour les pr\u00e9sidentielles qui va encha\u00eener directement ; et il pourrait bien imposer de p\u00e9nibles fractures internes aux deux grands partis de l&rsquo;<em>establishment<\/em>.<\/p>\n<\/p>\n<p><p>\tSi l&rsquo;on veut une analyse structurelle fondamentale de l&rsquo;\u00e9v\u00e9nement, on dirait que la fuite massive de <em>Wikileaks<\/em> peut appara\u00eetre comme le <em>surge<\/em> du syst\u00e8me de la communication, r\u00e9pondant au <em>surge<\/em> du syst\u00e8me du technologisme qu&rsquo;a constitu\u00e9 le renforcement des forces US en Afghanistan d\u00e9cid\u00e9 par le pr\u00e9sident Obama en d\u00e9cembre dernier. Ce qui est \u00e9videmment remarquable, c&rsquo;est, une fois de plus, la position antagoniste des deux piliers du syst\u00e8me, le syst\u00e8me de la communication et le syst\u00e8me du technologisme. La folie se retrouve largement aliment\u00e9e par le d\u00e9sordre caract\u00e9riel r\u00e9gnant \u00e0 Washington, au contraire du d\u00e9sordre n\u00e9vrotique qui r\u00e9gnait avant, cela impliquant le passage d&rsquo;une conscience excessive \u00e0 une conscience r\u00e9duite dans la perception (voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-la_folie_caracterielle_de_l_empire_19_07_2010.html\" class=\"gen\">19 juillet 2010<\/a>), notamment et essentiellement pour notre propos, des int\u00e9r\u00eats g\u00e9n\u00e9raux et essentiels du syst\u00e8me. Ainsi discorde et division ne cessent-elles de gagner.<\/p>\n<\/p>\n<p><p>\tL&rsquo;aventure en Afghanistan se trouve de plus en plus enferm\u00e9e dans les contradictions actives et autodestructrices du syst\u00e8me, qui ont atteint aujourd&rsquo;hui le stade final de la crise d&rsquo;effondrement de ce m\u00eame syst\u00e8me. D\u00e9sormais, depuis la fuite des 92.000 (91.731) documents, la guerre en Afghanistan n&rsquo;a absolument plus <strong>rien<\/strong> \u00e0 voir, ni avec la guerre, ni avec l&rsquo;Afghanistan, et tout \u00e0 voir avec la crise du syst\u00e8me. L&rsquo;int\u00e9gration de l&rsquo;Afghanistan, non dans le syst\u00e8me, mais dans la crise de la folie du syst\u00e8me, est compl\u00e8te et achev\u00e9e. On peut d\u00e9sormais commencer \u00e0 \u00eatre assur\u00e9 que l&rsquo;aventure en Afghanistan <strong>devra<\/strong> n\u00e9cessairement se terminer, d&rsquo;une fa\u00e7on ou d&rsquo;une autre, par une catastrophe pour le syst\u00e8me. Cette issue est devenue pratiquement une exigence organique de la situation g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le laboratoire de notre folie 27 juillet 2010 Comment d\u00e9finir l&rsquo;Afghanistan ? Ecartons les futilit\u00e9s habituelles, s&rsquo;il vous pla\u00eet, enjeux g\u00e9ostrat\u00e9giques, barrage contre l&rsquo;islamisme, les tchador ou pas pour les dames, et posons s\u00e9rieusement cette question. L&rsquo;Afghanistan est-il le laboratoire in vivo du d\u00e9roulement extr\u00eamement rapide de la folie occidentaliste et am\u00e9ricaniste ? Nous approchons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,9886,3015,2631,2651,3147,4020,855,2622,3873,3201,6263,3014,4268,9887],"class_list":["post-72132","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-assange","tag-communication","tag-de","tag-du","tag-ellsberg","tag-folie","tag-kerry","tag-la","tag-papers","tag-pentagon","tag-surge","tag-systeme","tag-technologisme","tag-wikileaks"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72132"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72132\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}