{"id":72181,"date":"2010-08-13T19:05:14","date_gmt":"2010-08-13T19:05:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/13\/la-premiere-generation-de-la-globalisation-generation-perdue\/"},"modified":"2010-08-13T19:05:14","modified_gmt":"2010-08-13T19:05:14","slug":"la-premiere-generation-de-la-globalisation-generation-perdue","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/13\/la-premiere-generation-de-la-globalisation-generation-perdue\/","title":{"rendered":"La premi\u00e8re g\u00e9n\u00e9ration de la globalisation, \u2013 \u201cg\u00e9n\u00e9ration perdue\u201d"},"content":{"rendered":"<p><p>Il y avait dans le monde globalis\u00e9 de la fin 2009 630 millions de 15-24 ans. 81 millions d&rsquo;entre eux \u00e9taient ch\u00f4meurs, 7,8 millions de plus qu&rsquo;\u00e0 la fin de 2007. Toutes les pr\u00e9visions montrent que cette situation s&rsquo;aggravera encore pour la fin 2010, d&rsquo;au moins 4-5 millions de ch\u00f4meurs de plus, et sans doute plus, selon l&rsquo;International Labor Organization (ILO). (Encore ces chiffres sont-ils officiels et, dans nombre de pays, comme les USA, dissimulent-ils une r\u00e9alit\u00e9 beaucoup plus dramatique.) Tout le reste est \u00e0 l&rsquo;avenant : les jeunes sont les plus vite d\u00e9courag\u00e9s dans la recherche d&rsquo;un emploi, ils sont les plus inclin\u00e9s \u00e0 verser dans la d\u00e9linquance, la drogue, la prostitution, etc. <\/p>\n<\/p>\n<p><p>\tHier a \u00e9t\u00e9 le premier jour de l&rsquo;Ann\u00e9e Internationale de la Jeunesse de l&rsquo;ONU. (Voir CNBC du <a href=\"http:\/\/www.cnbc.com\/id\/38674003\/\" class=\"gen\">12 ao\u00fbt 2010<\/a>.) Juan Somavia, directeur de l&rsquo;ILO :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The effects of the economic and financial crisis threaten to exacerbate the pre-existing decent work deficits among youth. The result is that the number of young people stuck in working poverty grows and the cycle of working poverty persists through at least another generation.<\/em> [] <em>Young people are the drivers of economic development. Foregoing this potential is an economic waste and can undermine social stability.<\/em> [] [<em>The crisis is<\/em>] <em>an opportunity to re-assess strategies for addressing the serious disadvantages that young people face as they enter the labor market.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Ce d\u00e9sastre qui frappe les jeunes touche en fait la premi\u00e8re g\u00e9n\u00e9ration v\u00e9ritablement globalis\u00e9e, de personnes n\u00e9es dans les ann\u00e9es o\u00f9 commence \u00e0 s&rsquo;installer la globalisation dans la version postmoderne dont nous go\u00fbtons aujourd&rsquo;hui les fruits. Cette g\u00e9n\u00e9ration-l\u00e0 est donc une g\u00e9n\u00e9ration perdue (<em>Lost Generation<\/em>), selon le terme affectionn\u00e9 depuis de longues d\u00e9cennies o\u00f9 apparurent diverses g\u00e9n\u00e9rations perdues, pour diverses raisons. (Le terme de g\u00e9n\u00e9ration perdue est utilis\u00e9e dans le rapport de l&rsquo;ILO : \u00ab<em>The world risks a crisis legacy of a lost g\u00e9n\u00e9ration of young people who dropped out of the job market, the organization added in its report.<\/em>\u00bb) Mais les arguments pour employer l&rsquo;expression sont aujourd&rsquo;hui tr\u00e8s diff\u00e9rents, puisqu&rsquo;ils sont purement \u00e9conomiques. (Le terme de <em>Lost Generation<\/em> fut employ\u00e9 initialement d&rsquo;une fa\u00e7on formelle par Gertrude Stein pour d\u00e9signer la g\u00e9n\u00e9ration d&rsquo;\u00e9crivains US qui s&rsquo;expatria temporairement en France \u00e0 la fin de la Grande Guerre et apr\u00e8s,  Dos Passos, Hemingway, Fitgzerald, Ezra Pound, Sherwood Anderson,  mais selon une acceptation de l&rsquo;expression tr\u00e8s diff\u00e9rente de celle qui est utilis\u00e9e ici. Hemingway expliqua qu&rsquo;il n&rsquo;y avait rien de tragique dans cette expression, mais qu&rsquo;elle exprimait plut\u00f4t le sens de ces jeunes \u00e9crivains qui constataient qu&rsquo;ils avaient perdu l&rsquo;Am\u00e9rique telle qui la concevaient, telle qu&rsquo;on le leur avait pr\u00e9sent\u00e9e, et telle qu&rsquo;il l&rsquo;avait d\u00e9couverte si diff\u00e9rente.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;aspect le plus impressionnant dans cette sorte de constat statistique qu&rsquo;on fait r\u00e9guli\u00e8rement concernant tel ou tel domaine, telle ou telle cat\u00e9gorie d&rsquo;activit\u00e9s ou de personnes, et qui est chaque fois catastrophique pour \u00eatre parfaitement conforme \u00e0 la situation g\u00e9n\u00e9rale, c&rsquo;est qu&rsquo;il est \u00e0 la fois compl\u00e8tement quantitatif et compl\u00e8tement fractionn\u00e9, et r\u00e9duit au sujet qu&rsquo;il aborde. Constater que la g\u00e9n\u00e9ration de jeunes est une g\u00e9n\u00e9ration perdue, qui va s&rsquo;ab\u00eemer dans le ch\u00f4mage, puis dans toutes les autres activit\u00e9s d\u00e9structurantes qui accompagnent cet \u00e9tat, n&rsquo;est faire que constater une \u00e9vidence imm\u00e9diate. Pour autant, aucune conclusion de quelque int\u00e9r\u00eat n&rsquo;est tir\u00e9e, sinon celle, d&rsquo;un conformisme proche de la naus\u00e9e, que cette r\u00e9alit\u00e9 d&rsquo;une g\u00e9n\u00e9ration perdue va priver l&rsquo;\u00e9conomie de son moteur principal, et qu&rsquo;elle va constituer un ferment d&rsquo;instabilit\u00e9 sociale.<\/p>\n<\/p>\n<p><p>\tAucun enseignement, d&rsquo;aucune sorte, m\u00eame sugg\u00e9r\u00e9, n&rsquo;est introduit sur les circonstances g\u00e9n\u00e9rales qui ont conduit \u00e0 la situation de cette jeunesse. Aucun argument n&rsquo;est d\u00e9velopp\u00e9 pour simplement offrir une mise en cause du syst\u00e8me qui aboutit \u00e0 une telle catastrophe, sinon l&rsquo;avertissement que ce m\u00eame syst\u00e8me, en se privant de ses jeunes, va se priver de son principal moteur Moteur pour quoi ? Pour poursuivre un syst\u00e8me dont l&rsquo;effet est d\u00e9sormais de produire une g\u00e9n\u00e9ration perdue apr\u00e8s l&rsquo;autre, puisqu&rsquo;aussi bien, les moins jeunes, \u00e9galement soumis au ch\u00f4mage, fournissent eux-m\u00eames des g\u00e9n\u00e9rations perdues.<\/p>\n<\/p>\n<p><p>\tIl y a un refus de l&rsquo;esprit, beaucoup plus encore qu&rsquo;une consigne pour l&rsquo;esprit, de se risquer \u00e0 tirer des conclusions d&rsquo;un fait aussi massif, puisqu&rsquo;il s&rsquo;agit d&rsquo;un r\u00e9sultat portant sur le monde globalis\u00e9, sans aucune distinction ni discrimination d&rsquo;aucune sorte. Deux ans apr\u00e8s la crise du 15 septembre 2008, alors que partout s&rsquo;accumulent les signes de l&rsquo;incapacit\u00e9 du syst\u00e8me de retrouver un fonctionnement simplement acceptable, alors que se multiplient les circonstances marquant une logique de d\u00e9structuration g\u00e9n\u00e9rale, passant par des destructions \u00e9conomiques et sociales sans fin, la seule constance remarquable concerne l&rsquo;\u00e9tat d&rsquo;esprit des \u00e9lites mondiales, y compris dans ce cas les \u00e9lites syndicales, qui est le refus de s&rsquo;aventurer dans des consid\u00e9rations g\u00e9n\u00e9rales \u00e0 partir de leur exp\u00e9rience de direction. Cette paralysie de l&rsquo;esprit est, de loin, la marque la plus remarquable de l&rsquo;attitude intellectuelle des directions, alors que n&rsquo;existe aucun espoir d&rsquo;une am\u00e9lioration quelconque de la situation g\u00e9n\u00e9rale, sinon une vague croyance superstitieuse, comme l&rsquo;on sollicite un miracle.<\/p>\n<\/p>\n<p><p>\tEn effet, et pour prendre le cas de ce dirigeant de l&rsquo;ILO, rien n&#8217;emp\u00eacherait \u00e0 une telle autorit\u00e9 de pr\u00e9senter la situation selon deux points de vue. Le premier serait de tirer les conclusions et les cons\u00e9quences pratiques de la situation qu&rsquo;il d\u00e9crit dans son rapport (c&rsquo;est ce qu&rsquo;il fait effectivement). Le second, qui est autant de son devoir, sinon plus, serait de tirer un enseignement plus g\u00e9n\u00e9ral consistant \u00e0 s&rsquo;interroger d&rsquo;une mani\u00e8re extr\u00eamement pressante et n\u00e9cessairement alarm\u00e9e sur la poursuite d&rsquo;un syst\u00e8me qui a engendr\u00e9 une telle situation, qui se poursuit sans que rien n&rsquo;y ait \u00e9t\u00e9 chang\u00e9, donc qui va produire des situations encore pires puisque les conditions de demande vont se faire de plus en plus pressantes tandis que les diverses pressions des autres innombrables crises vont continuer \u00e0 s&rsquo;accro\u00eetre. Il s&rsquo;agit certainement du cas le plus \u00e9trange dans le comportement des \u00e9lites mondiales, qui est le refus de consid\u00e9rer l&rsquo;avenir en fonction des exp\u00e9riences qu&rsquo;elles constatent chaque jour, et dont elles mesurent chaque jour les effets.<\/p>\n<\/p>\n<p><p>\tIl faut donc bien en revenir \u00e0 l&rsquo;hypoth\u00e8se de l&rsquo;homme soumis au syst\u00e8me, ressentant la pression de ce syst\u00e8me pour qu&rsquo;aucune mise en cause de lui-m\u00eame (le syst\u00e8me) ne soit faite. Il n&rsquo;y a l\u00e0 aucune corruption v\u00e9nale particuli\u00e8re,  sinon celles qui sont habituelles, une haute position, des privil\u00e8ges, etc., toutes choses qui ne sont certainement pas nouvelles. Il y a une soumission psychologique totale au <em>diktat<\/em> du syst\u00e8me pour qu&rsquo;aucune accusation fondamentale ne soit port\u00e9e contre lui.<\/p>\n<\/p>\n<p><p>\tOn ne voit rien qui puisse changer ces conditions psychologiques qui imposent de telles contraintes de fer, sans m\u00eame laisser \u00e0 ceux qui les subissent le simple loisir de r\u00e9fl\u00e9chir \u00e0 la coh\u00e9rence de cette attitude, voire \u00e0 son bon sens. Il n&rsquo;est en effet nullement acquis, et nous dirions m\u00eame au contraire, qu&rsquo;un dirigeant en place qui prononcerait une mise en garde fondamentale concernant l&rsquo;avenir du syst\u00e8me, la forme du syst\u00e8me, la n\u00e9cessit\u00e9 de le changer de fond en comble, voire de le briser, subirait des cons\u00e9quences dommageables. Il y a beaucoup d&rsquo;arguments pour penser qu&rsquo;il serait au contraire l&rsquo;objet de toutes les attentions et du plus grand int\u00e9r\u00eat, et qu&rsquo;il aurait le loisir de continuer sa critique avec un certain succ\u00e8s et une r\u00e9elle popularit\u00e9. Mais ces gens sont psychologiquement emprisonn\u00e9s, bien plus que corrompus ou quelque chose que ce soit.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 ao\u00fbt 2010 \u00e0 19H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y avait dans le monde globalis\u00e9 de la fin 2009 630 millions de 15-24 ans. 81 millions d&rsquo;entre eux \u00e9taient ch\u00f4meurs, 7,8 millions de plus qu&rsquo;\u00e0 la fin de 2007. Toutes les pr\u00e9visions montrent que cette situation s&rsquo;aggravera encore pour la fin 2010, d&rsquo;au moins 4-5 millions de ch\u00f4meurs de plus, et sans doute&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3354,3858,2856,7394,9932,3741,3014],"class_list":["post-72181","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chomage","tag-corruption","tag-critique","tag-generale","tag-ilo","tag-psychologique","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72181"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72181\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}