{"id":72182,"date":"2010-08-14T06:12:05","date_gmt":"2010-08-14T06:12:05","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/14\/le-jsf-et-les-languissantes-indecisions-des-amis\/"},"modified":"2010-08-14T06:12:05","modified_gmt":"2010-08-14T06:12:05","slug":"le-jsf-et-les-languissantes-indecisions-des-amis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/14\/le-jsf-et-les-languissantes-indecisions-des-amis\/","title":{"rendered":"Le JSF et les languissantes ind\u00e9cisions des amis"},"content":{"rendered":"<p><p>Deux nouvelles informations, une directe et l&rsquo;autre indirecte, ont \u00e9t\u00e9 donn\u00e9es concernant la commande du JSF par Isra\u00ebl, qui aurait d\u00fb \u00eatre pass\u00e9e et qui ne l&rsquo;est pas encore.<\/p>\n<\/p>\n<p><p>\t Un texte de <em>World Tribune<\/em> du <a href=\"http:\/\/www.worldtribune.com\/worldtribune\/WTARC\/2010\/me_israel0770_08_11.asp\" class=\"gen\">11 ao\u00fbt 2010<\/a>, qui d\u00e9taille surtout les d\u00e9saccords des experts sur la commande du JSF, avec une majorit\u00e9 contre la commande. Le texte annonce que le Pentagone veut une d\u00e9cision pour septembre. Il y a moins d&rsquo;un mois (le <a href=\"http:\/\/www.dedefensa.org\/article-bibi_les_usa_faciles_et_19_jsf_21_07_2010.html\" class=\"gen\">21 juillet 2010<\/a>), il exigeait une d\u00e9cision pour le 31 juillet.<\/p>\n<\/p>\n<p><p>\t Un article de David A. Fulghum, d&rsquo;<em>Aviation Week<\/em>, le <a href=\"http:\/\/www.aviationweek.com\/aw\/generic\/story_generic.jsp?channel=defense&#038;id=news\/awst\/2010\/08\/09\/AW_08_09_2010_p46-243841.xml&#038;headline=Will%20F-35%20Customers%20Get%20Advanced%20Jammer?\" class=\"gen\">12 ao\u00fbt 2010<\/a>, d&rsquo;une exemplaire confusion. Fulghum s&rsquo;est rendu \u00e0 Pentuxent River pour parler avec la Navy et Lockheed Martin des conditions de transfert des syst\u00e8mes ECM (contre-mesures \u00e9lectroniques) aux alli\u00e9s qui ach\u00e8teront (ach\u00e8teraient ?) le JSF. Conclusion : le probl\u00e8me est complexe, les contre-mesures \u00e9lectroniques encore plus, et les conditions de transfert, surtout vers Isra\u00ebl, restent extraordinairement n\u00e9buleuses. On ne sait pas grand&rsquo;chose de plus.<\/p>\n<\/p>\n<p><p>\tA ces diverses nouvelles qui n&rsquo;en sont gu\u00e8re, on ajoutera le rappel de la position <a href=\"http:\/\/www.dedefensa.org\/article-la_hollande_un_verrou_en_train_de_sauter__10_08_2010.html\" class=\"gen\">hollandaise<\/a>.<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Le psychodrame isra\u00e9lo-am\u00e9ricaniste sur le JSF est une affaire dont la constance, la dur\u00e9e et les p\u00e9rip\u00e9ties ne cessent d&rsquo;\u00e9tonner. C&rsquo;est depuis l&rsquo;\u00e9t\u00e9 2007 qu&rsquo;Isra\u00ebl est press\u00e9 de commander le JSF, apr\u00e8s y \u00eatre entr\u00e9 comme coop\u00e9rant en 2003. Les intentions de commande sont pass\u00e9es de 100 \u00e0 25, \u00e0 75, \u00e0 nouveau \u00e0 100, \u00e0 nouveau \u00e0 25, puis, d\u00e9sormais, semble stagner au chiffre \u00e9tonnant de 19 avions \u00e0 $160 millions,  en attendant mieux ou en n&rsquo;attendant rien d&rsquo;autre&#8230; Diverses nouvelles ont \u00e9t\u00e9 annonc\u00e9es ces derni\u00e8res semaines et la d\u00e9cision de commande devait \u00eatre prise fin juillet lors d&rsquo;une visite du ministre de la d\u00e9fense isra\u00e9lien Barak au Pentagone. Elle semble donc renvoy\u00e9e en septembre, tandis que le d\u00e9bat fait rage en Isra\u00ebl, avec une opposition \u00e0 la commande du JSF qui ne d\u00e9sarme pas, dans les milieux des experts les plus respect\u00e9s. Barak, personnalit\u00e9 falote et de peu de poids, peine beaucoup \u00e0 imposer une d\u00e9cision d&rsquo;achat, si d&rsquo;ailleurs il en est vraiment partisan, ce qui reste \u00e0 voir.<\/p>\n<\/p>\n<p><p>\tOn a vu, par ailleurs, que la position <a href=\"http:\/\/www.dedefensa.org\/article-la_hollande_un_verrou_en_train_de_sauter__10_08_2010.html\" class=\"gen\">hollandaise<\/a> n&rsquo;est pas plus encourageante (la Hollande et les USA n\u00e9gocient pour l&rsquo;instant la possibilit\u00e9 pour la Hollande de ne pas acheter le deuxi\u00e8me prototype, alors qu&rsquo;on sait que la d\u00e9cision de commande est sans doute renvoy\u00e9e \u00e0 2015). Avec Isra\u00ebl, il s&rsquo;agit de deux pays essentiels du programme, pour diverses raisons dont leur notori\u00e9t\u00e9 dans la communaut\u00e9 pro-am\u00e9ricaniste et leur capacit\u00e9 professionnelle ; deux pays sur lesquels le Pentagone et Lockheed Martin comptent comme deux locomotives des commandes internationales, qui peinent diablement \u00e0 s&rsquo;engager.<\/p>\n<\/p>\n<p><p>\tLes deux engagements de commande d\u00e9j\u00e0 annonc\u00e9s (l&rsquo;Australie et le Canada) sont fragiles,  surtout celle du Canada qui a \u00e9t\u00e9 faite sans mise en concurrence et dont l&rsquo;opposition a affirm\u00e9 qu&rsquo;elle reviendrait dessus si elle revenait au pouvoir. Dans tous les cas, ces deux engagements sont des intentions et ne sont nullement formalis\u00e9s par quelque document d&rsquo;engagement que ce soit. Les autres pays du programme JSF, y compris le Royaume-Uni, sont devenus extr\u00eamement prudents sur leurs intentions de commande, que ce soit du point de vue des chiffres ou du point de vue de la chronologie, et ils n&rsquo;ont annonc\u00e9 aucune intention ni d\u00e9cision. Tous sont confront\u00e9s \u00e0 une double pression qui est d&rsquo;une part l&rsquo;incertitude du programme et d&rsquo;autre part leurs propres incertitudes, tant du point de vue de leurs propres situations budg\u00e9taires que du point de vue de la valeur op\u00e9rationnelle de l&rsquo;avion, que de son opportunit\u00e9 op\u00e9rationnelle dans les conditions d&rsquo;\u00e9volution g\u00e9n\u00e9rale de la situation militaire.<\/p>\n<\/p>\n<p><p>\tSi l&rsquo;on fait ce d\u00e9compte rapide, c&rsquo;est parce que le programme JSF est nettement pass\u00e9 dans une nouvelle phase de communication dans son d\u00e9veloppement, dans une \u00e9poque o\u00f9 la communication joue un r\u00f4le pr\u00e9pond\u00e9rant. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, la vigueur de la contestation du programme sur Internet, en 2008-2009, s&rsquo;est aujourd&rsquo;hui tr\u00e8s fortement tarie. Il y a deux raisons principales \u00e0 cela. D&rsquo;une part, des actions ont \u00e9t\u00e9 prises contre cette contestation, dont l&rsquo;affaire Bill <a href=\"http:\/\/www.dedefensa.org\/article-bill_sweetman_interdit_de_jsf__11_05_2010.html\" class=\"gen\">Sweetman<\/a>, dont le <a href=\"http:\/\/www.dedefensa.org\/article-sweetman_est_de_retour__03_07_2010.html\" class=\"gen\">retour<\/a> n&rsquo;a nullement signifi\u00e9 une r\u00e9surrection de son attitude tr\u00e8s critique qui avait marqu\u00e9 son action. Certains sites tr\u00e8s actifs ont consid\u00e9rablement r\u00e9duit cette activit\u00e9 (<a href=\"http:\/\/www.jsfnieuws.nl\/\" class=\"gen\">voir<\/a>  <em>jsfnieuws.nl<\/em>), pour telle ou telle raison qui reste ouverte \u00e0 la sp\u00e9culation. D&rsquo;autre part, le passage \u00e0 un stade public (Pentagone, Congr\u00e8s) de la critique du programme JSF a, d&rsquo;une certaine fa\u00e7on, pris le relais de la critique d&rsquo;Internet contre l&rsquo;avion, ce qui conduit \u00e0 la conclusion qu&rsquo;Internet a jou\u00e9 son r\u00f4le dans la transformation d&rsquo;un programme prot\u00e9g\u00e9 et verrouill\u00e9 par une communication favorable absolument virtualiste, \u00e0 une situation de pol\u00e9mique publique qui restitue une certaine v\u00e9rit\u00e9 g\u00e9n\u00e9rale du programme.<\/p>\n<\/p>\n<p><p>\tLa nouvelle phase va s&rsquo;\u00e9tendre sur les quatre ou cinq prochaines ann\u00e9es et concernera d\u00e9sormais, d&rsquo;une fa\u00e7on directe, les positions fondamentales des acteurs officiels, que ce soit aux USA ou dans les pays coop\u00e9rants. La position d&rsquo;Isra\u00ebl est importante, parce qu&rsquo;elle a d&rsquo;ores et d\u00e9j\u00e0 contribu\u00e9 \u00e0 renforcer un doute fondamental sur l&rsquo;avion,  quelle que soit la d\u00e9cision prise,  annonc\u00e9e pour septembre d&rsquo;apr\u00e8s ce qu&rsquo;on a vu, mais dont les pr\u00e9visions \u00e0 cet \u00e9gard ne cessent de varier dans un sens ou l&rsquo;autre, refl\u00e9tant beaucoup plus l&rsquo;incertitude fondamentale de ce pays que des manuvres quelconques. Qui plus est, ce d\u00e9bat porte autour d&rsquo;une commande assez \u00e9trange de 19 exemplaires, qui est manifestement le r\u00e9sultat des pressions et de m\u00e9sententes entre USA et Isra\u00ebl, et cela contribue en soi \u00e0 alimenter la pol\u00e9mique. Que ce pays qui devrait \u00eatre fondamentalement un march\u00e9 captif pour le JSF, un engagement assur\u00e9, montre un tel comportement est une mesure exemplaire des \u00e9normes difficult\u00e9s qui caract\u00e9risent le programme, cette fois-ci directement au sein des acteurs centraux.<\/p>\n<\/p>\n<p><p>\tFinalement, l&rsquo;\u00e9poque nouvelle qui s&rsquo;ouvre pour le programme JSF verra l&rsquo;essentiel de la bataille se d\u00e9rouler \u00e0 Washington, au Congr\u00e8s, entre le Congr\u00e8s et le Pentagone, dans le cadre des \u00e9v\u00e9nements qui caract\u00e9riseront l&rsquo;actuelle bataille plus large engag\u00e9e pour des r\u00e9ductions importantes du budget du Pentagone. C&rsquo;est essentiellement dans ce cadre, parce qu&rsquo;il repr\u00e9sente un budget \u00e9norme et que son utilit\u00e9 est contest\u00e9e avec le d\u00e9savantage suppl\u00e9mentaire d&rsquo;un d\u00e9veloppement chaotique, que le sort du JSF sera r\u00e9gl\u00e9. Le Pentagone sait bien ce qui l&rsquo;attend, et Gates propose d\u00e9j\u00e0 de lui-m\u00eame certaines r\u00e9ductions du budget du Pentagone en g\u00e9n\u00e9ral pour \u00e9viter des actions unilat\u00e9rales du Congr\u00e8s. Voici ce qu&rsquo;en pense Winslow Wheeler, qui est impliqu\u00e9 dans un des <a href=\"http:\/\/www.dedefensa.org\/article-offensive_generale_contre_moby_dick_12_06_2010.html\" class=\"gen\">projets<\/a> de r\u00e9duction du Congr\u00e8s (dans <em>DoDBuzz<\/em> du <a href=\"http:\/\/www.dodbuzz.com\/2010\/08\/11\/gates-tries-hard-wont-stop-cuts\/\" class=\"gen\">11 ao\u00fbt 2010<\/a> ): \u00ab<em>While he explicitly did not, repeat not, say so, I suspect Gates knows he will lose his fight against <\/em>[<em>Congress<\/em>] cuts and that he seeks with these actions to help DOD survive the cuts that are coming.<D>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 ao\u00fbt 2010 \u00e0 06H14<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux nouvelles informations, une directe et l&rsquo;autre indirecte, ont \u00e9t\u00e9 donn\u00e9es concernant la commande du JSF par Isra\u00ebl, qui aurait d\u00fb \u00eatre pass\u00e9e et qui ne l&rsquo;est pas encore. Un texte de World Tribune du 11 ao\u00fbt 2010, qui d\u00e9taille surtout les d\u00e9saccords des experts sur la commande du JSF, avec une majorit\u00e9 contre la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3285,3203,60,2774,250,5619,6769,4995],"class_list":["post-72182","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-congres","tag-hollande","tag-internet","tag-israel","tag-jsf","tag-polemique","tag-sweetman","tag-wheeler"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72182"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72182\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}